{"id":13794,"date":"2023-05-26T09:51:23","date_gmt":"2023-05-26T09:51:23","guid":{"rendered":"https:\/\/smarttrader.community\/us-aktien-stagnieren-nach-ai-anstieg-in-der-vorangegangenen-sitzung-hoffnung-auf-fortschritte-bei-den-gespraechen-ueber-die-schuldenobergrenze-china-bleibt-schwach-2"},"modified":"2023-05-28T09:37:15","modified_gmt":"2023-05-28T09:37:15","slug":"us-aktien-stagnieren-nach-ai-anstieg-in-der-vorangegangenen-sitzung-hoffnung-auf-fortschritte-bei-den-gespraechen-ueber-die-schuldenobergrenze-china-bleibt-schwach-2","status":"publish","type":"post","link":"https:\/\/smarttrader.community\/de\/uncategorized-de\/us-aktien-stagnieren-nach-ai-anstieg-in-der-vorangegangenen-sitzung-hoffnung-auf-fortschritte-bei-den-gespraechen-ueber-die-schuldenobergrenze-china-bleibt-schwach-2\/","title":{"rendered":"US-Aktien stagnieren nach AI-Anstieg in der vorangegangenen Sitzung; Hoffnung auf Fortschritte bei den Gespr\u00e4chen \u00fcber die Schuldenobergrenze; China bleibt schwach"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">\ud83d\udcc6 Freitag, 26. Mai<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u25ba <strong>Europ\u00e4ische Aktien sind wenig ver\u00e4ndert<\/strong>, die nicht von dem gestrigen positiven Schlusskurs in New York profitieren konnten, der von einigen Aktien, insbesondere von <strong>Nvidia<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u25ba <strong>Asiatische Aktien sind uneinheitlich<\/strong>, mit dem <strong>Hang Seng schlie\u00dft erneut deutlich schw\u00e4cher bei -1,93%<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u25ba <strong>Britische Einzelhandelsums\u00e4tze im April 2023 um 0,5% gestiegen<\/strong>, nach einem R\u00fcckgang von 1,2 % im M\u00e4rz wieder erholt und <strong>\u00dcbertreffen der Markterwartungen<\/strong> ein Wachstum von 0,3 %, angetrieben durch einen Anstieg von 1,0 % im Non-Food-Einzelhandel, einen Anstieg von 0,7 % im Lebensmitteleinzelhandel und ein Wachstum von 0,2 % im Online-Handel, trotz eines R\u00fcckgangs von 2,2 % bei den Kraftstoffverk\u00e4ufen aufgrund des schlechten Wetters im April und der niedrigeren Kraftstoffpreise<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u25ba <strong>Marktstimmung in Europa\/Eurozone bleibt ged\u00e4mpft<\/strong> als <strong>Chinesische M\u00e4rkte zeigen starke Anzeichen von Schw\u00e4che<\/strong>Erwartungen an eine <strong>EZB und Bank of England erh\u00f6hen die Zinsen, Deutschland befindet sich in einer technischen Rezession<\/strong> (BIP-Wachstum q\/q in zwei aufeinanderfolgenden Quartalen negativ), und<strong> Die hohe Kerninflation h\u00e4lt an.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/smarttrader.community\/membership-join\">Abonnieren<\/a> um mehr zu sehen<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n","protected":false},"excerpt":{"rendered":"<p>\ud83d\udcc6 Freitag, 26. Mai \u25ba Europ\u00e4ische Aktien sind wenig ver\u00e4ndert, die nicht von dem gestrigen positiven Schlusskurs in New York&#8230;<\/p>\n","protected":false},"author":1,"featured_media":13313,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","pmpro_default_level":"","_daextam_enable_autolinks":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-13794","post","type-post","status-publish","format-standard","has-post-thumbnail","category-uncategorized","pmpro-has-access"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>US-Aktien stagnieren nach AI-Anstieg in der vorangegangenen Sitzung; Hoffnung auf Fortschritte bei den Gespr\u00e4chen \u00fcber die Schuldenobergrenze; China bleibt schwach - SmartTrader<\/title>\n<meta name=\"description\" content=\"US-Aktien stagnieren nach AI-Anstieg in der vorangegangenen Sitzung; Hoffnung auf Fortschritte bei den Gespr\u00e4chen \u00fcber die Schuldenobergrenze; China bleibt schwach...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/smarttrader.community\/de\/uncategorized-de\/us-aktien-stagnieren-nach-ai-anstieg-in-der-vorangegangenen-sitzung-hoffnung-auf-fortschritte-bei-den-gespraechen-ueber-die-schuldenobergrenze-china-bleibt-schwach-2\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"US-Aktien stagnieren nach AI-Anstieg in der vorangegangenen Sitzung; Hoffnung auf Fortschritte bei den Gespr\u00e4chen \u00fcber die Schuldenobergrenze; China bleibt schwach - SmartTrader\" \/>\n<meta property=\"og:description\" content=\"US-Aktien stagnieren nach AI-Anstieg in der vorangegangenen Sitzung; Hoffnung auf Fortschritte bei den Gespr\u00e4chen \u00fcber die Schuldenobergrenze; China bleibt schwach...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/smarttrader.community\/de\/uncategorized-de\/us-aktien-stagnieren-nach-ai-anstieg-in-der-vorangegangenen-sitzung-hoffnung-auf-fortschritte-bei-den-gespraechen-ueber-die-schuldenobergrenze-china-bleibt-schwach-2\/\" \/>\n<meta property=\"og:site_name\" content=\"SmartTrader\" \/>\n<meta property=\"article:published_time\" content=\"2023-05-26T09:51:23+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-05-28T09:37:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/04\/19-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"SmartTrader Analyst Team\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"SmartTrader Analyst Team\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/uncategorized-de\\\/us-aktien-stagnieren-nach-ai-anstieg-in-der-vorangegangenen-sitzung-hoffnung-auf-fortschritte-bei-den-gespraechen-ueber-die-schuldenobergrenze-china-bleibt-schwach-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/uncategorized-de\\\/us-aktien-stagnieren-nach-ai-anstieg-in-der-vorangegangenen-sitzung-hoffnung-auf-fortschritte-bei-den-gespraechen-ueber-die-schuldenobergrenze-china-bleibt-schwach-2\\\/\"},\"author\":{\"name\":\"SmartTrader Analyst Team\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/#\\\/schema\\\/person\\\/bfe0c456aafbdc04b9707983e59c4e05\"},\"headline\":\"US-Aktien stagnieren nach AI-Anstieg in der vorangegangenen Sitzung; Hoffnung auf Fortschritte bei den Gespr\u00e4chen \u00fcber die Schuldenobergrenze; China bleibt schwach\",\"datePublished\":\"2023-05-26T09:51:23+00:00\",\"dateModified\":\"2023-05-28T09:37:15+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/uncategorized-de\\\/us-aktien-stagnieren-nach-ai-anstieg-in-der-vorangegangenen-sitzung-hoffnung-auf-fortschritte-bei-den-gespraechen-ueber-die-schuldenobergrenze-china-bleibt-schwach-2\\\/\"},\"wordCount\":403,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/uncategorized-de\\\/us-aktien-stagnieren-nach-ai-anstieg-in-der-vorangegangenen-sitzung-hoffnung-auf-fortschritte-bei-den-gespraechen-ueber-die-schuldenobergrenze-china-bleibt-schwach-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/19-1.png\",\"articleSection\":[\"Uncategorized\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/smarttrader.community\\\/de\\\/uncategorized-de\\\/us-aktien-stagnieren-nach-ai-anstieg-in-der-vorangegangenen-sitzung-hoffnung-auf-fortschritte-bei-den-gespraechen-ueber-die-schuldenobergrenze-china-bleibt-schwach-2\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/uncategorized-de\\\/us-aktien-stagnieren-nach-ai-anstieg-in-der-vorangegangenen-sitzung-hoffnung-auf-fortschritte-bei-den-gespraechen-ueber-die-schuldenobergrenze-china-bleibt-schwach-2\\\/\",\"url\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/uncategorized-de\\\/us-aktien-stagnieren-nach-ai-anstieg-in-der-vorangegangenen-sitzung-hoffnung-auf-fortschritte-bei-den-gespraechen-ueber-die-schuldenobergrenze-china-bleibt-schwach-2\\\/\",\"name\":\"US-Aktien stagnieren nach AI-Anstieg in der vorangegangenen Sitzung; Hoffnung auf Fortschritte bei den Gespr\u00e4chen \u00fcber die Schuldenobergrenze; China bleibt schwach - SmartTrader\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/uncategorized-de\\\/us-aktien-stagnieren-nach-ai-anstieg-in-der-vorangegangenen-sitzung-hoffnung-auf-fortschritte-bei-den-gespraechen-ueber-die-schuldenobergrenze-china-bleibt-schwach-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/uncategorized-de\\\/us-aktien-stagnieren-nach-ai-anstieg-in-der-vorangegangenen-sitzung-hoffnung-auf-fortschritte-bei-den-gespraechen-ueber-die-schuldenobergrenze-china-bleibt-schwach-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/19-1.png\",\"datePublished\":\"2023-05-26T09:51:23+00:00\",\"dateModified\":\"2023-05-28T09:37:15+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/#\\\/schema\\\/person\\\/bfe0c456aafbdc04b9707983e59c4e05\"},\"description\":\"US-Aktien stagnieren nach AI-Anstieg in der vorangegangenen Sitzung; Hoffnung auf Fortschritte bei den Gespr\u00e4chen \u00fcber die Schuldenobergrenze; China bleibt schwach...\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/uncategorized-de\\\/us-aktien-stagnieren-nach-ai-anstieg-in-der-vorangegangenen-sitzung-hoffnung-auf-fortschritte-bei-den-gespraechen-ueber-die-schuldenobergrenze-china-bleibt-schwach-2\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/smarttrader.community\\\/de\\\/uncategorized-de\\\/us-aktien-stagnieren-nach-ai-anstieg-in-der-vorangegangenen-sitzung-hoffnung-auf-fortschritte-bei-den-gespraechen-ueber-die-schuldenobergrenze-china-bleibt-schwach-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/uncategorized-de\\\/us-aktien-stagnieren-nach-ai-anstieg-in-der-vorangegangenen-sitzung-hoffnung-auf-fortschritte-bei-den-gespraechen-ueber-die-schuldenobergrenze-china-bleibt-schwach-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/19-1.png\",\"contentUrl\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/19-1.png\",\"width\":800,\"height\":500},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/uncategorized-de\\\/us-aktien-stagnieren-nach-ai-anstieg-in-der-vorangegangenen-sitzung-hoffnung-auf-fortschritte-bei-den-gespraechen-ueber-die-schuldenobergrenze-china-bleibt-schwach-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"US-Aktien stagnieren nach AI-Anstieg in der vorangegangenen Sitzung; Hoffnung auf Fortschritte bei den Gespr\u00e4chen \u00fcber die Schuldenobergrenze; China bleibt schwach\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/\",\"name\":\"SmartTrader\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/#\\\/schema\\\/person\\\/bfe0c456aafbdc04b9707983e59c4e05\",\"name\":\"SmartTrader Analyst Team\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/admin_avatar_3-96x96.png\",\"url\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/admin_avatar_3-96x96.png\",\"contentUrl\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/admin_avatar_3-96x96.png\",\"caption\":\"SmartTrader Analyst Team\"},\"sameAs\":[\"https:\\\/\\\/smarttrader.community\"],\"url\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"US-Aktien stagnieren nach AI-Anstieg in der vorangegangenen Sitzung; Hoffnung auf Fortschritte bei den Gespr\u00e4chen \u00fcber die Schuldenobergrenze; China bleibt schwach - SmartTrader","description":"US-Aktien stagnieren nach AI-Anstieg in der vorangegangenen Sitzung; Hoffnung auf Fortschritte bei den Gespr\u00e4chen \u00fcber die Schuldenobergrenze; China bleibt schwach...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/smarttrader.community\/de\/uncategorized-de\/us-aktien-stagnieren-nach-ai-anstieg-in-der-vorangegangenen-sitzung-hoffnung-auf-fortschritte-bei-den-gespraechen-ueber-die-schuldenobergrenze-china-bleibt-schwach-2\/","og_locale":"de_DE","og_type":"article","og_title":"US-Aktien stagnieren nach AI-Anstieg in der vorangegangenen Sitzung; Hoffnung auf Fortschritte bei den Gespr\u00e4chen \u00fcber die Schuldenobergrenze; China bleibt schwach - SmartTrader","og_description":"US-Aktien stagnieren nach AI-Anstieg in der vorangegangenen Sitzung; Hoffnung auf Fortschritte bei den Gespr\u00e4chen \u00fcber die Schuldenobergrenze; China bleibt schwach...","og_url":"https:\/\/smarttrader.community\/de\/uncategorized-de\/us-aktien-stagnieren-nach-ai-anstieg-in-der-vorangegangenen-sitzung-hoffnung-auf-fortschritte-bei-den-gespraechen-ueber-die-schuldenobergrenze-china-bleibt-schwach-2\/","og_site_name":"SmartTrader","article_published_time":"2023-05-26T09:51:23+00:00","article_modified_time":"2023-05-28T09:37:15+00:00","og_image":[{"width":800,"height":500,"url":"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/04\/19-1.png","type":"image\/png"}],"author":"SmartTrader Analyst Team","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"SmartTrader Analyst Team","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/smarttrader.community\/de\/uncategorized-de\/us-aktien-stagnieren-nach-ai-anstieg-in-der-vorangegangenen-sitzung-hoffnung-auf-fortschritte-bei-den-gespraechen-ueber-die-schuldenobergrenze-china-bleibt-schwach-2\/#article","isPartOf":{"@id":"https:\/\/smarttrader.community\/de\/uncategorized-de\/us-aktien-stagnieren-nach-ai-anstieg-in-der-vorangegangenen-sitzung-hoffnung-auf-fortschritte-bei-den-gespraechen-ueber-die-schuldenobergrenze-china-bleibt-schwach-2\/"},"author":{"name":"SmartTrader Analyst Team","@id":"https:\/\/smarttrader.community\/de\/#\/schema\/person\/bfe0c456aafbdc04b9707983e59c4e05"},"headline":"US-Aktien stagnieren nach AI-Anstieg in der vorangegangenen Sitzung; Hoffnung auf Fortschritte bei den Gespr\u00e4chen \u00fcber die Schuldenobergrenze; China bleibt schwach","datePublished":"2023-05-26T09:51:23+00:00","dateModified":"2023-05-28T09:37:15+00:00","mainEntityOfPage":{"@id":"https:\/\/smarttrader.community\/de\/uncategorized-de\/us-aktien-stagnieren-nach-ai-anstieg-in-der-vorangegangenen-sitzung-hoffnung-auf-fortschritte-bei-den-gespraechen-ueber-die-schuldenobergrenze-china-bleibt-schwach-2\/"},"wordCount":403,"commentCount":0,"image":{"@id":"https:\/\/smarttrader.community\/de\/uncategorized-de\/us-aktien-stagnieren-nach-ai-anstieg-in-der-vorangegangenen-sitzung-hoffnung-auf-fortschritte-bei-den-gespraechen-ueber-die-schuldenobergrenze-china-bleibt-schwach-2\/#primaryimage"},"thumbnailUrl":"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/04\/19-1.png","articleSection":["Uncategorized"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/smarttrader.community\/de\/uncategorized-de\/us-aktien-stagnieren-nach-ai-anstieg-in-der-vorangegangenen-sitzung-hoffnung-auf-fortschritte-bei-den-gespraechen-ueber-die-schuldenobergrenze-china-bleibt-schwach-2\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/smarttrader.community\/de\/uncategorized-de\/us-aktien-stagnieren-nach-ai-anstieg-in-der-vorangegangenen-sitzung-hoffnung-auf-fortschritte-bei-den-gespraechen-ueber-die-schuldenobergrenze-china-bleibt-schwach-2\/","url":"https:\/\/smarttrader.community\/de\/uncategorized-de\/us-aktien-stagnieren-nach-ai-anstieg-in-der-vorangegangenen-sitzung-hoffnung-auf-fortschritte-bei-den-gespraechen-ueber-die-schuldenobergrenze-china-bleibt-schwach-2\/","name":"US-Aktien stagnieren nach AI-Anstieg in der vorangegangenen Sitzung; Hoffnung auf Fortschritte bei den Gespr\u00e4chen \u00fcber die Schuldenobergrenze; China bleibt schwach - SmartTrader","isPartOf":{"@id":"https:\/\/smarttrader.community\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/smarttrader.community\/de\/uncategorized-de\/us-aktien-stagnieren-nach-ai-anstieg-in-der-vorangegangenen-sitzung-hoffnung-auf-fortschritte-bei-den-gespraechen-ueber-die-schuldenobergrenze-china-bleibt-schwach-2\/#primaryimage"},"image":{"@id":"https:\/\/smarttrader.community\/de\/uncategorized-de\/us-aktien-stagnieren-nach-ai-anstieg-in-der-vorangegangenen-sitzung-hoffnung-auf-fortschritte-bei-den-gespraechen-ueber-die-schuldenobergrenze-china-bleibt-schwach-2\/#primaryimage"},"thumbnailUrl":"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/04\/19-1.png","datePublished":"2023-05-26T09:51:23+00:00","dateModified":"2023-05-28T09:37:15+00:00","author":{"@id":"https:\/\/smarttrader.community\/de\/#\/schema\/person\/bfe0c456aafbdc04b9707983e59c4e05"},"description":"US-Aktien stagnieren nach AI-Anstieg in der vorangegangenen Sitzung; Hoffnung auf Fortschritte bei den Gespr\u00e4chen \u00fcber die Schuldenobergrenze; China bleibt schwach...","breadcrumb":{"@id":"https:\/\/smarttrader.community\/de\/uncategorized-de\/us-aktien-stagnieren-nach-ai-anstieg-in-der-vorangegangenen-sitzung-hoffnung-auf-fortschritte-bei-den-gespraechen-ueber-die-schuldenobergrenze-china-bleibt-schwach-2\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/smarttrader.community\/de\/uncategorized-de\/us-aktien-stagnieren-nach-ai-anstieg-in-der-vorangegangenen-sitzung-hoffnung-auf-fortschritte-bei-den-gespraechen-ueber-die-schuldenobergrenze-china-bleibt-schwach-2\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/smarttrader.community\/de\/uncategorized-de\/us-aktien-stagnieren-nach-ai-anstieg-in-der-vorangegangenen-sitzung-hoffnung-auf-fortschritte-bei-den-gespraechen-ueber-die-schuldenobergrenze-china-bleibt-schwach-2\/#primaryimage","url":"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/04\/19-1.png","contentUrl":"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/04\/19-1.png","width":800,"height":500},{"@type":"BreadcrumbList","@id":"https:\/\/smarttrader.community\/de\/uncategorized-de\/us-aktien-stagnieren-nach-ai-anstieg-in-der-vorangegangenen-sitzung-hoffnung-auf-fortschritte-bei-den-gespraechen-ueber-die-schuldenobergrenze-china-bleibt-schwach-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/smarttrader.community\/de\/"},{"@type":"ListItem","position":2,"name":"US-Aktien stagnieren nach AI-Anstieg in der vorangegangenen Sitzung; Hoffnung auf Fortschritte bei den Gespr\u00e4chen \u00fcber die Schuldenobergrenze; China bleibt schwach"}]},{"@type":"WebSite","@id":"https:\/\/smarttrader.community\/de\/#website","url":"https:\/\/smarttrader.community\/de\/","name":"SmartTrader","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/smarttrader.community\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/smarttrader.community\/de\/#\/schema\/person\/bfe0c456aafbdc04b9707983e59c4e05","name":"SmartTrader Analyst Team","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/03\/admin_avatar_3-96x96.png","url":"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/03\/admin_avatar_3-96x96.png","contentUrl":"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/03\/admin_avatar_3-96x96.png","caption":"SmartTrader Analyst Team"},"sameAs":["https:\/\/smarttrader.community"],"url":"https:\/\/smarttrader.community\/de\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/posts\/13794","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/comments?post=13794"}],"version-history":[{"count":0,"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/posts\/13794\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/media\/13313"}],"wp:attachment":[{"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/media?parent=13794"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/categories?post=13794"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/tags?post=13794"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}