{"id":20968,"date":"2023-08-04T12:37:29","date_gmt":"2023-08-04T12:37:29","guid":{"rendered":"https:\/\/smarttrader.community\/?p=20968"},"modified":"2023-08-04T13:04:10","modified_gmt":"2023-08-04T13:04:10","slug":"%e2%80%bc%ef%b8%8f-maerkte-bleiben-vorsichtig-nach-juengsten-verlusten-vor-nfps","status":"publish","type":"post","link":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/%e2%80%bc%ef%b8%8f-maerkte-bleiben-vorsichtig-nach-juengsten-verlusten-vor-nfps\/","title":{"rendered":"M\u00e4rkte bleiben vorsichtig nach j\u00fcngsten Verlusten &#038; vor NFPs"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die Wall Street gab ihre vorb\u00f6rslichen Gewinne wieder ab, da die Anleger nach der schlechtesten Woche f\u00fcr die weltweiten Aktienm\u00e4rkte seit M\u00e4rz weiterhin vorsichtig bleiben. Die Aktien in Asien schlossen \u00fcberwiegend h\u00f6her, w\u00e4hrend der breite europ\u00e4ische Stoxx 600 Index seine Verluste ausweitete.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die Anleger sind nach wie vor besorgt dar\u00fcber, dass die j\u00fcngsten Arbeitsmarktdaten zeigen, dass die Zahl der Neueinstellungen weiterhin hoch ist, was die Wetten auf eine weitere Straffung der Fed weiter anheizen k\u00f6nnte. Analysten gehen davon aus, dass die USA im Juli 200.000 neue Arbeitspl\u00e4tze geschaffen haben. Das w\u00e4re zwar der niedrigste Wert seit Ende 2020, liegt aber historisch gesehen immer noch im oberen Bereich. Die j\u00fcngsten Daten von ADP zeigen, dass die Nachfrage nach Arbeitskr\u00e4ften anh\u00e4lt, da der Arbeitsmarkt weiterhin angespannt ist.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die Renditen der Staatsanleihen sind in dieser Woche stark gestiegen, was den USD ebenfalls gest\u00fctzt hat. Die US-Regierung wird die viertelj\u00e4hrlichen Anleiheverk\u00e4ufe auf $103 Mrd. erh\u00f6hen, mehr als erwartet, was wahrscheinlich zu einem weiteren Anstieg der Renditen f\u00fchren wird, da die H\u00e4ndler \u00fcber das erh\u00f6hte Angebot an Anleihen verunsichert sind.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nach Angaben der Bank of America ziehen sich die Kunden aus Aktien zur\u00fcck, da das Risiko eines wirtschaftlichen Abschwungs weiterhin hoch ist. BofA-Stratege Michael Hartnett sagte: &#8222;Die Privatkunden gehen wieder in den Risk-Off-Modus \u00fcber (\u2026)&#8220;.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Der Marktwert von Apple wird wieder unter die historische Marke von $3 Billionen fallen, da das iPhone nach dem dritten Quartalsbericht in Folge mit r\u00fcckl\u00e4ufigen Verkaufszahlen niedriger er\u00f6ffnet. Seit 2021 ist es Apple nicht mehr gelungen, die Verkaufszahlen zu steigern &#8211; w\u00e4hrend der Aktienkurs in die H\u00f6he schoss. Positiv zu vermerken ist jedoch, dass die Verk\u00e4ufe in China stark waren und Apple einen Rekordabsatz von iPhones in Indien meldete. Amazon wird im vorb\u00f6rslichen Handel um 8,7 % h\u00f6her gehandelt, nachdem der Umsatz des weltgr\u00f6\u00dften E-Commerce- und Cloud-Service-Unternehmens die Sch\u00e4tzungen \u00fcbertroffen hat.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Abh\u00e4ngig von den NFPs &#8211; die wahrscheinlich nicht schwach ausfallen werden &#8211; sehe ich die Investoren immer noch nerv\u00f6s. Gegen Ende der Woche k\u00f6nnte es zu weiteren Verk\u00e4ufen kommen, da die Anleger weiterhin vorsichtig bleiben. Die Hoffnung, dass Peking bald weitere Stimulierungsma\u00dfnahmen ank\u00fcndigt, gibt dem globalen Markt jedoch etwas R\u00fcckenwind.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die \u00d6lpreise bleiben in der N\u00e4he eines 3 1\/2-Monatshochs. Gold findet angesichts der hohen Renditen der US-Staatsanleihen weiterhin keine Unterst\u00fctzung. Industriemetalle bleiben trotz eines kleinen Aufschwungs bei chinesischen Aktien und der Hoffnung auf weitere Konjunkturma\u00dfnahmen schwach.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\ud83d\udc41 ROB'S MARKET OVERVIEW:<\/p>\n\n\n\n<ol class=\"wp-block-list\" start=\"4\">\n<li>August 2023<\/li>\n<\/ol>\n\n\n\n<p class=\"wp-block-paragraph\">\ud83c\uddfa\ud83c\uddf8 US-M\u00e4rkte \u2195\ufe0f<br>Zyklische Aktien \u2195\ufe0f<br>Tech\/Wachstumsaktien \u2195\ufe0f\/\u2198\ufe0f<br>Finanzaktien \u27a1\ufe0f<br>Defensive Aktien \u27a1\ufe0f\/\u2197\ufe0f<br>Energieaktien \u27a1\ufe0f\/\u2197\ufe0f<br>Rohstoffaktien \u27a1\ufe0f<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\ud83d\udcb1 Devisenmarkt<br>USD \u27a1\ufe0f\/\u2197\ufe0f<br>EUR, GBP \u27a1\ufe0f<br>AUD \u27a1\ufe0f (stabilisiert sich \/ leichter Aufschwung nach j\u00fcngsten Verlusten)<br>CHF, JPY, CAD \u27a1\ufe0f\/\u2198\ufe0f<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u2692 Rohstoffm\u00e4rkte \u2195\ufe0f<br>\u00d6lpreise \u27a1\ufe0f\/\u2197\ufe0f (\u00d6lmarkt bleibt angespannt)<br>Erdgaspreise \u27a1\ufe0f<br>Metallpreise \u27a1\ufe0f\/\u2198\ufe0f<br>Edelmetallpreise \u27a1\ufe0f (reduziertes Abw\u00e4rtspotenzial bei stabilisierenden Renditen)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u26a1\ufe0fKryptow\u00e4hrungen \u27a1\ufe0f\/\u2198\ufe0f (Risikoaversionsstimmung)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">(*\u2197\ufe0f bullisch, \u2198\ufe0f b\u00e4risch, \u27a1\ufe0f seitw\u00e4rts \/ stabil, \u2195\ufe0f gemischt \/ volatil)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dein Robert<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die Wall Street gab ihre vorb\u00f6rslichen Gewinne wieder ab, da die Anleger nach der schlechtesten Woche f\u00fcr die weltweiten Aktienm\u00e4rkte&#8230;<\/p>\n","protected":false},"author":663,"featured_media":20966,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","pmpro_default_level":"","_daextam_enable_autolinks":"","footnotes":""},"categories":[117,326],"tags":[],"class_list":["post-20968","post","type-post","status-publish","format-standard","has-post-thumbnail","category-taegliche-aktualisierungen","category-tagliche-aktualisierungen","pmpro-has-access"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>M\u00e4rkte bleiben vorsichtig nach j\u00fcngsten Verlusten &amp; vor NFPs - SmartTrader<\/title>\n<meta name=\"description\" content=\"Die Wall Street gab ihre vorb\u00f6rslichen Gewinne wieder ab, da die Anleger nach der schlechtesten Woche f\u00fcr die weltweiten Aktienm\u00e4rkte seit M\u00e4rz weiterhin vorsichtig bleiben. Die Aktien in Asien schlossen \u00fcberwiegend h\u00f6her, w\u00e4hrend der breite europ\u00e4ische Stoxx 600 Index seine Verluste ausweitete.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/%e2%80%bc%ef%b8%8f-maerkte-bleiben-vorsichtig-nach-juengsten-verlusten-vor-nfps\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"M\u00e4rkte bleiben vorsichtig nach j\u00fcngsten Verlusten &amp; vor NFPs - SmartTrader\" \/>\n<meta property=\"og:description\" content=\"Die Wall Street gab ihre vorb\u00f6rslichen Gewinne wieder ab, da die Anleger nach der schlechtesten Woche f\u00fcr die weltweiten Aktienm\u00e4rkte seit M\u00e4rz weiterhin vorsichtig bleiben. Die Aktien in Asien schlossen \u00fcberwiegend h\u00f6her, w\u00e4hrend der breite europ\u00e4ische Stoxx 600 Index seine Verluste ausweitete.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/%e2%80%bc%ef%b8%8f-maerkte-bleiben-vorsichtig-nach-juengsten-verlusten-vor-nfps\/\" \/>\n<meta property=\"og:site_name\" content=\"SmartTrader\" \/>\n<meta property=\"article:published_time\" content=\"2023-08-04T12:37:29+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-08-04T13:04:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/08\/04.08.2023_TITLE_Artboard-1-copy-9.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1081\" \/>\n\t<meta property=\"og:image:height\" content=\"721\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Robert Lindner\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Robert Lindner\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taegliche-aktualisierungen\\\/%e2%80%bc%ef%b8%8f-maerkte-bleiben-vorsichtig-nach-juengsten-verlusten-vor-nfps\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taegliche-aktualisierungen\\\/%e2%80%bc%ef%b8%8f-maerkte-bleiben-vorsichtig-nach-juengsten-verlusten-vor-nfps\\\/\"},\"author\":{\"name\":\"Robert Lindner\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/#\\\/schema\\\/person\\\/4f791355f3f400fd2dd91d9c57c4c067\"},\"headline\":\"M\u00e4rkte bleiben vorsichtig nach j\u00fcngsten Verlusten &#038; vor NFPs\",\"datePublished\":\"2023-08-04T12:37:29+00:00\",\"dateModified\":\"2023-08-04T13:04:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taegliche-aktualisierungen\\\/%e2%80%bc%ef%b8%8f-maerkte-bleiben-vorsichtig-nach-juengsten-verlusten-vor-nfps\\\/\"},\"wordCount\":489,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taegliche-aktualisierungen\\\/%e2%80%bc%ef%b8%8f-maerkte-bleiben-vorsichtig-nach-juengsten-verlusten-vor-nfps\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/04.08.2023_TITLE_Artboard-1-copy-9.png\",\"articleSection\":[\"T\u00e4gliche Aktualisierungen\",\"T\u00e4gliche Aktualisierungen\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/smarttrader.community\\\/de\\\/taegliche-aktualisierungen\\\/%e2%80%bc%ef%b8%8f-maerkte-bleiben-vorsichtig-nach-juengsten-verlusten-vor-nfps\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taegliche-aktualisierungen\\\/%e2%80%bc%ef%b8%8f-maerkte-bleiben-vorsichtig-nach-juengsten-verlusten-vor-nfps\\\/\",\"url\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taegliche-aktualisierungen\\\/%e2%80%bc%ef%b8%8f-maerkte-bleiben-vorsichtig-nach-juengsten-verlusten-vor-nfps\\\/\",\"name\":\"M\u00e4rkte bleiben vorsichtig nach j\u00fcngsten Verlusten & vor NFPs - SmartTrader\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taegliche-aktualisierungen\\\/%e2%80%bc%ef%b8%8f-maerkte-bleiben-vorsichtig-nach-juengsten-verlusten-vor-nfps\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taegliche-aktualisierungen\\\/%e2%80%bc%ef%b8%8f-maerkte-bleiben-vorsichtig-nach-juengsten-verlusten-vor-nfps\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/04.08.2023_TITLE_Artboard-1-copy-9.png\",\"datePublished\":\"2023-08-04T12:37:29+00:00\",\"dateModified\":\"2023-08-04T13:04:10+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/#\\\/schema\\\/person\\\/4f791355f3f400fd2dd91d9c57c4c067\"},\"description\":\"Die Wall Street gab ihre vorb\u00f6rslichen Gewinne wieder ab, da die Anleger nach der schlechtesten Woche f\u00fcr die weltweiten Aktienm\u00e4rkte seit M\u00e4rz weiterhin vorsichtig bleiben. Die Aktien in Asien schlossen \u00fcberwiegend h\u00f6her, w\u00e4hrend der breite europ\u00e4ische Stoxx 600 Index seine Verluste ausweitete.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taegliche-aktualisierungen\\\/%e2%80%bc%ef%b8%8f-maerkte-bleiben-vorsichtig-nach-juengsten-verlusten-vor-nfps\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/smarttrader.community\\\/de\\\/taegliche-aktualisierungen\\\/%e2%80%bc%ef%b8%8f-maerkte-bleiben-vorsichtig-nach-juengsten-verlusten-vor-nfps\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taegliche-aktualisierungen\\\/%e2%80%bc%ef%b8%8f-maerkte-bleiben-vorsichtig-nach-juengsten-verlusten-vor-nfps\\\/#primaryimage\",\"url\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/04.08.2023_TITLE_Artboard-1-copy-9.png\",\"contentUrl\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/04.08.2023_TITLE_Artboard-1-copy-9.png\",\"width\":1081,\"height\":721},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taegliche-aktualisierungen\\\/%e2%80%bc%ef%b8%8f-maerkte-bleiben-vorsichtig-nach-juengsten-verlusten-vor-nfps\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"M\u00e4rkte bleiben vorsichtig nach j\u00fcngsten Verlusten &#038; vor NFPs\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/\",\"name\":\"SmartTrader\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/#\\\/schema\\\/person\\\/4f791355f3f400fd2dd91d9c57c4c067\",\"name\":\"Robert Lindner\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/robert-lindner_avatar_1-96x96.png\",\"url\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/robert-lindner_avatar_1-96x96.png\",\"contentUrl\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/robert-lindner_avatar_1-96x96.png\",\"caption\":\"Robert Lindner\"},\"sameAs\":[\"https:\\\/\\\/wwww.smarttrader.community\\\/\"],\"url\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/author\\\/robert_smarttrader\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"M\u00e4rkte bleiben vorsichtig nach j\u00fcngsten Verlusten & vor NFPs - SmartTrader","description":"Die Wall Street gab ihre vorb\u00f6rslichen Gewinne wieder ab, da die Anleger nach der schlechtesten Woche f\u00fcr die weltweiten Aktienm\u00e4rkte seit M\u00e4rz weiterhin vorsichtig bleiben. Die Aktien in Asien schlossen \u00fcberwiegend h\u00f6her, w\u00e4hrend der breite europ\u00e4ische Stoxx 600 Index seine Verluste ausweitete.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/%e2%80%bc%ef%b8%8f-maerkte-bleiben-vorsichtig-nach-juengsten-verlusten-vor-nfps\/","og_locale":"de_DE","og_type":"article","og_title":"M\u00e4rkte bleiben vorsichtig nach j\u00fcngsten Verlusten & vor NFPs - SmartTrader","og_description":"Die Wall Street gab ihre vorb\u00f6rslichen Gewinne wieder ab, da die Anleger nach der schlechtesten Woche f\u00fcr die weltweiten Aktienm\u00e4rkte seit M\u00e4rz weiterhin vorsichtig bleiben. Die Aktien in Asien schlossen \u00fcberwiegend h\u00f6her, w\u00e4hrend der breite europ\u00e4ische Stoxx 600 Index seine Verluste ausweitete.","og_url":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/%e2%80%bc%ef%b8%8f-maerkte-bleiben-vorsichtig-nach-juengsten-verlusten-vor-nfps\/","og_site_name":"SmartTrader","article_published_time":"2023-08-04T12:37:29+00:00","article_modified_time":"2023-08-04T13:04:10+00:00","og_image":[{"width":1081,"height":721,"url":"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/08\/04.08.2023_TITLE_Artboard-1-copy-9.png","type":"image\/png"}],"author":"Robert Lindner","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Robert Lindner","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/%e2%80%bc%ef%b8%8f-maerkte-bleiben-vorsichtig-nach-juengsten-verlusten-vor-nfps\/#article","isPartOf":{"@id":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/%e2%80%bc%ef%b8%8f-maerkte-bleiben-vorsichtig-nach-juengsten-verlusten-vor-nfps\/"},"author":{"name":"Robert Lindner","@id":"https:\/\/smarttrader.community\/de\/#\/schema\/person\/4f791355f3f400fd2dd91d9c57c4c067"},"headline":"M\u00e4rkte bleiben vorsichtig nach j\u00fcngsten Verlusten &#038; vor NFPs","datePublished":"2023-08-04T12:37:29+00:00","dateModified":"2023-08-04T13:04:10+00:00","mainEntityOfPage":{"@id":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/%e2%80%bc%ef%b8%8f-maerkte-bleiben-vorsichtig-nach-juengsten-verlusten-vor-nfps\/"},"wordCount":489,"commentCount":0,"image":{"@id":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/%e2%80%bc%ef%b8%8f-maerkte-bleiben-vorsichtig-nach-juengsten-verlusten-vor-nfps\/#primaryimage"},"thumbnailUrl":"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/08\/04.08.2023_TITLE_Artboard-1-copy-9.png","articleSection":["T\u00e4gliche Aktualisierungen","T\u00e4gliche Aktualisierungen"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/%e2%80%bc%ef%b8%8f-maerkte-bleiben-vorsichtig-nach-juengsten-verlusten-vor-nfps\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/%e2%80%bc%ef%b8%8f-maerkte-bleiben-vorsichtig-nach-juengsten-verlusten-vor-nfps\/","url":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/%e2%80%bc%ef%b8%8f-maerkte-bleiben-vorsichtig-nach-juengsten-verlusten-vor-nfps\/","name":"M\u00e4rkte bleiben vorsichtig nach j\u00fcngsten Verlusten & vor NFPs - SmartTrader","isPartOf":{"@id":"https:\/\/smarttrader.community\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/%e2%80%bc%ef%b8%8f-maerkte-bleiben-vorsichtig-nach-juengsten-verlusten-vor-nfps\/#primaryimage"},"image":{"@id":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/%e2%80%bc%ef%b8%8f-maerkte-bleiben-vorsichtig-nach-juengsten-verlusten-vor-nfps\/#primaryimage"},"thumbnailUrl":"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/08\/04.08.2023_TITLE_Artboard-1-copy-9.png","datePublished":"2023-08-04T12:37:29+00:00","dateModified":"2023-08-04T13:04:10+00:00","author":{"@id":"https:\/\/smarttrader.community\/de\/#\/schema\/person\/4f791355f3f400fd2dd91d9c57c4c067"},"description":"Die Wall Street gab ihre vorb\u00f6rslichen Gewinne wieder ab, da die Anleger nach der schlechtesten Woche f\u00fcr die weltweiten Aktienm\u00e4rkte seit M\u00e4rz weiterhin vorsichtig bleiben. Die Aktien in Asien schlossen \u00fcberwiegend h\u00f6her, w\u00e4hrend der breite europ\u00e4ische Stoxx 600 Index seine Verluste ausweitete.","breadcrumb":{"@id":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/%e2%80%bc%ef%b8%8f-maerkte-bleiben-vorsichtig-nach-juengsten-verlusten-vor-nfps\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/%e2%80%bc%ef%b8%8f-maerkte-bleiben-vorsichtig-nach-juengsten-verlusten-vor-nfps\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/%e2%80%bc%ef%b8%8f-maerkte-bleiben-vorsichtig-nach-juengsten-verlusten-vor-nfps\/#primaryimage","url":"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/08\/04.08.2023_TITLE_Artboard-1-copy-9.png","contentUrl":"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/08\/04.08.2023_TITLE_Artboard-1-copy-9.png","width":1081,"height":721},{"@type":"BreadcrumbList","@id":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/%e2%80%bc%ef%b8%8f-maerkte-bleiben-vorsichtig-nach-juengsten-verlusten-vor-nfps\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/smarttrader.community\/de\/"},{"@type":"ListItem","position":2,"name":"M\u00e4rkte bleiben vorsichtig nach j\u00fcngsten Verlusten &#038; vor NFPs"}]},{"@type":"WebSite","@id":"https:\/\/smarttrader.community\/de\/#website","url":"https:\/\/smarttrader.community\/de\/","name":"SmartTrader","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/smarttrader.community\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/smarttrader.community\/de\/#\/schema\/person\/4f791355f3f400fd2dd91d9c57c4c067","name":"Robert Lindner","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/05\/robert-lindner_avatar_1-96x96.png","url":"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/05\/robert-lindner_avatar_1-96x96.png","contentUrl":"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/05\/robert-lindner_avatar_1-96x96.png","caption":"Robert Lindner"},"sameAs":["https:\/\/wwww.smarttrader.community\/"],"url":"https:\/\/smarttrader.community\/de\/author\/robert_smarttrader\/"}]}},"_links":{"self":[{"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/posts\/20968","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/users\/663"}],"replies":[{"embeddable":true,"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/comments?post=20968"}],"version-history":[{"count":0,"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/posts\/20968\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/media\/20966"}],"wp:attachment":[{"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/media?parent=20968"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/categories?post=20968"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/tags?post=20968"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}