{"id":21214,"date":"2023-08-11T12:25:52","date_gmt":"2023-08-11T12:25:52","guid":{"rendered":"https:\/\/smarttrader.community\/?p=21214"},"modified":"2023-08-11T12:29:45","modified_gmt":"2023-08-11T12:29:45","slug":"cn-schulden-sinkende-zinssenkungshoffnungen-belasten","status":"publish","type":"post","link":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/cn-schulden-sinkende-zinssenkungshoffnungen-belasten\/","title":{"rendered":"CN-Schulden &#038; sinkende Zinssenkungshoffnungen belasten"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>China wird den Provinzregierungen erlauben, rund 1 Billion Yuan<\/strong> ($139 Mrd.) durch den Verkauf von Anleihen zu beschaffen, <strong>um die massive Schuldenlast der lokalen Regierungen zu tilgen<\/strong>. Auch wenn es vielen Analysten nicht bekannt ist, bleibt <strong>Chinas massives Schuldenproblem in Verbindung mit den fallenden Immobilienpreisen eine der gr\u00f6\u00dften Bedrohungen f\u00fcr die Welt<\/strong> &#8211; auch f\u00fcr <strong>Chinas finanzielle Stabilit\u00e4t<\/strong>. Der Bautr\u00e4gerriese Country Garden Holdings sagte f\u00fcr das erste Halbjahr dieses Jahres einen Verlust in Milliardenh\u00f6he voraus und warf die Frage auf, wie die Schulden- und Immobilienkrise gel\u00f6st werden kann. Die <strong>chinesischen Aktien sind erneut stark gefallen<\/strong> und haben auch andere asiatische Indizes sowie <strong>Europa stark belastet<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Zus\u00e4tzlich zu den Sorgen um China sehen wir, dass die <strong>Erwartungen f\u00fcr Zinssenkungen angesichts einiger hawkischer Kommentare von Fed-Beamten<\/strong> und der Gefahr einer Verlangsamung der j\u00fcngsten Disinflation <strong>sinken<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Der <strong>USD ist auf dem Weg zu einer vierten Woche mit Kursgewinnen<\/strong>, was die zunehmenden Sorgen um die Weltwirtschaft und die <strong>Flucht der Anleger in den sicheren Hafen USD<\/strong> zeigt. Der USD wird auch durch die <strong>h\u00f6heren Renditen von Staatsanleihen<\/strong> und die Erwartung gest\u00fctzt, dass die <strong>Fed wenig Grund sieht, die Zinsen in n\u00e4chster Zeit zu senken<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Trotz der <strong>verschlechterten Risikostimmung sind die \u00d6lpreise diese Woche weiter gestiegen<\/strong> und erreichten gestern den h\u00f6chsten Stand seit November. Die <strong>Nachfrage nach \u00d6l<\/strong> bleibt trotz der Anzeichen einer sich verlangsamenden Wirtschaft und einer schwachen Produktion <strong>robust<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Das <strong>Vereinigte K\u00f6nigreich \u00fcberraschte mit einem schnelleren Wachstum als erwartet<\/strong> &#8211; doch anstatt f\u00fcr R\u00fcckenwind zu sorgen, <strong>stieg die Erwartung, dass die Bank of England die Zinsen weiter anheben kann<\/strong>, um die anhaltend hohe (aber abk\u00fchlende) Inflation im Vereinigten K\u00f6nigreich zu bek\u00e4mpfen. Das <strong>GBP profitierte ebenfalls von den steigenden Zinserh\u00f6hungserwartungen<\/strong>. Der Leitzins der BoE ist nur noch 0,25 % vom Leitzins der Fed von 5,5 % entfernt.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ich erwarte eine <strong>vor\u00fcbergehende Schw\u00e4che des USD als Reaktion auf die wahrscheinlich abk\u00fchlenden Erzeugerpreise<\/strong>. Ein starker R\u00fcckgang des chinesischen PPI k\u00f6nnte dazu beigetragen haben, dass auch die Erzeugerinflation in den USA zur\u00fcckgegangen ist. Ich halte es f\u00fcr wahrscheinlicher, dass die Daten <strong>etwas k\u00fchler als erwartet ausfallen<\/strong> oder den Erwartungen entsprechen (0,2 % gegen\u00fcber dem Vormonat sowohl f\u00fcr den PPI als auch den Kern-PPI). Nach einem <strong>kurzfristigen Abschwung wird der USD jedoch wieder an St\u00e4rke gewinnen<\/strong>. Aktien, insbesondere <strong>zins- und chinasensitive Aktien, bleiben unter Druck<\/strong>. Kursgewinne werden auf <strong>Gewinnmitnahmen<\/strong> treffen. Wir rechnen mit <strong>verst\u00e4rkten Gewinnmitnahmen zum NYSE-B\u00f6rsenschluss<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\ud83d\udc41 ROB'S MARKET OVERVIEW:<\/strong><\/p>\n\n\n\n<ol class=\"wp-block-list\" start=\"11\">\n<li>August, 2023<\/li>\n<\/ol>\n\n\n\n<p class=\"wp-block-paragraph\">\ud83c\uddfa\ud83c\uddf8 <strong>US-M\u00e4rkte<\/strong> \u2195\ufe0f\/\u2198\ufe0f<br>Zyklische Aktien \u2195\ufe0f\/\u2198\ufe0f<br>Tech\/Wachstumsaktien \u2198\ufe0f<br>Finanzaktien \u27a1\ufe0f<br>Defensive Aktien \u27a1\ufe0f\/\u2197\ufe0f<br>Energieaktien \u27a1\ufe0f (bleibt mittelfristig bullish)<br>Rohstoffaktien \u27a1\ufe0f\/\u2198\ufe0f<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\ud83d\udcb1 <strong>Devisenmarkt<\/strong><br>GBP \u2197\ufe0f (Profitiert vor\u00fcbergehend von erh\u00f6hten Erwartungen an Zinserh\u00f6hungen nach soliden UK-Wachstumsdaten)<br>USD \u2198\ufe0f\/\u2195\ufe0f\/\u2197\ufe0f (schw\u00e4cht sich ab wegen voraussichtlichem R\u00fcckgang des PPI &#8211; erholt sich aber zum Handelsschluss)<br>EUR, CAD \u27a1\ufe0f<br>AUD \u2197\ufe0f\/\u2195\ufe0f\/\u2198\ufe0f (wird die anf\u00e4nglichen Gewinne zum Handelsschluss verlieren)<br>JPY, CHF \u27a1\ufe0f\/\u2198\ufe0f (die Nachfrage nach sicheren Anlagen unterst\u00fctzt nur den USD, aufgrund h\u00f6herer Fed-Zinsen & Outperformance der US-Wirtschaft)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u2692 <strong>Rohstoffm\u00e4rkte<\/strong> \u2195\ufe0f<br>\u00d6lpreise \u2195\ufe0f\/\u2197\ufe0f<br>Erdgaspreise \u2195\ufe0f\/\u2197\ufe0f<br>Metallpreise \u2198\ufe0f<br>Edelmetallpreise \u27a1\ufe0f\/\u2198\ufe0f (da die Erwartungen an Zinserh\u00f6hungen steigen, wird Gold weiter unter Druck stehen)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u26a1\ufe0f<strong>Kryptow\u00e4hrungen<\/strong> \u27a1\ufe0f\/\u2198\ufe0f (Risk-off, st\u00e4rkerer USD und h\u00f6here Renditen belasten Kryptos)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">(*\u2197\ufe0f bullisch, \u2198\ufe0f b\u00e4risch, \u27a1\ufe0f seitw\u00e4rts \/ stabil, \u2195\ufe0f gemischt \/ volatil)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dein Robert<\/p>\n","protected":false},"excerpt":{"rendered":"<p>China wird den Provinzregierungen erlauben, rund 1 Billion Yuan ($139 Mrd.) durch den Verkauf von Anleihen zu beschaffen, um die&#8230;<\/p>\n","protected":false},"author":663,"featured_media":21212,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","pmpro_default_level":"","_daextam_enable_autolinks":"","footnotes":""},"categories":[117],"tags":[],"class_list":["post-21214","post","type-post","status-publish","format-standard","has-post-thumbnail","category-taegliche-aktualisierungen","pmpro-has-access"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>CN-Schulden &amp; sinkende Zinssenkungshoffnungen belasten - SmartTrader<\/title>\n<meta name=\"description\" content=\"China wird den Provinzregierungen erlauben, rund 1 Billion Yuan ($139 Mrd.) durch den Verkauf von Anleihen zu beschaffen, um die massive Schuldenlast der lokalen Regierungen zu tilgen. Auch wenn es vielen Analysten nicht bekannt ist, bleibt Chinas massives Schuldenproblem in Verbindung mit den fallenden Immobilienpreisen eine der gr\u00f6\u00dften Bedrohungen f\u00fcr die Welt - auch f\u00fcr Chinas finanzielle Stabilit\u00e4t. Der Bautr\u00e4gerriese Country Garden Holdings sagte f\u00fcr das erste Halbjahr dieses Jahres einen Verlust in Milliardenh\u00f6he voraus und warf die Frage auf, wie die Schulden- und Immobilienkrise gel\u00f6st werden kann. Die chinesischen Aktien sind erneut stark gefallen und haben auch andere asiatische Indizes sowie Europa stark belastet.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/cn-schulden-sinkende-zinssenkungshoffnungen-belasten\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"CN-Schulden &amp; sinkende Zinssenkungshoffnungen belasten - SmartTrader\" \/>\n<meta property=\"og:description\" content=\"China wird den Provinzregierungen erlauben, rund 1 Billion Yuan ($139 Mrd.) durch den Verkauf von Anleihen zu beschaffen, um die massive Schuldenlast der lokalen Regierungen zu tilgen. Auch wenn es vielen Analysten nicht bekannt ist, bleibt Chinas massives Schuldenproblem in Verbindung mit den fallenden Immobilienpreisen eine der gr\u00f6\u00dften Bedrohungen f\u00fcr die Welt - auch f\u00fcr Chinas finanzielle Stabilit\u00e4t. Der Bautr\u00e4gerriese Country Garden Holdings sagte f\u00fcr das erste Halbjahr dieses Jahres einen Verlust in Milliardenh\u00f6he voraus und warf die Frage auf, wie die Schulden- und Immobilienkrise gel\u00f6st werden kann. Die chinesischen Aktien sind erneut stark gefallen und haben auch andere asiatische Indizes sowie Europa stark belastet.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/cn-schulden-sinkende-zinssenkungshoffnungen-belasten\/\" \/>\n<meta property=\"og:site_name\" content=\"SmartTrader\" \/>\n<meta property=\"article:published_time\" content=\"2023-08-11T12:25:52+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-08-11T12:29:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/08\/11.08.2023_TITLE_Artboard-1-copy-9.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1081\" \/>\n\t<meta property=\"og:image:height\" content=\"721\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Robert Lindner\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Robert Lindner\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taegliche-aktualisierungen\\\/cn-schulden-sinkende-zinssenkungshoffnungen-belasten\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taegliche-aktualisierungen\\\/cn-schulden-sinkende-zinssenkungshoffnungen-belasten\\\/\"},\"author\":{\"name\":\"Robert Lindner\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/#\\\/schema\\\/person\\\/4f791355f3f400fd2dd91d9c57c4c067\"},\"headline\":\"CN-Schulden &#038; sinkende Zinssenkungshoffnungen belasten\",\"datePublished\":\"2023-08-11T12:25:52+00:00\",\"dateModified\":\"2023-08-11T12:29:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taegliche-aktualisierungen\\\/cn-schulden-sinkende-zinssenkungshoffnungen-belasten\\\/\"},\"wordCount\":543,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taegliche-aktualisierungen\\\/cn-schulden-sinkende-zinssenkungshoffnungen-belasten\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/11.08.2023_TITLE_Artboard-1-copy-9.png\",\"articleSection\":[\"T\u00e4gliche Aktualisierungen\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/smarttrader.community\\\/de\\\/taegliche-aktualisierungen\\\/cn-schulden-sinkende-zinssenkungshoffnungen-belasten\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taegliche-aktualisierungen\\\/cn-schulden-sinkende-zinssenkungshoffnungen-belasten\\\/\",\"url\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taegliche-aktualisierungen\\\/cn-schulden-sinkende-zinssenkungshoffnungen-belasten\\\/\",\"name\":\"CN-Schulden & sinkende Zinssenkungshoffnungen belasten - SmartTrader\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taegliche-aktualisierungen\\\/cn-schulden-sinkende-zinssenkungshoffnungen-belasten\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taegliche-aktualisierungen\\\/cn-schulden-sinkende-zinssenkungshoffnungen-belasten\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/11.08.2023_TITLE_Artboard-1-copy-9.png\",\"datePublished\":\"2023-08-11T12:25:52+00:00\",\"dateModified\":\"2023-08-11T12:29:45+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/#\\\/schema\\\/person\\\/4f791355f3f400fd2dd91d9c57c4c067\"},\"description\":\"China wird den Provinzregierungen erlauben, rund 1 Billion Yuan ($139 Mrd.) durch den Verkauf von Anleihen zu beschaffen, um die massive Schuldenlast der lokalen Regierungen zu tilgen. Auch wenn es vielen Analysten nicht bekannt ist, bleibt Chinas massives Schuldenproblem in Verbindung mit den fallenden Immobilienpreisen eine der gr\u00f6\u00dften Bedrohungen f\u00fcr die Welt - auch f\u00fcr Chinas finanzielle Stabilit\u00e4t. Der Bautr\u00e4gerriese Country Garden Holdings sagte f\u00fcr das erste Halbjahr dieses Jahres einen Verlust in Milliardenh\u00f6he voraus und warf die Frage auf, wie die Schulden- und Immobilienkrise gel\u00f6st werden kann. Die chinesischen Aktien sind erneut stark gefallen und haben auch andere asiatische Indizes sowie Europa stark belastet.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taegliche-aktualisierungen\\\/cn-schulden-sinkende-zinssenkungshoffnungen-belasten\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/smarttrader.community\\\/de\\\/taegliche-aktualisierungen\\\/cn-schulden-sinkende-zinssenkungshoffnungen-belasten\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taegliche-aktualisierungen\\\/cn-schulden-sinkende-zinssenkungshoffnungen-belasten\\\/#primaryimage\",\"url\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/11.08.2023_TITLE_Artboard-1-copy-9.png\",\"contentUrl\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/11.08.2023_TITLE_Artboard-1-copy-9.png\",\"width\":1081,\"height\":721},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taegliche-aktualisierungen\\\/cn-schulden-sinkende-zinssenkungshoffnungen-belasten\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"CN-Schulden &#038; sinkende Zinssenkungshoffnungen belasten\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/\",\"name\":\"SmartTrader\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/#\\\/schema\\\/person\\\/4f791355f3f400fd2dd91d9c57c4c067\",\"name\":\"Robert Lindner\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/robert-lindner_avatar_1-96x96.png\",\"url\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/robert-lindner_avatar_1-96x96.png\",\"contentUrl\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/robert-lindner_avatar_1-96x96.png\",\"caption\":\"Robert Lindner\"},\"sameAs\":[\"https:\\\/\\\/wwww.smarttrader.community\\\/\"],\"url\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/author\\\/robert_smarttrader\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"CN-Schulden & sinkende Zinssenkungshoffnungen belasten - SmartTrader","description":"China wird den Provinzregierungen erlauben, rund 1 Billion Yuan ($139 Mrd.) durch den Verkauf von Anleihen zu beschaffen, um die massive Schuldenlast der lokalen Regierungen zu tilgen. Auch wenn es vielen Analysten nicht bekannt ist, bleibt Chinas massives Schuldenproblem in Verbindung mit den fallenden Immobilienpreisen eine der gr\u00f6\u00dften Bedrohungen f\u00fcr die Welt - auch f\u00fcr Chinas finanzielle Stabilit\u00e4t. Der Bautr\u00e4gerriese Country Garden Holdings sagte f\u00fcr das erste Halbjahr dieses Jahres einen Verlust in Milliardenh\u00f6he voraus und warf die Frage auf, wie die Schulden- und Immobilienkrise gel\u00f6st werden kann. Die chinesischen Aktien sind erneut stark gefallen und haben auch andere asiatische Indizes sowie Europa stark belastet.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/cn-schulden-sinkende-zinssenkungshoffnungen-belasten\/","og_locale":"de_DE","og_type":"article","og_title":"CN-Schulden & sinkende Zinssenkungshoffnungen belasten - SmartTrader","og_description":"China wird den Provinzregierungen erlauben, rund 1 Billion Yuan ($139 Mrd.) durch den Verkauf von Anleihen zu beschaffen, um die massive Schuldenlast der lokalen Regierungen zu tilgen. Auch wenn es vielen Analysten nicht bekannt ist, bleibt Chinas massives Schuldenproblem in Verbindung mit den fallenden Immobilienpreisen eine der gr\u00f6\u00dften Bedrohungen f\u00fcr die Welt - auch f\u00fcr Chinas finanzielle Stabilit\u00e4t. Der Bautr\u00e4gerriese Country Garden Holdings sagte f\u00fcr das erste Halbjahr dieses Jahres einen Verlust in Milliardenh\u00f6he voraus und warf die Frage auf, wie die Schulden- und Immobilienkrise gel\u00f6st werden kann. Die chinesischen Aktien sind erneut stark gefallen und haben auch andere asiatische Indizes sowie Europa stark belastet.","og_url":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/cn-schulden-sinkende-zinssenkungshoffnungen-belasten\/","og_site_name":"SmartTrader","article_published_time":"2023-08-11T12:25:52+00:00","article_modified_time":"2023-08-11T12:29:45+00:00","og_image":[{"width":1081,"height":721,"url":"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/08\/11.08.2023_TITLE_Artboard-1-copy-9.png","type":"image\/png"}],"author":"Robert Lindner","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Robert Lindner","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/cn-schulden-sinkende-zinssenkungshoffnungen-belasten\/#article","isPartOf":{"@id":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/cn-schulden-sinkende-zinssenkungshoffnungen-belasten\/"},"author":{"name":"Robert Lindner","@id":"https:\/\/smarttrader.community\/de\/#\/schema\/person\/4f791355f3f400fd2dd91d9c57c4c067"},"headline":"CN-Schulden &#038; sinkende Zinssenkungshoffnungen belasten","datePublished":"2023-08-11T12:25:52+00:00","dateModified":"2023-08-11T12:29:45+00:00","mainEntityOfPage":{"@id":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/cn-schulden-sinkende-zinssenkungshoffnungen-belasten\/"},"wordCount":543,"commentCount":0,"image":{"@id":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/cn-schulden-sinkende-zinssenkungshoffnungen-belasten\/#primaryimage"},"thumbnailUrl":"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/08\/11.08.2023_TITLE_Artboard-1-copy-9.png","articleSection":["T\u00e4gliche Aktualisierungen"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/cn-schulden-sinkende-zinssenkungshoffnungen-belasten\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/cn-schulden-sinkende-zinssenkungshoffnungen-belasten\/","url":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/cn-schulden-sinkende-zinssenkungshoffnungen-belasten\/","name":"CN-Schulden & sinkende Zinssenkungshoffnungen belasten - SmartTrader","isPartOf":{"@id":"https:\/\/smarttrader.community\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/cn-schulden-sinkende-zinssenkungshoffnungen-belasten\/#primaryimage"},"image":{"@id":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/cn-schulden-sinkende-zinssenkungshoffnungen-belasten\/#primaryimage"},"thumbnailUrl":"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/08\/11.08.2023_TITLE_Artboard-1-copy-9.png","datePublished":"2023-08-11T12:25:52+00:00","dateModified":"2023-08-11T12:29:45+00:00","author":{"@id":"https:\/\/smarttrader.community\/de\/#\/schema\/person\/4f791355f3f400fd2dd91d9c57c4c067"},"description":"China wird den Provinzregierungen erlauben, rund 1 Billion Yuan ($139 Mrd.) durch den Verkauf von Anleihen zu beschaffen, um die massive Schuldenlast der lokalen Regierungen zu tilgen. Auch wenn es vielen Analysten nicht bekannt ist, bleibt Chinas massives Schuldenproblem in Verbindung mit den fallenden Immobilienpreisen eine der gr\u00f6\u00dften Bedrohungen f\u00fcr die Welt - auch f\u00fcr Chinas finanzielle Stabilit\u00e4t. Der Bautr\u00e4gerriese Country Garden Holdings sagte f\u00fcr das erste Halbjahr dieses Jahres einen Verlust in Milliardenh\u00f6he voraus und warf die Frage auf, wie die Schulden- und Immobilienkrise gel\u00f6st werden kann. Die chinesischen Aktien sind erneut stark gefallen und haben auch andere asiatische Indizes sowie Europa stark belastet.","breadcrumb":{"@id":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/cn-schulden-sinkende-zinssenkungshoffnungen-belasten\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/cn-schulden-sinkende-zinssenkungshoffnungen-belasten\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/cn-schulden-sinkende-zinssenkungshoffnungen-belasten\/#primaryimage","url":"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/08\/11.08.2023_TITLE_Artboard-1-copy-9.png","contentUrl":"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/08\/11.08.2023_TITLE_Artboard-1-copy-9.png","width":1081,"height":721},{"@type":"BreadcrumbList","@id":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/cn-schulden-sinkende-zinssenkungshoffnungen-belasten\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/smarttrader.community\/de\/"},{"@type":"ListItem","position":2,"name":"CN-Schulden &#038; sinkende Zinssenkungshoffnungen belasten"}]},{"@type":"WebSite","@id":"https:\/\/smarttrader.community\/de\/#website","url":"https:\/\/smarttrader.community\/de\/","name":"SmartTrader","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/smarttrader.community\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/smarttrader.community\/de\/#\/schema\/person\/4f791355f3f400fd2dd91d9c57c4c067","name":"Robert Lindner","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/05\/robert-lindner_avatar_1-96x96.png","url":"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/05\/robert-lindner_avatar_1-96x96.png","contentUrl":"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/05\/robert-lindner_avatar_1-96x96.png","caption":"Robert Lindner"},"sameAs":["https:\/\/wwww.smarttrader.community\/"],"url":"https:\/\/smarttrader.community\/de\/author\/robert_smarttrader\/"}]}},"_links":{"self":[{"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/posts\/21214","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/users\/663"}],"replies":[{"embeddable":true,"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/comments?post=21214"}],"version-history":[{"count":0,"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/posts\/21214\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/media\/21212"}],"wp:attachment":[{"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/media?parent=21214"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/categories?post=21214"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/tags?post=21214"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}