{"id":21353,"date":"2023-08-18T09:12:36","date_gmt":"2023-08-18T09:12:36","guid":{"rendered":"https:\/\/smarttrader.community\/?p=21353"},"modified":"2023-08-18T09:22:08","modified_gmt":"2023-08-18T09:22:08","slug":"globale-risikoanlagen-stuerzen-angesichts-der-probleme-in-china-erwartung-steigender-globaler-zinssaetze-weiter-ab","status":"publish","type":"post","link":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/globale-risikoanlagen-stuerzen-angesichts-der-probleme-in-china-erwartung-steigender-globaler-zinssaetze-weiter-ab\/","title":{"rendered":"Globale Risikoanlagen st\u00fcrzen angesichts der Probleme in China &amp; Erwartung steigender globaler Zinss\u00e4tze weiter ab"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">\ud83d\udcc6 Freitag, 18. August<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u25ba <strong>Europ\u00e4ische und asiatische Aktien, Rohstoffe<\/strong> und <strong>Kryptow\u00e4hrungen <\/strong>mussten aufgrund <strong>zunehmender Sorgen um China <\/strong>und der <strong>Bef\u00fcrchtung einer weiteren Straffung der Geldpolitik Einbu\u00dfen hinnehmen. <\/strong>Der <strong>Stoxx 600 sank um 0,4 %<\/strong> und blickt damit auf den <strong>dritten Wochenr\u00fcckgang in Folge.<\/strong> Auch die asiatischen Aktienbenchmarks aus <strong>Japan, China <\/strong>und <strong>S\u00fcdkorea lagen im Minus.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u25ba Die globalen <strong>M\u00e4rkte erlebten eine schwierige Woche,<\/strong> in der Sorgen \u00fcber eine anhaltende Inflation und <strong>Anleiherenditen, die sich dem Niveau der Finanzkrise<\/strong> (2008) <strong>ann\u00e4herten<\/strong>, im Vordergrund standen. Das j\u00fcngste <strong>Sitzungsprotokoll der Federal Reserve<\/strong> deutete auf eine <strong>m\u00f6gliche Fortsetzung der Zinserh\u00f6hungen<\/strong> hin, was die Anleger weiter verunsicherte.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u25ba In den <strong>USA mussten die wichtigsten Indizes den dritten Tag in Folge R\u00fcckg\u00e4nge hinnehmen<\/strong>, da die Ergebnisse der FOMC-Sitzung aufgrund der <strong>unerwarteten Widerstandsf\u00e4higkeit der US-Wirtschaft weitere Zinserh\u00f6hungen nahelegten.<\/strong> Der <strong>Nasdaq 100 (-1,21%), der S&P 500 (-0,8%) und der Dow Jones (-0,75%)<\/strong> verzeichneten erneut starke R\u00fcckg\u00e4nge. <strong>Bitcoin <\/strong>st\u00fcrzte nach der Nachricht \u00fcber den Verkauf von <strong>SpaceX <\/strong>um <strong>4,5% ab <\/strong>und verst\u00e4rkte damit den Abschwung der Kryptow\u00e4hrung.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/smarttrader.community\/membership-join\">Subscribe<\/a> to see more<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n","protected":false},"excerpt":{"rendered":"<p>\ud83d\udcc6 Freitag, 18. August \u25ba Europ\u00e4ische und asiatische Aktien, Rohstoffe und Kryptow\u00e4hrungen mussten aufgrund zunehmender Sorgen um China und der&#8230;<\/p>\n","protected":false},"author":1,"featured_media":21350,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","pmpro_default_level":"","_daextam_enable_autolinks":"","footnotes":""},"categories":[172],"tags":[],"class_list":["post-21353","post","type-post","status-publish","format-standard","has-post-thumbnail","category-taglicher-marktuberblick","pmpro-has-access"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Globale Risikoanlagen st\u00fcrzen angesichts der Probleme in China &amp; Erwartung steigender globaler Zinss\u00e4tze weiter ab - SmartTrader<\/title>\n<meta name=\"description\" content=\"\u25ba Europ\u00e4ische und asiatische Aktien, Rohstoffe und Kryptow\u00e4hrungen mussten aufgrund zunehmender Sorgen um China und der Bef\u00fcrchtung einer weiteren Straffung der Geldpolitik Einbu\u00dfen hinnehmen. Der Stoxx 600 sank um 0,4 % und blickt damit auf den dritten Wochenr\u00fcckgang in Folge. Auch die asiatischen Aktienbenchmarks aus Japan, China und S\u00fcdkorea lagen im Minus.\u25ba Die globalen M\u00e4rkte erlebten eine schwierige Woche, in der Sorgen \u00fcber eine anhaltende Inflation und Anleiherenditen, die sich dem Niveau der Finanzkrise (2008) ann\u00e4herten, im Vordergrund standen. Das j\u00fcngste Sitzungsprotokoll der Federal Reserve deutete auf eine m\u00f6gliche Fortsetzung der Zinserh\u00f6hungen hin, was die Anleger weiter verunsicherte.\u25ba In den USA mussten die wichtigsten Indizes den dritten Tag in Folge R\u00fcckg\u00e4nge hinnehmen, da die Ergebnisse der FOMC-Sitzung aufgrund der unerwarteten Widerstandsf\u00e4higkeit der US-Wirtschaft weitere Zinserh\u00f6hungen nahelegten. Der Nasdaq 100 (-1,21%), der S&amp;P 500 (-0,8%) und der Dow Jones (-0,75%) verzeichneten erneut starke R\u00fcckg\u00e4nge. Bitcoin st\u00fcrzte nach der Nachricht \u00fcber den Verkauf von SpaceX um 4,5% ab und verst\u00e4rkte damit den Abschwung der Kryptow\u00e4hrung.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/globale-risikoanlagen-stuerzen-angesichts-der-probleme-in-china-erwartung-steigender-globaler-zinssaetze-weiter-ab\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Globale Risikoanlagen st\u00fcrzen angesichts der Probleme in China &amp; Erwartung steigender globaler Zinss\u00e4tze weiter ab - SmartTrader\" \/>\n<meta property=\"og:description\" content=\"\u25ba Europ\u00e4ische und asiatische Aktien, Rohstoffe und Kryptow\u00e4hrungen mussten aufgrund zunehmender Sorgen um China und der Bef\u00fcrchtung einer weiteren Straffung der Geldpolitik Einbu\u00dfen hinnehmen. Der Stoxx 600 sank um 0,4 % und blickt damit auf den dritten Wochenr\u00fcckgang in Folge. Auch die asiatischen Aktienbenchmarks aus Japan, China und S\u00fcdkorea lagen im Minus.\u25ba Die globalen M\u00e4rkte erlebten eine schwierige Woche, in der Sorgen \u00fcber eine anhaltende Inflation und Anleiherenditen, die sich dem Niveau der Finanzkrise (2008) ann\u00e4herten, im Vordergrund standen. Das j\u00fcngste Sitzungsprotokoll der Federal Reserve deutete auf eine m\u00f6gliche Fortsetzung der Zinserh\u00f6hungen hin, was die Anleger weiter verunsicherte.\u25ba In den USA mussten die wichtigsten Indizes den dritten Tag in Folge R\u00fcckg\u00e4nge hinnehmen, da die Ergebnisse der FOMC-Sitzung aufgrund der unerwarteten Widerstandsf\u00e4higkeit der US-Wirtschaft weitere Zinserh\u00f6hungen nahelegten. Der Nasdaq 100 (-1,21%), der S&amp;P 500 (-0,8%) und der Dow Jones (-0,75%) verzeichneten erneut starke R\u00fcckg\u00e4nge. Bitcoin st\u00fcrzte nach der Nachricht \u00fcber den Verkauf von SpaceX um 4,5% ab und verst\u00e4rkte damit den Abschwung der Kryptow\u00e4hrung.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/globale-risikoanlagen-stuerzen-angesichts-der-probleme-in-china-erwartung-steigender-globaler-zinssaetze-weiter-ab\/\" \/>\n<meta property=\"og:site_name\" content=\"SmartTrader\" \/>\n<meta property=\"article:published_time\" content=\"2023-08-18T09:12:36+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-08-18T09:22:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/08\/images.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"SmartTrader Analyst Team\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"SmartTrader Analyst Team\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taglicher-marktuberblick\\\/globale-risikoanlagen-stuerzen-angesichts-der-probleme-in-china-erwartung-steigender-globaler-zinssaetze-weiter-ab\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taglicher-marktuberblick\\\/globale-risikoanlagen-stuerzen-angesichts-der-probleme-in-china-erwartung-steigender-globaler-zinssaetze-weiter-ab\\\/\"},\"author\":{\"name\":\"SmartTrader Analyst Team\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/#\\\/schema\\\/person\\\/bfe0c456aafbdc04b9707983e59c4e05\"},\"headline\":\"Globale Risikoanlagen st\u00fcrzen angesichts der Probleme in China &amp; Erwartung steigender globaler Zinss\u00e4tze weiter ab\",\"datePublished\":\"2023-08-18T09:12:36+00:00\",\"dateModified\":\"2023-08-18T09:22:08+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taglicher-marktuberblick\\\/globale-risikoanlagen-stuerzen-angesichts-der-probleme-in-china-erwartung-steigender-globaler-zinssaetze-weiter-ab\\\/\"},\"wordCount\":534,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taglicher-marktuberblick\\\/globale-risikoanlagen-stuerzen-angesichts-der-probleme-in-china-erwartung-steigender-globaler-zinssaetze-weiter-ab\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/images.png\",\"articleSection\":[\"T\u00e4glicher Markt\u00fcberblick\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/smarttrader.community\\\/de\\\/taglicher-marktuberblick\\\/globale-risikoanlagen-stuerzen-angesichts-der-probleme-in-china-erwartung-steigender-globaler-zinssaetze-weiter-ab\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taglicher-marktuberblick\\\/globale-risikoanlagen-stuerzen-angesichts-der-probleme-in-china-erwartung-steigender-globaler-zinssaetze-weiter-ab\\\/\",\"url\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taglicher-marktuberblick\\\/globale-risikoanlagen-stuerzen-angesichts-der-probleme-in-china-erwartung-steigender-globaler-zinssaetze-weiter-ab\\\/\",\"name\":\"Globale Risikoanlagen st\u00fcrzen angesichts der Probleme in China &amp; Erwartung steigender globaler Zinss\u00e4tze weiter ab - SmartTrader\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taglicher-marktuberblick\\\/globale-risikoanlagen-stuerzen-angesichts-der-probleme-in-china-erwartung-steigender-globaler-zinssaetze-weiter-ab\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taglicher-marktuberblick\\\/globale-risikoanlagen-stuerzen-angesichts-der-probleme-in-china-erwartung-steigender-globaler-zinssaetze-weiter-ab\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/images.png\",\"datePublished\":\"2023-08-18T09:12:36+00:00\",\"dateModified\":\"2023-08-18T09:22:08+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/#\\\/schema\\\/person\\\/bfe0c456aafbdc04b9707983e59c4e05\"},\"description\":\"\u25ba Europ\u00e4ische und asiatische Aktien, Rohstoffe und Kryptow\u00e4hrungen mussten aufgrund zunehmender Sorgen um China und der Bef\u00fcrchtung einer weiteren Straffung der Geldpolitik Einbu\u00dfen hinnehmen. Der Stoxx 600 sank um 0,4 % und blickt damit auf den dritten Wochenr\u00fcckgang in Folge. Auch die asiatischen Aktienbenchmarks aus Japan, China und S\u00fcdkorea lagen im Minus.\u25ba Die globalen M\u00e4rkte erlebten eine schwierige Woche, in der Sorgen \u00fcber eine anhaltende Inflation und Anleiherenditen, die sich dem Niveau der Finanzkrise (2008) ann\u00e4herten, im Vordergrund standen. Das j\u00fcngste Sitzungsprotokoll der Federal Reserve deutete auf eine m\u00f6gliche Fortsetzung der Zinserh\u00f6hungen hin, was die Anleger weiter verunsicherte.\u25ba In den USA mussten die wichtigsten Indizes den dritten Tag in Folge R\u00fcckg\u00e4nge hinnehmen, da die Ergebnisse der FOMC-Sitzung aufgrund der unerwarteten Widerstandsf\u00e4higkeit der US-Wirtschaft weitere Zinserh\u00f6hungen nahelegten. Der Nasdaq 100 (-1,21%), der S&P 500 (-0,8%) und der Dow Jones (-0,75%) verzeichneten erneut starke R\u00fcckg\u00e4nge. Bitcoin st\u00fcrzte nach der Nachricht \u00fcber den Verkauf von SpaceX um 4,5% ab und verst\u00e4rkte damit den Abschwung der Kryptow\u00e4hrung.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taglicher-marktuberblick\\\/globale-risikoanlagen-stuerzen-angesichts-der-probleme-in-china-erwartung-steigender-globaler-zinssaetze-weiter-ab\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/smarttrader.community\\\/de\\\/taglicher-marktuberblick\\\/globale-risikoanlagen-stuerzen-angesichts-der-probleme-in-china-erwartung-steigender-globaler-zinssaetze-weiter-ab\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taglicher-marktuberblick\\\/globale-risikoanlagen-stuerzen-angesichts-der-probleme-in-china-erwartung-steigender-globaler-zinssaetze-weiter-ab\\\/#primaryimage\",\"url\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/images.png\",\"contentUrl\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/images.png\",\"width\":800,\"height\":500},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taglicher-marktuberblick\\\/globale-risikoanlagen-stuerzen-angesichts-der-probleme-in-china-erwartung-steigender-globaler-zinssaetze-weiter-ab\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Globale Risikoanlagen st\u00fcrzen angesichts der Probleme in China &amp; Erwartung steigender globaler Zinss\u00e4tze weiter ab\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/\",\"name\":\"SmartTrader\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/#\\\/schema\\\/person\\\/bfe0c456aafbdc04b9707983e59c4e05\",\"name\":\"SmartTrader Analyst Team\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/admin_avatar_3-96x96.png\",\"url\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/admin_avatar_3-96x96.png\",\"contentUrl\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/admin_avatar_3-96x96.png\",\"caption\":\"SmartTrader Analyst Team\"},\"sameAs\":[\"https:\\\/\\\/smarttrader.community\"],\"url\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Globale Risikoanlagen st\u00fcrzen angesichts der Probleme in China &amp; Erwartung steigender globaler Zinss\u00e4tze weiter ab - SmartTrader","description":"\u25ba Europ\u00e4ische und asiatische Aktien, Rohstoffe und Kryptow\u00e4hrungen mussten aufgrund zunehmender Sorgen um China und der Bef\u00fcrchtung einer weiteren Straffung der Geldpolitik Einbu\u00dfen hinnehmen. Der Stoxx 600 sank um 0,4 % und blickt damit auf den dritten Wochenr\u00fcckgang in Folge. Auch die asiatischen Aktienbenchmarks aus Japan, China und S\u00fcdkorea lagen im Minus.\u25ba Die globalen M\u00e4rkte erlebten eine schwierige Woche, in der Sorgen \u00fcber eine anhaltende Inflation und Anleiherenditen, die sich dem Niveau der Finanzkrise (2008) ann\u00e4herten, im Vordergrund standen. Das j\u00fcngste Sitzungsprotokoll der Federal Reserve deutete auf eine m\u00f6gliche Fortsetzung der Zinserh\u00f6hungen hin, was die Anleger weiter verunsicherte.\u25ba In den USA mussten die wichtigsten Indizes den dritten Tag in Folge R\u00fcckg\u00e4nge hinnehmen, da die Ergebnisse der FOMC-Sitzung aufgrund der unerwarteten Widerstandsf\u00e4higkeit der US-Wirtschaft weitere Zinserh\u00f6hungen nahelegten. Der Nasdaq 100 (-1,21%), der S&P 500 (-0,8%) und der Dow Jones (-0,75%) verzeichneten erneut starke R\u00fcckg\u00e4nge. Bitcoin st\u00fcrzte nach der Nachricht \u00fcber den Verkauf von SpaceX um 4,5% ab und verst\u00e4rkte damit den Abschwung der Kryptow\u00e4hrung.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/globale-risikoanlagen-stuerzen-angesichts-der-probleme-in-china-erwartung-steigender-globaler-zinssaetze-weiter-ab\/","og_locale":"de_DE","og_type":"article","og_title":"Globale Risikoanlagen st\u00fcrzen angesichts der Probleme in China &amp; Erwartung steigender globaler Zinss\u00e4tze weiter ab - SmartTrader","og_description":"\u25ba Europ\u00e4ische und asiatische Aktien, Rohstoffe und Kryptow\u00e4hrungen mussten aufgrund zunehmender Sorgen um China und der Bef\u00fcrchtung einer weiteren Straffung der Geldpolitik Einbu\u00dfen hinnehmen. Der Stoxx 600 sank um 0,4 % und blickt damit auf den dritten Wochenr\u00fcckgang in Folge. Auch die asiatischen Aktienbenchmarks aus Japan, China und S\u00fcdkorea lagen im Minus.\u25ba Die globalen M\u00e4rkte erlebten eine schwierige Woche, in der Sorgen \u00fcber eine anhaltende Inflation und Anleiherenditen, die sich dem Niveau der Finanzkrise (2008) ann\u00e4herten, im Vordergrund standen. Das j\u00fcngste Sitzungsprotokoll der Federal Reserve deutete auf eine m\u00f6gliche Fortsetzung der Zinserh\u00f6hungen hin, was die Anleger weiter verunsicherte.\u25ba In den USA mussten die wichtigsten Indizes den dritten Tag in Folge R\u00fcckg\u00e4nge hinnehmen, da die Ergebnisse der FOMC-Sitzung aufgrund der unerwarteten Widerstandsf\u00e4higkeit der US-Wirtschaft weitere Zinserh\u00f6hungen nahelegten. Der Nasdaq 100 (-1,21%), der S&P 500 (-0,8%) und der Dow Jones (-0,75%) verzeichneten erneut starke R\u00fcckg\u00e4nge. Bitcoin st\u00fcrzte nach der Nachricht \u00fcber den Verkauf von SpaceX um 4,5% ab und verst\u00e4rkte damit den Abschwung der Kryptow\u00e4hrung.","og_url":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/globale-risikoanlagen-stuerzen-angesichts-der-probleme-in-china-erwartung-steigender-globaler-zinssaetze-weiter-ab\/","og_site_name":"SmartTrader","article_published_time":"2023-08-18T09:12:36+00:00","article_modified_time":"2023-08-18T09:22:08+00:00","og_image":[{"width":800,"height":500,"url":"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/08\/images.png","type":"image\/png"}],"author":"SmartTrader Analyst Team","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"SmartTrader Analyst Team","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/globale-risikoanlagen-stuerzen-angesichts-der-probleme-in-china-erwartung-steigender-globaler-zinssaetze-weiter-ab\/#article","isPartOf":{"@id":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/globale-risikoanlagen-stuerzen-angesichts-der-probleme-in-china-erwartung-steigender-globaler-zinssaetze-weiter-ab\/"},"author":{"name":"SmartTrader Analyst Team","@id":"https:\/\/smarttrader.community\/de\/#\/schema\/person\/bfe0c456aafbdc04b9707983e59c4e05"},"headline":"Globale Risikoanlagen st\u00fcrzen angesichts der Probleme in China &amp; Erwartung steigender globaler Zinss\u00e4tze weiter ab","datePublished":"2023-08-18T09:12:36+00:00","dateModified":"2023-08-18T09:22:08+00:00","mainEntityOfPage":{"@id":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/globale-risikoanlagen-stuerzen-angesichts-der-probleme-in-china-erwartung-steigender-globaler-zinssaetze-weiter-ab\/"},"wordCount":534,"commentCount":0,"image":{"@id":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/globale-risikoanlagen-stuerzen-angesichts-der-probleme-in-china-erwartung-steigender-globaler-zinssaetze-weiter-ab\/#primaryimage"},"thumbnailUrl":"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/08\/images.png","articleSection":["T\u00e4glicher Markt\u00fcberblick"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/globale-risikoanlagen-stuerzen-angesichts-der-probleme-in-china-erwartung-steigender-globaler-zinssaetze-weiter-ab\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/globale-risikoanlagen-stuerzen-angesichts-der-probleme-in-china-erwartung-steigender-globaler-zinssaetze-weiter-ab\/","url":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/globale-risikoanlagen-stuerzen-angesichts-der-probleme-in-china-erwartung-steigender-globaler-zinssaetze-weiter-ab\/","name":"Globale Risikoanlagen st\u00fcrzen angesichts der Probleme in China &amp; Erwartung steigender globaler Zinss\u00e4tze weiter ab - SmartTrader","isPartOf":{"@id":"https:\/\/smarttrader.community\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/globale-risikoanlagen-stuerzen-angesichts-der-probleme-in-china-erwartung-steigender-globaler-zinssaetze-weiter-ab\/#primaryimage"},"image":{"@id":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/globale-risikoanlagen-stuerzen-angesichts-der-probleme-in-china-erwartung-steigender-globaler-zinssaetze-weiter-ab\/#primaryimage"},"thumbnailUrl":"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/08\/images.png","datePublished":"2023-08-18T09:12:36+00:00","dateModified":"2023-08-18T09:22:08+00:00","author":{"@id":"https:\/\/smarttrader.community\/de\/#\/schema\/person\/bfe0c456aafbdc04b9707983e59c4e05"},"description":"\u25ba Europ\u00e4ische und asiatische Aktien, Rohstoffe und Kryptow\u00e4hrungen mussten aufgrund zunehmender Sorgen um China und der Bef\u00fcrchtung einer weiteren Straffung der Geldpolitik Einbu\u00dfen hinnehmen. Der Stoxx 600 sank um 0,4 % und blickt damit auf den dritten Wochenr\u00fcckgang in Folge. Auch die asiatischen Aktienbenchmarks aus Japan, China und S\u00fcdkorea lagen im Minus.\u25ba Die globalen M\u00e4rkte erlebten eine schwierige Woche, in der Sorgen \u00fcber eine anhaltende Inflation und Anleiherenditen, die sich dem Niveau der Finanzkrise (2008) ann\u00e4herten, im Vordergrund standen. Das j\u00fcngste Sitzungsprotokoll der Federal Reserve deutete auf eine m\u00f6gliche Fortsetzung der Zinserh\u00f6hungen hin, was die Anleger weiter verunsicherte.\u25ba In den USA mussten die wichtigsten Indizes den dritten Tag in Folge R\u00fcckg\u00e4nge hinnehmen, da die Ergebnisse der FOMC-Sitzung aufgrund der unerwarteten Widerstandsf\u00e4higkeit der US-Wirtschaft weitere Zinserh\u00f6hungen nahelegten. Der Nasdaq 100 (-1,21%), der S&P 500 (-0,8%) und der Dow Jones (-0,75%) verzeichneten erneut starke R\u00fcckg\u00e4nge. Bitcoin st\u00fcrzte nach der Nachricht \u00fcber den Verkauf von SpaceX um 4,5% ab und verst\u00e4rkte damit den Abschwung der Kryptow\u00e4hrung.","breadcrumb":{"@id":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/globale-risikoanlagen-stuerzen-angesichts-der-probleme-in-china-erwartung-steigender-globaler-zinssaetze-weiter-ab\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/globale-risikoanlagen-stuerzen-angesichts-der-probleme-in-china-erwartung-steigender-globaler-zinssaetze-weiter-ab\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/globale-risikoanlagen-stuerzen-angesichts-der-probleme-in-china-erwartung-steigender-globaler-zinssaetze-weiter-ab\/#primaryimage","url":"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/08\/images.png","contentUrl":"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/08\/images.png","width":800,"height":500},{"@type":"BreadcrumbList","@id":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/globale-risikoanlagen-stuerzen-angesichts-der-probleme-in-china-erwartung-steigender-globaler-zinssaetze-weiter-ab\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/smarttrader.community\/de\/"},{"@type":"ListItem","position":2,"name":"Globale Risikoanlagen st\u00fcrzen angesichts der Probleme in China &amp; Erwartung steigender globaler Zinss\u00e4tze weiter ab"}]},{"@type":"WebSite","@id":"https:\/\/smarttrader.community\/de\/#website","url":"https:\/\/smarttrader.community\/de\/","name":"SmartTrader","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/smarttrader.community\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/smarttrader.community\/de\/#\/schema\/person\/bfe0c456aafbdc04b9707983e59c4e05","name":"SmartTrader Analyst Team","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/03\/admin_avatar_3-96x96.png","url":"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/03\/admin_avatar_3-96x96.png","contentUrl":"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/03\/admin_avatar_3-96x96.png","caption":"SmartTrader Analyst Team"},"sameAs":["https:\/\/smarttrader.community"],"url":"https:\/\/smarttrader.community\/de\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/posts\/21353","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/comments?post=21353"}],"version-history":[{"count":0,"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/posts\/21353\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/media\/21350"}],"wp:attachment":[{"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/media?parent=21353"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/categories?post=21353"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/tags?post=21353"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}