{"id":22003,"date":"2023-09-11T13:07:44","date_gmt":"2023-09-11T13:07:44","guid":{"rendered":"https:\/\/smarttrader.community\/?p=22003"},"modified":"2023-09-11T13:15:22","modified_gmt":"2023-09-11T13:15:22","slug":"fallender-usd-cn-hoffnung-helfen-stimmung-an-ruhigem-tag","status":"publish","type":"post","link":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/fallender-usd-cn-hoffnung-helfen-stimmung-an-ruhigem-tag\/","title":{"rendered":"Fallender USD, CN-Hoffnung helfen Stimmung an ruhigem Tag"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Der <strong>USD fiel im asiatischen\/europ\u00e4ischen Handel so stark wie seit zwei Wochen nicht mehr<\/strong>, wobei der <strong>JPY <\/strong>gegen\u00fcber den anderen W\u00e4hrungen zeitweise um mehr als 1 % zulegte, nachdem die <strong>Bank of Japan ein Ende der extrem akkommodierenden Politik angedeutet hatte<\/strong>. Die USD-St\u00e4rke lie\u00df auch leicht nach, nachdem <strong>Daten aus China Anzeichen f\u00fcr eine Stabilisierung zeigten<\/strong> (was den Yuan ebenfalls st\u00fctzte) und US-Finanzministerin Janet Yellen sich zuversichtlich zeigte, dass die USA die Inflation eind\u00e4mmen k\u00f6nnen, ohne der US-Wirtschaft oder dem US-Arbeitsmarkt gr\u00f6\u00dferen Schaden zuzuf\u00fcgen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die Pause der USD-St\u00e4rke sorgt f\u00fcr eine gewisse <strong>Erleichterung an der Wall Street<\/strong>. Wir sehen in den vorb\u00f6rslichen Kursgewinnen vor allem die in der letzten Woche stark verkauften <strong>Tech-Aktien h\u00f6her. <\/strong>Tesla f\u00fchrt die vorb\u00f6rslichen Gewinne an und notiert nach einer Heraufstufung durch Morgan Stanley mehr als 6% (!) h\u00f6her.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Wir haben einen <strong>ruhigen Start in die Woche,<\/strong> in der jedoch einige wichtige Daten\/Ereignisse anstehen, wie z. B. am <strong>Mittwoch die US-Verbraucherpreisindexdaten<\/strong>, die die Erwartungen bez\u00fcglich der Fed-Zinsaussichten beeinflussen werden, und am <strong>Donnerstag die EZB-Zinsentscheidung.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Der <strong>schw\u00e4chere USD hat dazu beigetragen, dass sich die Rohstoffpreise stabilisiert haben<\/strong>, auch wenn die <strong>\u00d6lpreise kaum ver\u00e4ndert sind<\/strong> und aufgrund einiger technischer Verk\u00e4ufe unter den H\u00f6chstst\u00e4nden der letzten Woche liegen. Wir gehen davon aus, dass die <strong>\u00d6lpreise weiter steigen werden<\/strong> &#8211; die Anzeichen f\u00fcr einen <strong>weiteren R\u00fcckgang der US-Lagerbest\u00e4nde<\/strong> werden weiterhin das Bild eines knappen \u00d6langebots zeichnen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Wir sehen <strong>risikoreichere W\u00e4hrungen f\u00fcr den gr\u00f6\u00dften Teil des heutigen Tages im Rebound-Modus<\/strong>. Der <strong>JPY <\/strong>b\u00fc\u00dfte den gr\u00f6\u00dften Teil seiner Gewinne ein, nachdem der Gouverneur der Bank of Japan, <strong>Kazuo Ueda<\/strong>, angedeutet hatte, dass die ultralockere Geldpolitik in den n\u00e4chsten drei bis vier Monaten ein Ende finden k\u00f6nnte. Der <strong>JPY <\/strong>wird jedoch weiterhin von den Anzeichen profitieren, dass die Zinsdifferenzen nicht mehr steigen und die Chancen auf eine<strong> Normalisierung der Geldpolitik durch die Bank of Japan steigen.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Wir gehen davon aus, dass sich die <strong>Aktien heute positiv entwickeln werden<\/strong>, wobei das Handelsvolumen relativ gering bleibt. Die <strong>morgigen ZEW-Stimmungsdaten werden wahrscheinlich wieder Druck auf die Aktien in Deutschland <\/strong>und der Eurozone aus\u00fcben.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">\ud83d\udc41 ROB'S MARKET OVERVIEW:<\/h3>\n\n\n\n<ol class=\"wp-block-list\" start=\"11\">\n<li><em>September, 2023 (\ud83c\uddfa\ud83c\uddf8\ud83d\udd4a)<\/em><\/li>\n<\/ol>\n\n\n\n<p class=\"wp-block-paragraph\">\ud83c\uddfa\ud83c\uddf8 <strong>US-M\u00e4rkte<\/strong> \u2195\ufe0f\/\u2197\ufe0f<br><em>Zyklische Aktien \u2195\ufe0f\/\u2197\ufe0f<br>Tech\/Wachstumsaktien \u2197\ufe0f (steigend \/ seitw\u00e4rts in der zweiten H\u00e4lfte des US-Handels)<br>Finanzaktien \u27a1\ufe0f\/\u2197\ufe0f<br>Defensive Aktien \u27a1\ufe0f<br>Energieaktien \u27a1\ufe0f<br>Rohstoffaktien \u2197\ufe0f<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\ud83d\udcb1 <strong>Devisenmarkt<\/strong><br><em>AUD \u2197\ufe0f<br>GBP, JPY, CAD \u27a1\ufe0f\/\u2197\ufe0f<br>EUR, CHF \u27a1\ufe0f<br>USD \u27a1\ufe0f\/\u2198\ufe0f (Stabilisierung in der zweiten H\u00e4lfte des US-Handels)<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u2692 <strong>Rohstoffm\u00e4rkte <\/strong>\u2195\ufe0f<br><em>\u00d6lpreise \u2198\ufe0f\/\u27a1\ufe0f\/\u2197\ufe0f (bleiben unterst\u00fctzt und erholen sich von leichten Verlusten)<br>Erdgaspreise \u27a1\ufe0f\/\u2197\ufe0f<br>Metallpreise \u2197\ufe0f\/\u27a1\ufe0f (geringe zus\u00e4tzliche Gewinne w\u00e4hrend des US-Handels)<br>Edelmetallpreise \u2197\ufe0f\/\u27a1\ufe0f (USD wird sich w\u00e4hrend des US-Handels stabilisieren, was zus\u00e4tzliche Goldgewinne begrenzt)<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u26a1\ufe0f<strong>Kryptow\u00e4hrungen <\/strong>\u27a1\ufe0f\/\u2198\ufe0f (Kryptow\u00e4hrungen bleiben unattraktiv)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>(*\u2197\ufe0f bullisch, \u2198\ufe0f b\u00e4risch, \u27a1\ufe0f seitw\u00e4rts \/ stabil, \u2195\ufe0f gemischt \/ volatil)<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dein <strong>Robert<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Der USD fiel im asiatischen\/europ\u00e4ischen Handel so stark wie seit zwei Wochen nicht mehr, wobei der JPY gegen\u00fcber den anderen&#8230;<\/p>\n","protected":false},"author":663,"featured_media":22001,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","pmpro_default_level":"","_daextam_enable_autolinks":"","footnotes":""},"categories":[117],"tags":[],"class_list":["post-22003","post","type-post","status-publish","format-standard","has-post-thumbnail","category-taegliche-aktualisierungen","pmpro-has-access"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Fallender USD, CN-Hoffnung helfen Stimmung an ruhigem Tag - SmartTrader<\/title>\n<meta name=\"description\" content=\"Fallender USD, CN-Hoffnung helfen Stimmung an ruhigem Tag.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/fallender-usd-cn-hoffnung-helfen-stimmung-an-ruhigem-tag\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fallender USD, CN-Hoffnung helfen Stimmung an ruhigem Tag - SmartTrader\" \/>\n<meta property=\"og:description\" content=\"Fallender USD, CN-Hoffnung helfen Stimmung an ruhigem Tag.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/fallender-usd-cn-hoffnung-helfen-stimmung-an-ruhigem-tag\/\" \/>\n<meta property=\"og:site_name\" content=\"SmartTrader\" \/>\n<meta property=\"article:published_time\" content=\"2023-09-11T13:07:44+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-09-11T13:15:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/09\/11.09.2023_TITLE_Artboard-1-copy-9.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1081\" \/>\n\t<meta property=\"og:image:height\" content=\"721\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Robert Lindner\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Robert Lindner\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taegliche-aktualisierungen\\\/fallender-usd-cn-hoffnung-helfen-stimmung-an-ruhigem-tag\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taegliche-aktualisierungen\\\/fallender-usd-cn-hoffnung-helfen-stimmung-an-ruhigem-tag\\\/\"},\"author\":{\"name\":\"Robert Lindner\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/#\\\/schema\\\/person\\\/4f791355f3f400fd2dd91d9c57c4c067\"},\"headline\":\"Fallender USD, CN-Hoffnung helfen Stimmung an ruhigem Tag\",\"datePublished\":\"2023-09-11T13:07:44+00:00\",\"dateModified\":\"2023-09-11T13:15:22+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taegliche-aktualisierungen\\\/fallender-usd-cn-hoffnung-helfen-stimmung-an-ruhigem-tag\\\/\"},\"wordCount\":471,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taegliche-aktualisierungen\\\/fallender-usd-cn-hoffnung-helfen-stimmung-an-ruhigem-tag\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/11.09.2023_TITLE_Artboard-1-copy-9.webp\",\"articleSection\":[\"T\u00e4gliche Aktualisierungen\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/smarttrader.community\\\/de\\\/taegliche-aktualisierungen\\\/fallender-usd-cn-hoffnung-helfen-stimmung-an-ruhigem-tag\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taegliche-aktualisierungen\\\/fallender-usd-cn-hoffnung-helfen-stimmung-an-ruhigem-tag\\\/\",\"url\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taegliche-aktualisierungen\\\/fallender-usd-cn-hoffnung-helfen-stimmung-an-ruhigem-tag\\\/\",\"name\":\"Fallender USD, CN-Hoffnung helfen Stimmung an ruhigem Tag - SmartTrader\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taegliche-aktualisierungen\\\/fallender-usd-cn-hoffnung-helfen-stimmung-an-ruhigem-tag\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taegliche-aktualisierungen\\\/fallender-usd-cn-hoffnung-helfen-stimmung-an-ruhigem-tag\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/11.09.2023_TITLE_Artboard-1-copy-9.webp\",\"datePublished\":\"2023-09-11T13:07:44+00:00\",\"dateModified\":\"2023-09-11T13:15:22+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/#\\\/schema\\\/person\\\/4f791355f3f400fd2dd91d9c57c4c067\"},\"description\":\"Fallender USD, CN-Hoffnung helfen Stimmung an ruhigem Tag.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taegliche-aktualisierungen\\\/fallender-usd-cn-hoffnung-helfen-stimmung-an-ruhigem-tag\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/smarttrader.community\\\/de\\\/taegliche-aktualisierungen\\\/fallender-usd-cn-hoffnung-helfen-stimmung-an-ruhigem-tag\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taegliche-aktualisierungen\\\/fallender-usd-cn-hoffnung-helfen-stimmung-an-ruhigem-tag\\\/#primaryimage\",\"url\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/11.09.2023_TITLE_Artboard-1-copy-9.webp\",\"contentUrl\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/11.09.2023_TITLE_Artboard-1-copy-9.webp\",\"width\":1081,\"height\":721},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taegliche-aktualisierungen\\\/fallender-usd-cn-hoffnung-helfen-stimmung-an-ruhigem-tag\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Fallender USD, CN-Hoffnung helfen Stimmung an ruhigem Tag\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/\",\"name\":\"SmartTrader\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/#\\\/schema\\\/person\\\/4f791355f3f400fd2dd91d9c57c4c067\",\"name\":\"Robert Lindner\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/robert-lindner_avatar_1-96x96.png\",\"url\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/robert-lindner_avatar_1-96x96.png\",\"contentUrl\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/robert-lindner_avatar_1-96x96.png\",\"caption\":\"Robert Lindner\"},\"sameAs\":[\"https:\\\/\\\/wwww.smarttrader.community\\\/\"],\"url\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/author\\\/robert_smarttrader\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fallender USD, CN-Hoffnung helfen Stimmung an ruhigem Tag - SmartTrader","description":"Fallender USD, CN-Hoffnung helfen Stimmung an ruhigem Tag.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/fallender-usd-cn-hoffnung-helfen-stimmung-an-ruhigem-tag\/","og_locale":"de_DE","og_type":"article","og_title":"Fallender USD, CN-Hoffnung helfen Stimmung an ruhigem Tag - SmartTrader","og_description":"Fallender USD, CN-Hoffnung helfen Stimmung an ruhigem Tag.","og_url":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/fallender-usd-cn-hoffnung-helfen-stimmung-an-ruhigem-tag\/","og_site_name":"SmartTrader","article_published_time":"2023-09-11T13:07:44+00:00","article_modified_time":"2023-09-11T13:15:22+00:00","og_image":[{"width":1081,"height":721,"url":"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/09\/11.09.2023_TITLE_Artboard-1-copy-9.webp","type":"image\/webp"}],"author":"Robert Lindner","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Robert Lindner","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/fallender-usd-cn-hoffnung-helfen-stimmung-an-ruhigem-tag\/#article","isPartOf":{"@id":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/fallender-usd-cn-hoffnung-helfen-stimmung-an-ruhigem-tag\/"},"author":{"name":"Robert Lindner","@id":"https:\/\/smarttrader.community\/de\/#\/schema\/person\/4f791355f3f400fd2dd91d9c57c4c067"},"headline":"Fallender USD, CN-Hoffnung helfen Stimmung an ruhigem Tag","datePublished":"2023-09-11T13:07:44+00:00","dateModified":"2023-09-11T13:15:22+00:00","mainEntityOfPage":{"@id":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/fallender-usd-cn-hoffnung-helfen-stimmung-an-ruhigem-tag\/"},"wordCount":471,"commentCount":0,"image":{"@id":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/fallender-usd-cn-hoffnung-helfen-stimmung-an-ruhigem-tag\/#primaryimage"},"thumbnailUrl":"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/09\/11.09.2023_TITLE_Artboard-1-copy-9.webp","articleSection":["T\u00e4gliche Aktualisierungen"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/fallender-usd-cn-hoffnung-helfen-stimmung-an-ruhigem-tag\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/fallender-usd-cn-hoffnung-helfen-stimmung-an-ruhigem-tag\/","url":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/fallender-usd-cn-hoffnung-helfen-stimmung-an-ruhigem-tag\/","name":"Fallender USD, CN-Hoffnung helfen Stimmung an ruhigem Tag - SmartTrader","isPartOf":{"@id":"https:\/\/smarttrader.community\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/fallender-usd-cn-hoffnung-helfen-stimmung-an-ruhigem-tag\/#primaryimage"},"image":{"@id":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/fallender-usd-cn-hoffnung-helfen-stimmung-an-ruhigem-tag\/#primaryimage"},"thumbnailUrl":"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/09\/11.09.2023_TITLE_Artboard-1-copy-9.webp","datePublished":"2023-09-11T13:07:44+00:00","dateModified":"2023-09-11T13:15:22+00:00","author":{"@id":"https:\/\/smarttrader.community\/de\/#\/schema\/person\/4f791355f3f400fd2dd91d9c57c4c067"},"description":"Fallender USD, CN-Hoffnung helfen Stimmung an ruhigem Tag.","breadcrumb":{"@id":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/fallender-usd-cn-hoffnung-helfen-stimmung-an-ruhigem-tag\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/fallender-usd-cn-hoffnung-helfen-stimmung-an-ruhigem-tag\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/fallender-usd-cn-hoffnung-helfen-stimmung-an-ruhigem-tag\/#primaryimage","url":"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/09\/11.09.2023_TITLE_Artboard-1-copy-9.webp","contentUrl":"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/09\/11.09.2023_TITLE_Artboard-1-copy-9.webp","width":1081,"height":721},{"@type":"BreadcrumbList","@id":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/fallender-usd-cn-hoffnung-helfen-stimmung-an-ruhigem-tag\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/smarttrader.community\/de\/"},{"@type":"ListItem","position":2,"name":"Fallender USD, CN-Hoffnung helfen Stimmung an ruhigem Tag"}]},{"@type":"WebSite","@id":"https:\/\/smarttrader.community\/de\/#website","url":"https:\/\/smarttrader.community\/de\/","name":"SmartTrader","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/smarttrader.community\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/smarttrader.community\/de\/#\/schema\/person\/4f791355f3f400fd2dd91d9c57c4c067","name":"Robert Lindner","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/05\/robert-lindner_avatar_1-96x96.png","url":"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/05\/robert-lindner_avatar_1-96x96.png","contentUrl":"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/05\/robert-lindner_avatar_1-96x96.png","caption":"Robert Lindner"},"sameAs":["https:\/\/wwww.smarttrader.community\/"],"url":"https:\/\/smarttrader.community\/de\/author\/robert_smarttrader\/"}]}},"_links":{"self":[{"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/posts\/22003","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/users\/663"}],"replies":[{"embeddable":true,"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/comments?post=22003"}],"version-history":[{"count":0,"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/posts\/22003\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/media\/22001"}],"wp:attachment":[{"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/media?parent=22003"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/categories?post=22003"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/tags?post=22003"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}