{"id":22164,"date":"2023-09-18T13:14:47","date_gmt":"2023-09-18T13:14:47","guid":{"rendered":"https:\/\/smarttrader.community\/?p=22164"},"modified":"2023-09-18T13:19:31","modified_gmt":"2023-09-18T13:19:31","slug":"sorge-ueber-hawkishe-fed-steigt-oelpreise-erhoehen-kostendruck","status":"publish","type":"post","link":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/sorge-ueber-hawkishe-fed-steigt-oelpreise-erhoehen-kostendruck\/","title":{"rendered":"Sorge \u00fcber hawkishe Fed steigt; \u00d6lpreise erh\u00f6hen Kostendruck"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Wir sehen einen <strong>langsamen Start in eine weitere wahrscheinlich holprige Woche<\/strong>, in der die Anleger auf <strong>wichtige <\/strong>Z<strong>insentscheidungen der Zentralbanken warten<\/strong>. Die Anleger sind wieder <strong>vorsichtiger <\/strong>geworden, nachdem gemischte <strong>Wirtschaftsdaten <\/strong>keinen klaren Ausblick auf die Entwicklung der Wirtschaftst\u00e4tigkeit geben und auch f\u00fcr die Fed ein gemischtes Bild zeichnen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Erschwert wird die Aufgabe der Zentralbanken durch die <strong>stark steigenden Energiepreise<\/strong>, da der \u00d6lpreis in den letzten drei Wochen <strong>um mehr als 11%<\/strong> gestiegen ist. W\u00e4hrend wir heute einen sehr ruhigen Wirtschaftskalender haben, blicken die Investoren auch nach <strong>Calgary, wo der saudische Energieminister Prinz Abdulaziz bin Salman \u00fcber die Erd\u00f6lpolitik des K\u00f6nigreichs sprechen wird,<\/strong> nachdem die j\u00fcngsten Produktionsk\u00fcrzungen dazu beigetragen haben, die \u00d6lpreise nach oben zu treiben und den globalen Kostendruck zu erh\u00f6hen. Die \u00d6lpreise stiegen trotz positiver Nachrichten von Chevron, das die volle Produktion einer Fl\u00fcssigerdgas-Exportanlage in Australien wieder aufgenommen hat<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Im G<strong>egensatz zu der verwirrenden Positionierung der EZB<\/strong> in der Vorwoche erwarten wir, dass die <strong>Fed die dovishen Hoffnungen der Investoren zur\u00fcckdr\u00e4ngen und stattdessen vor einer zunehmend hartn\u00e4ckigen Inflation warnen wird<\/strong>. Wir rechnen jedoch nicht mit einer Zinserh\u00f6hung am Mittwoch, da die Fed in den kommenden Wochen wahrscheinlich weitere Daten abwarten m\u00f6chte. Der Dot Plot k\u00f6nnte darauf hindeuten, dass die Fed-Mitglieder Zinssenkungen in weite Ferne r\u00fccken &#8211; was zu <strong>erheblichem Gegenwind f\u00fcr Aktien <\/strong>f\u00fchren k\u00f6nnte, insbesondere f\u00fcr zinssensible Wachstumswerte.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Wir sehen einen<strong> leicht schw\u00e4cheren USD<\/strong> &#8211; was jedoch nur vor\u00fcbergehend zu sein scheint. Die Erwartung l\u00e4nger anhaltender hoher Zinsen, steigende \u00d6lpreise und die Widerstandsf\u00e4higkeit der US-Wirtschaft werden den <strong>USD weiterhin st\u00fctzen<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die <strong>Umschichtung von Wachstumswerten in defensivere Werte wird sich in dieser Woche wahrscheinlich verst\u00e4rken<\/strong> &#8211; auch wenn wir insgesamt mit Gegenwind f\u00fcr Aktien rechnen, da die Erwartungen steigen, dass die Zentralbanken aufgrund des hohen Kosten-\/Preisdrucks die Geldpolitik nicht l\u00e4nger lockern werden. E<strong>nergie wird angesichts steigender \u00d6lpreise (wieder) outperformen <\/strong>&#8211; <em>wir haben am Freitag einen guten Einstieg gefunden.<\/em><\/p>\n\n\n\n<h3 class=\"wp-block-heading\">\ud83d\udc41 ROB'S MARKET OVERVIEW:<\/h3>\n\n\n\n<ol class=\"wp-block-list\" start=\"18\">\n<li><em>September, 2023<\/em><\/li>\n<\/ol>\n\n\n\n<p class=\"wp-block-paragraph\">\ud83c\uddfa\ud83c\uddf8 <strong>US-M\u00e4rkte <\/strong>\u27a1\ufe0f\/\u2198\ufe0f<br><em>Zyklische Aktien \u27a1\ufe0f\/\u2198\ufe0f<br>Tech\/Wachstumsaktien \u27a1\ufe0f\/\u2198\ufe0f (Chip-Aktien \u2198\ufe0f)<br>Finanzaktien \u27a1\ufe0f\/\u2198\ufe0f<br>Defensive Aktien \u27a1\ufe0f\/\u2197\ufe0f<br>Energieaktien \u2197\ufe0f<br>Rohstoffaktien \u27a1\ufe0f\/\u2197\ufe0f<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\ud83d\udcb1 <strong>Devisenmarkt<\/strong><br><em>USD \u27a1\ufe0f\/\u2197\ufe0f (meist seitw\u00e4rts, aber bleibt bullish)<br>CAD \u27a1\ufe0f\/\u2197\ufe0f<br>AUD, CHF, JPY \u27a1\ufe0f<br>EUR \u27a1\ufe0f\/\u2198\ufe0f (EUR stabilisiert sich, bleibt aber bearish)<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u2692 <strong>Rohstoffm\u00e4rkte <\/strong>\u2195\ufe0f\/\u2197\ufe0f<br><em>\u00d6lpreise \u27a1\ufe0f\/\u2197\ufe0f (\u00d6lpreise bleiben bullish)<br>Erdgaspreise \u2195\ufe0f<br>Metallpreise \u2195\ufe0f\/\u2197\ufe0f (mit mehr Optimismus in China)<br>Edelmetallpreise \u27a1\ufe0f\/\u2198\ufe0f (Gold unter Druck durch steigende Renditen)<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u26a1\ufe0f<strong>Kryptow\u00e4hrungen <\/strong>\u2195\ufe0f\/\u2197\ufe0f<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">(<em>*\u2197\ufe0f bullisch, \u2198\ufe0f b\u00e4risch, \u27a1\ufe0f seitw\u00e4rts \/ stabil, \u2195\ufe0f gemischt \/ volatil<\/em>)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dein <strong>Robert<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Wir sehen einen langsamen Start in eine weitere wahrscheinlich holprige Woche, in der die Anleger auf wichtige Zinsentscheidungen der Zentralbanken&#8230;<\/p>\n","protected":false},"author":663,"featured_media":22162,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","pmpro_default_level":"","_daextam_enable_autolinks":"","footnotes":""},"categories":[117],"tags":[],"class_list":["post-22164","post","type-post","status-publish","format-standard","has-post-thumbnail","category-taegliche-aktualisierungen","pmpro-has-access"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sorge \u00fcber hawkishe Fed steigt; \u00d6lpreise erh\u00f6hen Kostendruck - SmartTrader<\/title>\n<meta name=\"description\" content=\"Sorge \u00fcber hawkishe Fed steigt; \u00d6lpreise erh\u00f6hen Kostendruck.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/sorge-ueber-hawkishe-fed-steigt-oelpreise-erhoehen-kostendruck\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sorge \u00fcber hawkishe Fed steigt; \u00d6lpreise erh\u00f6hen Kostendruck - SmartTrader\" \/>\n<meta property=\"og:description\" content=\"Sorge \u00fcber hawkishe Fed steigt; \u00d6lpreise erh\u00f6hen Kostendruck.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/sorge-ueber-hawkishe-fed-steigt-oelpreise-erhoehen-kostendruck\/\" \/>\n<meta property=\"og:site_name\" content=\"SmartTrader\" \/>\n<meta property=\"article:published_time\" content=\"2023-09-18T13:14:47+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-09-18T13:19:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/09\/18.09.2023_TITLE_Artboard-1-copy-9.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1081\" \/>\n\t<meta property=\"og:image:height\" content=\"721\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Robert Lindner\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Robert Lindner\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taegliche-aktualisierungen\\\/sorge-ueber-hawkishe-fed-steigt-oelpreise-erhoehen-kostendruck\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taegliche-aktualisierungen\\\/sorge-ueber-hawkishe-fed-steigt-oelpreise-erhoehen-kostendruck\\\/\"},\"author\":{\"name\":\"Robert Lindner\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/#\\\/schema\\\/person\\\/4f791355f3f400fd2dd91d9c57c4c067\"},\"headline\":\"Sorge \u00fcber hawkishe Fed steigt; \u00d6lpreise erh\u00f6hen Kostendruck\",\"datePublished\":\"2023-09-18T13:14:47+00:00\",\"dateModified\":\"2023-09-18T13:19:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taegliche-aktualisierungen\\\/sorge-ueber-hawkishe-fed-steigt-oelpreise-erhoehen-kostendruck\\\/\"},\"wordCount\":413,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taegliche-aktualisierungen\\\/sorge-ueber-hawkishe-fed-steigt-oelpreise-erhoehen-kostendruck\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/18.09.2023_TITLE_Artboard-1-copy-9.webp\",\"articleSection\":[\"T\u00e4gliche Aktualisierungen\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/smarttrader.community\\\/de\\\/taegliche-aktualisierungen\\\/sorge-ueber-hawkishe-fed-steigt-oelpreise-erhoehen-kostendruck\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taegliche-aktualisierungen\\\/sorge-ueber-hawkishe-fed-steigt-oelpreise-erhoehen-kostendruck\\\/\",\"url\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taegliche-aktualisierungen\\\/sorge-ueber-hawkishe-fed-steigt-oelpreise-erhoehen-kostendruck\\\/\",\"name\":\"Sorge \u00fcber hawkishe Fed steigt; \u00d6lpreise erh\u00f6hen Kostendruck - SmartTrader\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taegliche-aktualisierungen\\\/sorge-ueber-hawkishe-fed-steigt-oelpreise-erhoehen-kostendruck\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taegliche-aktualisierungen\\\/sorge-ueber-hawkishe-fed-steigt-oelpreise-erhoehen-kostendruck\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/18.09.2023_TITLE_Artboard-1-copy-9.webp\",\"datePublished\":\"2023-09-18T13:14:47+00:00\",\"dateModified\":\"2023-09-18T13:19:31+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/#\\\/schema\\\/person\\\/4f791355f3f400fd2dd91d9c57c4c067\"},\"description\":\"Sorge \u00fcber hawkishe Fed steigt; \u00d6lpreise erh\u00f6hen Kostendruck.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taegliche-aktualisierungen\\\/sorge-ueber-hawkishe-fed-steigt-oelpreise-erhoehen-kostendruck\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/smarttrader.community\\\/de\\\/taegliche-aktualisierungen\\\/sorge-ueber-hawkishe-fed-steigt-oelpreise-erhoehen-kostendruck\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taegliche-aktualisierungen\\\/sorge-ueber-hawkishe-fed-steigt-oelpreise-erhoehen-kostendruck\\\/#primaryimage\",\"url\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/18.09.2023_TITLE_Artboard-1-copy-9.webp\",\"contentUrl\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/18.09.2023_TITLE_Artboard-1-copy-9.webp\",\"width\":1081,\"height\":721},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taegliche-aktualisierungen\\\/sorge-ueber-hawkishe-fed-steigt-oelpreise-erhoehen-kostendruck\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sorge \u00fcber hawkishe Fed steigt; \u00d6lpreise erh\u00f6hen Kostendruck\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/\",\"name\":\"SmartTrader\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/#\\\/schema\\\/person\\\/4f791355f3f400fd2dd91d9c57c4c067\",\"name\":\"Robert Lindner\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/robert-lindner_avatar_1-96x96.png\",\"url\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/robert-lindner_avatar_1-96x96.png\",\"contentUrl\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/robert-lindner_avatar_1-96x96.png\",\"caption\":\"Robert Lindner\"},\"sameAs\":[\"https:\\\/\\\/wwww.smarttrader.community\\\/\"],\"url\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/author\\\/robert_smarttrader\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sorge \u00fcber hawkishe Fed steigt; \u00d6lpreise erh\u00f6hen Kostendruck - SmartTrader","description":"Sorge \u00fcber hawkishe Fed steigt; \u00d6lpreise erh\u00f6hen Kostendruck.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/sorge-ueber-hawkishe-fed-steigt-oelpreise-erhoehen-kostendruck\/","og_locale":"de_DE","og_type":"article","og_title":"Sorge \u00fcber hawkishe Fed steigt; \u00d6lpreise erh\u00f6hen Kostendruck - SmartTrader","og_description":"Sorge \u00fcber hawkishe Fed steigt; \u00d6lpreise erh\u00f6hen Kostendruck.","og_url":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/sorge-ueber-hawkishe-fed-steigt-oelpreise-erhoehen-kostendruck\/","og_site_name":"SmartTrader","article_published_time":"2023-09-18T13:14:47+00:00","article_modified_time":"2023-09-18T13:19:31+00:00","og_image":[{"width":1081,"height":721,"url":"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/09\/18.09.2023_TITLE_Artboard-1-copy-9.webp","type":"image\/webp"}],"author":"Robert Lindner","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Robert Lindner","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/sorge-ueber-hawkishe-fed-steigt-oelpreise-erhoehen-kostendruck\/#article","isPartOf":{"@id":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/sorge-ueber-hawkishe-fed-steigt-oelpreise-erhoehen-kostendruck\/"},"author":{"name":"Robert Lindner","@id":"https:\/\/smarttrader.community\/de\/#\/schema\/person\/4f791355f3f400fd2dd91d9c57c4c067"},"headline":"Sorge \u00fcber hawkishe Fed steigt; \u00d6lpreise erh\u00f6hen Kostendruck","datePublished":"2023-09-18T13:14:47+00:00","dateModified":"2023-09-18T13:19:31+00:00","mainEntityOfPage":{"@id":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/sorge-ueber-hawkishe-fed-steigt-oelpreise-erhoehen-kostendruck\/"},"wordCount":413,"commentCount":0,"image":{"@id":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/sorge-ueber-hawkishe-fed-steigt-oelpreise-erhoehen-kostendruck\/#primaryimage"},"thumbnailUrl":"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/09\/18.09.2023_TITLE_Artboard-1-copy-9.webp","articleSection":["T\u00e4gliche Aktualisierungen"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/sorge-ueber-hawkishe-fed-steigt-oelpreise-erhoehen-kostendruck\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/sorge-ueber-hawkishe-fed-steigt-oelpreise-erhoehen-kostendruck\/","url":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/sorge-ueber-hawkishe-fed-steigt-oelpreise-erhoehen-kostendruck\/","name":"Sorge \u00fcber hawkishe Fed steigt; \u00d6lpreise erh\u00f6hen Kostendruck - SmartTrader","isPartOf":{"@id":"https:\/\/smarttrader.community\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/sorge-ueber-hawkishe-fed-steigt-oelpreise-erhoehen-kostendruck\/#primaryimage"},"image":{"@id":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/sorge-ueber-hawkishe-fed-steigt-oelpreise-erhoehen-kostendruck\/#primaryimage"},"thumbnailUrl":"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/09\/18.09.2023_TITLE_Artboard-1-copy-9.webp","datePublished":"2023-09-18T13:14:47+00:00","dateModified":"2023-09-18T13:19:31+00:00","author":{"@id":"https:\/\/smarttrader.community\/de\/#\/schema\/person\/4f791355f3f400fd2dd91d9c57c4c067"},"description":"Sorge \u00fcber hawkishe Fed steigt; \u00d6lpreise erh\u00f6hen Kostendruck.","breadcrumb":{"@id":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/sorge-ueber-hawkishe-fed-steigt-oelpreise-erhoehen-kostendruck\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/sorge-ueber-hawkishe-fed-steigt-oelpreise-erhoehen-kostendruck\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/sorge-ueber-hawkishe-fed-steigt-oelpreise-erhoehen-kostendruck\/#primaryimage","url":"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/09\/18.09.2023_TITLE_Artboard-1-copy-9.webp","contentUrl":"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/09\/18.09.2023_TITLE_Artboard-1-copy-9.webp","width":1081,"height":721},{"@type":"BreadcrumbList","@id":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/sorge-ueber-hawkishe-fed-steigt-oelpreise-erhoehen-kostendruck\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/smarttrader.community\/de\/"},{"@type":"ListItem","position":2,"name":"Sorge \u00fcber hawkishe Fed steigt; \u00d6lpreise erh\u00f6hen Kostendruck"}]},{"@type":"WebSite","@id":"https:\/\/smarttrader.community\/de\/#website","url":"https:\/\/smarttrader.community\/de\/","name":"SmartTrader","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/smarttrader.community\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/smarttrader.community\/de\/#\/schema\/person\/4f791355f3f400fd2dd91d9c57c4c067","name":"Robert Lindner","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/05\/robert-lindner_avatar_1-96x96.png","url":"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/05\/robert-lindner_avatar_1-96x96.png","contentUrl":"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/05\/robert-lindner_avatar_1-96x96.png","caption":"Robert Lindner"},"sameAs":["https:\/\/wwww.smarttrader.community\/"],"url":"https:\/\/smarttrader.community\/de\/author\/robert_smarttrader\/"}]}},"_links":{"self":[{"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/posts\/22164","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/users\/663"}],"replies":[{"embeddable":true,"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/comments?post=22164"}],"version-history":[{"count":0,"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/posts\/22164\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/media\/22162"}],"wp:attachment":[{"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/media?parent=22164"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/categories?post=22164"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/tags?post=22164"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}