{"id":22403,"date":"2023-09-27T13:15:34","date_gmt":"2023-09-27T13:15:34","guid":{"rendered":"https:\/\/smarttrader.community\/?p=22403"},"modified":"2023-09-27T13:21:40","modified_gmt":"2023-09-27T13:21:40","slug":"maerkte-beruhigen-sich-vorerst-stabilisieren-oelpreise-steigen","status":"publish","type":"post","link":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/maerkte-beruhigen-sich-vorerst-stabilisieren-oelpreise-steigen\/","title":{"rendered":"M\u00e4rkte beruhigen sich vorerst &amp; stabilisieren; \u00d6lpreise steigen"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Der <strong>schlimmste Ausverkauf bei Aktien und Anleihen in diesem Jahr <\/strong>hat sich etwas <strong>beruhigt<\/strong>, nachdem die Sorge um<strong> &#8222;h\u00f6here Zinsen f\u00fcr l\u00e4nger&#8220;<\/strong> die Anleger verschreckt und die Aktien auf den niedrigsten Stand seit Monaten gedr\u00fcckt hat.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die <strong>US-Aktien deuten auf eine leicht h\u00f6here Er\u00f6ffnung hin<\/strong> (+0,25 %-0,50 %), die auch von <strong>leicht niedrigeren Renditen <\/strong>und dem Ausverkauf profitiert, der bereits wichtige Niveaus erreicht hat, die nur mit zus\u00e4tzlicher \u00dcberzeugungskraft \u00fcberwunden werden k\u00f6nnen. Der Dow Jones liegt unter dem <strong>gleitenden 200-Tage-Durchschnitt<\/strong>, was als ein starkes technisches Signal daf\u00fcr gilt, dass die M\u00e4rkte <strong>\u00fcberverkauft <\/strong>sind.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">An einem eher ruhigen Tag, aber<strong> vor wichtigen Inflationsdaten aus der Eurozone<\/strong>, ist die <strong>Volatilit\u00e4t heute ebenfalls gesunken<\/strong>. Der Cboe Volatilit\u00e4tsindex oder VIX (oft als &#8222;Angstindex&#8220; bezeichnet) ging zur\u00fcck, nachdem er den h\u00f6chsten Stand seit Mai erreicht hatte.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00c4hnlich wie gestern fielen auch die<strong> Renditen der US-Staatsanleihen<\/strong>, nachdem sie ein 16-Jahres-Hoch erreicht hatten, ausgel\u00f6st durch Spekulationen, dass die Federal Reserve bis Ende 2024 oder l\u00e4nger in der N\u00e4he des aktuellen Niveaus bleiben wird. Der <strong>USD bleibt jedoch in der N\u00e4he seines H\u00f6chststandes<\/strong> gegen\u00fcber seinen Konkurrenten, was zeigt, dass die Anleger die <strong>Fed immer noch als hawkischer einsch\u00e4tzen als andere Zentralbanken.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die <strong>Stabilisierung hat auch die j\u00fcngste Korrektur der \u00d6lpreise gestoppt<\/strong>, die nicht fundamental begr\u00fcndet war. Wir gehen davon aus, dass die <strong>\u00d6lpreise wieder steigen werden<\/strong>, da der Preis f\u00fcr amerikanisches Roh\u00f6l auf <strong>$92<\/strong>\/Barrel gestiegen ist und starke Anzeichen f\u00fcr einen weiteren Anstieg zeigt.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die<strong> Risikofaktoren bleiben alle voll intakt <\/strong>und die <strong>\u00d6lpreise setzen ihren Aufw\u00e4rtstrend fort<\/strong>, was die Inflationssorgen verst\u00e4rkt.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die <strong>drohende Immobilienkrise in China<\/strong> bleibt ein starker <strong>Angstfaktor f\u00fcr die chinesischen M\u00e4rkte<\/strong>. Die deutschen Stimmungsdaten zeigen, dass die <strong>deutschen Verbraucher extrem pessimistisch sind<\/strong> (noch schlechter als erwartet). Ein Indikator f\u00fcr die Verbraucherstimmung in den USA fiel von 108,7 im August (gestern gemeldet) auf 103 und verfehlte damit die Mediansch\u00e4tzung von 105,5, was ebenfalls zeigt, dass sich die <strong>Stimmung in den USA verschlechtert<\/strong> &#8211; allerdings von einem noch gesunden Niveau aus.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die <strong>M\u00e4rkte werden sich heute stabilisieren<\/strong>, aber es gibt <strong>keine fundamentalen Gr\u00fcnde<\/strong>, die eine anhaltende Rallye erwarten lassen. F\u00fcr die kommenden Sitzungen erwarten wir <strong>weitere Verluste<\/strong>.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">\ud83d\udc41 ROB'S MARKET OVERVIEW:<\/h3>\n\n\n\n<ol class=\"wp-block-list\" start=\"27\">\n<li><em>September, 2023<\/em><\/li>\n<\/ol>\n\n\n\n<p class=\"wp-block-paragraph\">\ud83c\uddfa\ud83c\uddf8 <strong>US-M\u00e4rkte <\/strong><em>\u2197\ufe0f\/\u27a1\ufe0f (leichte &#8222;Erholungs&#8220;-Gewinne &#8211; danach seitw\u00e4rts Bewegung)<br>Zyklische Aktien \u2197\ufe0f\/\u27a1\ufe0f<br>Tech\/Wachstumsaktien \u2197\ufe0f\/\u27a1\ufe0f<br>Finanzaktien \u2197\ufe0f (werden den Tag h\u00f6her beenden)<br>Defensivaktien \u27a1\ufe0f\/\u2197\ufe0f (profitieren von der anhaltenden Umschichtung von Wachstum zu Defensiv)<br>Energieaktien \u2197\ufe0f<br>Rohstoffaktien \u2197\ufe0f\/\u27a1\ufe0f<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\ud83d\udcb1 <strong>Forex<\/strong><br><em>USD \u2197\ufe0f\/\u27a1\ufe0f (bleibt bullisch &#8211; heute haupts\u00e4chlich Seitw\u00e4rtsbewegung)<br>CAD \u27a1\ufe0f\/\u2197\ufe0f (profitiert von bullischen \u00d6lpreisen)<br>EUR, GBP \u27a1\ufe0f\/\u2197\ufe0f (kurzfristig leicht \u00fcberverkauft)<br>JPY \u27a1\ufe0f<br>AUD, CHF \u27a1\ufe0f\/\u2198\ufe0f<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u2692 <strong>Rohstoffm\u00e4rkte <\/strong>\u2195\ufe0f<br><em>\u00d6lpreise \u2197\ufe0f (\u00d6l &#8222;endlich&#8220; wieder im bullischen Preisbereich)<br>Erdgaspreise \u2197\ufe0f<br>Metallpreise \u2195\ufe0f\/\u2198\ufe0f<br>Edelmetallpreise \u27a1\ufe0f\/\u2198\ufe0f (hohe Renditen + starker USD schm\u00e4lern die Attraktivit\u00e4t von Gold)<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u26a1\ufe0f<strong>Kryptos <\/strong><em>\u2197\ufe0f\/\u27a1\ufe0f (profitieren von vor\u00fcbergehend verbessertem Sentiment und j\u00fcngsten Verlusten; Kryptos bleiben f\u00fcr Investoren unattraktiv)<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>(*\u2197\ufe0f bullisch, \u2198\ufe0f b\u00e4risch, \u27a1\ufe0f seitw\u00e4rts \/ stabil, \u2195\ufe0f gemischt \/ volatil)<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dein <strong>Robert<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Der schlimmste Ausverkauf bei Aktien und Anleihen in diesem Jahr hat sich etwas beruhigt, nachdem die Sorge um &#8222;h\u00f6here Zinsen&#8230;<\/p>\n","protected":false},"author":663,"featured_media":22402,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","pmpro_default_level":"","_daextam_enable_autolinks":"","footnotes":""},"categories":[117],"tags":[],"class_list":["post-22403","post","type-post","status-publish","format-standard","has-post-thumbnail","category-taegliche-aktualisierungen","pmpro-has-access"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>M\u00e4rkte beruhigen sich vorerst &amp; stabilisieren; \u00d6lpreise steigen - SmartTrader<\/title>\n<meta name=\"description\" content=\"M\u00e4rkte beruhigen sich vorerst &amp; stabilisieren; \u00d6lpreise steigen. Der schlimmste Ausverkauf bei Aktien und Anleihen in diesem Jahr hat...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/maerkte-beruhigen-sich-vorerst-stabilisieren-oelpreise-steigen\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"M\u00e4rkte beruhigen sich vorerst &amp; stabilisieren; \u00d6lpreise steigen - SmartTrader\" \/>\n<meta property=\"og:description\" content=\"M\u00e4rkte beruhigen sich vorerst &amp; stabilisieren; \u00d6lpreise steigen. Der schlimmste Ausverkauf bei Aktien und Anleihen in diesem Jahr hat...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/maerkte-beruhigen-sich-vorerst-stabilisieren-oelpreise-steigen\/\" \/>\n<meta property=\"og:site_name\" content=\"SmartTrader\" \/>\n<meta property=\"article:published_time\" content=\"2023-09-27T13:15:34+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-09-27T13:21:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/09\/27.09.2023_TITLE_Artboard-1-copy-9.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1081\" \/>\n\t<meta property=\"og:image:height\" content=\"721\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Robert Lindner\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Robert Lindner\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taegliche-aktualisierungen\\\/maerkte-beruhigen-sich-vorerst-stabilisieren-oelpreise-steigen\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taegliche-aktualisierungen\\\/maerkte-beruhigen-sich-vorerst-stabilisieren-oelpreise-steigen\\\/\"},\"author\":{\"name\":\"Robert Lindner\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/#\\\/schema\\\/person\\\/4f791355f3f400fd2dd91d9c57c4c067\"},\"headline\":\"M\u00e4rkte beruhigen sich vorerst &amp; stabilisieren; \u00d6lpreise steigen\",\"datePublished\":\"2023-09-27T13:15:34+00:00\",\"dateModified\":\"2023-09-27T13:21:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taegliche-aktualisierungen\\\/maerkte-beruhigen-sich-vorerst-stabilisieren-oelpreise-steigen\\\/\"},\"wordCount\":499,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taegliche-aktualisierungen\\\/maerkte-beruhigen-sich-vorerst-stabilisieren-oelpreise-steigen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/27.09.2023_TITLE_Artboard-1-copy-9.webp\",\"articleSection\":[\"T\u00e4gliche Aktualisierungen\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/smarttrader.community\\\/de\\\/taegliche-aktualisierungen\\\/maerkte-beruhigen-sich-vorerst-stabilisieren-oelpreise-steigen\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taegliche-aktualisierungen\\\/maerkte-beruhigen-sich-vorerst-stabilisieren-oelpreise-steigen\\\/\",\"url\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taegliche-aktualisierungen\\\/maerkte-beruhigen-sich-vorerst-stabilisieren-oelpreise-steigen\\\/\",\"name\":\"M\u00e4rkte beruhigen sich vorerst &amp; stabilisieren; \u00d6lpreise steigen - SmartTrader\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taegliche-aktualisierungen\\\/maerkte-beruhigen-sich-vorerst-stabilisieren-oelpreise-steigen\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taegliche-aktualisierungen\\\/maerkte-beruhigen-sich-vorerst-stabilisieren-oelpreise-steigen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/27.09.2023_TITLE_Artboard-1-copy-9.webp\",\"datePublished\":\"2023-09-27T13:15:34+00:00\",\"dateModified\":\"2023-09-27T13:21:40+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/#\\\/schema\\\/person\\\/4f791355f3f400fd2dd91d9c57c4c067\"},\"description\":\"M\u00e4rkte beruhigen sich vorerst & stabilisieren; \u00d6lpreise steigen. Der schlimmste Ausverkauf bei Aktien und Anleihen in diesem Jahr hat...\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taegliche-aktualisierungen\\\/maerkte-beruhigen-sich-vorerst-stabilisieren-oelpreise-steigen\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/smarttrader.community\\\/de\\\/taegliche-aktualisierungen\\\/maerkte-beruhigen-sich-vorerst-stabilisieren-oelpreise-steigen\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taegliche-aktualisierungen\\\/maerkte-beruhigen-sich-vorerst-stabilisieren-oelpreise-steigen\\\/#primaryimage\",\"url\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/27.09.2023_TITLE_Artboard-1-copy-9.webp\",\"contentUrl\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/27.09.2023_TITLE_Artboard-1-copy-9.webp\",\"width\":1081,\"height\":721},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taegliche-aktualisierungen\\\/maerkte-beruhigen-sich-vorerst-stabilisieren-oelpreise-steigen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"M\u00e4rkte beruhigen sich vorerst &amp; stabilisieren; \u00d6lpreise steigen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/\",\"name\":\"SmartTrader\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/#\\\/schema\\\/person\\\/4f791355f3f400fd2dd91d9c57c4c067\",\"name\":\"Robert Lindner\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/robert-lindner_avatar_1-96x96.png\",\"url\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/robert-lindner_avatar_1-96x96.png\",\"contentUrl\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/robert-lindner_avatar_1-96x96.png\",\"caption\":\"Robert Lindner\"},\"sameAs\":[\"https:\\\/\\\/wwww.smarttrader.community\\\/\"],\"url\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/author\\\/robert_smarttrader\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"M\u00e4rkte beruhigen sich vorerst &amp; stabilisieren; \u00d6lpreise steigen - SmartTrader","description":"M\u00e4rkte beruhigen sich vorerst & stabilisieren; \u00d6lpreise steigen. Der schlimmste Ausverkauf bei Aktien und Anleihen in diesem Jahr hat...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/maerkte-beruhigen-sich-vorerst-stabilisieren-oelpreise-steigen\/","og_locale":"de_DE","og_type":"article","og_title":"M\u00e4rkte beruhigen sich vorerst &amp; stabilisieren; \u00d6lpreise steigen - SmartTrader","og_description":"M\u00e4rkte beruhigen sich vorerst & stabilisieren; \u00d6lpreise steigen. Der schlimmste Ausverkauf bei Aktien und Anleihen in diesem Jahr hat...","og_url":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/maerkte-beruhigen-sich-vorerst-stabilisieren-oelpreise-steigen\/","og_site_name":"SmartTrader","article_published_time":"2023-09-27T13:15:34+00:00","article_modified_time":"2023-09-27T13:21:40+00:00","og_image":[{"width":1081,"height":721,"url":"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/09\/27.09.2023_TITLE_Artboard-1-copy-9.webp","type":"image\/webp"}],"author":"Robert Lindner","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Robert Lindner","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/maerkte-beruhigen-sich-vorerst-stabilisieren-oelpreise-steigen\/#article","isPartOf":{"@id":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/maerkte-beruhigen-sich-vorerst-stabilisieren-oelpreise-steigen\/"},"author":{"name":"Robert Lindner","@id":"https:\/\/smarttrader.community\/de\/#\/schema\/person\/4f791355f3f400fd2dd91d9c57c4c067"},"headline":"M\u00e4rkte beruhigen sich vorerst &amp; stabilisieren; \u00d6lpreise steigen","datePublished":"2023-09-27T13:15:34+00:00","dateModified":"2023-09-27T13:21:40+00:00","mainEntityOfPage":{"@id":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/maerkte-beruhigen-sich-vorerst-stabilisieren-oelpreise-steigen\/"},"wordCount":499,"commentCount":0,"image":{"@id":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/maerkte-beruhigen-sich-vorerst-stabilisieren-oelpreise-steigen\/#primaryimage"},"thumbnailUrl":"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/09\/27.09.2023_TITLE_Artboard-1-copy-9.webp","articleSection":["T\u00e4gliche Aktualisierungen"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/maerkte-beruhigen-sich-vorerst-stabilisieren-oelpreise-steigen\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/maerkte-beruhigen-sich-vorerst-stabilisieren-oelpreise-steigen\/","url":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/maerkte-beruhigen-sich-vorerst-stabilisieren-oelpreise-steigen\/","name":"M\u00e4rkte beruhigen sich vorerst &amp; stabilisieren; \u00d6lpreise steigen - SmartTrader","isPartOf":{"@id":"https:\/\/smarttrader.community\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/maerkte-beruhigen-sich-vorerst-stabilisieren-oelpreise-steigen\/#primaryimage"},"image":{"@id":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/maerkte-beruhigen-sich-vorerst-stabilisieren-oelpreise-steigen\/#primaryimage"},"thumbnailUrl":"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/09\/27.09.2023_TITLE_Artboard-1-copy-9.webp","datePublished":"2023-09-27T13:15:34+00:00","dateModified":"2023-09-27T13:21:40+00:00","author":{"@id":"https:\/\/smarttrader.community\/de\/#\/schema\/person\/4f791355f3f400fd2dd91d9c57c4c067"},"description":"M\u00e4rkte beruhigen sich vorerst & stabilisieren; \u00d6lpreise steigen. Der schlimmste Ausverkauf bei Aktien und Anleihen in diesem Jahr hat...","breadcrumb":{"@id":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/maerkte-beruhigen-sich-vorerst-stabilisieren-oelpreise-steigen\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/maerkte-beruhigen-sich-vorerst-stabilisieren-oelpreise-steigen\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/maerkte-beruhigen-sich-vorerst-stabilisieren-oelpreise-steigen\/#primaryimage","url":"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/09\/27.09.2023_TITLE_Artboard-1-copy-9.webp","contentUrl":"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/09\/27.09.2023_TITLE_Artboard-1-copy-9.webp","width":1081,"height":721},{"@type":"BreadcrumbList","@id":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/maerkte-beruhigen-sich-vorerst-stabilisieren-oelpreise-steigen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/smarttrader.community\/de\/"},{"@type":"ListItem","position":2,"name":"M\u00e4rkte beruhigen sich vorerst &amp; stabilisieren; \u00d6lpreise steigen"}]},{"@type":"WebSite","@id":"https:\/\/smarttrader.community\/de\/#website","url":"https:\/\/smarttrader.community\/de\/","name":"SmartTrader","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/smarttrader.community\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/smarttrader.community\/de\/#\/schema\/person\/4f791355f3f400fd2dd91d9c57c4c067","name":"Robert Lindner","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/05\/robert-lindner_avatar_1-96x96.png","url":"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/05\/robert-lindner_avatar_1-96x96.png","contentUrl":"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/05\/robert-lindner_avatar_1-96x96.png","caption":"Robert Lindner"},"sameAs":["https:\/\/wwww.smarttrader.community\/"],"url":"https:\/\/smarttrader.community\/de\/author\/robert_smarttrader\/"}]}},"_links":{"self":[{"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/posts\/22403","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/users\/663"}],"replies":[{"embeddable":true,"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/comments?post=22403"}],"version-history":[{"count":0,"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/posts\/22403\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/media\/22402"}],"wp:attachment":[{"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/media?parent=22403"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/categories?post=22403"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/tags?post=22403"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}