{"id":23090,"date":"2023-10-06T12:19:00","date_gmt":"2023-10-06T12:19:00","guid":{"rendered":"https:\/\/smarttrader.community\/?p=23090"},"modified":"2023-10-06T12:41:15","modified_gmt":"2023-10-06T12:41:15","slug":"investoren-mit-leichtem-optimismus-aber-abwartend-vor-nfp-bericht","status":"publish","type":"post","link":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/investoren-mit-leichtem-optimismus-aber-abwartend-vor-nfp-bericht\/","title":{"rendered":"Investoren mit leichtem Optimismus, aber abwartend vor NFP-Bericht"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Wir sehen die <strong>US-Indexfutures bei geringem Handelsvolumen<\/strong> und geringer Volatilit\u00e4t flach \/ leicht h\u00f6her, da sich die Trader auf <strong>einen wichtigen US-Arbeitsmarktbericht vorbereiten<\/strong>, der den Druck auf die Federal Reserve, die Zinsen wieder anzuheben, m\u00f6glicherweise verringern k\u00f6nnte.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Aktien in Europa handeln um ~0,5% h\u00f6her<\/strong>, wobei Versicherer und Bergbauunternehmen die Gewinne anf\u00fchren. Die Rohstoffpreise, insbesondere der <strong>\u00d6lpreis<\/strong>, zeigen Anzeichen einer Bodenbildung, nachdem sie in den letzten Sitzungen stark gefallen waren, weil die Bef\u00fcrchtung weit verbreitet war, dass die Zinserh\u00f6hungsprognose der US-Notenbank und die Renditen auf einem Niveau wie zuletzt 2007 die M\u00e4rkte und die Nachfrage der Verbraucher\/Unternehmen weiter belasten w\u00fcrden.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tesla belastet den S&P 500 und den Nasdaq, nachdem das Unternehmen eine weitere Runde von Preissenkungen angek\u00fcndigt hat, und notiert derzeit 1,6% niedriger.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Alle Augen richten sich jedoch auf den Bericht \u00fcber die Besch\u00e4ftigtenzahlen au\u00dferhalb der Landwirtschaft (NFP)<\/strong>, aus dem hervorgeht, dass die Arbeitgeber im September <strong>170.000 neue Arbeitspl\u00e4tze geschaffen haben, gegen\u00fcber 187.000 im August. <\/strong>Die Arbeitsmarktdaten zu Beginn der Woche boten ein gemischtes Bild: Die Zahl der offenen Stellen lag \u00fcber den Sch\u00e4tzungen, die ADP-Besch\u00e4ftigungsdaten f\u00fcr den privaten Sektor fielen schw\u00e4cher aus als erwartet und die gestrigen Antr\u00e4ge auf Arbeitslosenunterst\u00fctzung blieben auf einem niedrigen Niveau. Ich <strong>glaube, dass die &#8222;echten&#8220; Erwartungen nach dem ADP-Bericht vom Mittwoch etwas unter 170.000 liegen, was Raum f\u00fcr Entt\u00e4uschungen er\u00f6ffnet.<\/strong> Ich erwarte nicht, dass die NFP-Daten eine \u00e4hnliche Abschw\u00e4chung wie der ADP-Personalbericht zeigen werden.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Insgesamt erwarte ich keine gro\u00dfe \u00dcberraschung oder Daten,<\/strong> die den Zinsausblick der Fed ver\u00e4ndern k\u00f6nnten. Angesichts der typischerweise schwachen Einstellungszahlen im September und der j\u00fcngsten Anzeichen einer Verlangsamung ist es jedoch wahrscheinlich, dass die Zahl der Besch\u00e4ftigten weiter gesunken ist. <strong>Das Gesamtbild wird sich jedoch wahrscheinlich nicht \u00e4ndern &#8211; der US-Arbeitsmarkt ist robust und auch die Lohninflation bleibt hartn\u00e4ckig.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Wir gehen davon aus, <strong>dass die Renditen der Staatsanleihen im Vorfeld der Daten steigen werden<\/strong>. Eine leichte Verlangsamung der <strong>Neueinstellungen w\u00fcrde die Renditen vor\u00fcbergehend zur\u00fcckgehen<\/strong> lassen und den Aktien etwas Erleichterung verschaffen &#8211; aber die Gesamtaussichten bleiben ziemlich d\u00fcster.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ich erwarte, <strong>dass das Umsatzwachstum der Unternehmen in den kommenden Monaten weiter zur\u00fcckgehen wird<\/strong>, und das werden die US-Unternehmen zunehmend zu sp\u00fcren bekommen. Die Wall Street wird immer noch auf historisch hohen Niveaus gehandelt, vor allem wenn man bedenkt, dass sich das zuk\u00fcnftige Umsatzwachstum verlangsamen wird.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">In einer<strong> ersten Reaktion k\u00f6nnten wir nach den j\u00fcngsten starken Verk\u00e4ufen Gegenbewegungen sehen. <\/strong>Auch die <strong>\u00d6lpreise k\u00f6nnten sich nach den starken Verk\u00e4ufen endlich etwas erholen und aus dem \u00fcberverkauften Bereich herauskommen.<\/strong> Das Gesamtbild wird sich jedoch nicht \u00e4ndern. Die Renditen werden wahrscheinlich weiter steigen, wobei die Renditen 10-j\u00e4hriger Anleihen in den kommenden Wochen weiter in Richtung 5% steigen d\u00fcrften.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>WENN<\/strong> (!) die<strong> NFP-Daten eine deutliche Verlangsamung des Besch\u00e4ftigungswachstums zeigen<\/strong>, werden wir einen <strong>starken Anstieg bei Aktien erleben<\/strong> &#8211; insbesondere bei <strong>zinssensiblen Aktien<\/strong>. Die Renditen w\u00fcrden vor\u00fcbergehend sinken (m\u00f6glicherweise um mehr als 10 Basispunkte &#8211; je nach den tats\u00e4chlichen Zahlen) und der <strong>USD <\/strong>w\u00fcrde deutlich schw\u00e4cher werden, was anderen <strong>Risikoanlagen wie den Rohstoffpreisen zugute k\u00e4me<\/strong>. Ich rechne jedoch NICHT mit einer deutlichen Abschw\u00e4chung.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>\ud83d\udc41 ROB'S MARKET OVERVIEW:<\/strong><\/h3>\n\n\n\n<ol class=\"wp-block-list\" start=\"6\">\n<li><em>October, 2023<\/em><\/li>\n<\/ol>\n\n\n\n<p class=\"wp-block-paragraph\">\ud83c\udde8\ud83c\uddf3 <em>Die chinesischen Festlandsm\u00e4rkte blieben aufgrund von Feiertagen geschlossen.<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u26a0\ufe0f <em>Wir erwarten keine gro\u00dfen \u00dcberraschungen von den NFP-Daten \/ leichter R\u00fcckgang bei den Einstellungen.<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\ud83c\uddfa\ud83c\uddf8 US-<strong>M\u00e4rkte <\/strong><em>\u2195\ufe0f\/\u2197\ufe0f\/\u27a1\ufe0f (die wahrscheinlich etwas niedrigeren NFP-Daten k\u00f6nnten die Aktien zun\u00e4chst st\u00fctzen; Ohne gro\u00dfe \u00c4nderung in der Prognose sind die Gewinne begrenzt und die Anleger werden gegen Ende des heutigen Handelstages wieder vorsichtiger).<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Zyklische Aktien<\/strong> \u2195\ufe0f\/\u2197\ufe0f\/\u2198\ufe0f<br>T<em>ech\/Wachstumsaktien \u2195\ufe0f\/\u2197\ufe0f\/\u27a1\ufe0f<br>Finanzaktien \u2195\ufe0f\/\u2197\ufe0f\/\u27a1\ufe0f<br>Defensive Aktien \u27a1\ufe0f\/\u2197\ufe0f<br>Energieaktien \u2195\ufe0f\/\u2197\ufe0f (\u00d6l findet heute einen Boden)<br>Rohstoffaktien \u2195\ufe0f\/\u2197\ufe0f<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\ud83d\udcb1 <strong>Forex<\/strong><br><em>AUD \u2197\ufe0f (profitiert von h\u00f6heren Eisenerzpreisen, leicht verbesserte Risikostimmung)<br>EUR, GBP \u2197\ufe0f\/\u27a1\ufe0f (leichte Erholungsgewinne &#8211; insgesamt jedoch b\u00e4risch gegen\u00fcber USD)<br>CHF \u27a1\ufe0f<br>USD \u2198\ufe0f\/\u2197\ufe0f (wahrscheinlich zuerst einige Verk\u00e4ufe &#8211; USD bleibt stark &#8211; Zinserwartung der Fed wahrscheinlich unver\u00e4ndert)<br>CAD \u2198\ufe0f\/\u27a1\ufe0f (Stabilisierung mit \u00d6lpreisen, die einen Boden finden)<br>JPY \u2198\ufe0f (bleibt b\u00e4risch)<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u2692 <strong>Rohstoffm\u00e4rkte <\/strong>\u2197\ufe0f<br><em>\u00d6lpreise \u27a1\ufe0f\/\u2197\ufe0f (nach starken Verlusten, Stabilisierung der Preise, m\u00f6glicherweise leichte Erholungsgewinne)<br>Erdgaspreise \u2195\ufe0f\/\u2197\ufe0f<br>Metallpreise \u2197\ufe0f (Anzeichen f\u00fcr mehr Nachfrage aus China)<br>Gold \u2197\ufe0f\/\u27a1\ufe0f (zuerst Gewinne, dann Stabilisierung)<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u26a1\ufe0f<strong>Kryptos <\/strong><em>\u2197\ufe0f\/\u27a1\ufe0f (zuerst Gewinne, dann Stabilisierung)<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>(*\u2197\ufe0f bullisch, \u2198\ufe0f b\u00e4risch, \u27a1\ufe0f seitw\u00e4rts \/ stabil, \u2195\ufe0f gemischt \/ volatil)<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dein <strong>Robert<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Wir sehen die US-Indexfutures bei geringem Handelsvolumen und geringer Volatilit\u00e4t flach \/ leicht h\u00f6her, da sich die Trader auf einen&#8230;<\/p>\n","protected":false},"author":663,"featured_media":23088,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","pmpro_default_level":"","_daextam_enable_autolinks":"","footnotes":""},"categories":[117],"tags":[],"class_list":["post-23090","post","type-post","status-publish","format-standard","has-post-thumbnail","category-taegliche-aktualisierungen","pmpro-has-access"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Investoren mit leichtem Optimismus, aber abwartend vor NFP-Bericht - SmartTrader<\/title>\n<meta name=\"description\" content=\"Investoren mit leichtem Optimismus, aber abwartend vor NFP-Bericht. Wir sehen die US-Indexfutures bei geringem Handelsvolumen und...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/investoren-mit-leichtem-optimismus-aber-abwartend-vor-nfp-bericht\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Investoren mit leichtem Optimismus, aber abwartend vor NFP-Bericht - SmartTrader\" \/>\n<meta property=\"og:description\" content=\"Investoren mit leichtem Optimismus, aber abwartend vor NFP-Bericht. Wir sehen die US-Indexfutures bei geringem Handelsvolumen und...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/investoren-mit-leichtem-optimismus-aber-abwartend-vor-nfp-bericht\/\" \/>\n<meta property=\"og:site_name\" content=\"SmartTrader\" \/>\n<meta property=\"article:published_time\" content=\"2023-10-06T12:19:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-10-06T12:41:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/10\/06.10.2023_TITLE_Artboard-1-copy-9.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1081\" \/>\n\t<meta property=\"og:image:height\" content=\"721\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Robert Lindner\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Robert Lindner\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taegliche-aktualisierungen\\\/investoren-mit-leichtem-optimismus-aber-abwartend-vor-nfp-bericht\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taegliche-aktualisierungen\\\/investoren-mit-leichtem-optimismus-aber-abwartend-vor-nfp-bericht\\\/\"},\"author\":{\"name\":\"Robert Lindner\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/#\\\/schema\\\/person\\\/4f791355f3f400fd2dd91d9c57c4c067\"},\"headline\":\"Investoren mit leichtem Optimismus, aber abwartend vor NFP-Bericht\",\"datePublished\":\"2023-10-06T12:19:00+00:00\",\"dateModified\":\"2023-10-06T12:41:15+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taegliche-aktualisierungen\\\/investoren-mit-leichtem-optimismus-aber-abwartend-vor-nfp-bericht\\\/\"},\"wordCount\":723,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taegliche-aktualisierungen\\\/investoren-mit-leichtem-optimismus-aber-abwartend-vor-nfp-bericht\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/06.10.2023_TITLE_Artboard-1-copy-9.webp\",\"articleSection\":[\"T\u00e4gliche Aktualisierungen\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/smarttrader.community\\\/de\\\/taegliche-aktualisierungen\\\/investoren-mit-leichtem-optimismus-aber-abwartend-vor-nfp-bericht\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taegliche-aktualisierungen\\\/investoren-mit-leichtem-optimismus-aber-abwartend-vor-nfp-bericht\\\/\",\"url\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taegliche-aktualisierungen\\\/investoren-mit-leichtem-optimismus-aber-abwartend-vor-nfp-bericht\\\/\",\"name\":\"Investoren mit leichtem Optimismus, aber abwartend vor NFP-Bericht - SmartTrader\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taegliche-aktualisierungen\\\/investoren-mit-leichtem-optimismus-aber-abwartend-vor-nfp-bericht\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taegliche-aktualisierungen\\\/investoren-mit-leichtem-optimismus-aber-abwartend-vor-nfp-bericht\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/06.10.2023_TITLE_Artboard-1-copy-9.webp\",\"datePublished\":\"2023-10-06T12:19:00+00:00\",\"dateModified\":\"2023-10-06T12:41:15+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/#\\\/schema\\\/person\\\/4f791355f3f400fd2dd91d9c57c4c067\"},\"description\":\"Investoren mit leichtem Optimismus, aber abwartend vor NFP-Bericht. Wir sehen die US-Indexfutures bei geringem Handelsvolumen und...\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taegliche-aktualisierungen\\\/investoren-mit-leichtem-optimismus-aber-abwartend-vor-nfp-bericht\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/smarttrader.community\\\/de\\\/taegliche-aktualisierungen\\\/investoren-mit-leichtem-optimismus-aber-abwartend-vor-nfp-bericht\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taegliche-aktualisierungen\\\/investoren-mit-leichtem-optimismus-aber-abwartend-vor-nfp-bericht\\\/#primaryimage\",\"url\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/06.10.2023_TITLE_Artboard-1-copy-9.webp\",\"contentUrl\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/06.10.2023_TITLE_Artboard-1-copy-9.webp\",\"width\":1081,\"height\":721},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taegliche-aktualisierungen\\\/investoren-mit-leichtem-optimismus-aber-abwartend-vor-nfp-bericht\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Investoren mit leichtem Optimismus, aber abwartend vor NFP-Bericht\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/\",\"name\":\"SmartTrader\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/#\\\/schema\\\/person\\\/4f791355f3f400fd2dd91d9c57c4c067\",\"name\":\"Robert Lindner\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/robert-lindner_avatar_1-96x96.png\",\"url\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/robert-lindner_avatar_1-96x96.png\",\"contentUrl\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/robert-lindner_avatar_1-96x96.png\",\"caption\":\"Robert Lindner\"},\"sameAs\":[\"https:\\\/\\\/wwww.smarttrader.community\\\/\"],\"url\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/author\\\/robert_smarttrader\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Investoren mit leichtem Optimismus, aber abwartend vor NFP-Bericht - SmartTrader","description":"Investoren mit leichtem Optimismus, aber abwartend vor NFP-Bericht. Wir sehen die US-Indexfutures bei geringem Handelsvolumen und...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/investoren-mit-leichtem-optimismus-aber-abwartend-vor-nfp-bericht\/","og_locale":"de_DE","og_type":"article","og_title":"Investoren mit leichtem Optimismus, aber abwartend vor NFP-Bericht - SmartTrader","og_description":"Investoren mit leichtem Optimismus, aber abwartend vor NFP-Bericht. Wir sehen die US-Indexfutures bei geringem Handelsvolumen und...","og_url":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/investoren-mit-leichtem-optimismus-aber-abwartend-vor-nfp-bericht\/","og_site_name":"SmartTrader","article_published_time":"2023-10-06T12:19:00+00:00","article_modified_time":"2023-10-06T12:41:15+00:00","og_image":[{"width":1081,"height":721,"url":"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/10\/06.10.2023_TITLE_Artboard-1-copy-9.webp","type":"image\/webp"}],"author":"Robert Lindner","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Robert Lindner","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/investoren-mit-leichtem-optimismus-aber-abwartend-vor-nfp-bericht\/#article","isPartOf":{"@id":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/investoren-mit-leichtem-optimismus-aber-abwartend-vor-nfp-bericht\/"},"author":{"name":"Robert Lindner","@id":"https:\/\/smarttrader.community\/de\/#\/schema\/person\/4f791355f3f400fd2dd91d9c57c4c067"},"headline":"Investoren mit leichtem Optimismus, aber abwartend vor NFP-Bericht","datePublished":"2023-10-06T12:19:00+00:00","dateModified":"2023-10-06T12:41:15+00:00","mainEntityOfPage":{"@id":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/investoren-mit-leichtem-optimismus-aber-abwartend-vor-nfp-bericht\/"},"wordCount":723,"commentCount":0,"image":{"@id":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/investoren-mit-leichtem-optimismus-aber-abwartend-vor-nfp-bericht\/#primaryimage"},"thumbnailUrl":"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/10\/06.10.2023_TITLE_Artboard-1-copy-9.webp","articleSection":["T\u00e4gliche Aktualisierungen"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/investoren-mit-leichtem-optimismus-aber-abwartend-vor-nfp-bericht\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/investoren-mit-leichtem-optimismus-aber-abwartend-vor-nfp-bericht\/","url":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/investoren-mit-leichtem-optimismus-aber-abwartend-vor-nfp-bericht\/","name":"Investoren mit leichtem Optimismus, aber abwartend vor NFP-Bericht - SmartTrader","isPartOf":{"@id":"https:\/\/smarttrader.community\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/investoren-mit-leichtem-optimismus-aber-abwartend-vor-nfp-bericht\/#primaryimage"},"image":{"@id":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/investoren-mit-leichtem-optimismus-aber-abwartend-vor-nfp-bericht\/#primaryimage"},"thumbnailUrl":"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/10\/06.10.2023_TITLE_Artboard-1-copy-9.webp","datePublished":"2023-10-06T12:19:00+00:00","dateModified":"2023-10-06T12:41:15+00:00","author":{"@id":"https:\/\/smarttrader.community\/de\/#\/schema\/person\/4f791355f3f400fd2dd91d9c57c4c067"},"description":"Investoren mit leichtem Optimismus, aber abwartend vor NFP-Bericht. Wir sehen die US-Indexfutures bei geringem Handelsvolumen und...","breadcrumb":{"@id":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/investoren-mit-leichtem-optimismus-aber-abwartend-vor-nfp-bericht\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/investoren-mit-leichtem-optimismus-aber-abwartend-vor-nfp-bericht\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/investoren-mit-leichtem-optimismus-aber-abwartend-vor-nfp-bericht\/#primaryimage","url":"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/10\/06.10.2023_TITLE_Artboard-1-copy-9.webp","contentUrl":"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/10\/06.10.2023_TITLE_Artboard-1-copy-9.webp","width":1081,"height":721},{"@type":"BreadcrumbList","@id":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/investoren-mit-leichtem-optimismus-aber-abwartend-vor-nfp-bericht\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/smarttrader.community\/de\/"},{"@type":"ListItem","position":2,"name":"Investoren mit leichtem Optimismus, aber abwartend vor NFP-Bericht"}]},{"@type":"WebSite","@id":"https:\/\/smarttrader.community\/de\/#website","url":"https:\/\/smarttrader.community\/de\/","name":"SmartTrader","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/smarttrader.community\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/smarttrader.community\/de\/#\/schema\/person\/4f791355f3f400fd2dd91d9c57c4c067","name":"Robert Lindner","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/05\/robert-lindner_avatar_1-96x96.png","url":"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/05\/robert-lindner_avatar_1-96x96.png","contentUrl":"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/05\/robert-lindner_avatar_1-96x96.png","caption":"Robert Lindner"},"sameAs":["https:\/\/wwww.smarttrader.community\/"],"url":"https:\/\/smarttrader.community\/de\/author\/robert_smarttrader\/"}]}},"_links":{"self":[{"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/posts\/23090","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/users\/663"}],"replies":[{"embeddable":true,"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/comments?post=23090"}],"version-history":[{"count":0,"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/posts\/23090\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/media\/23088"}],"wp:attachment":[{"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/media?parent=23090"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/categories?post=23090"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/tags?post=23090"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}