{"id":23208,"date":"2023-10-10T13:45:58","date_gmt":"2023-10-10T13:45:58","guid":{"rendered":"https:\/\/smarttrader.community\/?p=23208"},"modified":"2023-10-10T13:51:21","modified_gmt":"2023-10-10T13:51:21","slug":"analysten-updates-alphabet-apple-electronic-arts-tesla-usw","status":"publish","type":"post","link":"https:\/\/smarttrader.community\/de\/aktualisierungen-der-analystenbewertungen\/analysten-updates-alphabet-apple-electronic-arts-tesla-usw\/","title":{"rendered":"Analysten-Updates: Alphabet \ud83d\udfe1, Apple \ud83d\udfe1, Electronic Arts\u00a0 \ud83d\udfe2, Tesla \ud83d\udfe1 usw."},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">\ud83d\udcc6 Dienstag, 10. Oktober<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\ud83d\udfe2 <strong>Positive Bewertungen:<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Amazon <\/strong>(AMZN) \ud83c\uddfa\ud83c\uddf8\ud83d\udfe2<br>Analyst:<strong> Wells Fargo<\/strong> stuft die Aktie erneut mit &#8222;OVERWEIGHT&#8220; ein.<br>Kursziel: $165<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Arm Holdings<\/strong> (ARM) \ud83c\uddec\ud83c\udde7\ud83d\udfe2<br>Analyst: <strong>Daiwa<\/strong> stuft die Aktie mit &#8222;BUY&#8220; ein<br>Kursziel: $63<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Block <\/strong>(SQ) \ud83c\uddfa\ud83c\uddf8\ud83d\udfe2<br>Analyst: <strong>Bank of America<\/strong> stuft die Aktie erneut als &#8222;BUY&#8220; ein.<br>Kursziel: $86<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/smarttrader.community\/membership-join\">Subscribe<\/a> to see more<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n","protected":false},"excerpt":{"rendered":"<p>\ud83d\udcc6 Dienstag, 10. Oktober \ud83d\udfe2 Positive Bewertungen: Amazon (AMZN) \ud83c\uddfa\ud83c\uddf8\ud83d\udfe2Analyst: Wells Fargo stuft die Aktie erneut mit &#8222;OVERWEIGHT&#8220; ein.Kursziel: $165&#8230;<\/p>\n","protected":false},"author":1,"featured_media":21079,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","pmpro_default_level":"","_daextam_enable_autolinks":"","footnotes":""},"categories":[174],"tags":[],"class_list":["post-23208","post","type-post","status-publish","format-standard","has-post-thumbnail","category-aktualisierungen-der-analystenbewertungen","pmpro-has-access"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Analysten-Updates: Alphabet \ud83d\udfe1, Apple \ud83d\udfe1, Electronic Arts\u00a0 \ud83d\udfe2, Tesla \ud83d\udfe1 usw. - SmartTrader<\/title>\n<meta name=\"description\" content=\"Analysten-Updates: Alphabet \ud83d\udfe1, Apple \ud83d\udfe1, Electronic Arts\u00a0 \ud83d\udfe2, Tesla \ud83d\udfe1 usw. Amazon (AMZN) \ud83c\uddfa\ud83c\uddf8\ud83d\udfe2Analyst: Wells Fargo stuft die Aktie...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/smarttrader.community\/de\/aktualisierungen-der-analystenbewertungen\/analysten-updates-alphabet-apple-electronic-arts-tesla-usw\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Analysten-Updates: Alphabet \ud83d\udfe1, Apple \ud83d\udfe1, Electronic Arts\u00a0 \ud83d\udfe2, Tesla \ud83d\udfe1 usw. - SmartTrader\" \/>\n<meta property=\"og:description\" content=\"Analysten-Updates: Alphabet \ud83d\udfe1, Apple \ud83d\udfe1, Electronic Arts\u00a0 \ud83d\udfe2, Tesla \ud83d\udfe1 usw. Amazon (AMZN) \ud83c\uddfa\ud83c\uddf8\ud83d\udfe2Analyst: Wells Fargo stuft die Aktie...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/smarttrader.community\/de\/aktualisierungen-der-analystenbewertungen\/analysten-updates-alphabet-apple-electronic-arts-tesla-usw\/\" \/>\n<meta property=\"og:site_name\" content=\"SmartTrader\" \/>\n<meta property=\"article:published_time\" content=\"2023-10-10T13:45:58+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-10-10T13:51:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/08\/images-10.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"SmartTrader Analyst Team\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"SmartTrader Analyst Team\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/aktualisierungen-der-analystenbewertungen\\\/analysten-updates-alphabet-apple-electronic-arts-tesla-usw\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/aktualisierungen-der-analystenbewertungen\\\/analysten-updates-alphabet-apple-electronic-arts-tesla-usw\\\/\"},\"author\":{\"name\":\"SmartTrader Analyst Team\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/#\\\/schema\\\/person\\\/bfe0c456aafbdc04b9707983e59c4e05\"},\"headline\":\"Analysten-Updates: Alphabet \ud83d\udfe1, Apple \ud83d\udfe1, Electronic Arts\u00a0 \ud83d\udfe2, Tesla \ud83d\udfe1 usw.\",\"datePublished\":\"2023-10-10T13:45:58+00:00\",\"dateModified\":\"2023-10-10T13:51:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/aktualisierungen-der-analystenbewertungen\\\/analysten-updates-alphabet-apple-electronic-arts-tesla-usw\\\/\"},\"wordCount\":301,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/aktualisierungen-der-analystenbewertungen\\\/analysten-updates-alphabet-apple-electronic-arts-tesla-usw\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/images-10.jpg\",\"articleSection\":[\"Aktualisierungen der Analystenbewertungen\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/smarttrader.community\\\/de\\\/aktualisierungen-der-analystenbewertungen\\\/analysten-updates-alphabet-apple-electronic-arts-tesla-usw\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/aktualisierungen-der-analystenbewertungen\\\/analysten-updates-alphabet-apple-electronic-arts-tesla-usw\\\/\",\"url\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/aktualisierungen-der-analystenbewertungen\\\/analysten-updates-alphabet-apple-electronic-arts-tesla-usw\\\/\",\"name\":\"Analysten-Updates: Alphabet \ud83d\udfe1, Apple \ud83d\udfe1, Electronic Arts\u00a0 \ud83d\udfe2, Tesla \ud83d\udfe1 usw. - SmartTrader\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/aktualisierungen-der-analystenbewertungen\\\/analysten-updates-alphabet-apple-electronic-arts-tesla-usw\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/aktualisierungen-der-analystenbewertungen\\\/analysten-updates-alphabet-apple-electronic-arts-tesla-usw\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/images-10.jpg\",\"datePublished\":\"2023-10-10T13:45:58+00:00\",\"dateModified\":\"2023-10-10T13:51:21+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/#\\\/schema\\\/person\\\/bfe0c456aafbdc04b9707983e59c4e05\"},\"description\":\"Analysten-Updates: Alphabet \ud83d\udfe1, Apple \ud83d\udfe1, Electronic Arts\u00a0 \ud83d\udfe2, Tesla \ud83d\udfe1 usw. Amazon (AMZN) \ud83c\uddfa\ud83c\uddf8\ud83d\udfe2Analyst: Wells Fargo stuft die Aktie...\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/aktualisierungen-der-analystenbewertungen\\\/analysten-updates-alphabet-apple-electronic-arts-tesla-usw\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/smarttrader.community\\\/de\\\/aktualisierungen-der-analystenbewertungen\\\/analysten-updates-alphabet-apple-electronic-arts-tesla-usw\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/aktualisierungen-der-analystenbewertungen\\\/analysten-updates-alphabet-apple-electronic-arts-tesla-usw\\\/#primaryimage\",\"url\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/images-10.jpg\",\"contentUrl\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/images-10.jpg\",\"width\":800,\"height\":500},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/aktualisierungen-der-analystenbewertungen\\\/analysten-updates-alphabet-apple-electronic-arts-tesla-usw\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Analysten-Updates: Alphabet \ud83d\udfe1, Apple \ud83d\udfe1, Electronic Arts\u00a0 \ud83d\udfe2, Tesla \ud83d\udfe1 usw.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/\",\"name\":\"SmartTrader\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/#\\\/schema\\\/person\\\/bfe0c456aafbdc04b9707983e59c4e05\",\"name\":\"SmartTrader Analyst Team\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/admin_avatar_3-96x96.png\",\"url\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/admin_avatar_3-96x96.png\",\"contentUrl\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/admin_avatar_3-96x96.png\",\"caption\":\"SmartTrader Analyst Team\"},\"sameAs\":[\"https:\\\/\\\/smarttrader.community\"],\"url\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Analysten-Updates: Alphabet \ud83d\udfe1, Apple \ud83d\udfe1, Electronic Arts\u00a0 \ud83d\udfe2, Tesla \ud83d\udfe1 usw. - SmartTrader","description":"Analysten-Updates: Alphabet \ud83d\udfe1, Apple \ud83d\udfe1, Electronic Arts\u00a0 \ud83d\udfe2, Tesla \ud83d\udfe1 usw. Amazon (AMZN) \ud83c\uddfa\ud83c\uddf8\ud83d\udfe2Analyst: Wells Fargo stuft die Aktie...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/smarttrader.community\/de\/aktualisierungen-der-analystenbewertungen\/analysten-updates-alphabet-apple-electronic-arts-tesla-usw\/","og_locale":"de_DE","og_type":"article","og_title":"Analysten-Updates: Alphabet \ud83d\udfe1, Apple \ud83d\udfe1, Electronic Arts\u00a0 \ud83d\udfe2, Tesla \ud83d\udfe1 usw. - SmartTrader","og_description":"Analysten-Updates: Alphabet \ud83d\udfe1, Apple \ud83d\udfe1, Electronic Arts\u00a0 \ud83d\udfe2, Tesla \ud83d\udfe1 usw. Amazon (AMZN) \ud83c\uddfa\ud83c\uddf8\ud83d\udfe2Analyst: Wells Fargo stuft die Aktie...","og_url":"https:\/\/smarttrader.community\/de\/aktualisierungen-der-analystenbewertungen\/analysten-updates-alphabet-apple-electronic-arts-tesla-usw\/","og_site_name":"SmartTrader","article_published_time":"2023-10-10T13:45:58+00:00","article_modified_time":"2023-10-10T13:51:21+00:00","og_image":[{"width":800,"height":500,"url":"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/08\/images-10.jpg","type":"image\/jpeg"}],"author":"SmartTrader Analyst Team","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"SmartTrader Analyst Team","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/smarttrader.community\/de\/aktualisierungen-der-analystenbewertungen\/analysten-updates-alphabet-apple-electronic-arts-tesla-usw\/#article","isPartOf":{"@id":"https:\/\/smarttrader.community\/de\/aktualisierungen-der-analystenbewertungen\/analysten-updates-alphabet-apple-electronic-arts-tesla-usw\/"},"author":{"name":"SmartTrader Analyst Team","@id":"https:\/\/smarttrader.community\/de\/#\/schema\/person\/bfe0c456aafbdc04b9707983e59c4e05"},"headline":"Analysten-Updates: Alphabet \ud83d\udfe1, Apple \ud83d\udfe1, Electronic Arts\u00a0 \ud83d\udfe2, Tesla \ud83d\udfe1 usw.","datePublished":"2023-10-10T13:45:58+00:00","dateModified":"2023-10-10T13:51:21+00:00","mainEntityOfPage":{"@id":"https:\/\/smarttrader.community\/de\/aktualisierungen-der-analystenbewertungen\/analysten-updates-alphabet-apple-electronic-arts-tesla-usw\/"},"wordCount":301,"commentCount":0,"image":{"@id":"https:\/\/smarttrader.community\/de\/aktualisierungen-der-analystenbewertungen\/analysten-updates-alphabet-apple-electronic-arts-tesla-usw\/#primaryimage"},"thumbnailUrl":"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/08\/images-10.jpg","articleSection":["Aktualisierungen der Analystenbewertungen"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/smarttrader.community\/de\/aktualisierungen-der-analystenbewertungen\/analysten-updates-alphabet-apple-electronic-arts-tesla-usw\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/smarttrader.community\/de\/aktualisierungen-der-analystenbewertungen\/analysten-updates-alphabet-apple-electronic-arts-tesla-usw\/","url":"https:\/\/smarttrader.community\/de\/aktualisierungen-der-analystenbewertungen\/analysten-updates-alphabet-apple-electronic-arts-tesla-usw\/","name":"Analysten-Updates: Alphabet \ud83d\udfe1, Apple \ud83d\udfe1, Electronic Arts\u00a0 \ud83d\udfe2, Tesla \ud83d\udfe1 usw. - SmartTrader","isPartOf":{"@id":"https:\/\/smarttrader.community\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/smarttrader.community\/de\/aktualisierungen-der-analystenbewertungen\/analysten-updates-alphabet-apple-electronic-arts-tesla-usw\/#primaryimage"},"image":{"@id":"https:\/\/smarttrader.community\/de\/aktualisierungen-der-analystenbewertungen\/analysten-updates-alphabet-apple-electronic-arts-tesla-usw\/#primaryimage"},"thumbnailUrl":"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/08\/images-10.jpg","datePublished":"2023-10-10T13:45:58+00:00","dateModified":"2023-10-10T13:51:21+00:00","author":{"@id":"https:\/\/smarttrader.community\/de\/#\/schema\/person\/bfe0c456aafbdc04b9707983e59c4e05"},"description":"Analysten-Updates: Alphabet \ud83d\udfe1, Apple \ud83d\udfe1, Electronic Arts\u00a0 \ud83d\udfe2, Tesla \ud83d\udfe1 usw. Amazon (AMZN) \ud83c\uddfa\ud83c\uddf8\ud83d\udfe2Analyst: Wells Fargo stuft die Aktie...","breadcrumb":{"@id":"https:\/\/smarttrader.community\/de\/aktualisierungen-der-analystenbewertungen\/analysten-updates-alphabet-apple-electronic-arts-tesla-usw\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/smarttrader.community\/de\/aktualisierungen-der-analystenbewertungen\/analysten-updates-alphabet-apple-electronic-arts-tesla-usw\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/smarttrader.community\/de\/aktualisierungen-der-analystenbewertungen\/analysten-updates-alphabet-apple-electronic-arts-tesla-usw\/#primaryimage","url":"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/08\/images-10.jpg","contentUrl":"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/08\/images-10.jpg","width":800,"height":500},{"@type":"BreadcrumbList","@id":"https:\/\/smarttrader.community\/de\/aktualisierungen-der-analystenbewertungen\/analysten-updates-alphabet-apple-electronic-arts-tesla-usw\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/smarttrader.community\/de\/"},{"@type":"ListItem","position":2,"name":"Analysten-Updates: Alphabet \ud83d\udfe1, Apple \ud83d\udfe1, Electronic Arts\u00a0 \ud83d\udfe2, Tesla \ud83d\udfe1 usw."}]},{"@type":"WebSite","@id":"https:\/\/smarttrader.community\/de\/#website","url":"https:\/\/smarttrader.community\/de\/","name":"SmartTrader","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/smarttrader.community\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/smarttrader.community\/de\/#\/schema\/person\/bfe0c456aafbdc04b9707983e59c4e05","name":"SmartTrader Analyst Team","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/03\/admin_avatar_3-96x96.png","url":"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/03\/admin_avatar_3-96x96.png","contentUrl":"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/03\/admin_avatar_3-96x96.png","caption":"SmartTrader Analyst Team"},"sameAs":["https:\/\/smarttrader.community"],"url":"https:\/\/smarttrader.community\/de\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/posts\/23208","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/comments?post=23208"}],"version-history":[{"count":0,"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/posts\/23208\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/media\/21079"}],"wp:attachment":[{"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/media?parent=23208"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/categories?post=23208"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/tags?post=23208"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}