{"id":23369,"date":"2023-10-18T13:20:42","date_gmt":"2023-10-18T13:20:42","guid":{"rendered":"https:\/\/smarttrader.community\/?p=23369"},"modified":"2023-10-18T13:28:20","modified_gmt":"2023-10-18T13:28:20","slug":"aktien-unter-druck-oelpreisanstieg-geo-spannungen-mixed-earnings","status":"publish","type":"post","link":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/aktien-unter-druck-oelpreisanstieg-geo-spannungen-mixed-earnings\/","title":{"rendered":"Aktien unter Druck; \u00d6lpreisanstieg, Geo-Spannungen &amp; mixed Earnings"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die <strong>\u00d6lpreise stiegen<\/strong> und die <strong>Aktienkurse fielen<\/strong>, als der <strong>Iran <\/strong>seine <strong>Rhetorik gegen Israel<\/strong> versch\u00e4rfte, nachdem eine<strong> Explosion in einem Krankenhaus im Gazastreifen <\/strong>die diplomatischen Bem\u00fchungen zur Eind\u00e4mmung des Nahostkonflikts erschwerte.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die Kontrakte auf den<strong> S&P 500 <\/strong>und den<strong> Nasdaq 100<\/strong> notieren im vorb\u00f6rslichen US-Handel <strong>mehr als 0,4 % niedriger<\/strong>. Die <strong>Roh\u00f6lpreise stiegen um mehr als 3 %<\/strong>, als der Au\u00dfenminister des Iran, eines wichtigen Exporteurs, ein \u00d6lembargo gegen Israel forderte. Die \u00d6lpreise <strong>k\u00fchlten sich nach dem Preisanstieg um 1% ab<\/strong>. Der <strong>Goldpreis <\/strong>stieg, da Investoren in sicherere Anlagen fl\u00fcchteten, und \u00fcberschritt zum ersten Mal seit mehr als 45 Tagen die Marke von <strong>$1.950.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Inmitten der geopolitischen Bedenken verfolgen die H\u00e4ndler auch die <strong>j\u00fcngsten Unternehmensgewinne.<\/strong> <strong>Morgan Stanley<\/strong> fiel im vorb\u00f6rslichen Handel um ~3,0%, nachdem die Einnahmen aus der Verm\u00f6gensverwaltung im dritten Quartal die Sch\u00e4tzungen verfehlt hatten. Das <strong>rezessionsresistente Unternehmen Procter & Gamble stieg<\/strong> im vorb\u00f6rslichen Handel (derzeit +1,5%), nachdem der organische Umsatz die Erwartungen \u00fcbertraf. In Europa brach <strong>ASML<\/strong>, Europas wertvollstes Technologieunternehmen, um 1,7% ein, nachdem die Auftr\u00e4ge im dritten Quartal eingebrochen waren. Adidas stieg um mehr als 5%, nachdem der Sportartikelhersteller seine Prognosen angehoben hatte. Die insgesamt <strong>gemischten Ergebnisse verst\u00e4rken die Besorgnis \u00fcber sich verschlechternde Umsatzprognosen<\/strong> &#8211; insbesondere vor den wichtigen Gewinnberichten von <strong>Netflix <\/strong>und <strong>Tesla<\/strong>, beides teure Aktien.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">In Asien fiel ein wichtiger Index f\u00fcr chinesische Bautr\u00e4ger auf den <strong>niedrigsten Stand seit 2009<\/strong>, nachdem der in Schwierigkeiten geratene chinesische Bautr\u00e4ger <strong>Country Garden Holdings signalisierte<\/strong>, dass er kurz vor der ersten <strong>Zahlungsunf\u00e4higkeit <\/strong>steht &#8211; <em>was einen <strong>Teufelskreis <\/strong>ausl\u00f6sen w\u00fcrde.<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die <strong>Inflation im Vereinigten K\u00f6nigreich \u00fcbertraf die Prognosen<\/strong> und gab dem <strong>GBP <\/strong>nach der j\u00fcngsten Schw\u00e4che Auftrieb, da sie die Wahrscheinlichkeit einer weiteren Zinserh\u00f6hung durch die <strong>Bank of England wieder erh\u00f6hte<\/strong>. Ich halte die Zuw\u00e4chse beim GBP aber f\u00fcr nur kurzfristig. Die nach wie vor <strong>wackelige Risikostimmung<\/strong> und die starken Anzeichen daf\u00fcr, dass sich die Lage im Nahen Osten trotz des Besuchs von US-Pr\u00e4sident Joe Biden in der Region weiter verschlechtern wird, werden jedoch weiterhin auf die Stimmung an den M\u00e4rkten dr\u00fccken und die <strong>Nachfrage nach sicheren H\u00e4fen<\/strong>, einschlie\u00dflich des <strong>USD <\/strong>und insbesondere Gold, steigen lassen. In Kombination mit den immer wiederkehrenden Bef\u00fcrchtungen, dass die Zinsen l\u00e4nger hoch bleiben werden und die Renditen der US-Staatsanleihen nahe ihrem <strong>16-Jahres-Hoch liegen<\/strong>, sehen wir heute ein <strong>hohes Risiko f\u00fcr weitere Verk\u00e4ufe bei Aktien.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Aufgrund der <strong>sehr hohen Anleiherenditen<\/strong> und der Besorgnis \u00fcber <strong>schwache Gewinnberichte<\/strong> und &#8211;<strong>prognosen <\/strong>von <strong>Tesla <\/strong>und <strong>Netflix <\/strong>werden die <strong>Verluste bei zinssensiblen Aktien und Technologiewerten gr\u00f6\u00dfer sein.<\/strong><\/p>\n\n\n\n<h3 class=\"wp-block-heading\">\ud83d\udc41 ROB'S MARKET OVERVIEW:<\/h3>\n\n\n\n<ol class=\"wp-block-list\" start=\"18\">\n<li><em>Oktober 2023<\/em><\/li>\n<\/ol>\n\n\n\n<p class=\"wp-block-paragraph\">\ud83c\uddfa\ud83c\uddf8 <strong>US-M\u00e4rkte<\/strong> \u2195\ufe0f\/\u2198\ufe0f<br><em>Zyklische Aktien \u2195\ufe0f\/\u2198\ufe0f<br>Tech\/Wachstumsaktien \u2198\ufe0f<br>Finanzaktien \u27a1\ufe0f\/\u2198\ufe0f<br>Defensive Aktien \u27a1\ufe0f<br>Energieaktien \u2197\ufe0f (heute stark \u00fcberdurchschnittlich)<br>Materialaktien \u2198\ufe0f (CN-Immobilienkrise belastet)<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\ud83d\udcb1 <strong>Forex<\/strong><br><em>JPY, CHF, CAD \u27a1\ufe0f\/\u2197\ufe0f<br>USD \u2198\ufe0f\/\u2197\ufe0f (fr\u00fchere Verluste reduziert &#8211; Zugewinne w\u00e4hrend des US-Handels)<br>GBP \u2197\ufe0f\/\u2198\ufe0f (wahrscheinlich nicht in der Lage, Gewinne zu halten &#8211; aufgrund der sich verschlechternden Risikostimmung)<br>AUD, EUR \u27a1\ufe0f\/\u2198\ufe0f<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u2692 <strong>Rohstoffm\u00e4rkte <\/strong>\u2195\ufe0f\/\u2197\ufe0f<br><em>\u00d6lpreise \u2197\ufe0f<br>Erdgaspreise \u2197\ufe0f<br>Metallpreise \u2195\ufe0f\/\u2198\ufe0f<br>Gold \u2197\ufe0f<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u26a1\ufe0f<strong>Kryptow\u00e4hrungen <\/strong><em>\u27a1\ufe0f\/\u2198\ufe0f (da die M\u00e4rkte nerv\u00f6s bleiben; Kryptow\u00e4hrungen bleiben unattraktiv)<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>(*\u2197\ufe0f bullisch, \u2198\ufe0f b\u00e4risch, \u27a1\ufe0f seitw\u00e4rts \/ stabil, \u2195\ufe0f gemischt \/ volatil)<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dein <strong>Robert<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die \u00d6lpreise stiegen und die Aktienkurse fielen, als der Iran seine Rhetorik gegen Israel versch\u00e4rfte, nachdem eine Explosion in einem&#8230;<\/p>\n","protected":false},"author":663,"featured_media":23367,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","pmpro_default_level":"","_daextam_enable_autolinks":"","footnotes":""},"categories":[117],"tags":[],"class_list":["post-23369","post","type-post","status-publish","format-standard","has-post-thumbnail","category-taegliche-aktualisierungen","pmpro-has-access"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Aktien unter Druck; \u00d6lpreisanstieg, Geo-Spannungen &amp; mixed Earnings - SmartTrader<\/title>\n<meta name=\"description\" content=\"Aktien unter Druck; \u00d6lpreisanstieg, Geo-Spannungen &amp; mixed Earnings. Die \u00d6lpreise stiegen und die Aktienkurse fielen, als der Iran seine...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/aktien-unter-druck-oelpreisanstieg-geo-spannungen-mixed-earnings\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Aktien unter Druck; \u00d6lpreisanstieg, Geo-Spannungen &amp; mixed Earnings - SmartTrader\" \/>\n<meta property=\"og:description\" content=\"Aktien unter Druck; \u00d6lpreisanstieg, Geo-Spannungen &amp; mixed Earnings. Die \u00d6lpreise stiegen und die Aktienkurse fielen, als der Iran seine...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/aktien-unter-druck-oelpreisanstieg-geo-spannungen-mixed-earnings\/\" \/>\n<meta property=\"og:site_name\" content=\"SmartTrader\" \/>\n<meta property=\"article:published_time\" content=\"2023-10-18T13:20:42+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-10-18T13:28:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/10\/18.10.2023_TITLE_Artboard-1-copy-9.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1081\" \/>\n\t<meta property=\"og:image:height\" content=\"721\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Robert Lindner\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Robert Lindner\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taegliche-aktualisierungen\\\/aktien-unter-druck-oelpreisanstieg-geo-spannungen-mixed-earnings\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taegliche-aktualisierungen\\\/aktien-unter-druck-oelpreisanstieg-geo-spannungen-mixed-earnings\\\/\"},\"author\":{\"name\":\"Robert Lindner\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/#\\\/schema\\\/person\\\/4f791355f3f400fd2dd91d9c57c4c067\"},\"headline\":\"Aktien unter Druck; \u00d6lpreisanstieg, Geo-Spannungen &amp; mixed Earnings\",\"datePublished\":\"2023-10-18T13:20:42+00:00\",\"dateModified\":\"2023-10-18T13:28:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taegliche-aktualisierungen\\\/aktien-unter-druck-oelpreisanstieg-geo-spannungen-mixed-earnings\\\/\"},\"wordCount\":525,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taegliche-aktualisierungen\\\/aktien-unter-druck-oelpreisanstieg-geo-spannungen-mixed-earnings\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/18.10.2023_TITLE_Artboard-1-copy-9.webp\",\"articleSection\":[\"T\u00e4gliche Aktualisierungen\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/smarttrader.community\\\/de\\\/taegliche-aktualisierungen\\\/aktien-unter-druck-oelpreisanstieg-geo-spannungen-mixed-earnings\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taegliche-aktualisierungen\\\/aktien-unter-druck-oelpreisanstieg-geo-spannungen-mixed-earnings\\\/\",\"url\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taegliche-aktualisierungen\\\/aktien-unter-druck-oelpreisanstieg-geo-spannungen-mixed-earnings\\\/\",\"name\":\"Aktien unter Druck; \u00d6lpreisanstieg, Geo-Spannungen &amp; mixed Earnings - SmartTrader\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taegliche-aktualisierungen\\\/aktien-unter-druck-oelpreisanstieg-geo-spannungen-mixed-earnings\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taegliche-aktualisierungen\\\/aktien-unter-druck-oelpreisanstieg-geo-spannungen-mixed-earnings\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/18.10.2023_TITLE_Artboard-1-copy-9.webp\",\"datePublished\":\"2023-10-18T13:20:42+00:00\",\"dateModified\":\"2023-10-18T13:28:20+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/#\\\/schema\\\/person\\\/4f791355f3f400fd2dd91d9c57c4c067\"},\"description\":\"Aktien unter Druck; \u00d6lpreisanstieg, Geo-Spannungen & mixed Earnings. Die \u00d6lpreise stiegen und die Aktienkurse fielen, als der Iran seine...\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taegliche-aktualisierungen\\\/aktien-unter-druck-oelpreisanstieg-geo-spannungen-mixed-earnings\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/smarttrader.community\\\/de\\\/taegliche-aktualisierungen\\\/aktien-unter-druck-oelpreisanstieg-geo-spannungen-mixed-earnings\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taegliche-aktualisierungen\\\/aktien-unter-druck-oelpreisanstieg-geo-spannungen-mixed-earnings\\\/#primaryimage\",\"url\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/18.10.2023_TITLE_Artboard-1-copy-9.webp\",\"contentUrl\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/18.10.2023_TITLE_Artboard-1-copy-9.webp\",\"width\":1081,\"height\":721},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taegliche-aktualisierungen\\\/aktien-unter-druck-oelpreisanstieg-geo-spannungen-mixed-earnings\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Aktien unter Druck; \u00d6lpreisanstieg, Geo-Spannungen &amp; mixed Earnings\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/\",\"name\":\"SmartTrader\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/#\\\/schema\\\/person\\\/4f791355f3f400fd2dd91d9c57c4c067\",\"name\":\"Robert Lindner\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/robert-lindner_avatar_1-96x96.png\",\"url\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/robert-lindner_avatar_1-96x96.png\",\"contentUrl\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/robert-lindner_avatar_1-96x96.png\",\"caption\":\"Robert Lindner\"},\"sameAs\":[\"https:\\\/\\\/wwww.smarttrader.community\\\/\"],\"url\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/author\\\/robert_smarttrader\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Aktien unter Druck; \u00d6lpreisanstieg, Geo-Spannungen &amp; mixed Earnings - SmartTrader","description":"Aktien unter Druck; \u00d6lpreisanstieg, Geo-Spannungen & mixed Earnings. Die \u00d6lpreise stiegen und die Aktienkurse fielen, als der Iran seine...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/aktien-unter-druck-oelpreisanstieg-geo-spannungen-mixed-earnings\/","og_locale":"de_DE","og_type":"article","og_title":"Aktien unter Druck; \u00d6lpreisanstieg, Geo-Spannungen &amp; mixed Earnings - SmartTrader","og_description":"Aktien unter Druck; \u00d6lpreisanstieg, Geo-Spannungen & mixed Earnings. Die \u00d6lpreise stiegen und die Aktienkurse fielen, als der Iran seine...","og_url":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/aktien-unter-druck-oelpreisanstieg-geo-spannungen-mixed-earnings\/","og_site_name":"SmartTrader","article_published_time":"2023-10-18T13:20:42+00:00","article_modified_time":"2023-10-18T13:28:20+00:00","og_image":[{"width":1081,"height":721,"url":"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/10\/18.10.2023_TITLE_Artboard-1-copy-9.webp","type":"image\/webp"}],"author":"Robert Lindner","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Robert Lindner","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/aktien-unter-druck-oelpreisanstieg-geo-spannungen-mixed-earnings\/#article","isPartOf":{"@id":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/aktien-unter-druck-oelpreisanstieg-geo-spannungen-mixed-earnings\/"},"author":{"name":"Robert Lindner","@id":"https:\/\/smarttrader.community\/de\/#\/schema\/person\/4f791355f3f400fd2dd91d9c57c4c067"},"headline":"Aktien unter Druck; \u00d6lpreisanstieg, Geo-Spannungen &amp; mixed Earnings","datePublished":"2023-10-18T13:20:42+00:00","dateModified":"2023-10-18T13:28:20+00:00","mainEntityOfPage":{"@id":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/aktien-unter-druck-oelpreisanstieg-geo-spannungen-mixed-earnings\/"},"wordCount":525,"commentCount":0,"image":{"@id":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/aktien-unter-druck-oelpreisanstieg-geo-spannungen-mixed-earnings\/#primaryimage"},"thumbnailUrl":"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/10\/18.10.2023_TITLE_Artboard-1-copy-9.webp","articleSection":["T\u00e4gliche Aktualisierungen"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/aktien-unter-druck-oelpreisanstieg-geo-spannungen-mixed-earnings\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/aktien-unter-druck-oelpreisanstieg-geo-spannungen-mixed-earnings\/","url":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/aktien-unter-druck-oelpreisanstieg-geo-spannungen-mixed-earnings\/","name":"Aktien unter Druck; \u00d6lpreisanstieg, Geo-Spannungen &amp; mixed Earnings - SmartTrader","isPartOf":{"@id":"https:\/\/smarttrader.community\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/aktien-unter-druck-oelpreisanstieg-geo-spannungen-mixed-earnings\/#primaryimage"},"image":{"@id":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/aktien-unter-druck-oelpreisanstieg-geo-spannungen-mixed-earnings\/#primaryimage"},"thumbnailUrl":"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/10\/18.10.2023_TITLE_Artboard-1-copy-9.webp","datePublished":"2023-10-18T13:20:42+00:00","dateModified":"2023-10-18T13:28:20+00:00","author":{"@id":"https:\/\/smarttrader.community\/de\/#\/schema\/person\/4f791355f3f400fd2dd91d9c57c4c067"},"description":"Aktien unter Druck; \u00d6lpreisanstieg, Geo-Spannungen & mixed Earnings. Die \u00d6lpreise stiegen und die Aktienkurse fielen, als der Iran seine...","breadcrumb":{"@id":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/aktien-unter-druck-oelpreisanstieg-geo-spannungen-mixed-earnings\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/aktien-unter-druck-oelpreisanstieg-geo-spannungen-mixed-earnings\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/aktien-unter-druck-oelpreisanstieg-geo-spannungen-mixed-earnings\/#primaryimage","url":"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/10\/18.10.2023_TITLE_Artboard-1-copy-9.webp","contentUrl":"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/10\/18.10.2023_TITLE_Artboard-1-copy-9.webp","width":1081,"height":721},{"@type":"BreadcrumbList","@id":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/aktien-unter-druck-oelpreisanstieg-geo-spannungen-mixed-earnings\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/smarttrader.community\/de\/"},{"@type":"ListItem","position":2,"name":"Aktien unter Druck; \u00d6lpreisanstieg, Geo-Spannungen &amp; mixed Earnings"}]},{"@type":"WebSite","@id":"https:\/\/smarttrader.community\/de\/#website","url":"https:\/\/smarttrader.community\/de\/","name":"SmartTrader","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/smarttrader.community\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/smarttrader.community\/de\/#\/schema\/person\/4f791355f3f400fd2dd91d9c57c4c067","name":"Robert Lindner","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/05\/robert-lindner_avatar_1-96x96.png","url":"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/05\/robert-lindner_avatar_1-96x96.png","contentUrl":"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/05\/robert-lindner_avatar_1-96x96.png","caption":"Robert Lindner"},"sameAs":["https:\/\/wwww.smarttrader.community\/"],"url":"https:\/\/smarttrader.community\/de\/author\/robert_smarttrader\/"}]}},"_links":{"self":[{"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/posts\/23369","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/users\/663"}],"replies":[{"embeddable":true,"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/comments?post=23369"}],"version-history":[{"count":0,"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/posts\/23369\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/media\/23367"}],"wp:attachment":[{"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/media?parent=23369"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/categories?post=23369"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/tags?post=23369"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}