{"id":23874,"date":"2023-10-24T13:03:46","date_gmt":"2023-10-24T13:03:46","guid":{"rendered":"https:\/\/smarttrader.community\/?p=23874"},"modified":"2023-10-24T13:09:05","modified_gmt":"2023-10-24T13:09:05","slug":"big-tech-optimismus-stabile-renditen-stuetzen-stimmung-gewinne-im-fokus","status":"publish","type":"post","link":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/big-tech-optimismus-stabile-renditen-stuetzen-stimmung-gewinne-im-fokus\/","title":{"rendered":"Big-Tech-Optimismus &amp; stabile Renditen st\u00fctzen Stimmung; Gewinne im Fokus"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die <strong>Aktien steigen im US Pre-Market-Handel<\/strong>, wobei <strong>Big Tech die Gewinne anf\u00fchrt<\/strong>, da <strong>Microsoft<\/strong>, <strong>Alphabet <\/strong>und die anderen Tech-Giganten voraussichtlich wieder <strong>starke Gewinne <\/strong>melden werden. Die <strong>Staatsanleihen stabilisierten sich<\/strong>, nachdem die 10-j\u00e4hrigen US-Staatsanleihen gestern (erneut) den Widerstand bei 5% erreicht hatten. Der S&P 500 (und der Dow Jones) gaben ihre fr\u00fchen Gewinne von gestern wieder ab und schlossen am Montag erneut niedriger, er\u00f6ffnen aber heute h\u00f6her.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Auch die <strong>europ\u00e4ischen Aktien legten trotz schwacher PMI-Daten zu<\/strong>, da die Wall Street vorb\u00f6rslich zulegte und <strong>Hermes <\/strong>einen starken Gewinnbericht ver\u00f6ffentlichte. Der <strong>EUR beendete jedoch seinen j\u00fcngsten H\u00f6henflug <\/strong>und wird heute niedriger gehandelt. Deutschland, Frankreich und die Eurozone als Ganzes haben weiterhin zu k\u00e4mpfen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die <strong>Renditen zehnj\u00e4hriger Staatsanleihen fielen<\/strong> um bis zu f\u00fcnf Basispunkte auf ein Wochentief von 4,80%, bevor sie sich wieder erholten. Der europ\u00e4ische Stoxx 600-Index stieg leicht an, w\u00e4hrend die US-Futures darauf hindeuteten, dass die Aktien ihre f\u00fcnft\u00e4gige Verlustserie beenden w\u00fcrden. Asien schloss mit Gewinnen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Der <strong>Bitcoin durchbrach vor\u00fcbergehend die Marke von $35.000<\/strong>, was auch den Goldpreis belastete, der trotz anhaltender Nachfrage nach sicheren H\u00e4fen kurzzeitig unter 1.960 $ fiel. Die m\u00f6gliche Genehmigung der ersten US-amerikanischen Bitcoin-ETFs in den kommenden Wochen sch\u00fcrte den Appetit auf Bitcoin.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die Marktstimmung wurde auch durch <strong>den Anstieg chinesischer Aktien leicht aufgehellt <\/strong>&#8211; allerdings nur, weil der Staatsfonds des Landes b\u00f6rsengehandelte Fonds kaufte, um die Preise zu st\u00fctzen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Wir sehen eine <strong>wackelige Stabilisierung auf dem R\u00fccken der gro\u00dfen Tech-Werte <\/strong>(wie so oft in den letzten Jahren\/Monaten), die den Markt und die Stimmung antreiben.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Der franz\u00f6sische Pr\u00e4sident Emmanuel <strong>Macron<\/strong> rief zu einer internationalen Koalition zur Bek\u00e4mpfung der Hamas auf. Der Krieg zwischen Israel und der Hamas steht weiterhin im Mittelpunkt des Interesses. Die j\u00fcngsten Entwicklungen haben die Besorgnis \u00fcber eine Versch\u00e4rfung des Konflikts etwas gemildert, aber es ist <strong>unwahrscheinlich<\/strong>, dass er sich in absehbarer Zeit <strong>deutlich entspannen<\/strong> wird, zumal sich die Lage im Gazastreifen von Tag zu Tag verschlechtert.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ich erwarte, dass der <strong>Optimismus \u00fcber gute Gewinne bei den Big Tech-Unternehmen<\/strong> die Wall Street heute <strong>stabilisieren\/unterst\u00fctzen <\/strong>wird. Da Big Tech im Vorfeld der Unternehmensgewinne steigt, besteht das <strong>Risiko von Gewinnmitnahmen<\/strong> aufgrund der Bef\u00fcrchtung, dass die Gewinne nicht so stark ausfallen werden k\u00f6nnten wie erhofft, bevor die NYSE heute schlie\u00dft.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">\ud83d\udc41 ROB'S MARKET OVERVIEW:<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><em>October 24, 2023<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\ud83c\uddfa\ud83c\uddf8 <strong>US-M\u00e4rkte<\/strong> <em>\u2197\ufe0f\/\u2195\ufe0f (fr\u00fche Gewinne werden vor NYSE-Schluss durch Gewinnmitnahmen getroffen)<br>Zyklische Aktien \u2197\ufe0f\/\u2195\ufe0f<br>Tech\/Wachstumsaktien \u2197\ufe0f\/\u2195\ufe0f<br>Finanzaktien \u2197\ufe0f\/\u27a1\ufe0f<br>Defensive Aktien \u27a1\ufe0f\/\u2197\ufe0f<br>Energieaktien \u27a1\ufe0f\/\u2197\ufe0f (Erholung von j\u00fcngsten \u00fcberm\u00e4\u00dfigen Verk\u00e4ufen)<br>Materialaktien \u2197\ufe0f\/\u27a1\ufe0f<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\ud83d\udcb1 <strong>Forex<\/strong><br><em>USD \u27a1\ufe0f\/\u2197\ufe0f<br>AUD \u27a1\ufe0f\/\u2197\ufe0f (profitiert von verbessertem Risikosentiment, keine CN-Verluste)<br>CAD \u27a1\ufe0f<br>GBP \u2197\ufe0f\/\u27a1\ufe0f (profitiert von starkem Arbeitsmarkt, Aufw\u00e4rtspotential begrenzt)<br>CHF, JPY \u27a1\ufe0f\/\u2198\ufe0f (Gegenwind durch verbessertes Risikosentiment)<br>EUR \u2198\ufe0f (Verluste nach schwachem PMI, j\u00fcngste \u00dcberperformance)<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u2692 <strong>Rohstoffm\u00e4rkte <\/strong>\u2195\ufe0f<br><em>\u00d6lpreise \u2195\ufe0f\/\u2197\ufe0f<br>Erdgaspreise \u2197\ufe0f\/\u27a1\ufe0f<br>Metallpreise \u2195\ufe0f\/\u2197\ufe0f<br>Gold \u2198\ufe0f\/\u27a1\ufe0f (sieht nach j\u00fcngsten Gewinnen einige Gewinnmitnahmen)<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u26a1\ufe0f<strong>Kryptos <\/strong>\u2197\ufe0f <em>(Kryptos verzeichnen Gewinne aufgrund von ETF-Optimismus &#8211; sto\u00dfen vorerst bei 35K $ auf Widerstand)<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>(*\u2197\ufe0f bullisch, \u2198\ufe0f b\u00e4risch, \u27a1\ufe0f seitw\u00e4rts \/ stabil, \u2195\ufe0f gemischt \/ volatil)<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dein <strong>Robert<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die Aktien steigen im US Pre-Market-Handel, wobei Big Tech die Gewinne anf\u00fchrt, da Microsoft, Alphabet und die anderen Tech-Giganten voraussichtlich&#8230;<\/p>\n","protected":false},"author":663,"featured_media":23872,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","pmpro_default_level":"","_daextam_enable_autolinks":"","footnotes":""},"categories":[117],"tags":[],"class_list":["post-23874","post","type-post","status-publish","format-standard","has-post-thumbnail","category-taegliche-aktualisierungen","pmpro-has-access"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Big-Tech-Optimismus &amp; stabile Renditen st\u00fctzen Stimmung; Gewinne im Fokus - SmartTrader<\/title>\n<meta name=\"description\" content=\"Big-Tech-Optimismus &amp; stabile Renditen st\u00fctzen Stimmung; Gewinne im Fokus. Die Aktien steigen im US Pre-Market-Handel, wobei Big Tech die...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/big-tech-optimismus-stabile-renditen-stuetzen-stimmung-gewinne-im-fokus\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Big-Tech-Optimismus &amp; stabile Renditen st\u00fctzen Stimmung; Gewinne im Fokus - SmartTrader\" \/>\n<meta property=\"og:description\" content=\"Big-Tech-Optimismus &amp; stabile Renditen st\u00fctzen Stimmung; Gewinne im Fokus. Die Aktien steigen im US Pre-Market-Handel, wobei Big Tech die...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/big-tech-optimismus-stabile-renditen-stuetzen-stimmung-gewinne-im-fokus\/\" \/>\n<meta property=\"og:site_name\" content=\"SmartTrader\" \/>\n<meta property=\"article:published_time\" content=\"2023-10-24T13:03:46+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-10-24T13:09:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/10\/24.10.2023_TITLE_Artboard-1-copy-9.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1081\" \/>\n\t<meta property=\"og:image:height\" content=\"721\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Robert Lindner\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Robert Lindner\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taegliche-aktualisierungen\\\/big-tech-optimismus-stabile-renditen-stuetzen-stimmung-gewinne-im-fokus\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taegliche-aktualisierungen\\\/big-tech-optimismus-stabile-renditen-stuetzen-stimmung-gewinne-im-fokus\\\/\"},\"author\":{\"name\":\"Robert Lindner\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/#\\\/schema\\\/person\\\/4f791355f3f400fd2dd91d9c57c4c067\"},\"headline\":\"Big-Tech-Optimismus &amp; stabile Renditen st\u00fctzen Stimmung; Gewinne im Fokus\",\"datePublished\":\"2023-10-24T13:03:46+00:00\",\"dateModified\":\"2023-10-24T13:09:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taegliche-aktualisierungen\\\/big-tech-optimismus-stabile-renditen-stuetzen-stimmung-gewinne-im-fokus\\\/\"},\"wordCount\":508,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taegliche-aktualisierungen\\\/big-tech-optimismus-stabile-renditen-stuetzen-stimmung-gewinne-im-fokus\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/24.10.2023_TITLE_Artboard-1-copy-9.webp\",\"articleSection\":[\"T\u00e4gliche Aktualisierungen\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/smarttrader.community\\\/de\\\/taegliche-aktualisierungen\\\/big-tech-optimismus-stabile-renditen-stuetzen-stimmung-gewinne-im-fokus\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taegliche-aktualisierungen\\\/big-tech-optimismus-stabile-renditen-stuetzen-stimmung-gewinne-im-fokus\\\/\",\"url\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taegliche-aktualisierungen\\\/big-tech-optimismus-stabile-renditen-stuetzen-stimmung-gewinne-im-fokus\\\/\",\"name\":\"Big-Tech-Optimismus &amp; stabile Renditen st\u00fctzen Stimmung; Gewinne im Fokus - SmartTrader\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taegliche-aktualisierungen\\\/big-tech-optimismus-stabile-renditen-stuetzen-stimmung-gewinne-im-fokus\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taegliche-aktualisierungen\\\/big-tech-optimismus-stabile-renditen-stuetzen-stimmung-gewinne-im-fokus\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/24.10.2023_TITLE_Artboard-1-copy-9.webp\",\"datePublished\":\"2023-10-24T13:03:46+00:00\",\"dateModified\":\"2023-10-24T13:09:05+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/#\\\/schema\\\/person\\\/4f791355f3f400fd2dd91d9c57c4c067\"},\"description\":\"Big-Tech-Optimismus & stabile Renditen st\u00fctzen Stimmung; Gewinne im Fokus. Die Aktien steigen im US Pre-Market-Handel, wobei Big Tech die...\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taegliche-aktualisierungen\\\/big-tech-optimismus-stabile-renditen-stuetzen-stimmung-gewinne-im-fokus\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/smarttrader.community\\\/de\\\/taegliche-aktualisierungen\\\/big-tech-optimismus-stabile-renditen-stuetzen-stimmung-gewinne-im-fokus\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taegliche-aktualisierungen\\\/big-tech-optimismus-stabile-renditen-stuetzen-stimmung-gewinne-im-fokus\\\/#primaryimage\",\"url\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/24.10.2023_TITLE_Artboard-1-copy-9.webp\",\"contentUrl\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/24.10.2023_TITLE_Artboard-1-copy-9.webp\",\"width\":1081,\"height\":721},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taegliche-aktualisierungen\\\/big-tech-optimismus-stabile-renditen-stuetzen-stimmung-gewinne-im-fokus\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Big-Tech-Optimismus &amp; stabile Renditen st\u00fctzen Stimmung; Gewinne im Fokus\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/\",\"name\":\"SmartTrader\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/#\\\/schema\\\/person\\\/4f791355f3f400fd2dd91d9c57c4c067\",\"name\":\"Robert Lindner\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/robert-lindner_avatar_1-96x96.png\",\"url\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/robert-lindner_avatar_1-96x96.png\",\"contentUrl\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/robert-lindner_avatar_1-96x96.png\",\"caption\":\"Robert Lindner\"},\"sameAs\":[\"https:\\\/\\\/wwww.smarttrader.community\\\/\"],\"url\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/author\\\/robert_smarttrader\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Big-Tech-Optimismus &amp; stabile Renditen st\u00fctzen Stimmung; Gewinne im Fokus - SmartTrader","description":"Big-Tech-Optimismus & stabile Renditen st\u00fctzen Stimmung; Gewinne im Fokus. Die Aktien steigen im US Pre-Market-Handel, wobei Big Tech die...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/big-tech-optimismus-stabile-renditen-stuetzen-stimmung-gewinne-im-fokus\/","og_locale":"de_DE","og_type":"article","og_title":"Big-Tech-Optimismus &amp; stabile Renditen st\u00fctzen Stimmung; Gewinne im Fokus - SmartTrader","og_description":"Big-Tech-Optimismus & stabile Renditen st\u00fctzen Stimmung; Gewinne im Fokus. Die Aktien steigen im US Pre-Market-Handel, wobei Big Tech die...","og_url":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/big-tech-optimismus-stabile-renditen-stuetzen-stimmung-gewinne-im-fokus\/","og_site_name":"SmartTrader","article_published_time":"2023-10-24T13:03:46+00:00","article_modified_time":"2023-10-24T13:09:05+00:00","og_image":[{"width":1081,"height":721,"url":"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/10\/24.10.2023_TITLE_Artboard-1-copy-9.webp","type":"image\/webp"}],"author":"Robert Lindner","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Robert Lindner","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/big-tech-optimismus-stabile-renditen-stuetzen-stimmung-gewinne-im-fokus\/#article","isPartOf":{"@id":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/big-tech-optimismus-stabile-renditen-stuetzen-stimmung-gewinne-im-fokus\/"},"author":{"name":"Robert Lindner","@id":"https:\/\/smarttrader.community\/de\/#\/schema\/person\/4f791355f3f400fd2dd91d9c57c4c067"},"headline":"Big-Tech-Optimismus &amp; stabile Renditen st\u00fctzen Stimmung; Gewinne im Fokus","datePublished":"2023-10-24T13:03:46+00:00","dateModified":"2023-10-24T13:09:05+00:00","mainEntityOfPage":{"@id":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/big-tech-optimismus-stabile-renditen-stuetzen-stimmung-gewinne-im-fokus\/"},"wordCount":508,"commentCount":0,"image":{"@id":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/big-tech-optimismus-stabile-renditen-stuetzen-stimmung-gewinne-im-fokus\/#primaryimage"},"thumbnailUrl":"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/10\/24.10.2023_TITLE_Artboard-1-copy-9.webp","articleSection":["T\u00e4gliche Aktualisierungen"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/big-tech-optimismus-stabile-renditen-stuetzen-stimmung-gewinne-im-fokus\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/big-tech-optimismus-stabile-renditen-stuetzen-stimmung-gewinne-im-fokus\/","url":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/big-tech-optimismus-stabile-renditen-stuetzen-stimmung-gewinne-im-fokus\/","name":"Big-Tech-Optimismus &amp; stabile Renditen st\u00fctzen Stimmung; Gewinne im Fokus - SmartTrader","isPartOf":{"@id":"https:\/\/smarttrader.community\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/big-tech-optimismus-stabile-renditen-stuetzen-stimmung-gewinne-im-fokus\/#primaryimage"},"image":{"@id":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/big-tech-optimismus-stabile-renditen-stuetzen-stimmung-gewinne-im-fokus\/#primaryimage"},"thumbnailUrl":"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/10\/24.10.2023_TITLE_Artboard-1-copy-9.webp","datePublished":"2023-10-24T13:03:46+00:00","dateModified":"2023-10-24T13:09:05+00:00","author":{"@id":"https:\/\/smarttrader.community\/de\/#\/schema\/person\/4f791355f3f400fd2dd91d9c57c4c067"},"description":"Big-Tech-Optimismus & stabile Renditen st\u00fctzen Stimmung; Gewinne im Fokus. Die Aktien steigen im US Pre-Market-Handel, wobei Big Tech die...","breadcrumb":{"@id":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/big-tech-optimismus-stabile-renditen-stuetzen-stimmung-gewinne-im-fokus\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/big-tech-optimismus-stabile-renditen-stuetzen-stimmung-gewinne-im-fokus\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/big-tech-optimismus-stabile-renditen-stuetzen-stimmung-gewinne-im-fokus\/#primaryimage","url":"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/10\/24.10.2023_TITLE_Artboard-1-copy-9.webp","contentUrl":"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/10\/24.10.2023_TITLE_Artboard-1-copy-9.webp","width":1081,"height":721},{"@type":"BreadcrumbList","@id":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/big-tech-optimismus-stabile-renditen-stuetzen-stimmung-gewinne-im-fokus\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/smarttrader.community\/de\/"},{"@type":"ListItem","position":2,"name":"Big-Tech-Optimismus &amp; stabile Renditen st\u00fctzen Stimmung; Gewinne im Fokus"}]},{"@type":"WebSite","@id":"https:\/\/smarttrader.community\/de\/#website","url":"https:\/\/smarttrader.community\/de\/","name":"SmartTrader","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/smarttrader.community\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/smarttrader.community\/de\/#\/schema\/person\/4f791355f3f400fd2dd91d9c57c4c067","name":"Robert Lindner","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/05\/robert-lindner_avatar_1-96x96.png","url":"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/05\/robert-lindner_avatar_1-96x96.png","contentUrl":"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/05\/robert-lindner_avatar_1-96x96.png","caption":"Robert Lindner"},"sameAs":["https:\/\/wwww.smarttrader.community\/"],"url":"https:\/\/smarttrader.community\/de\/author\/robert_smarttrader\/"}]}},"_links":{"self":[{"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/posts\/23874","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/users\/663"}],"replies":[{"embeddable":true,"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/comments?post=23874"}],"version-history":[{"count":0,"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/posts\/23874\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/media\/23872"}],"wp:attachment":[{"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/media?parent=23874"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/categories?post=23874"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/tags?post=23874"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}