{"id":25109,"date":"2023-11-03T10:23:19","date_gmt":"2023-11-03T10:23:19","guid":{"rendered":"https:\/\/smarttrader.community\/?p=25109"},"modified":"2023-11-03T10:26:12","modified_gmt":"2023-11-03T10:26:12","slug":"globale-aktien-vor-wichtigen-us-arbeitsmarktdaten-gemischt-apple-faellt-angesichts-anhaltend-langsamen-umsatzwachstums-anzeichen-fuer-nachlassende-china-verkaeufe","status":"publish","type":"post","link":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/globale-aktien-vor-wichtigen-us-arbeitsmarktdaten-gemischt-apple-faellt-angesichts-anhaltend-langsamen-umsatzwachstums-anzeichen-fuer-nachlassende-china-verkaeufe\/","title":{"rendered":"Globale Aktien vor wichtigen US-Arbeitsmarktdaten gemischt; Apple f\u00e4llt angesichts anhaltend langsamen Umsatzwachstums &amp; Anzeichen f\u00fcr nachlassende China-Verk\u00e4ufe"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u25ba Der Stoxx 600 notiert mit einem leichten Plus von 0,1% sah aber nach einer deutlich positiven Er\u00f6ffnung Gewinnmitnahmen. Die gestrigen Apple-Gewinnzahlen dr\u00fcckten auf die Stimmung und brachten Sorgen \u00fcber ein langsameres Umsatzwachstum und unsichere Verk\u00e4ufe in China zur\u00fcck.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u25ba Beeindruckend war die Leistung von BMW, dessen Umsatz im Jahresvergleich um 3,4 % gestiegen ist, was dem robusten Absatz von Elektrofahrzeugen zu verdanken ist, der die Gewinnmargen erh\u00f6ht hat. Die Aktien von A.P. Moller-Maersk fielen um \u00fcber 7 %, nachdem das Unternehmen einen umfangreichen Stellenabbau angek\u00fcndigt hatte, um die Rentabilit\u00e4t zu erhalten. Gestern hat die Bank of England die Zinss\u00e4tze beibehalten und sich damit an die Haltung der weltweiten Zentralbanken angeglichen. Die Anleger warten auf wichtige US-Arbeitsmarktdaten, die im Laufe des Tages ver\u00f6ffentlicht werden (NFP).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u25ba Die US-Aktienfutures gaben nach, der Nasdaq fiel um 0,35%. Vor allem Apple gab vorb\u00f6rslich um -3,4 % nach, nachdem das Unternehmen gestern seinen Ergebnisbericht ver\u00f6ffentlicht hatte. Apple \u00fcbertraf mit seinen j\u00fcngsten Ergebnissen dank einer starken Leistung in Apple Services die niedrigen Erwartungen geringf\u00fcgig. Die iPhone-Verk\u00e4ufe entsprachen den (niedrigen) Erwartungen und die Mac-Verk\u00e4ufe entt\u00e4uschten. Insgesamt stagniert der Umsatz von Apple und es gibt wachsende Bedenken wegen des nachlassenden Umsatzwachstums in China. Der Ausblick ist vorsichtig mit erwarteten leichten Verlusten, obwohl der robuste Dienstleistungssektor eine vielversprechende langfristige Perspektive im Vergleich zu schneller wachsenden gro\u00dfen Tech-Unternehmen bietet. Die meisten Analysten waren im Vorfeld sehr optimistisch f\u00fcr Apple und wurde entt\u00e4uscht &#8211; unser Chefanalyst Robert Lindner hingegen erwartete ein langsames Umsatzwachstum, unscheinbare iPhone-Verk\u00e4ufe und wachsende Sorgen um China &#8211; Gl\u00fcckwunsch an ihn und die Community &#8211; eine perfekte Vorhersage.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/smarttrader.community\/membership-join\">Subscribe<\/a> to see more<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n","protected":false},"excerpt":{"rendered":"<p>\u25ba Der Stoxx 600 notiert mit einem leichten Plus von 0,1% sah aber nach einer deutlich positiven Er\u00f6ffnung Gewinnmitnahmen. Die&#8230;<\/p>\n","protected":false},"author":1,"featured_media":25112,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","pmpro_default_level":"","_daextam_enable_autolinks":"","footnotes":""},"categories":[172],"tags":[],"class_list":["post-25109","post","type-post","status-publish","format-standard","has-post-thumbnail","category-taglicher-marktuberblick","pmpro-has-access"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Globale Aktien vor wichtigen US-Arbeitsmarktdaten gemischt; Apple f\u00e4llt angesichts anhaltend langsamen Umsatzwachstums &amp; Anzeichen f\u00fcr nachlassende China-Verk\u00e4ufe - SmartTrader<\/title>\n<meta name=\"description\" content=\"Der Stoxx 600 notiert mit einem leichten Plus von 0,1% sah aber nach einer deutlich positiven Er\u00f6ffnung Gewinnmitnahmen. Die gestrigen Apple-Gewinnzahlen dr\u00fcckten auf die Stimmung und brachten Sorgen \u00fcber ein langsameres Umsatzwachstum und unsichere Verk\u00e4ufe in China zur\u00fcck.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/globale-aktien-vor-wichtigen-us-arbeitsmarktdaten-gemischt-apple-faellt-angesichts-anhaltend-langsamen-umsatzwachstums-anzeichen-fuer-nachlassende-china-verkaeufe\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Globale Aktien vor wichtigen US-Arbeitsmarktdaten gemischt; Apple f\u00e4llt angesichts anhaltend langsamen Umsatzwachstums &amp; Anzeichen f\u00fcr nachlassende China-Verk\u00e4ufe - SmartTrader\" \/>\n<meta property=\"og:description\" content=\"Der Stoxx 600 notiert mit einem leichten Plus von 0,1% sah aber nach einer deutlich positiven Er\u00f6ffnung Gewinnmitnahmen. Die gestrigen Apple-Gewinnzahlen dr\u00fcckten auf die Stimmung und brachten Sorgen \u00fcber ein langsameres Umsatzwachstum und unsichere Verk\u00e4ufe in China zur\u00fcck.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/globale-aktien-vor-wichtigen-us-arbeitsmarktdaten-gemischt-apple-faellt-angesichts-anhaltend-langsamen-umsatzwachstums-anzeichen-fuer-nachlassende-china-verkaeufe\/\" \/>\n<meta property=\"og:site_name\" content=\"SmartTrader\" \/>\n<meta property=\"article:published_time\" content=\"2023-11-03T10:23:19+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-03T10:26:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/11\/images-54.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"SmartTrader Analyst Team\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"SmartTrader Analyst Team\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taglicher-marktuberblick\\\/globale-aktien-vor-wichtigen-us-arbeitsmarktdaten-gemischt-apple-faellt-angesichts-anhaltend-langsamen-umsatzwachstums-anzeichen-fuer-nachlassende-china-verkaeufe\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taglicher-marktuberblick\\\/globale-aktien-vor-wichtigen-us-arbeitsmarktdaten-gemischt-apple-faellt-angesichts-anhaltend-langsamen-umsatzwachstums-anzeichen-fuer-nachlassende-china-verkaeufe\\\/\"},\"author\":{\"name\":\"SmartTrader Analyst Team\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/#\\\/schema\\\/person\\\/bfe0c456aafbdc04b9707983e59c4e05\"},\"headline\":\"Globale Aktien vor wichtigen US-Arbeitsmarktdaten gemischt; Apple f\u00e4llt angesichts anhaltend langsamen Umsatzwachstums &amp; Anzeichen f\u00fcr nachlassende China-Verk\u00e4ufe\",\"datePublished\":\"2023-11-03T10:23:19+00:00\",\"dateModified\":\"2023-11-03T10:26:12+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taglicher-marktuberblick\\\/globale-aktien-vor-wichtigen-us-arbeitsmarktdaten-gemischt-apple-faellt-angesichts-anhaltend-langsamen-umsatzwachstums-anzeichen-fuer-nachlassende-china-verkaeufe\\\/\"},\"wordCount\":639,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taglicher-marktuberblick\\\/globale-aktien-vor-wichtigen-us-arbeitsmarktdaten-gemischt-apple-faellt-angesichts-anhaltend-langsamen-umsatzwachstums-anzeichen-fuer-nachlassende-china-verkaeufe\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/images-54.jpg\",\"articleSection\":[\"T\u00e4glicher Markt\u00fcberblick\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/smarttrader.community\\\/de\\\/taglicher-marktuberblick\\\/globale-aktien-vor-wichtigen-us-arbeitsmarktdaten-gemischt-apple-faellt-angesichts-anhaltend-langsamen-umsatzwachstums-anzeichen-fuer-nachlassende-china-verkaeufe\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taglicher-marktuberblick\\\/globale-aktien-vor-wichtigen-us-arbeitsmarktdaten-gemischt-apple-faellt-angesichts-anhaltend-langsamen-umsatzwachstums-anzeichen-fuer-nachlassende-china-verkaeufe\\\/\",\"url\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taglicher-marktuberblick\\\/globale-aktien-vor-wichtigen-us-arbeitsmarktdaten-gemischt-apple-faellt-angesichts-anhaltend-langsamen-umsatzwachstums-anzeichen-fuer-nachlassende-china-verkaeufe\\\/\",\"name\":\"Globale Aktien vor wichtigen US-Arbeitsmarktdaten gemischt; Apple f\u00e4llt angesichts anhaltend langsamen Umsatzwachstums &amp; Anzeichen f\u00fcr nachlassende China-Verk\u00e4ufe - SmartTrader\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taglicher-marktuberblick\\\/globale-aktien-vor-wichtigen-us-arbeitsmarktdaten-gemischt-apple-faellt-angesichts-anhaltend-langsamen-umsatzwachstums-anzeichen-fuer-nachlassende-china-verkaeufe\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taglicher-marktuberblick\\\/globale-aktien-vor-wichtigen-us-arbeitsmarktdaten-gemischt-apple-faellt-angesichts-anhaltend-langsamen-umsatzwachstums-anzeichen-fuer-nachlassende-china-verkaeufe\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/images-54.jpg\",\"datePublished\":\"2023-11-03T10:23:19+00:00\",\"dateModified\":\"2023-11-03T10:26:12+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/#\\\/schema\\\/person\\\/bfe0c456aafbdc04b9707983e59c4e05\"},\"description\":\"Der Stoxx 600 notiert mit einem leichten Plus von 0,1% sah aber nach einer deutlich positiven Er\u00f6ffnung Gewinnmitnahmen. Die gestrigen Apple-Gewinnzahlen dr\u00fcckten auf die Stimmung und brachten Sorgen \u00fcber ein langsameres Umsatzwachstum und unsichere Verk\u00e4ufe in China zur\u00fcck.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taglicher-marktuberblick\\\/globale-aktien-vor-wichtigen-us-arbeitsmarktdaten-gemischt-apple-faellt-angesichts-anhaltend-langsamen-umsatzwachstums-anzeichen-fuer-nachlassende-china-verkaeufe\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/smarttrader.community\\\/de\\\/taglicher-marktuberblick\\\/globale-aktien-vor-wichtigen-us-arbeitsmarktdaten-gemischt-apple-faellt-angesichts-anhaltend-langsamen-umsatzwachstums-anzeichen-fuer-nachlassende-china-verkaeufe\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taglicher-marktuberblick\\\/globale-aktien-vor-wichtigen-us-arbeitsmarktdaten-gemischt-apple-faellt-angesichts-anhaltend-langsamen-umsatzwachstums-anzeichen-fuer-nachlassende-china-verkaeufe\\\/#primaryimage\",\"url\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/images-54.jpg\",\"contentUrl\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/images-54.jpg\",\"width\":800,\"height\":500},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taglicher-marktuberblick\\\/globale-aktien-vor-wichtigen-us-arbeitsmarktdaten-gemischt-apple-faellt-angesichts-anhaltend-langsamen-umsatzwachstums-anzeichen-fuer-nachlassende-china-verkaeufe\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Globale Aktien vor wichtigen US-Arbeitsmarktdaten gemischt; Apple f\u00e4llt angesichts anhaltend langsamen Umsatzwachstums &amp; Anzeichen f\u00fcr nachlassende China-Verk\u00e4ufe\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/\",\"name\":\"SmartTrader\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/#\\\/schema\\\/person\\\/bfe0c456aafbdc04b9707983e59c4e05\",\"name\":\"SmartTrader Analyst Team\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/admin_avatar_3-96x96.png\",\"url\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/admin_avatar_3-96x96.png\",\"contentUrl\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/admin_avatar_3-96x96.png\",\"caption\":\"SmartTrader Analyst Team\"},\"sameAs\":[\"https:\\\/\\\/smarttrader.community\"],\"url\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Globale Aktien vor wichtigen US-Arbeitsmarktdaten gemischt; Apple f\u00e4llt angesichts anhaltend langsamen Umsatzwachstums &amp; Anzeichen f\u00fcr nachlassende China-Verk\u00e4ufe - SmartTrader","description":"Der Stoxx 600 notiert mit einem leichten Plus von 0,1% sah aber nach einer deutlich positiven Er\u00f6ffnung Gewinnmitnahmen. Die gestrigen Apple-Gewinnzahlen dr\u00fcckten auf die Stimmung und brachten Sorgen \u00fcber ein langsameres Umsatzwachstum und unsichere Verk\u00e4ufe in China zur\u00fcck.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/globale-aktien-vor-wichtigen-us-arbeitsmarktdaten-gemischt-apple-faellt-angesichts-anhaltend-langsamen-umsatzwachstums-anzeichen-fuer-nachlassende-china-verkaeufe\/","og_locale":"de_DE","og_type":"article","og_title":"Globale Aktien vor wichtigen US-Arbeitsmarktdaten gemischt; Apple f\u00e4llt angesichts anhaltend langsamen Umsatzwachstums &amp; Anzeichen f\u00fcr nachlassende China-Verk\u00e4ufe - SmartTrader","og_description":"Der Stoxx 600 notiert mit einem leichten Plus von 0,1% sah aber nach einer deutlich positiven Er\u00f6ffnung Gewinnmitnahmen. Die gestrigen Apple-Gewinnzahlen dr\u00fcckten auf die Stimmung und brachten Sorgen \u00fcber ein langsameres Umsatzwachstum und unsichere Verk\u00e4ufe in China zur\u00fcck.","og_url":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/globale-aktien-vor-wichtigen-us-arbeitsmarktdaten-gemischt-apple-faellt-angesichts-anhaltend-langsamen-umsatzwachstums-anzeichen-fuer-nachlassende-china-verkaeufe\/","og_site_name":"SmartTrader","article_published_time":"2023-11-03T10:23:19+00:00","article_modified_time":"2023-11-03T10:26:12+00:00","og_image":[{"width":800,"height":500,"url":"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/11\/images-54.jpg","type":"image\/jpeg"}],"author":"SmartTrader Analyst Team","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"SmartTrader Analyst Team","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/globale-aktien-vor-wichtigen-us-arbeitsmarktdaten-gemischt-apple-faellt-angesichts-anhaltend-langsamen-umsatzwachstums-anzeichen-fuer-nachlassende-china-verkaeufe\/#article","isPartOf":{"@id":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/globale-aktien-vor-wichtigen-us-arbeitsmarktdaten-gemischt-apple-faellt-angesichts-anhaltend-langsamen-umsatzwachstums-anzeichen-fuer-nachlassende-china-verkaeufe\/"},"author":{"name":"SmartTrader Analyst Team","@id":"https:\/\/smarttrader.community\/de\/#\/schema\/person\/bfe0c456aafbdc04b9707983e59c4e05"},"headline":"Globale Aktien vor wichtigen US-Arbeitsmarktdaten gemischt; Apple f\u00e4llt angesichts anhaltend langsamen Umsatzwachstums &amp; Anzeichen f\u00fcr nachlassende China-Verk\u00e4ufe","datePublished":"2023-11-03T10:23:19+00:00","dateModified":"2023-11-03T10:26:12+00:00","mainEntityOfPage":{"@id":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/globale-aktien-vor-wichtigen-us-arbeitsmarktdaten-gemischt-apple-faellt-angesichts-anhaltend-langsamen-umsatzwachstums-anzeichen-fuer-nachlassende-china-verkaeufe\/"},"wordCount":639,"commentCount":0,"image":{"@id":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/globale-aktien-vor-wichtigen-us-arbeitsmarktdaten-gemischt-apple-faellt-angesichts-anhaltend-langsamen-umsatzwachstums-anzeichen-fuer-nachlassende-china-verkaeufe\/#primaryimage"},"thumbnailUrl":"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/11\/images-54.jpg","articleSection":["T\u00e4glicher Markt\u00fcberblick"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/globale-aktien-vor-wichtigen-us-arbeitsmarktdaten-gemischt-apple-faellt-angesichts-anhaltend-langsamen-umsatzwachstums-anzeichen-fuer-nachlassende-china-verkaeufe\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/globale-aktien-vor-wichtigen-us-arbeitsmarktdaten-gemischt-apple-faellt-angesichts-anhaltend-langsamen-umsatzwachstums-anzeichen-fuer-nachlassende-china-verkaeufe\/","url":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/globale-aktien-vor-wichtigen-us-arbeitsmarktdaten-gemischt-apple-faellt-angesichts-anhaltend-langsamen-umsatzwachstums-anzeichen-fuer-nachlassende-china-verkaeufe\/","name":"Globale Aktien vor wichtigen US-Arbeitsmarktdaten gemischt; Apple f\u00e4llt angesichts anhaltend langsamen Umsatzwachstums &amp; Anzeichen f\u00fcr nachlassende China-Verk\u00e4ufe - SmartTrader","isPartOf":{"@id":"https:\/\/smarttrader.community\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/globale-aktien-vor-wichtigen-us-arbeitsmarktdaten-gemischt-apple-faellt-angesichts-anhaltend-langsamen-umsatzwachstums-anzeichen-fuer-nachlassende-china-verkaeufe\/#primaryimage"},"image":{"@id":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/globale-aktien-vor-wichtigen-us-arbeitsmarktdaten-gemischt-apple-faellt-angesichts-anhaltend-langsamen-umsatzwachstums-anzeichen-fuer-nachlassende-china-verkaeufe\/#primaryimage"},"thumbnailUrl":"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/11\/images-54.jpg","datePublished":"2023-11-03T10:23:19+00:00","dateModified":"2023-11-03T10:26:12+00:00","author":{"@id":"https:\/\/smarttrader.community\/de\/#\/schema\/person\/bfe0c456aafbdc04b9707983e59c4e05"},"description":"Der Stoxx 600 notiert mit einem leichten Plus von 0,1% sah aber nach einer deutlich positiven Er\u00f6ffnung Gewinnmitnahmen. Die gestrigen Apple-Gewinnzahlen dr\u00fcckten auf die Stimmung und brachten Sorgen \u00fcber ein langsameres Umsatzwachstum und unsichere Verk\u00e4ufe in China zur\u00fcck.","breadcrumb":{"@id":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/globale-aktien-vor-wichtigen-us-arbeitsmarktdaten-gemischt-apple-faellt-angesichts-anhaltend-langsamen-umsatzwachstums-anzeichen-fuer-nachlassende-china-verkaeufe\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/globale-aktien-vor-wichtigen-us-arbeitsmarktdaten-gemischt-apple-faellt-angesichts-anhaltend-langsamen-umsatzwachstums-anzeichen-fuer-nachlassende-china-verkaeufe\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/globale-aktien-vor-wichtigen-us-arbeitsmarktdaten-gemischt-apple-faellt-angesichts-anhaltend-langsamen-umsatzwachstums-anzeichen-fuer-nachlassende-china-verkaeufe\/#primaryimage","url":"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/11\/images-54.jpg","contentUrl":"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/11\/images-54.jpg","width":800,"height":500},{"@type":"BreadcrumbList","@id":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/globale-aktien-vor-wichtigen-us-arbeitsmarktdaten-gemischt-apple-faellt-angesichts-anhaltend-langsamen-umsatzwachstums-anzeichen-fuer-nachlassende-china-verkaeufe\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/smarttrader.community\/de\/"},{"@type":"ListItem","position":2,"name":"Globale Aktien vor wichtigen US-Arbeitsmarktdaten gemischt; Apple f\u00e4llt angesichts anhaltend langsamen Umsatzwachstums &amp; Anzeichen f\u00fcr nachlassende China-Verk\u00e4ufe"}]},{"@type":"WebSite","@id":"https:\/\/smarttrader.community\/de\/#website","url":"https:\/\/smarttrader.community\/de\/","name":"SmartTrader","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/smarttrader.community\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/smarttrader.community\/de\/#\/schema\/person\/bfe0c456aafbdc04b9707983e59c4e05","name":"SmartTrader Analyst Team","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/03\/admin_avatar_3-96x96.png","url":"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/03\/admin_avatar_3-96x96.png","contentUrl":"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/03\/admin_avatar_3-96x96.png","caption":"SmartTrader Analyst Team"},"sameAs":["https:\/\/smarttrader.community"],"url":"https:\/\/smarttrader.community\/de\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/posts\/25109","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/comments?post=25109"}],"version-history":[{"count":0,"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/posts\/25109\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/media\/25112"}],"wp:attachment":[{"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/media?parent=25109"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/categories?post=25109"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/tags?post=25109"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}