{"id":27818,"date":"2023-11-16T14:16:29","date_gmt":"2023-11-16T14:16:29","guid":{"rendered":"https:\/\/smarttrader.community\/?p=27818"},"modified":"2023-11-16T14:24:12","modified_gmt":"2023-11-16T14:24:12","slug":"schwache-ergebnisberichte-wiegen-auf-stimmung-renditen-fallen-wieder","status":"publish","type":"post","link":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/schwache-ergebnisberichte-wiegen-auf-stimmung-renditen-fallen-wieder\/","title":{"rendered":"Schwache Ergebnisberichte wiegen auf Stimmung; Renditen fallen wieder"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Die Euphorie \u00fcber die stark abk\u00fchlende Inflation<\/strong> und eine m\u00f6gliche <strong>Lockerung der Zentralbank l\u00e4sst nach<\/strong> und die Aktien in Europa und Asien stehen unter Druck, da eine Reihe von Unternehmen <strong>entt\u00e4uschende Ergebnisberichte<\/strong> vorgelegt und <strong>vorsichtige Prognosen<\/strong> abgegeben haben.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">An der Wall Street gibt es vorb\u00f6rslich kaum Ver\u00e4nderungen. Der <strong>S&P 500 notiert etwa 0,1%<\/strong> niedriger als gestern. <strong>Alibaba <\/strong>wird in New York deutlich niedriger gehandelt, im Gegensatz zu seinem chinesischen Konkurrenten <strong>JD, <\/strong>der gestern nach einem optimistischen Gewinnbericht stark gestiegen ist. Der Einzelhandelsriese <strong>Walmart fiel ebenfalls um 3,6 %,<\/strong> nachdem er seine Gewinnprognose leicht angehoben hatte, sich aber vorsichtig \u00fcber die Aussichten f\u00fcr die US-Konsumenten \u00e4u\u00dferte &#8211; im Gegensatz zu <strong>Target<\/strong>, das gestern um mehr als 15 % zulegte, nachdem es einen viel besser als erwarteten Gewinnbericht vorgelegt hatte. Das Einzelhandelsunternehmen <strong>Macy's<\/strong> verzeichnete heute ebenfalls einen deutlichen Kursanstieg und legte im vorb\u00f6rslichen Handel aufgrund h\u00f6herer Gewinne um 13% zu. Die Luxusmarke Burberry gab um mehr als 9% nach, nachdem das Unternehmen mitgeteilt hatte, dass es seine Umsatzprognose aufgrund einer schw\u00e4cheren Nachfrage nach hochwertigen Waren nicht erf\u00fcllen kann. Luxusunternehmen haben gemischte Ergebnisse gemeldet. Der deutsche Anbieter von Mahlzeitenpaketen, <strong>HelloFresh<\/strong>, senkte seine Umsatzerwartungen um 18% &#8211; die Aktie st\u00fcrzte um fast 25% (!) ab.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Vor allem die <strong>Gewinnberichte der europ\u00e4ischen Unternehmen sind eher negativ<\/strong> und die Aussichten sind ged\u00e4mpft, was zeigt, dass die Konjunkturabschw\u00e4chung in Europa und beim europ\u00e4ischen\/asiatischen Verbraucher bereits weiter <strong>fortgeschritten <\/strong>ist. Die <strong>allgemeine Verlangsamung der Volkswirtschaften<\/strong>, einschlie\u00dflich der US-Wirtschaft, bleibt die <strong>gr\u00f6\u00dfte Bedrohung f\u00fcr die aktuelle Rallye<\/strong>. Die Bewertungen sind zu hoch und werden sinken m\u00fcssen, sobald die Jahresendrallye und der Zinssenkungsoptimismus nachlassen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die M\u00e4rkte werden jetzt auch realistischer, was <strong>Zinssenkungen <\/strong>angeht. Die Investoren sind immer noch \u00fcberm\u00e4\u00dfig optimistisch und erwarten schnelle Zinssenkungen im Jahr 2024. Der <strong>US-Verbraucher ist nach wie vor stark<\/strong>, was wahrscheinlich dazu f\u00fchren wird, dass die <strong>Fed ihren insgesamt hawkishen Ton beibeh\u00e4lt<\/strong>. Mehrere Fed-Beamte werden heute Reden halten.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ich gehe davon aus, dass die <strong>Phase geringer Volatilit\u00e4t<\/strong> mit einem eher d\u00fcnnen Wirtschaftskalender heute weitergeht. Angesichts der <strong>Erstantr\u00e4ge auf Arbeitslosenunterst\u00fctzung<\/strong>, die auf eine weitere <strong>Entspannung am Arbeitsmarkt<\/strong> hindeuten, gehe ich jedoch davon aus, dass die meisten Investoren weiterhin erstmal optimistisch sind, dass die Fed mit der aktuellen Entwicklung der Wirtschaftsdaten zufrieden ist, die auf eine moderate Verlangsamung, eine Lockerung der angespannten Arbeitsmarktlage und vor allem auf eine <strong>Fortsetzung der Disinflation<\/strong> hinweisen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Wir sehen die <strong>Renditen wieder sinken<\/strong>. Die recht <strong>positiven Gespr\u00e4che zwischen US-Pr\u00e4sident Biden und seinem chinesischen Amtskollegen Xi Jinping<\/strong> deuten ebenfalls auf eine vorsichtige Verbesserung der Beziehungen hin.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Wir gehen davon aus, dass Gold von dem erneuten <strong>R\u00fcckgang der Renditen profitiert.<\/strong> Die schwachen chinesischen Immobilienpreise <strong>belasten Rohstoffe<\/strong> wie Industriemetalle, aber ich erwarte, dass die Marktstimmung insgesamt positiv bleibt. Die <strong>\u00d6lpreise sind weiterhin \u00fcberverkauft<\/strong> und haben wenig Spielraum, um weiter zu fallen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Auch der <strong>USD ist \u00fcberverkauft<\/strong>. W\u00e4hrend die mittel- bis langfristigen Aussichten f\u00fcr den USD r\u00fcckl\u00e4ufig sind, gibt es kurzfristig vielleicht nicht genug Gr\u00fcnde f\u00fcr einen ausgedehnten USD-Verkauf.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">\ud83d\udc41 ROB'S MARKET OVERVIEW:<\/h3>\n\n\n\n<ol class=\"wp-block-list\" start=\"16\">\n<li><em>November 2023<\/em><\/li>\n<\/ol>\n\n\n\n<p class=\"wp-block-paragraph\">\ud83c\uddfa\ud83c\uddf8 <strong>US-M\u00e4rkte<\/strong> <em>\u2198\ufe0f\/\u27a1\ufe0f\/\u2197\ufe0f (schwache Gewinnberichte belasten zun\u00e4chst; nachlassende US-Arbeitsmarktdaten k\u00f6nnten Optimismus f\u00fcr Zinssenkungen wiederbeleben)<br>Zyklische Aktien \u2198\ufe0f\/\u27a1\ufe0f\/\u2197\ufe0f<br>Technologie-\/Wachstumsaktien \u2198\ufe0f\/\u27a1\ufe0f\/\u2197\ufe0f<br>Finanzaktien \u27a1\ufe0f\/\u2197\ufe0f<br>Defensive Aktien \u27a1\ufe0f\/\u2197\ufe0f<br>Energieaktien \u2198\ufe0f\/\u27a1\ufe0f<br>Rohstoffaktien \u2198\ufe0f\/\u27a1\ufe0f<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\ud83d\udcb1 <strong>Forex<\/strong><br><em>USD \u27a1\ufe0f\/\u2197\ufe0f (gr\u00f6\u00dftenteils seitw\u00e4rts &#8211; mit etwas Erholungspotenzial nach \u00dcberverkauf)<br>EUR, JPY \u27a1\ufe0f\/\u2197\ufe0f<br>CHF \u27a1\ufe0f<br>GBP, AUD, CAD \u27a1\ufe0f\/\u2198\ufe0f<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u2692 <strong>Rohstoffm\u00e4rkte <\/strong>\u2195\ufe0f<br><em>\u00d6lpreise \u2198\ufe0f\/\u27a1\ufe0f\/\u2197\ufe0f<br>Erdgaspreise \u27a1\ufe0f<br>Metallpreise \u2198\ufe0f\/\u27a1\ufe0f<br>Gold \u27a1\ufe0f\/\u2197\ufe0f (Ich erwarte, dass die Renditen nach schw\u00e4cheren Arbeitsmarktdaten wieder leicht sinken)<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u26a1\ufe0f<strong>Kryptos <\/strong><em>\u27a1\ufe0f (BTC pendelt nahe bei $36K &#8211; $37K)<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>(*\u2197\ufe0f bullisch, \u2198\ufe0f b\u00e4risch, \u27a1\ufe0f seitw\u00e4rts \/ stabil, \u2195\ufe0f gemischt \/ volatil)<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dein <strong>Robert<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die Euphorie \u00fcber die stark abk\u00fchlende Inflation und eine m\u00f6gliche Lockerung der Zentralbank l\u00e4sst nach und die Aktien in Europa&#8230;<\/p>\n","protected":false},"author":663,"featured_media":27815,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","pmpro_default_level":"","_daextam_enable_autolinks":"","footnotes":""},"categories":[117],"tags":[],"class_list":["post-27818","post","type-post","status-publish","format-standard","has-post-thumbnail","category-taegliche-aktualisierungen","pmpro-has-access"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Schwache Ergebnisberichte wiegen auf Stimmung; Renditen fallen wieder - SmartTrader<\/title>\n<meta name=\"description\" content=\"Schwache Ergebnisberichte wiegen auf Stimmung; Renditen fallen wieder. Die Euphorie \u00fcber die stark abk\u00fchlende Inflation und eine m\u00f6gliche...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/schwache-ergebnisberichte-wiegen-auf-stimmung-renditen-fallen-wieder\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Schwache Ergebnisberichte wiegen auf Stimmung; Renditen fallen wieder - SmartTrader\" \/>\n<meta property=\"og:description\" content=\"Schwache Ergebnisberichte wiegen auf Stimmung; Renditen fallen wieder. Die Euphorie \u00fcber die stark abk\u00fchlende Inflation und eine m\u00f6gliche...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/schwache-ergebnisberichte-wiegen-auf-stimmung-renditen-fallen-wieder\/\" \/>\n<meta property=\"og:site_name\" content=\"SmartTrader\" \/>\n<meta property=\"article:published_time\" content=\"2023-11-16T14:16:29+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-16T14:24:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/11\/16.11.2023_TITLE_Artboard-1-copy-9.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1081\" \/>\n\t<meta property=\"og:image:height\" content=\"721\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Robert Lindner\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Robert Lindner\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taegliche-aktualisierungen\\\/schwache-ergebnisberichte-wiegen-auf-stimmung-renditen-fallen-wieder\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taegliche-aktualisierungen\\\/schwache-ergebnisberichte-wiegen-auf-stimmung-renditen-fallen-wieder\\\/\"},\"author\":{\"name\":\"Robert Lindner\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/#\\\/schema\\\/person\\\/4f791355f3f400fd2dd91d9c57c4c067\"},\"headline\":\"Schwache Ergebnisberichte wiegen auf Stimmung; Renditen fallen wieder\",\"datePublished\":\"2023-11-16T14:16:29+00:00\",\"dateModified\":\"2023-11-16T14:24:12+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taegliche-aktualisierungen\\\/schwache-ergebnisberichte-wiegen-auf-stimmung-renditen-fallen-wieder\\\/\"},\"wordCount\":604,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taegliche-aktualisierungen\\\/schwache-ergebnisberichte-wiegen-auf-stimmung-renditen-fallen-wieder\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/16.11.2023_TITLE_Artboard-1-copy-9.webp\",\"articleSection\":[\"T\u00e4gliche Aktualisierungen\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/smarttrader.community\\\/de\\\/taegliche-aktualisierungen\\\/schwache-ergebnisberichte-wiegen-auf-stimmung-renditen-fallen-wieder\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taegliche-aktualisierungen\\\/schwache-ergebnisberichte-wiegen-auf-stimmung-renditen-fallen-wieder\\\/\",\"url\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taegliche-aktualisierungen\\\/schwache-ergebnisberichte-wiegen-auf-stimmung-renditen-fallen-wieder\\\/\",\"name\":\"Schwache Ergebnisberichte wiegen auf Stimmung; Renditen fallen wieder - SmartTrader\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taegliche-aktualisierungen\\\/schwache-ergebnisberichte-wiegen-auf-stimmung-renditen-fallen-wieder\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taegliche-aktualisierungen\\\/schwache-ergebnisberichte-wiegen-auf-stimmung-renditen-fallen-wieder\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/16.11.2023_TITLE_Artboard-1-copy-9.webp\",\"datePublished\":\"2023-11-16T14:16:29+00:00\",\"dateModified\":\"2023-11-16T14:24:12+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/#\\\/schema\\\/person\\\/4f791355f3f400fd2dd91d9c57c4c067\"},\"description\":\"Schwache Ergebnisberichte wiegen auf Stimmung; Renditen fallen wieder. Die Euphorie \u00fcber die stark abk\u00fchlende Inflation und eine m\u00f6gliche...\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taegliche-aktualisierungen\\\/schwache-ergebnisberichte-wiegen-auf-stimmung-renditen-fallen-wieder\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/smarttrader.community\\\/de\\\/taegliche-aktualisierungen\\\/schwache-ergebnisberichte-wiegen-auf-stimmung-renditen-fallen-wieder\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taegliche-aktualisierungen\\\/schwache-ergebnisberichte-wiegen-auf-stimmung-renditen-fallen-wieder\\\/#primaryimage\",\"url\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/16.11.2023_TITLE_Artboard-1-copy-9.webp\",\"contentUrl\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/16.11.2023_TITLE_Artboard-1-copy-9.webp\",\"width\":1081,\"height\":721},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taegliche-aktualisierungen\\\/schwache-ergebnisberichte-wiegen-auf-stimmung-renditen-fallen-wieder\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Schwache Ergebnisberichte wiegen auf Stimmung; Renditen fallen wieder\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/\",\"name\":\"SmartTrader\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/#\\\/schema\\\/person\\\/4f791355f3f400fd2dd91d9c57c4c067\",\"name\":\"Robert Lindner\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/robert-lindner_avatar_1-96x96.png\",\"url\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/robert-lindner_avatar_1-96x96.png\",\"contentUrl\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/robert-lindner_avatar_1-96x96.png\",\"caption\":\"Robert Lindner\"},\"sameAs\":[\"https:\\\/\\\/wwww.smarttrader.community\\\/\"],\"url\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/author\\\/robert_smarttrader\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Schwache Ergebnisberichte wiegen auf Stimmung; Renditen fallen wieder - SmartTrader","description":"Schwache Ergebnisberichte wiegen auf Stimmung; Renditen fallen wieder. Die Euphorie \u00fcber die stark abk\u00fchlende Inflation und eine m\u00f6gliche...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/schwache-ergebnisberichte-wiegen-auf-stimmung-renditen-fallen-wieder\/","og_locale":"de_DE","og_type":"article","og_title":"Schwache Ergebnisberichte wiegen auf Stimmung; Renditen fallen wieder - SmartTrader","og_description":"Schwache Ergebnisberichte wiegen auf Stimmung; Renditen fallen wieder. Die Euphorie \u00fcber die stark abk\u00fchlende Inflation und eine m\u00f6gliche...","og_url":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/schwache-ergebnisberichte-wiegen-auf-stimmung-renditen-fallen-wieder\/","og_site_name":"SmartTrader","article_published_time":"2023-11-16T14:16:29+00:00","article_modified_time":"2023-11-16T14:24:12+00:00","og_image":[{"width":1081,"height":721,"url":"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/11\/16.11.2023_TITLE_Artboard-1-copy-9.webp","type":"image\/webp"}],"author":"Robert Lindner","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Robert Lindner","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/schwache-ergebnisberichte-wiegen-auf-stimmung-renditen-fallen-wieder\/#article","isPartOf":{"@id":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/schwache-ergebnisberichte-wiegen-auf-stimmung-renditen-fallen-wieder\/"},"author":{"name":"Robert Lindner","@id":"https:\/\/smarttrader.community\/de\/#\/schema\/person\/4f791355f3f400fd2dd91d9c57c4c067"},"headline":"Schwache Ergebnisberichte wiegen auf Stimmung; Renditen fallen wieder","datePublished":"2023-11-16T14:16:29+00:00","dateModified":"2023-11-16T14:24:12+00:00","mainEntityOfPage":{"@id":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/schwache-ergebnisberichte-wiegen-auf-stimmung-renditen-fallen-wieder\/"},"wordCount":604,"commentCount":0,"image":{"@id":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/schwache-ergebnisberichte-wiegen-auf-stimmung-renditen-fallen-wieder\/#primaryimage"},"thumbnailUrl":"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/11\/16.11.2023_TITLE_Artboard-1-copy-9.webp","articleSection":["T\u00e4gliche Aktualisierungen"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/schwache-ergebnisberichte-wiegen-auf-stimmung-renditen-fallen-wieder\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/schwache-ergebnisberichte-wiegen-auf-stimmung-renditen-fallen-wieder\/","url":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/schwache-ergebnisberichte-wiegen-auf-stimmung-renditen-fallen-wieder\/","name":"Schwache Ergebnisberichte wiegen auf Stimmung; Renditen fallen wieder - SmartTrader","isPartOf":{"@id":"https:\/\/smarttrader.community\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/schwache-ergebnisberichte-wiegen-auf-stimmung-renditen-fallen-wieder\/#primaryimage"},"image":{"@id":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/schwache-ergebnisberichte-wiegen-auf-stimmung-renditen-fallen-wieder\/#primaryimage"},"thumbnailUrl":"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/11\/16.11.2023_TITLE_Artboard-1-copy-9.webp","datePublished":"2023-11-16T14:16:29+00:00","dateModified":"2023-11-16T14:24:12+00:00","author":{"@id":"https:\/\/smarttrader.community\/de\/#\/schema\/person\/4f791355f3f400fd2dd91d9c57c4c067"},"description":"Schwache Ergebnisberichte wiegen auf Stimmung; Renditen fallen wieder. Die Euphorie \u00fcber die stark abk\u00fchlende Inflation und eine m\u00f6gliche...","breadcrumb":{"@id":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/schwache-ergebnisberichte-wiegen-auf-stimmung-renditen-fallen-wieder\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/schwache-ergebnisberichte-wiegen-auf-stimmung-renditen-fallen-wieder\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/schwache-ergebnisberichte-wiegen-auf-stimmung-renditen-fallen-wieder\/#primaryimage","url":"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/11\/16.11.2023_TITLE_Artboard-1-copy-9.webp","contentUrl":"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/11\/16.11.2023_TITLE_Artboard-1-copy-9.webp","width":1081,"height":721},{"@type":"BreadcrumbList","@id":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/schwache-ergebnisberichte-wiegen-auf-stimmung-renditen-fallen-wieder\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/smarttrader.community\/de\/"},{"@type":"ListItem","position":2,"name":"Schwache Ergebnisberichte wiegen auf Stimmung; Renditen fallen wieder"}]},{"@type":"WebSite","@id":"https:\/\/smarttrader.community\/de\/#website","url":"https:\/\/smarttrader.community\/de\/","name":"SmartTrader","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/smarttrader.community\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/smarttrader.community\/de\/#\/schema\/person\/4f791355f3f400fd2dd91d9c57c4c067","name":"Robert Lindner","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/05\/robert-lindner_avatar_1-96x96.png","url":"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/05\/robert-lindner_avatar_1-96x96.png","contentUrl":"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/05\/robert-lindner_avatar_1-96x96.png","caption":"Robert Lindner"},"sameAs":["https:\/\/wwww.smarttrader.community\/"],"url":"https:\/\/smarttrader.community\/de\/author\/robert_smarttrader\/"}]}},"_links":{"self":[{"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/posts\/27818","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/users\/663"}],"replies":[{"embeddable":true,"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/comments?post=27818"}],"version-history":[{"count":0,"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/posts\/27818\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/media\/27815"}],"wp:attachment":[{"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/media?parent=27818"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/categories?post=27818"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/tags?post=27818"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}