{"id":28221,"date":"2023-11-20T14:26:06","date_gmt":"2023-11-20T14:26:06","guid":{"rendered":"https:\/\/smarttrader.community\/?p=28221"},"modified":"2023-11-20T14:32:20","modified_gmt":"2023-11-20T14:32:20","slug":"zinssenkungs-hoffnung-bleibt-usd-faellt-weiter-altman-fuehrt-microsoft-ai-team","status":"publish","type":"post","link":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/zinssenkungs-hoffnung-bleibt-usd-faellt-weiter-altman-fuehrt-microsoft-ai-team\/","title":{"rendered":"Zinssenkungs-Hoffnung bleibt: USD f\u00e4llt weiter; Altman f\u00fchrt Microsoft AI-Team"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Der <strong>USD setzt seine Talfahrt<\/strong> (= Normalisierung) gegen\u00fcber seinen Konkurrenten fort, da die Erwartung besteht, dass die US-Notenbank das <strong>Ende ihres Zinserh\u00f6hungszyklus<\/strong> erreicht hat und dass bereits im <strong>M\u00e4rz Zinssenkungen folgen k\u00f6nnten<\/strong>. Der USD ist jetzt auf dem niedrigsten Stand seit August. Der <strong>JPY<\/strong>, der immer noch sehr schwach ist, sowie der <strong>EUR <\/strong>profitieren von der Schw\u00e4che des USD. Die W\u00e4hrungsm\u00e4rkte werden weiterhin von der <strong>USD-Schw\u00e4che<\/strong> (+GBP) und einem sich <strong>erholenden JPY<\/strong> (+EUR) dominiert.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nach den k\u00fchlen Inflationsdaten der letzten Woche rechnen H\u00e4ndler derzeit mit einer <strong>Wahrscheinlichkeit von etwa 30% f\u00fcr eine erste Zinssenkung der Fed im M\u00e4rz<\/strong> &#8211; meiner Meinung nach sehr optimistisch. Es ist m\u00f6glich, dass diese Erwartungen nach der <strong>Ver\u00f6ffentlichung des Protokolls der letzten Fed-Sitzung (morgen) etwas zur\u00fcckgeschraubt werden<\/strong>. Im Moment bleiben jedoch die allgemein dovishen Erwartungen f\u00fcr die Fed, aber auch f\u00fcr andere gro\u00dfe Zentralbanken, bestehen und sind der Hauptgrund daf\u00fcr, dass sich die M\u00e4rkte in der N\u00e4he der H\u00f6chstst\u00e4nde von 2023 halten. Der <strong>Nikkei hat heute sogar ein neues Allzeithoch erreicht.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Wir sehen, dass die <strong>Aktien in Europa und den USA nach einer dreiw\u00f6chigen Rallye stabil bleiben<\/strong>. Die <strong>Investoren sind geschockt <\/strong>und sehen sich mit Verlusten und Opportunit\u00e4tskosten konfrontiert, nachdem sie Microsoft nach der Altman-Nachricht \u00fcber den Weggang von OpenAI <strong>in Panik verkauft haben<\/strong>, und werden noch mehr Verluste hinnehmen, da Microsoft vorb\u00f6rslich um fast 3 % steigt.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Gratulation an die Community <\/em>\ud83c\udf89, wir haben gegen den Markt gehandelt und uns nach den Panikverk\u00e4ufen vom Freitag stattdessen <strong>LONG in Microsoft<\/strong> positioniert.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Da Altman das KI-Team von Microsoft leiten wird, werden die Investoren wahrscheinlich noch mehr Vertrauen in <strong>Microsofts F\u00fchrungsrolle im Bereich KI gewinnen.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ich sehe immer <strong>weniger Spielraum f\u00fcr weitere Kursgewinne im Jahr 2023<\/strong> &#8211; zumal die Rallye schon weit fortgeschritten ist, zumal es starke Anzeichen daf\u00fcr gibt, dass sich das <strong>Umsatzwachstum vorerst (weiter) verlangsamen wird<\/strong>. Weitere gemischte Ergebnisse in Europa, auch vom deutschen Pharmariesen Bayer, werden uns belasten. Wir gehen davon aus, dass Gewinnmitnahmen bald die Oberhand gewinnen werden &#8211; aber vieles wird von den Renditen abh\u00e4ngen. Solange die Renditen weiter fallen k\u00f6nnen, k\u00f6nnte es noch etwas <strong>Aufw\u00e4rtspotenzial f\u00fcr Aktien<\/strong> (und <strong>Gold<\/strong>) geben.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ein weiteres Risiko &#8211; insbesondere f\u00fcr die europ\u00e4ischen M\u00e4rkte, aber auch f\u00fcr die anhaltende Disinflation &#8211; sind die <strong>steigenden Energiepreise<\/strong>. Die europ\u00e4ischen Gasfutures stiegen um bis zu 6,9 %. Der Anstieg wurde auch durch k\u00e4ltere Wettervorhersagen und h\u00f6here Roh\u00f6lpreise im Vorfeld eines OPEC+-Treffens Ende dieser Woche verursacht. Ich erwarte, dass die OPEC+ versuchen wird, die \u00d6lpreise weiter zu st\u00fctzen &#8211; sogar noch st\u00e4rkere Produktionsk\u00fcrzungen k\u00f6nnten m\u00f6glich sein und die \u00d6lpreise kurzfristig nach oben treiben. Wir haben den steigenden Energiesektor am Freitag sehr gut gehandelt und erwarten, dass die <strong>\u00d6lpreise und der Energiesektor im Erholungsmodus bleiben.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Insgesamt werden wir heute jedoch eher eine Seitw\u00e4rtsbewegung sehen, da der Wirtschaftskalender wenig Action verspricht.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">\ud83d\udc41 ROB'S MARKET OVERVIEW:<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><em>November 20, 2023<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\ud83c\uddfa\ud83c\uddf8 <strong>US-M\u00e4rkte<\/strong> <em>\u27a1\ufe0f\/\u2197\ufe0f (Heute wenig Bewegung, US-M\u00e4rkte schneiden besser ab als Europa aufgrund dovisher Hoffnungen \/ Gewinne bei Microsoft)<br>Zyklische Aktien \u27a1\ufe0f\/\u2197\ufe0f<br>Tech-\/Wachstumsaktien \u27a1\ufe0f\/\u2197\ufe0f<br>Finanzaktien \u27a1\ufe0f<br>Defensive Aktien \u27a1\ufe0f<br>Energieaktien \u2197\ufe0f<br>Rohstoffaktien \u2197\ufe0f\/\u27a1\ufe0f<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\ud83d\udcb1 <strong>Forex<\/strong><br><em>JPY \u2197\ufe0f<br>EUR, AUD \u27a1\ufe0f\/\u2197\ufe0f<br>CAD, CHF \u27a1\ufe0f<br>USD, GBP \u27a1\ufe0f\/\u2198\ufe0f<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u2692 <strong>Rohstoffm\u00e4rkte <\/strong>\u2195\ufe0f<em>\/\u2197\ufe0f (profitieren von schwachem USD)<br>\u00d6lpreise \u2197\ufe0f<br>Erdgaspreise \u2195\ufe0f\/\u2197\ufe0f<br>Metallpreise \u2197\ufe0f<br>Gold \u2198\ufe0f\/\u27a1\ufe0f\/\u2197\ufe0f<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u26a1\ufe0f<strong>Kryptow\u00e4hrungen <\/strong><em>\u27a1\ufe0f\/\u2197\ufe0f (profitieren von der Schw\u00e4che des USD \/ dovishen Hoffnungen)<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>(*\u2197\ufe0f bullisch, \u2198\ufe0f b\u00e4risch, \u27a1\ufe0f seitw\u00e4rts \/ stabil, \u2195\ufe0f gemischt \/ volatil)<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dein <strong>Robert<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Der USD setzt seine Talfahrt (= Normalisierung) gegen\u00fcber seinen Konkurrenten fort, da die Erwartung besteht, dass die US-Notenbank das Ende&#8230;<\/p>\n","protected":false},"author":663,"featured_media":28219,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","pmpro_default_level":"","_daextam_enable_autolinks":"","footnotes":""},"categories":[117],"tags":[],"class_list":["post-28221","post","type-post","status-publish","format-standard","has-post-thumbnail","category-taegliche-aktualisierungen","pmpro-has-access"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Zinssenkungs-Hoffnung bleibt: USD f\u00e4llt weiter; Altman f\u00fchrt Microsoft AI-Team - SmartTrader<\/title>\n<meta name=\"description\" content=\"Zinssenkungs-Hoffnung bleibt: USD f\u00e4llt weiter; Altman f\u00fchrt Microsoft AI-Team. Der USD setzt seine Talfahrt (= Normalisierung) gegen\u00fcber...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/zinssenkungs-hoffnung-bleibt-usd-faellt-weiter-altman-fuehrt-microsoft-ai-team\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Zinssenkungs-Hoffnung bleibt: USD f\u00e4llt weiter; Altman f\u00fchrt Microsoft AI-Team - SmartTrader\" \/>\n<meta property=\"og:description\" content=\"Zinssenkungs-Hoffnung bleibt: USD f\u00e4llt weiter; Altman f\u00fchrt Microsoft AI-Team. Der USD setzt seine Talfahrt (= Normalisierung) gegen\u00fcber...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/zinssenkungs-hoffnung-bleibt-usd-faellt-weiter-altman-fuehrt-microsoft-ai-team\/\" \/>\n<meta property=\"og:site_name\" content=\"SmartTrader\" \/>\n<meta property=\"article:published_time\" content=\"2023-11-20T14:26:06+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-20T14:32:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/11\/20.11.2023_TITLE_Artboard-1-copy-9.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1081\" \/>\n\t<meta property=\"og:image:height\" content=\"721\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Robert Lindner\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Robert Lindner\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taegliche-aktualisierungen\\\/zinssenkungs-hoffnung-bleibt-usd-faellt-weiter-altman-fuehrt-microsoft-ai-team\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taegliche-aktualisierungen\\\/zinssenkungs-hoffnung-bleibt-usd-faellt-weiter-altman-fuehrt-microsoft-ai-team\\\/\"},\"author\":{\"name\":\"Robert Lindner\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/#\\\/schema\\\/person\\\/4f791355f3f400fd2dd91d9c57c4c067\"},\"headline\":\"Zinssenkungs-Hoffnung bleibt: USD f\u00e4llt weiter; Altman f\u00fchrt Microsoft AI-Team\",\"datePublished\":\"2023-11-20T14:26:06+00:00\",\"dateModified\":\"2023-11-20T14:32:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taegliche-aktualisierungen\\\/zinssenkungs-hoffnung-bleibt-usd-faellt-weiter-altman-fuehrt-microsoft-ai-team\\\/\"},\"wordCount\":582,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taegliche-aktualisierungen\\\/zinssenkungs-hoffnung-bleibt-usd-faellt-weiter-altman-fuehrt-microsoft-ai-team\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/20.11.2023_TITLE_Artboard-1-copy-9.webp\",\"articleSection\":[\"T\u00e4gliche Aktualisierungen\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/smarttrader.community\\\/de\\\/taegliche-aktualisierungen\\\/zinssenkungs-hoffnung-bleibt-usd-faellt-weiter-altman-fuehrt-microsoft-ai-team\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taegliche-aktualisierungen\\\/zinssenkungs-hoffnung-bleibt-usd-faellt-weiter-altman-fuehrt-microsoft-ai-team\\\/\",\"url\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taegliche-aktualisierungen\\\/zinssenkungs-hoffnung-bleibt-usd-faellt-weiter-altman-fuehrt-microsoft-ai-team\\\/\",\"name\":\"Zinssenkungs-Hoffnung bleibt: USD f\u00e4llt weiter; Altman f\u00fchrt Microsoft AI-Team - SmartTrader\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taegliche-aktualisierungen\\\/zinssenkungs-hoffnung-bleibt-usd-faellt-weiter-altman-fuehrt-microsoft-ai-team\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taegliche-aktualisierungen\\\/zinssenkungs-hoffnung-bleibt-usd-faellt-weiter-altman-fuehrt-microsoft-ai-team\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/20.11.2023_TITLE_Artboard-1-copy-9.webp\",\"datePublished\":\"2023-11-20T14:26:06+00:00\",\"dateModified\":\"2023-11-20T14:32:20+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/#\\\/schema\\\/person\\\/4f791355f3f400fd2dd91d9c57c4c067\"},\"description\":\"Zinssenkungs-Hoffnung bleibt: USD f\u00e4llt weiter; Altman f\u00fchrt Microsoft AI-Team. Der USD setzt seine Talfahrt (= Normalisierung) gegen\u00fcber...\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taegliche-aktualisierungen\\\/zinssenkungs-hoffnung-bleibt-usd-faellt-weiter-altman-fuehrt-microsoft-ai-team\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/smarttrader.community\\\/de\\\/taegliche-aktualisierungen\\\/zinssenkungs-hoffnung-bleibt-usd-faellt-weiter-altman-fuehrt-microsoft-ai-team\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taegliche-aktualisierungen\\\/zinssenkungs-hoffnung-bleibt-usd-faellt-weiter-altman-fuehrt-microsoft-ai-team\\\/#primaryimage\",\"url\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/20.11.2023_TITLE_Artboard-1-copy-9.webp\",\"contentUrl\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/20.11.2023_TITLE_Artboard-1-copy-9.webp\",\"width\":1081,\"height\":721},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taegliche-aktualisierungen\\\/zinssenkungs-hoffnung-bleibt-usd-faellt-weiter-altman-fuehrt-microsoft-ai-team\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Zinssenkungs-Hoffnung bleibt: USD f\u00e4llt weiter; Altman f\u00fchrt Microsoft AI-Team\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/\",\"name\":\"SmartTrader\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/#\\\/schema\\\/person\\\/4f791355f3f400fd2dd91d9c57c4c067\",\"name\":\"Robert Lindner\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/robert-lindner_avatar_1-96x96.png\",\"url\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/robert-lindner_avatar_1-96x96.png\",\"contentUrl\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/robert-lindner_avatar_1-96x96.png\",\"caption\":\"Robert Lindner\"},\"sameAs\":[\"https:\\\/\\\/wwww.smarttrader.community\\\/\"],\"url\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/author\\\/robert_smarttrader\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Zinssenkungs-Hoffnung bleibt: USD f\u00e4llt weiter; Altman f\u00fchrt Microsoft AI-Team - SmartTrader","description":"Zinssenkungs-Hoffnung bleibt: USD f\u00e4llt weiter; Altman f\u00fchrt Microsoft AI-Team. Der USD setzt seine Talfahrt (= Normalisierung) gegen\u00fcber...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/zinssenkungs-hoffnung-bleibt-usd-faellt-weiter-altman-fuehrt-microsoft-ai-team\/","og_locale":"de_DE","og_type":"article","og_title":"Zinssenkungs-Hoffnung bleibt: USD f\u00e4llt weiter; Altman f\u00fchrt Microsoft AI-Team - SmartTrader","og_description":"Zinssenkungs-Hoffnung bleibt: USD f\u00e4llt weiter; Altman f\u00fchrt Microsoft AI-Team. Der USD setzt seine Talfahrt (= Normalisierung) gegen\u00fcber...","og_url":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/zinssenkungs-hoffnung-bleibt-usd-faellt-weiter-altman-fuehrt-microsoft-ai-team\/","og_site_name":"SmartTrader","article_published_time":"2023-11-20T14:26:06+00:00","article_modified_time":"2023-11-20T14:32:20+00:00","og_image":[{"width":1081,"height":721,"url":"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/11\/20.11.2023_TITLE_Artboard-1-copy-9.webp","type":"image\/webp"}],"author":"Robert Lindner","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Robert Lindner","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/zinssenkungs-hoffnung-bleibt-usd-faellt-weiter-altman-fuehrt-microsoft-ai-team\/#article","isPartOf":{"@id":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/zinssenkungs-hoffnung-bleibt-usd-faellt-weiter-altman-fuehrt-microsoft-ai-team\/"},"author":{"name":"Robert Lindner","@id":"https:\/\/smarttrader.community\/de\/#\/schema\/person\/4f791355f3f400fd2dd91d9c57c4c067"},"headline":"Zinssenkungs-Hoffnung bleibt: USD f\u00e4llt weiter; Altman f\u00fchrt Microsoft AI-Team","datePublished":"2023-11-20T14:26:06+00:00","dateModified":"2023-11-20T14:32:20+00:00","mainEntityOfPage":{"@id":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/zinssenkungs-hoffnung-bleibt-usd-faellt-weiter-altman-fuehrt-microsoft-ai-team\/"},"wordCount":582,"commentCount":0,"image":{"@id":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/zinssenkungs-hoffnung-bleibt-usd-faellt-weiter-altman-fuehrt-microsoft-ai-team\/#primaryimage"},"thumbnailUrl":"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/11\/20.11.2023_TITLE_Artboard-1-copy-9.webp","articleSection":["T\u00e4gliche Aktualisierungen"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/zinssenkungs-hoffnung-bleibt-usd-faellt-weiter-altman-fuehrt-microsoft-ai-team\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/zinssenkungs-hoffnung-bleibt-usd-faellt-weiter-altman-fuehrt-microsoft-ai-team\/","url":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/zinssenkungs-hoffnung-bleibt-usd-faellt-weiter-altman-fuehrt-microsoft-ai-team\/","name":"Zinssenkungs-Hoffnung bleibt: USD f\u00e4llt weiter; Altman f\u00fchrt Microsoft AI-Team - SmartTrader","isPartOf":{"@id":"https:\/\/smarttrader.community\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/zinssenkungs-hoffnung-bleibt-usd-faellt-weiter-altman-fuehrt-microsoft-ai-team\/#primaryimage"},"image":{"@id":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/zinssenkungs-hoffnung-bleibt-usd-faellt-weiter-altman-fuehrt-microsoft-ai-team\/#primaryimage"},"thumbnailUrl":"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/11\/20.11.2023_TITLE_Artboard-1-copy-9.webp","datePublished":"2023-11-20T14:26:06+00:00","dateModified":"2023-11-20T14:32:20+00:00","author":{"@id":"https:\/\/smarttrader.community\/de\/#\/schema\/person\/4f791355f3f400fd2dd91d9c57c4c067"},"description":"Zinssenkungs-Hoffnung bleibt: USD f\u00e4llt weiter; Altman f\u00fchrt Microsoft AI-Team. Der USD setzt seine Talfahrt (= Normalisierung) gegen\u00fcber...","breadcrumb":{"@id":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/zinssenkungs-hoffnung-bleibt-usd-faellt-weiter-altman-fuehrt-microsoft-ai-team\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/zinssenkungs-hoffnung-bleibt-usd-faellt-weiter-altman-fuehrt-microsoft-ai-team\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/zinssenkungs-hoffnung-bleibt-usd-faellt-weiter-altman-fuehrt-microsoft-ai-team\/#primaryimage","url":"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/11\/20.11.2023_TITLE_Artboard-1-copy-9.webp","contentUrl":"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/11\/20.11.2023_TITLE_Artboard-1-copy-9.webp","width":1081,"height":721},{"@type":"BreadcrumbList","@id":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/zinssenkungs-hoffnung-bleibt-usd-faellt-weiter-altman-fuehrt-microsoft-ai-team\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/smarttrader.community\/de\/"},{"@type":"ListItem","position":2,"name":"Zinssenkungs-Hoffnung bleibt: USD f\u00e4llt weiter; Altman f\u00fchrt Microsoft AI-Team"}]},{"@type":"WebSite","@id":"https:\/\/smarttrader.community\/de\/#website","url":"https:\/\/smarttrader.community\/de\/","name":"SmartTrader","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/smarttrader.community\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/smarttrader.community\/de\/#\/schema\/person\/4f791355f3f400fd2dd91d9c57c4c067","name":"Robert Lindner","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/05\/robert-lindner_avatar_1-96x96.png","url":"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/05\/robert-lindner_avatar_1-96x96.png","contentUrl":"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/05\/robert-lindner_avatar_1-96x96.png","caption":"Robert Lindner"},"sameAs":["https:\/\/wwww.smarttrader.community\/"],"url":"https:\/\/smarttrader.community\/de\/author\/robert_smarttrader\/"}]}},"_links":{"self":[{"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/posts\/28221","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/users\/663"}],"replies":[{"embeddable":true,"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/comments?post=28221"}],"version-history":[{"count":0,"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/posts\/28221\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/media\/28219"}],"wp:attachment":[{"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/media?parent=28221"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/categories?post=28221"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/tags?post=28221"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}