{"id":28233,"date":"2023-11-21T10:49:46","date_gmt":"2023-11-21T10:49:46","guid":{"rendered":"https:\/\/smarttrader.community\/?p=28233"},"modified":"2023-11-21T10:55:32","modified_gmt":"2023-11-21T10:55:32","slug":"tech-giganten-treiben-wall-street-an-aber-frage-nach-nachhaltigkeit-der-rallye-wird-lauter-investoren-warten-gespannt-auf-nvidias-ergebnisbericht","status":"publish","type":"post","link":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/tech-giganten-treiben-wall-street-an-aber-frage-nach-nachhaltigkeit-der-rallye-wird-lauter-investoren-warten-gespannt-auf-nvidias-ergebnisbericht\/","title":{"rendered":"Tech-Giganten treiben Wall Street an, aber Frage nach Nachhaltigkeit der Rallye wird lauter; Investoren warten gespannt auf Nvidia&#8217;s Ergebnisbericht"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">\ud83d\udcc6 Dienstag, 21. November<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u25ba In <strong>Europa er\u00f6ffnete der Stoxx 600 Index flat <\/strong>zwischen Gewinnen bei Rohstoffwerten und R\u00fcckg\u00e4ngen im Bankensektor. Die Stimmung an den M\u00e4rkten wird vorsichtiger, da die Investoren \u00fcber die von EZB-Politiker Francois Villeroy de Galhau angedeutete m\u00f6gliche Zinswende der EZB nachdenken. F\u00fcr unseren Chefanalysten Robert Lindner sind keine weiteren Zinserh\u00f6hungen der EZB in Sicht, da die Konjunkturabschw\u00e4chung anh\u00e4lt und sich die Inflation rasch abk\u00fchlt.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u25ba In den <strong>USA blieben die Aktienfutures stabil, nachdem der S&P 500 den h\u00f6chsten Schlussstand seit August erreicht hatte<\/strong>, w\u00e4hrend der Nasdaq 100 auf ein 22-Monats-Hoch stieg. Technologieriesen wie <strong>Microsoft <\/strong>und <strong>Nvidia <\/strong>spielten eine entscheidende Rolle bei dem Marktaufschwung. Insbesondere die Gewinne von Microsoft kamen f\u00fcr den Markt nach dem chaotischen Abgang von Sam Altman bei <strong>OpenAi <\/strong>&#8211; an dem Microsoft stark beteiligt ist &#8211; \u00fcberraschend. Microsofts Umgang mit der Situation, einschlie\u00dflich der Einstellung von OpenAIs <strong>Altman <\/strong>und<strong> Greg Brockman<\/strong> als Leiter des Microsoft-KI-Teams, war ein wichtiger Treiber f\u00fcr die Aktie, w\u00e4hrend Nvidias erwarteter Ergebnisbericht die Erwartung des Marktes erh\u00f6ht hat. Die Investoren warten nun auf das letzte <strong>FOMC-Protokoll<\/strong>, das Aufschluss \u00fcber die geldpolitische Ausrichtung der Fed geben soll. Gewinnberichte von Unternehmen wie Lowe's, Best Buy und HP stehen ebenfalls an. Die Aktien des chinesischen Tech-Giganten <strong>Baidu <\/strong>stiegen nach einem Umsatzplus um 2%.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/smarttrader.community\/membership-join\">Subscribe<\/a> to see more<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n","protected":false},"excerpt":{"rendered":"<p>\ud83d\udcc6 Dienstag, 21. November \u25ba In Europa er\u00f6ffnete der Stoxx 600 Index flat zwischen Gewinnen bei Rohstoffwerten und R\u00fcckg\u00e4ngen im&#8230;<\/p>\n","protected":false},"author":1,"featured_media":21493,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","pmpro_default_level":"","_daextam_enable_autolinks":"","footnotes":""},"categories":[172],"tags":[],"class_list":["post-28233","post","type-post","status-publish","format-standard","has-post-thumbnail","category-taglicher-marktuberblick","pmpro-has-access"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Tech-Giganten treiben Wall Street an, aber Frage nach Nachhaltigkeit der Rallye wird lauter; Investoren warten gespannt auf Nvidia&#039;s Ergebnisbericht - SmartTrader<\/title>\n<meta name=\"description\" content=\"Tech-Giganten treiben Wall Street an, aber Frage nach Nachhaltigkeit der Rallye wird lauter; Investoren warten gespannt auf Nvidia&#039;s...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/tech-giganten-treiben-wall-street-an-aber-frage-nach-nachhaltigkeit-der-rallye-wird-lauter-investoren-warten-gespannt-auf-nvidias-ergebnisbericht\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tech-Giganten treiben Wall Street an, aber Frage nach Nachhaltigkeit der Rallye wird lauter; Investoren warten gespannt auf Nvidia&#039;s Ergebnisbericht - SmartTrader\" \/>\n<meta property=\"og:description\" content=\"Tech-Giganten treiben Wall Street an, aber Frage nach Nachhaltigkeit der Rallye wird lauter; Investoren warten gespannt auf Nvidia&#039;s...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/tech-giganten-treiben-wall-street-an-aber-frage-nach-nachhaltigkeit-der-rallye-wird-lauter-investoren-warten-gespannt-auf-nvidias-ergebnisbericht\/\" \/>\n<meta property=\"og:site_name\" content=\"SmartTrader\" \/>\n<meta property=\"article:published_time\" content=\"2023-11-21T10:49:46+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-21T10:55:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/08\/Copy-of-images-4-1.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"SmartTrader Analyst Team\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"SmartTrader Analyst Team\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taglicher-marktuberblick\\\/tech-giganten-treiben-wall-street-an-aber-frage-nach-nachhaltigkeit-der-rallye-wird-lauter-investoren-warten-gespannt-auf-nvidias-ergebnisbericht\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taglicher-marktuberblick\\\/tech-giganten-treiben-wall-street-an-aber-frage-nach-nachhaltigkeit-der-rallye-wird-lauter-investoren-warten-gespannt-auf-nvidias-ergebnisbericht\\\/\"},\"author\":{\"name\":\"SmartTrader Analyst Team\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/#\\\/schema\\\/person\\\/bfe0c456aafbdc04b9707983e59c4e05\"},\"headline\":\"Tech-Giganten treiben Wall Street an, aber Frage nach Nachhaltigkeit der Rallye wird lauter; Investoren warten gespannt auf Nvidia&#8217;s Ergebnisbericht\",\"datePublished\":\"2023-11-21T10:49:46+00:00\",\"dateModified\":\"2023-11-21T10:55:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taglicher-marktuberblick\\\/tech-giganten-treiben-wall-street-an-aber-frage-nach-nachhaltigkeit-der-rallye-wird-lauter-investoren-warten-gespannt-auf-nvidias-ergebnisbericht\\\/\"},\"wordCount\":457,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taglicher-marktuberblick\\\/tech-giganten-treiben-wall-street-an-aber-frage-nach-nachhaltigkeit-der-rallye-wird-lauter-investoren-warten-gespannt-auf-nvidias-ergebnisbericht\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/Copy-of-images-4-1.webp\",\"articleSection\":[\"T\u00e4glicher Markt\u00fcberblick\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/smarttrader.community\\\/de\\\/taglicher-marktuberblick\\\/tech-giganten-treiben-wall-street-an-aber-frage-nach-nachhaltigkeit-der-rallye-wird-lauter-investoren-warten-gespannt-auf-nvidias-ergebnisbericht\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taglicher-marktuberblick\\\/tech-giganten-treiben-wall-street-an-aber-frage-nach-nachhaltigkeit-der-rallye-wird-lauter-investoren-warten-gespannt-auf-nvidias-ergebnisbericht\\\/\",\"url\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taglicher-marktuberblick\\\/tech-giganten-treiben-wall-street-an-aber-frage-nach-nachhaltigkeit-der-rallye-wird-lauter-investoren-warten-gespannt-auf-nvidias-ergebnisbericht\\\/\",\"name\":\"Tech-Giganten treiben Wall Street an, aber Frage nach Nachhaltigkeit der Rallye wird lauter; Investoren warten gespannt auf Nvidia's Ergebnisbericht - SmartTrader\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taglicher-marktuberblick\\\/tech-giganten-treiben-wall-street-an-aber-frage-nach-nachhaltigkeit-der-rallye-wird-lauter-investoren-warten-gespannt-auf-nvidias-ergebnisbericht\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taglicher-marktuberblick\\\/tech-giganten-treiben-wall-street-an-aber-frage-nach-nachhaltigkeit-der-rallye-wird-lauter-investoren-warten-gespannt-auf-nvidias-ergebnisbericht\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/Copy-of-images-4-1.webp\",\"datePublished\":\"2023-11-21T10:49:46+00:00\",\"dateModified\":\"2023-11-21T10:55:32+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/#\\\/schema\\\/person\\\/bfe0c456aafbdc04b9707983e59c4e05\"},\"description\":\"Tech-Giganten treiben Wall Street an, aber Frage nach Nachhaltigkeit der Rallye wird lauter; Investoren warten gespannt auf Nvidia's...\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taglicher-marktuberblick\\\/tech-giganten-treiben-wall-street-an-aber-frage-nach-nachhaltigkeit-der-rallye-wird-lauter-investoren-warten-gespannt-auf-nvidias-ergebnisbericht\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/smarttrader.community\\\/de\\\/taglicher-marktuberblick\\\/tech-giganten-treiben-wall-street-an-aber-frage-nach-nachhaltigkeit-der-rallye-wird-lauter-investoren-warten-gespannt-auf-nvidias-ergebnisbericht\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taglicher-marktuberblick\\\/tech-giganten-treiben-wall-street-an-aber-frage-nach-nachhaltigkeit-der-rallye-wird-lauter-investoren-warten-gespannt-auf-nvidias-ergebnisbericht\\\/#primaryimage\",\"url\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/Copy-of-images-4-1.webp\",\"contentUrl\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/Copy-of-images-4-1.webp\",\"width\":800,\"height\":500},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taglicher-marktuberblick\\\/tech-giganten-treiben-wall-street-an-aber-frage-nach-nachhaltigkeit-der-rallye-wird-lauter-investoren-warten-gespannt-auf-nvidias-ergebnisbericht\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tech-Giganten treiben Wall Street an, aber Frage nach Nachhaltigkeit der Rallye wird lauter; Investoren warten gespannt auf Nvidia&#8217;s Ergebnisbericht\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/\",\"name\":\"SmartTrader\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/#\\\/schema\\\/person\\\/bfe0c456aafbdc04b9707983e59c4e05\",\"name\":\"SmartTrader Analyst Team\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/admin_avatar_3-96x96.png\",\"url\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/admin_avatar_3-96x96.png\",\"contentUrl\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/admin_avatar_3-96x96.png\",\"caption\":\"SmartTrader Analyst Team\"},\"sameAs\":[\"https:\\\/\\\/smarttrader.community\"],\"url\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tech-Giganten treiben Wall Street an, aber Frage nach Nachhaltigkeit der Rallye wird lauter; Investoren warten gespannt auf Nvidia's Ergebnisbericht - SmartTrader","description":"Tech-Giganten treiben Wall Street an, aber Frage nach Nachhaltigkeit der Rallye wird lauter; Investoren warten gespannt auf Nvidia's...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/tech-giganten-treiben-wall-street-an-aber-frage-nach-nachhaltigkeit-der-rallye-wird-lauter-investoren-warten-gespannt-auf-nvidias-ergebnisbericht\/","og_locale":"de_DE","og_type":"article","og_title":"Tech-Giganten treiben Wall Street an, aber Frage nach Nachhaltigkeit der Rallye wird lauter; Investoren warten gespannt auf Nvidia's Ergebnisbericht - SmartTrader","og_description":"Tech-Giganten treiben Wall Street an, aber Frage nach Nachhaltigkeit der Rallye wird lauter; Investoren warten gespannt auf Nvidia's...","og_url":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/tech-giganten-treiben-wall-street-an-aber-frage-nach-nachhaltigkeit-der-rallye-wird-lauter-investoren-warten-gespannt-auf-nvidias-ergebnisbericht\/","og_site_name":"SmartTrader","article_published_time":"2023-11-21T10:49:46+00:00","article_modified_time":"2023-11-21T10:55:32+00:00","og_image":[{"width":800,"height":500,"url":"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/08\/Copy-of-images-4-1.webp","type":"image\/webp"}],"author":"SmartTrader Analyst Team","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"SmartTrader Analyst Team","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/tech-giganten-treiben-wall-street-an-aber-frage-nach-nachhaltigkeit-der-rallye-wird-lauter-investoren-warten-gespannt-auf-nvidias-ergebnisbericht\/#article","isPartOf":{"@id":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/tech-giganten-treiben-wall-street-an-aber-frage-nach-nachhaltigkeit-der-rallye-wird-lauter-investoren-warten-gespannt-auf-nvidias-ergebnisbericht\/"},"author":{"name":"SmartTrader Analyst Team","@id":"https:\/\/smarttrader.community\/de\/#\/schema\/person\/bfe0c456aafbdc04b9707983e59c4e05"},"headline":"Tech-Giganten treiben Wall Street an, aber Frage nach Nachhaltigkeit der Rallye wird lauter; Investoren warten gespannt auf Nvidia&#8217;s Ergebnisbericht","datePublished":"2023-11-21T10:49:46+00:00","dateModified":"2023-11-21T10:55:32+00:00","mainEntityOfPage":{"@id":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/tech-giganten-treiben-wall-street-an-aber-frage-nach-nachhaltigkeit-der-rallye-wird-lauter-investoren-warten-gespannt-auf-nvidias-ergebnisbericht\/"},"wordCount":457,"commentCount":0,"image":{"@id":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/tech-giganten-treiben-wall-street-an-aber-frage-nach-nachhaltigkeit-der-rallye-wird-lauter-investoren-warten-gespannt-auf-nvidias-ergebnisbericht\/#primaryimage"},"thumbnailUrl":"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/08\/Copy-of-images-4-1.webp","articleSection":["T\u00e4glicher Markt\u00fcberblick"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/tech-giganten-treiben-wall-street-an-aber-frage-nach-nachhaltigkeit-der-rallye-wird-lauter-investoren-warten-gespannt-auf-nvidias-ergebnisbericht\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/tech-giganten-treiben-wall-street-an-aber-frage-nach-nachhaltigkeit-der-rallye-wird-lauter-investoren-warten-gespannt-auf-nvidias-ergebnisbericht\/","url":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/tech-giganten-treiben-wall-street-an-aber-frage-nach-nachhaltigkeit-der-rallye-wird-lauter-investoren-warten-gespannt-auf-nvidias-ergebnisbericht\/","name":"Tech-Giganten treiben Wall Street an, aber Frage nach Nachhaltigkeit der Rallye wird lauter; Investoren warten gespannt auf Nvidia's Ergebnisbericht - SmartTrader","isPartOf":{"@id":"https:\/\/smarttrader.community\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/tech-giganten-treiben-wall-street-an-aber-frage-nach-nachhaltigkeit-der-rallye-wird-lauter-investoren-warten-gespannt-auf-nvidias-ergebnisbericht\/#primaryimage"},"image":{"@id":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/tech-giganten-treiben-wall-street-an-aber-frage-nach-nachhaltigkeit-der-rallye-wird-lauter-investoren-warten-gespannt-auf-nvidias-ergebnisbericht\/#primaryimage"},"thumbnailUrl":"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/08\/Copy-of-images-4-1.webp","datePublished":"2023-11-21T10:49:46+00:00","dateModified":"2023-11-21T10:55:32+00:00","author":{"@id":"https:\/\/smarttrader.community\/de\/#\/schema\/person\/bfe0c456aafbdc04b9707983e59c4e05"},"description":"Tech-Giganten treiben Wall Street an, aber Frage nach Nachhaltigkeit der Rallye wird lauter; Investoren warten gespannt auf Nvidia's...","breadcrumb":{"@id":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/tech-giganten-treiben-wall-street-an-aber-frage-nach-nachhaltigkeit-der-rallye-wird-lauter-investoren-warten-gespannt-auf-nvidias-ergebnisbericht\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/tech-giganten-treiben-wall-street-an-aber-frage-nach-nachhaltigkeit-der-rallye-wird-lauter-investoren-warten-gespannt-auf-nvidias-ergebnisbericht\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/tech-giganten-treiben-wall-street-an-aber-frage-nach-nachhaltigkeit-der-rallye-wird-lauter-investoren-warten-gespannt-auf-nvidias-ergebnisbericht\/#primaryimage","url":"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/08\/Copy-of-images-4-1.webp","contentUrl":"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/08\/Copy-of-images-4-1.webp","width":800,"height":500},{"@type":"BreadcrumbList","@id":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/tech-giganten-treiben-wall-street-an-aber-frage-nach-nachhaltigkeit-der-rallye-wird-lauter-investoren-warten-gespannt-auf-nvidias-ergebnisbericht\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/smarttrader.community\/de\/"},{"@type":"ListItem","position":2,"name":"Tech-Giganten treiben Wall Street an, aber Frage nach Nachhaltigkeit der Rallye wird lauter; Investoren warten gespannt auf Nvidia&#8217;s Ergebnisbericht"}]},{"@type":"WebSite","@id":"https:\/\/smarttrader.community\/de\/#website","url":"https:\/\/smarttrader.community\/de\/","name":"SmartTrader","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/smarttrader.community\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/smarttrader.community\/de\/#\/schema\/person\/bfe0c456aafbdc04b9707983e59c4e05","name":"SmartTrader Analyst Team","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/03\/admin_avatar_3-96x96.png","url":"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/03\/admin_avatar_3-96x96.png","contentUrl":"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/03\/admin_avatar_3-96x96.png","caption":"SmartTrader Analyst Team"},"sameAs":["https:\/\/smarttrader.community"],"url":"https:\/\/smarttrader.community\/de\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/posts\/28233","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/comments?post=28233"}],"version-history":[{"count":0,"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/posts\/28233\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/media\/21493"}],"wp:attachment":[{"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/media?parent=28233"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/categories?post=28233"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/tags?post=28233"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}