{"id":31924,"date":"2024-01-08T10:45:45","date_gmt":"2024-01-08T10:45:45","guid":{"rendered":"https:\/\/smarttrader.community\/?p=31924"},"modified":"2024-01-08T10:52:34","modified_gmt":"2024-01-08T10:52:34","slug":"asiatische-maerkte-bleiben-unter-druck-europaeische-futures-wackeln-us-inflationsdaten-werden-erwartet","status":"publish","type":"post","link":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/asiatische-maerkte-bleiben-unter-druck-europaeische-futures-wackeln-us-inflationsdaten-werden-erwartet\/","title":{"rendered":"Asiatische M\u00e4rkte bleiben unter Druck, europ\u00e4ische Futures wackeln &amp; US-Inflationsdaten werden erwartet"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">\u25ba Globale Investoren beobachten aufmerksam die <strong>US-Inflationsdaten<\/strong> und die <strong>Gewinne der gro\u00dfen Banken<\/strong>, die im Laufe dieser Woche ver\u00f6ffentlicht werden. Diese werden Aufschluss \u00fcber den Zustand der Wirtschaft und den <strong>Zinssenkungskurs der Federal Reserve geben<\/strong>. Au\u00dferdem wird erwartet, dass die australischen Inflationsdaten Aufschluss \u00fcber die politischen Entscheidungen der Reserve Bank of Australia geben werden. Die <strong>robusten US-Arbeitsmarktdaten<\/strong> der letzten Woche haben die <strong>Zinssenkungserwartungen bereits verringert.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u25ba Die <strong>europ\u00e4ischen Aktienfutures gaben deutlich nach<\/strong>, der Stoxx 600 Index notierte <strong>0,45%<\/strong> niedriger. Die M\u00e4rkte der Eurozone starteten bereits mit leichten Verlusten in die Woche und verzeichneten dann weitere Verk\u00e4ufe, nachdem die Wirtschaftsdaten zeigten, dass die <strong>Einzelhandelsums\u00e4tze und die Industrieproduktion weiterhin r\u00fcckl\u00e4ufig sind.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u25ba In den <strong>USA blieben die Aktienfutures relativ unver\u00e4ndert<\/strong>, zeigen aber auch Anzeichen f\u00fcr weitere Verk\u00e4ufe. Der Fokus liegt nun auf den anstehenden US-Inflationsdaten (11. Januar), die einen R\u00fcckgang des zugrunde liegenden Inflationsma\u00dfes erwarten lassen. Unser Chefanalyst Robert Lindner geht jedoch davon aus, dass die gesunde Verbrauchernachfrage \/ das Weihnachtsgesch\u00e4ft und die sehr gute Performance der Aktienm\u00e4rkte zu einer Verlangsamung der US-D disinflation gef\u00fchrt haben. Die US-M\u00e4rkte bereiten sich auch auf den <strong>Beginn der Gewinnsaison vor<\/strong>, da wichtige Finanzinstitute wie <strong>JPMorgan, Bank of America <\/strong>und <strong>Citigroup <\/strong>ihre Quartalsergebnisse ver\u00f6ffentlichen werden. Der USD verzeichnete auch gegen\u00fcber den meisten W\u00e4hrungen der Gruppe der 10 weitere <strong>Kursgewinne<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>   <p><a href=\"https:\/\/smarttrader.community\/membership-join\">Subscribe<\/a> to see more<\/p>   <p><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u25ba Globale Investoren beobachten aufmerksam die US-Inflationsdaten und die Gewinne der gro\u00dfen Banken, die im Laufe dieser Woche ver\u00f6ffentlicht werden&#8230;.<\/p>\n","protected":false},"author":1,"featured_media":23060,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","pmpro_default_level":"0","_daextam_enable_autolinks":"1","footnotes":""},"categories":[172],"tags":[],"class_list":["post-31924","post","type-post","status-publish","format-standard","has-post-thumbnail","category-taglicher-marktuberblick","pmpro-has-access"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Asiatische M\u00e4rkte bleiben unter Druck, europ\u00e4ische Futures wackeln &amp; US-Inflationsdaten werden erwartet - SmartTrader<\/title>\n<meta name=\"description\" content=\"Asiatische M\u00e4rkte bleiben unter Druck, europ\u00e4ische Futures wackeln &amp; US-Inflationsdaten werden erwartet. Globale Investoren beobachten...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/asiatische-maerkte-bleiben-unter-druck-europaeische-futures-wackeln-us-inflationsdaten-werden-erwartet\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Asiatische M\u00e4rkte bleiben unter Druck, europ\u00e4ische Futures wackeln &amp; US-Inflationsdaten werden erwartet - SmartTrader\" \/>\n<meta property=\"og:description\" content=\"Asiatische M\u00e4rkte bleiben unter Druck, europ\u00e4ische Futures wackeln &amp; US-Inflationsdaten werden erwartet. Globale Investoren beobachten...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/asiatische-maerkte-bleiben-unter-druck-europaeische-futures-wackeln-us-inflationsdaten-werden-erwartet\/\" \/>\n<meta property=\"og:site_name\" content=\"SmartTrader\" \/>\n<meta property=\"article:published_time\" content=\"2024-01-08T10:45:45+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-01-08T10:52:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/10\/images-36.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"SmartTrader Analyst Team\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"SmartTrader Analyst Team\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taglicher-marktuberblick\\\/asiatische-maerkte-bleiben-unter-druck-europaeische-futures-wackeln-us-inflationsdaten-werden-erwartet\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taglicher-marktuberblick\\\/asiatische-maerkte-bleiben-unter-druck-europaeische-futures-wackeln-us-inflationsdaten-werden-erwartet\\\/\"},\"author\":{\"name\":\"SmartTrader Analyst Team\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/#\\\/schema\\\/person\\\/bfe0c456aafbdc04b9707983e59c4e05\"},\"headline\":\"Asiatische M\u00e4rkte bleiben unter Druck, europ\u00e4ische Futures wackeln &amp; US-Inflationsdaten werden erwartet\",\"datePublished\":\"2024-01-08T10:45:45+00:00\",\"dateModified\":\"2024-01-08T10:52:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taglicher-marktuberblick\\\/asiatische-maerkte-bleiben-unter-druck-europaeische-futures-wackeln-us-inflationsdaten-werden-erwartet\\\/\"},\"wordCount\":565,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taglicher-marktuberblick\\\/asiatische-maerkte-bleiben-unter-druck-europaeische-futures-wackeln-us-inflationsdaten-werden-erwartet\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/images-36.jpg\",\"articleSection\":[\"T\u00e4glicher Markt\u00fcberblick\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/smarttrader.community\\\/de\\\/taglicher-marktuberblick\\\/asiatische-maerkte-bleiben-unter-druck-europaeische-futures-wackeln-us-inflationsdaten-werden-erwartet\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taglicher-marktuberblick\\\/asiatische-maerkte-bleiben-unter-druck-europaeische-futures-wackeln-us-inflationsdaten-werden-erwartet\\\/\",\"url\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taglicher-marktuberblick\\\/asiatische-maerkte-bleiben-unter-druck-europaeische-futures-wackeln-us-inflationsdaten-werden-erwartet\\\/\",\"name\":\"Asiatische M\u00e4rkte bleiben unter Druck, europ\u00e4ische Futures wackeln &amp; US-Inflationsdaten werden erwartet - SmartTrader\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taglicher-marktuberblick\\\/asiatische-maerkte-bleiben-unter-druck-europaeische-futures-wackeln-us-inflationsdaten-werden-erwartet\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taglicher-marktuberblick\\\/asiatische-maerkte-bleiben-unter-druck-europaeische-futures-wackeln-us-inflationsdaten-werden-erwartet\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/images-36.jpg\",\"datePublished\":\"2024-01-08T10:45:45+00:00\",\"dateModified\":\"2024-01-08T10:52:34+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/#\\\/schema\\\/person\\\/bfe0c456aafbdc04b9707983e59c4e05\"},\"description\":\"Asiatische M\u00e4rkte bleiben unter Druck, europ\u00e4ische Futures wackeln & US-Inflationsdaten werden erwartet. Globale Investoren beobachten...\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taglicher-marktuberblick\\\/asiatische-maerkte-bleiben-unter-druck-europaeische-futures-wackeln-us-inflationsdaten-werden-erwartet\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/smarttrader.community\\\/de\\\/taglicher-marktuberblick\\\/asiatische-maerkte-bleiben-unter-druck-europaeische-futures-wackeln-us-inflationsdaten-werden-erwartet\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taglicher-marktuberblick\\\/asiatische-maerkte-bleiben-unter-druck-europaeische-futures-wackeln-us-inflationsdaten-werden-erwartet\\\/#primaryimage\",\"url\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/images-36.jpg\",\"contentUrl\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/images-36.jpg\",\"width\":800,\"height\":500},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taglicher-marktuberblick\\\/asiatische-maerkte-bleiben-unter-druck-europaeische-futures-wackeln-us-inflationsdaten-werden-erwartet\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Asiatische M\u00e4rkte bleiben unter Druck, europ\u00e4ische Futures wackeln &amp; US-Inflationsdaten werden erwartet\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/\",\"name\":\"SmartTrader\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/#\\\/schema\\\/person\\\/bfe0c456aafbdc04b9707983e59c4e05\",\"name\":\"SmartTrader Analyst Team\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/admin_avatar_3-96x96.png\",\"url\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/admin_avatar_3-96x96.png\",\"contentUrl\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/admin_avatar_3-96x96.png\",\"caption\":\"SmartTrader Analyst Team\"},\"sameAs\":[\"https:\\\/\\\/smarttrader.community\"],\"url\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Asiatische M\u00e4rkte bleiben unter Druck, europ\u00e4ische Futures wackeln &amp; US-Inflationsdaten werden erwartet - SmartTrader","description":"Asiatische M\u00e4rkte bleiben unter Druck, europ\u00e4ische Futures wackeln & US-Inflationsdaten werden erwartet. Globale Investoren beobachten...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/asiatische-maerkte-bleiben-unter-druck-europaeische-futures-wackeln-us-inflationsdaten-werden-erwartet\/","og_locale":"de_DE","og_type":"article","og_title":"Asiatische M\u00e4rkte bleiben unter Druck, europ\u00e4ische Futures wackeln &amp; US-Inflationsdaten werden erwartet - SmartTrader","og_description":"Asiatische M\u00e4rkte bleiben unter Druck, europ\u00e4ische Futures wackeln & US-Inflationsdaten werden erwartet. Globale Investoren beobachten...","og_url":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/asiatische-maerkte-bleiben-unter-druck-europaeische-futures-wackeln-us-inflationsdaten-werden-erwartet\/","og_site_name":"SmartTrader","article_published_time":"2024-01-08T10:45:45+00:00","article_modified_time":"2024-01-08T10:52:34+00:00","og_image":[{"width":800,"height":500,"url":"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/10\/images-36.jpg","type":"image\/jpeg"}],"author":"SmartTrader Analyst Team","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"SmartTrader Analyst Team","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/asiatische-maerkte-bleiben-unter-druck-europaeische-futures-wackeln-us-inflationsdaten-werden-erwartet\/#article","isPartOf":{"@id":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/asiatische-maerkte-bleiben-unter-druck-europaeische-futures-wackeln-us-inflationsdaten-werden-erwartet\/"},"author":{"name":"SmartTrader Analyst Team","@id":"https:\/\/smarttrader.community\/de\/#\/schema\/person\/bfe0c456aafbdc04b9707983e59c4e05"},"headline":"Asiatische M\u00e4rkte bleiben unter Druck, europ\u00e4ische Futures wackeln &amp; US-Inflationsdaten werden erwartet","datePublished":"2024-01-08T10:45:45+00:00","dateModified":"2024-01-08T10:52:34+00:00","mainEntityOfPage":{"@id":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/asiatische-maerkte-bleiben-unter-druck-europaeische-futures-wackeln-us-inflationsdaten-werden-erwartet\/"},"wordCount":565,"commentCount":0,"image":{"@id":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/asiatische-maerkte-bleiben-unter-druck-europaeische-futures-wackeln-us-inflationsdaten-werden-erwartet\/#primaryimage"},"thumbnailUrl":"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/10\/images-36.jpg","articleSection":["T\u00e4glicher Markt\u00fcberblick"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/asiatische-maerkte-bleiben-unter-druck-europaeische-futures-wackeln-us-inflationsdaten-werden-erwartet\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/asiatische-maerkte-bleiben-unter-druck-europaeische-futures-wackeln-us-inflationsdaten-werden-erwartet\/","url":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/asiatische-maerkte-bleiben-unter-druck-europaeische-futures-wackeln-us-inflationsdaten-werden-erwartet\/","name":"Asiatische M\u00e4rkte bleiben unter Druck, europ\u00e4ische Futures wackeln &amp; US-Inflationsdaten werden erwartet - SmartTrader","isPartOf":{"@id":"https:\/\/smarttrader.community\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/asiatische-maerkte-bleiben-unter-druck-europaeische-futures-wackeln-us-inflationsdaten-werden-erwartet\/#primaryimage"},"image":{"@id":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/asiatische-maerkte-bleiben-unter-druck-europaeische-futures-wackeln-us-inflationsdaten-werden-erwartet\/#primaryimage"},"thumbnailUrl":"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/10\/images-36.jpg","datePublished":"2024-01-08T10:45:45+00:00","dateModified":"2024-01-08T10:52:34+00:00","author":{"@id":"https:\/\/smarttrader.community\/de\/#\/schema\/person\/bfe0c456aafbdc04b9707983e59c4e05"},"description":"Asiatische M\u00e4rkte bleiben unter Druck, europ\u00e4ische Futures wackeln & US-Inflationsdaten werden erwartet. Globale Investoren beobachten...","breadcrumb":{"@id":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/asiatische-maerkte-bleiben-unter-druck-europaeische-futures-wackeln-us-inflationsdaten-werden-erwartet\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/asiatische-maerkte-bleiben-unter-druck-europaeische-futures-wackeln-us-inflationsdaten-werden-erwartet\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/asiatische-maerkte-bleiben-unter-druck-europaeische-futures-wackeln-us-inflationsdaten-werden-erwartet\/#primaryimage","url":"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/10\/images-36.jpg","contentUrl":"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/10\/images-36.jpg","width":800,"height":500},{"@type":"BreadcrumbList","@id":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/asiatische-maerkte-bleiben-unter-druck-europaeische-futures-wackeln-us-inflationsdaten-werden-erwartet\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/smarttrader.community\/de\/"},{"@type":"ListItem","position":2,"name":"Asiatische M\u00e4rkte bleiben unter Druck, europ\u00e4ische Futures wackeln &amp; US-Inflationsdaten werden erwartet"}]},{"@type":"WebSite","@id":"https:\/\/smarttrader.community\/de\/#website","url":"https:\/\/smarttrader.community\/de\/","name":"SmartTrader","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/smarttrader.community\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/smarttrader.community\/de\/#\/schema\/person\/bfe0c456aafbdc04b9707983e59c4e05","name":"SmartTrader Analyst Team","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/03\/admin_avatar_3-96x96.png","url":"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/03\/admin_avatar_3-96x96.png","contentUrl":"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/03\/admin_avatar_3-96x96.png","caption":"SmartTrader Analyst Team"},"sameAs":["https:\/\/smarttrader.community"],"url":"https:\/\/smarttrader.community\/de\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/posts\/31924","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/comments?post=31924"}],"version-history":[{"count":0,"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/posts\/31924\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/media\/23060"}],"wp:attachment":[{"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/media?parent=31924"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/categories?post=31924"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/tags?post=31924"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}