{"id":32436,"date":"2024-01-18T14:10:08","date_gmt":"2024-01-18T14:10:08","guid":{"rendered":"https:\/\/smarttrader.community\/?p=32436"},"modified":"2024-01-18T14:15:35","modified_gmt":"2024-01-18T14:15:35","slug":"investoren-wagen-sich-erstmal-zurueck-aktien-steigen-vor-allem-chip-aktien","status":"publish","type":"post","link":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/investoren-wagen-sich-erstmal-zurueck-aktien-steigen-vor-allem-chip-aktien\/","title":{"rendered":"Investoren wagen sich erstmal zur\u00fcck; Aktien steigen vor allem Chip-Aktien"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Im <strong>fr\u00fchen Donnerstagshandel stiegen die Aktien und US-Futures<\/strong>, da die Investoren wieder in Aktien investierten und sich vorerst mit der Erkenntnis abfanden, dass sich die <strong>Zinssenkungen \u00fcber das erste Quartal hinaus verz\u00f6gern k\u00f6nnten<\/strong>. Die globalen Aktien <strong>starteten positiv<\/strong>, wobei die asiatischen Aktien nach den gestrigen starken Verlusten in China\/Hongkong stiegen &#8211; ein starker <strong>Anstieg im ETF-Handel deutete jedoch auf eine Beteiligung staatlicher (chinesischer) Fonds <\/strong>hin. Die europ\u00e4ischen Aktien <strong>werden positiv gehandelt<\/strong>, was in den USA in diesem Jahr an jedem Tag zu einem positiven Abschluss gef\u00fchrt hat.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die <strong>Chiphersteller <\/strong>haben sich wieder einmal besser entwickelt, auch weil <strong>Taiwan Semiconductor Manufacturing<\/strong>, ein wichtiger Zulieferer von Apple und Nvidia, angek\u00fcndigt hat, dass sie in diesem Quartal wieder ein solides Wachstum erwarten. <strong>Microchip Technology, AMD<\/strong> und <strong>Applied Materials <\/strong>liegen alle mehr als 2 % im Plus &#8211; und auch die Schwergewichte Apple und Nvidia haben im vorb\u00f6rslichen Handel rund 1,7 % zugelegt, was zu einer kr\u00e4ftigen Erholung an der Wall Street f\u00fchrte. Auch die Aktien der Chipindustrie in Europa sind gestiegen &#8211; wie z.B. die niederl\u00e4ndische <strong>ASML<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Auch <strong>Boeing<\/strong>, einer der schlechtesten Performer in diesem Jahr bzw. in den vergangenen Sitzungen, notiert deutlich im gr\u00fcnen Bereich, nachdem die j\u00fcngste indische Fluggesellschaft 150 ihrer problembehafteten 737 Max-Jets bestellt hat.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Auch wenn sich die <strong>Aussichten auf Zinssenkungen verschlechtert haben<\/strong>, sind die Investoren insgesamt immer noch eher optimistisch, dass <strong>Zinssenkungen im Laufe des Jahres die Aktienm\u00e4rkte st\u00fctzen werden<\/strong>. Auch die Unterst\u00fctzung von Aktien durch chinesische Staatsfonds hat der <strong>Risikostimmung (vorerst) gut getan<\/strong>, ebenso wie eine leichte Erholung bei Anleihen (die dazu f\u00fchrte, dass die Renditen einen Teil der gestrigen starken Gewinne wieder abgaben).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Der <strong>USD gab auch einen Teil seines viert\u00e4gigen Aufw\u00e4rtstrends wieder ab &#8211; bleibt aber insgesamt gefragt.<\/strong> Ich sehe die Renditen jedoch nach wie vor gest\u00fctzt und weitere Zuw\u00e4chse &#8211; was bedeutet, dass Wachstumsaktien und andere renditesensitive Anlagen (wie Gold) wieder unter Druck geraten werden.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Niedriger als erwartet ausgefallene Erstantr\u00e4ge auf Arbeitslosenunterst\u00fctzung<\/strong> k\u00f6nnten jedoch die Hoffnung auf eine <strong>Zinssenkung weiter d\u00e4mpfen<\/strong> und werden wahrscheinlich dazu f\u00fchren, dass der USD nach einem schwachen asiatischen Handelstag Unterst\u00fctzung findet bzw. zur\u00fcckgeht.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die <strong>\u00d6lpreise <\/strong>sind nach einem weiteren Erholungsversuch infolge der anhaltenden Spannungen im Nahen Osten &#8211; jetzt mit dem <strong>R\u00fcckschlag der pakistanischen Armee gegen den Iran<\/strong> &#8211; kaum ver\u00e4ndert. Zwar haben die Spannungen in der Region (vor allem im Roten Meer) die weltweite Schifffahrt vorerst &#8222;lahmgelegt&#8220; und zu einigen Unterbrechungen gef\u00fchrt, aber die <strong>Nachfrageaussichten sind nach wie vor fragil. Der Goldpreis stieg leicht<\/strong> an und fand wie vorhergesagt Unterst\u00fctzung oberhalb von $2.000 und profitierte von den Renditen, die einen Teil der j\u00fcngsten Gewinne wieder abgaben. <strong>Gold bleibt unter Druck<\/strong>, vor allem wenn sich die <strong>Renditen stabilisieren bzw. wieder ansteigen. Bitcoin<\/strong> wird weiterhin in einer engen Spanne gehandelt und bekam Gegenwind von JPMorgan CEO Dimon, der sagte, er wolle sich nicht in Bitcoin engagieren. Ich stimme Dimon zwar zu, dass Bitcoin nur begrenzt einsetzbar ist, aber die steigende Nachfrage nach Bitcoin und die bevorstehenden Zinssenkungen werden wahrscheinlich zu einem (weiteren) guten Jahr f\u00fcr die Kryptow\u00e4hrung f\u00fchren.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">\ud83d\udc41 ROB'S MARKET OVERVIEW:<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><em>January 18, 2024<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\ud83c\udf10\/\ud83c\uddfa\ud83c\uddf8 <strong>Globale\/US-M\u00e4rkte<\/strong> <em>\u2197\ufe0f\/\u2195\ufe0f\/\u27a1\ufe0f (breite Kaufinteressen mit mehr Vorsicht in der zweiten H\u00e4lfte)<br>Zyklische Aktien \u2198\ufe0f<br>Technologie-\/Wachstumsaktien \u2197\ufe0f\/\u2195\ufe0f\/\u27a1\ufe0f (Chip-Aktien weiterhin \u00fcberlegen)<br>Finanzaktien \u27a1\ufe0f\/\u2198\ufe0f<br>Defensivaktien \u27a1\ufe0f<br>Energieaktien \u27a1\ufe0f<br>Rohstoffaktien \u27a1\ufe0f\/\u2198\ufe0f<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\ud83d\udcb1 <strong>Devisenmarkt<\/strong><br><em>USD \u27a1\ufe0f\/\u2197\ufe0f (USD bleibt gefragt \/ wird weiterhin von sinkenden Zinssenkungserwartungen profitieren)<br>GBP \u2197\ufe0f\/\u27a1\ufe0f<br>EUR \u27a1\ufe0f (aufgrund reduzierter Zinssenkungserwartungen)<br>JPY \u2197\ufe0f\/\u2198\ufe0f<br>AUD, CAD \u27a1\ufe0f\/\u2198\ufe0f<br>CHF \u2198\ufe0f<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u2692 <strong>Rohstoffm\u00e4rkte <\/strong><em>\u2195\ufe0f\/\u2198\ufe0f<br>\u00d6lpreise \u2197\ufe0f\/\u2198\ufe0f<br>Erdgaspreise \u2195\ufe0f\/\u2198\ufe0f<br>Metallpreise \u2195\ufe0f\/\u2198\ufe0f<br>Gold \u2195\ufe0f (Gold wahrscheinlich vorerst mit Unterst\u00fctzung im Bereich von $2.000 &#8211; $2.010)<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u26a1\ufe0f<strong>Kryptow\u00e4hrungen <\/strong><em>\u27a1\ufe0f (derzeit seitw\u00e4rts &#8211; keine Katalysatoren; potenziell leichte Gewinne bei tempor\u00e4r verbessertem Risikosentiment)<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>(*\u2197\ufe0f bullisch, \u2198\ufe0f b\u00e4risch, \u27a1\ufe0f seitw\u00e4rts \/ stabil, \u2195\ufe0f gemischt \/ volatil)<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dein <strong>Robert<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Im fr\u00fchen Donnerstagshandel stiegen die Aktien und US-Futures, da die Investoren wieder in Aktien investierten und sich vorerst mit der&#8230;<\/p>\n","protected":false},"author":663,"featured_media":32434,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","pmpro_default_level":"0","_daextam_enable_autolinks":"1","footnotes":""},"categories":[117],"tags":[],"class_list":["post-32436","post","type-post","status-publish","format-standard","has-post-thumbnail","category-taegliche-aktualisierungen","pmpro-has-access"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Investoren wagen sich erstmal zur\u00fcck; Aktien steigen vor allem Chip-Aktien - SmartTrader<\/title>\n<meta name=\"description\" content=\"Investoren wagen sich erstmal zur\u00fcck; Aktien steigen vor allem Chip-Aktien. Im fr\u00fchen Donnerstagshandel stiegen die Aktien und US-Futures...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/investoren-wagen-sich-erstmal-zurueck-aktien-steigen-vor-allem-chip-aktien\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Investoren wagen sich erstmal zur\u00fcck; Aktien steigen vor allem Chip-Aktien - SmartTrader\" \/>\n<meta property=\"og:description\" content=\"Investoren wagen sich erstmal zur\u00fcck; Aktien steigen vor allem Chip-Aktien. Im fr\u00fchen Donnerstagshandel stiegen die Aktien und US-Futures...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/investoren-wagen-sich-erstmal-zurueck-aktien-steigen-vor-allem-chip-aktien\/\" \/>\n<meta property=\"og:site_name\" content=\"SmartTrader\" \/>\n<meta property=\"article:published_time\" content=\"2024-01-18T14:10:08+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-01-18T14:15:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/smarttrader.community\/wp-content\/uploads\/2024\/01\/18.01.2024_TITLE_Artboard-1-copy-9.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1081\" \/>\n\t<meta property=\"og:image:height\" content=\"721\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Robert Lindner\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Robert Lindner\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taegliche-aktualisierungen\\\/investoren-wagen-sich-erstmal-zurueck-aktien-steigen-vor-allem-chip-aktien\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taegliche-aktualisierungen\\\/investoren-wagen-sich-erstmal-zurueck-aktien-steigen-vor-allem-chip-aktien\\\/\"},\"author\":{\"name\":\"Robert Lindner\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/#\\\/schema\\\/person\\\/4f791355f3f400fd2dd91d9c57c4c067\"},\"headline\":\"Investoren wagen sich erstmal zur\u00fcck; Aktien steigen vor allem Chip-Aktien\",\"datePublished\":\"2024-01-18T14:10:08+00:00\",\"dateModified\":\"2024-01-18T14:15:35+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taegliche-aktualisierungen\\\/investoren-wagen-sich-erstmal-zurueck-aktien-steigen-vor-allem-chip-aktien\\\/\"},\"wordCount\":630,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taegliche-aktualisierungen\\\/investoren-wagen-sich-erstmal-zurueck-aktien-steigen-vor-allem-chip-aktien\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/18.01.2024_TITLE_Artboard-1-copy-9.webp\",\"articleSection\":[\"T\u00e4gliche Aktualisierungen\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/smarttrader.community\\\/de\\\/taegliche-aktualisierungen\\\/investoren-wagen-sich-erstmal-zurueck-aktien-steigen-vor-allem-chip-aktien\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taegliche-aktualisierungen\\\/investoren-wagen-sich-erstmal-zurueck-aktien-steigen-vor-allem-chip-aktien\\\/\",\"url\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taegliche-aktualisierungen\\\/investoren-wagen-sich-erstmal-zurueck-aktien-steigen-vor-allem-chip-aktien\\\/\",\"name\":\"Investoren wagen sich erstmal zur\u00fcck; Aktien steigen vor allem Chip-Aktien - SmartTrader\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taegliche-aktualisierungen\\\/investoren-wagen-sich-erstmal-zurueck-aktien-steigen-vor-allem-chip-aktien\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taegliche-aktualisierungen\\\/investoren-wagen-sich-erstmal-zurueck-aktien-steigen-vor-allem-chip-aktien\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/18.01.2024_TITLE_Artboard-1-copy-9.webp\",\"datePublished\":\"2024-01-18T14:10:08+00:00\",\"dateModified\":\"2024-01-18T14:15:35+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/#\\\/schema\\\/person\\\/4f791355f3f400fd2dd91d9c57c4c067\"},\"description\":\"Investoren wagen sich erstmal zur\u00fcck; Aktien steigen vor allem Chip-Aktien. Im fr\u00fchen Donnerstagshandel stiegen die Aktien und US-Futures...\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taegliche-aktualisierungen\\\/investoren-wagen-sich-erstmal-zurueck-aktien-steigen-vor-allem-chip-aktien\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/smarttrader.community\\\/de\\\/taegliche-aktualisierungen\\\/investoren-wagen-sich-erstmal-zurueck-aktien-steigen-vor-allem-chip-aktien\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taegliche-aktualisierungen\\\/investoren-wagen-sich-erstmal-zurueck-aktien-steigen-vor-allem-chip-aktien\\\/#primaryimage\",\"url\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/18.01.2024_TITLE_Artboard-1-copy-9.webp\",\"contentUrl\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/18.01.2024_TITLE_Artboard-1-copy-9.webp\",\"width\":1081,\"height\":721},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taegliche-aktualisierungen\\\/investoren-wagen-sich-erstmal-zurueck-aktien-steigen-vor-allem-chip-aktien\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Investoren wagen sich erstmal zur\u00fcck; Aktien steigen vor allem Chip-Aktien\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/\",\"name\":\"SmartTrader\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/#\\\/schema\\\/person\\\/4f791355f3f400fd2dd91d9c57c4c067\",\"name\":\"Robert Lindner\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/robert-lindner_avatar_1-96x96.png\",\"url\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/robert-lindner_avatar_1-96x96.png\",\"contentUrl\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/robert-lindner_avatar_1-96x96.png\",\"caption\":\"Robert Lindner\"},\"sameAs\":[\"https:\\\/\\\/wwww.smarttrader.community\\\/\"],\"url\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/author\\\/robert_smarttrader\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Investoren wagen sich erstmal zur\u00fcck; Aktien steigen vor allem Chip-Aktien - SmartTrader","description":"Investoren wagen sich erstmal zur\u00fcck; Aktien steigen vor allem Chip-Aktien. Im fr\u00fchen Donnerstagshandel stiegen die Aktien und US-Futures...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/investoren-wagen-sich-erstmal-zurueck-aktien-steigen-vor-allem-chip-aktien\/","og_locale":"de_DE","og_type":"article","og_title":"Investoren wagen sich erstmal zur\u00fcck; Aktien steigen vor allem Chip-Aktien - SmartTrader","og_description":"Investoren wagen sich erstmal zur\u00fcck; Aktien steigen vor allem Chip-Aktien. Im fr\u00fchen Donnerstagshandel stiegen die Aktien und US-Futures...","og_url":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/investoren-wagen-sich-erstmal-zurueck-aktien-steigen-vor-allem-chip-aktien\/","og_site_name":"SmartTrader","article_published_time":"2024-01-18T14:10:08+00:00","article_modified_time":"2024-01-18T14:15:35+00:00","og_image":[{"width":1081,"height":721,"url":"https:\/\/smarttrader.community\/wp-content\/uploads\/2024\/01\/18.01.2024_TITLE_Artboard-1-copy-9.webp","type":"image\/webp"}],"author":"Robert Lindner","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Robert Lindner","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/investoren-wagen-sich-erstmal-zurueck-aktien-steigen-vor-allem-chip-aktien\/#article","isPartOf":{"@id":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/investoren-wagen-sich-erstmal-zurueck-aktien-steigen-vor-allem-chip-aktien\/"},"author":{"name":"Robert Lindner","@id":"https:\/\/smarttrader.community\/de\/#\/schema\/person\/4f791355f3f400fd2dd91d9c57c4c067"},"headline":"Investoren wagen sich erstmal zur\u00fcck; Aktien steigen vor allem Chip-Aktien","datePublished":"2024-01-18T14:10:08+00:00","dateModified":"2024-01-18T14:15:35+00:00","mainEntityOfPage":{"@id":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/investoren-wagen-sich-erstmal-zurueck-aktien-steigen-vor-allem-chip-aktien\/"},"wordCount":630,"commentCount":0,"image":{"@id":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/investoren-wagen-sich-erstmal-zurueck-aktien-steigen-vor-allem-chip-aktien\/#primaryimage"},"thumbnailUrl":"https:\/\/smarttrader.community\/wp-content\/uploads\/2024\/01\/18.01.2024_TITLE_Artboard-1-copy-9.webp","articleSection":["T\u00e4gliche Aktualisierungen"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/investoren-wagen-sich-erstmal-zurueck-aktien-steigen-vor-allem-chip-aktien\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/investoren-wagen-sich-erstmal-zurueck-aktien-steigen-vor-allem-chip-aktien\/","url":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/investoren-wagen-sich-erstmal-zurueck-aktien-steigen-vor-allem-chip-aktien\/","name":"Investoren wagen sich erstmal zur\u00fcck; Aktien steigen vor allem Chip-Aktien - SmartTrader","isPartOf":{"@id":"https:\/\/smarttrader.community\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/investoren-wagen-sich-erstmal-zurueck-aktien-steigen-vor-allem-chip-aktien\/#primaryimage"},"image":{"@id":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/investoren-wagen-sich-erstmal-zurueck-aktien-steigen-vor-allem-chip-aktien\/#primaryimage"},"thumbnailUrl":"https:\/\/smarttrader.community\/wp-content\/uploads\/2024\/01\/18.01.2024_TITLE_Artboard-1-copy-9.webp","datePublished":"2024-01-18T14:10:08+00:00","dateModified":"2024-01-18T14:15:35+00:00","author":{"@id":"https:\/\/smarttrader.community\/de\/#\/schema\/person\/4f791355f3f400fd2dd91d9c57c4c067"},"description":"Investoren wagen sich erstmal zur\u00fcck; Aktien steigen vor allem Chip-Aktien. Im fr\u00fchen Donnerstagshandel stiegen die Aktien und US-Futures...","breadcrumb":{"@id":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/investoren-wagen-sich-erstmal-zurueck-aktien-steigen-vor-allem-chip-aktien\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/investoren-wagen-sich-erstmal-zurueck-aktien-steigen-vor-allem-chip-aktien\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/investoren-wagen-sich-erstmal-zurueck-aktien-steigen-vor-allem-chip-aktien\/#primaryimage","url":"https:\/\/smarttrader.community\/wp-content\/uploads\/2024\/01\/18.01.2024_TITLE_Artboard-1-copy-9.webp","contentUrl":"https:\/\/smarttrader.community\/wp-content\/uploads\/2024\/01\/18.01.2024_TITLE_Artboard-1-copy-9.webp","width":1081,"height":721},{"@type":"BreadcrumbList","@id":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/investoren-wagen-sich-erstmal-zurueck-aktien-steigen-vor-allem-chip-aktien\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/smarttrader.community\/de\/"},{"@type":"ListItem","position":2,"name":"Investoren wagen sich erstmal zur\u00fcck; Aktien steigen vor allem Chip-Aktien"}]},{"@type":"WebSite","@id":"https:\/\/smarttrader.community\/de\/#website","url":"https:\/\/smarttrader.community\/de\/","name":"SmartTrader","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/smarttrader.community\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/smarttrader.community\/de\/#\/schema\/person\/4f791355f3f400fd2dd91d9c57c4c067","name":"Robert Lindner","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/05\/robert-lindner_avatar_1-96x96.png","url":"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/05\/robert-lindner_avatar_1-96x96.png","contentUrl":"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/05\/robert-lindner_avatar_1-96x96.png","caption":"Robert Lindner"},"sameAs":["https:\/\/wwww.smarttrader.community\/"],"url":"https:\/\/smarttrader.community\/de\/author\/robert_smarttrader\/"}]}},"_links":{"self":[{"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/posts\/32436","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/users\/663"}],"replies":[{"embeddable":true,"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/comments?post=32436"}],"version-history":[{"count":0,"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/posts\/32436\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/media\/32434"}],"wp:attachment":[{"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/media?parent=32436"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/categories?post=32436"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/tags?post=32436"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}