{"id":33091,"date":"2024-02-06T14:10:50","date_gmt":"2024-02-06T14:10:50","guid":{"rendered":"https:\/\/smarttrader.community\/?p=33091"},"modified":"2024-02-06T14:17:13","modified_gmt":"2024-02-06T14:17:13","slug":"maerkte-bewegen-sich-seitwaerts-trader-bewerten-die-zinsaussichten","status":"publish","type":"post","link":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/maerkte-bewegen-sich-seitwaerts-trader-bewerten-die-zinsaussichten\/","title":{"rendered":"M\u00e4rkte bewegen sich seitw\u00e4rts; Trader bewerten die Zinsaussichten"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Die <strong>globalen Anleihem\u00e4rkte<\/strong> haben sich <strong>beruhigt <\/strong>nach dem gr\u00f6\u00dften zweit\u00e4gigen Ausverkauf seit Monaten, ausgel\u00f6st durch die <strong>sehr starken die NFP-Daten<\/strong> und nachdem die Fed die M\u00f6glichkeit einer <strong>Zinssenkung im M\u00e4rz als sehr unwahrscheinlich ansieht<\/strong>. Die globalen Aktienm\u00e4rkte sind weiterhin <strong>uneinheitlich <\/strong>und suchen nach weiteren Anhaltspunkten.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die <strong>Aktienmarktrallye legt derzeit eine Pause ein<\/strong>, da die Investoren die <strong>Zinssenkungserwartungen <\/strong>neu bewerten. Wir sehen die M\u00e4rkte in Europa wenig ver\u00e4ndert, aber befl\u00fcgelt durch die starken Gewinne von BP (+7%), nachdem der \u00d6l- und Gasriese angek\u00fcndigt hatte, in der ersten Jahresh\u00e4lfte Aktien im Wert von $3,5 Milliarden zur\u00fcckzukaufen. Die <strong>UBS Group<\/strong> gab nach, nachdem ihre Gewinne die Analysten entt\u00e4uschten, w\u00e4hrend der deutsche Chipkonzern Infineon Verluste hinnehmen musste, nachdem er von einer sinkenden Nachfrage seitens der industriellen Abnehmer sprach. Palantir Technologies stieg im vorb\u00f6rslichen Handel um mehr als 20 %, nachdem das Big-Data-Unternehmen aufgrund der <strong>Nachfrage nach Produkten der k\u00fcnstlichen Intelligenz<\/strong> einen h\u00f6her als erwarteten Gewinnausblick gab.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die <strong>M\u00e4rkte sind weiterhin auf der Suche nach mehr Klarheit \u00fcber bevorstehende Zinssenkungen<\/strong>. Eine Reihe von <strong>Fed-Vertretern<\/strong> wird diese Woche eine Rede halten und wahrscheinlich wiederholen, dass die Fed keinen Druck hat, die Zinsen zu senken, und dass eine abwartende Haltung eingenommen wird; au\u00dferdem k\u00f6nnten sie sich zu den Risiken \u00e4u\u00dfern, dass die Inflation auf einem hohen Niveau verharrt.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die <strong>M\u00e4rkte in Asien bewegen sich etwas mehr<\/strong> (meist positiv), nachdem <strong>Peking weitere energische Ma\u00dfnahmen zur Beendigung der B\u00f6rsenkrise ergriffen hat.<\/strong> Ein Gro\u00dfteil der Gewinne ist jedoch auf <strong>staatliche K\u00e4ufe<\/strong> zur\u00fcckzuf\u00fchren. Auch wenn Peking deutliche Anzeichen daf\u00fcr zeigt, dass es entschlossen ist, die chinesische Wirtschaft und den sehr schwachen Aktienmarkt zu st\u00fctzen &#8211; ich erwarte <strong>nur vor\u00fcbergehenden R\u00fcckenwind<\/strong>, da ausl\u00e4ndische Investoren den chinesischen Aktienmarkt weiterhin meiden.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die Ma\u00dfnahmen Pekings f\u00fchrten jedoch zu <strong>starken Kursgewinnen an den chinesischen M\u00e4rkten<\/strong>, wie z. B. beim Hang Seng China Enterprises Index, der um fast 5 % zulegte. Auch andere Schwellenl\u00e4nderaktien verzeichneten solide Gewinne.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Der <strong>S&P 500 und der Nasdaq 100 legten ebenfalls zu<\/strong>, wobei die <strong>Tech-Werte die Gewinne <\/strong>anf\u00fchrten. Die <strong>Markttiefe ist jedoch nach wie vor schlecht<\/strong> &#8211; die meisten Aktien verloren in dieser Woche an Wert.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Da wir eine <strong>anhaltende Seitw\u00e4rtsbewegung <\/strong>beobachten, <strong>steigt das Risiko einer Korrektur<\/strong>. Der <strong>Aufschwung in China wird wahrscheinlich nur von kurzer Dauer<\/strong> sein, hat aber auch dazu beigetragen, dass die <strong>\u00d6lpreise <\/strong>einen Boden gefunden haben. Das Hauptaugenmerk wird auf den Renditen liegen. Nach zwei Tagen mit sehr starken Zuw\u00e4chsen sehen wir, dass sie sich derzeit auf hohem Niveau stabilisieren &#8211; was weiterhin <strong>Druck auf Aktien und Gold<\/strong> aus\u00fcbt.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">\ud83d\udc41 ROB'S MARKET OVERVIEW:<\/h3>\n\n\n\n<ol class=\"wp-block-list\" start=\"6\">\n<li><em>Februar 2024<\/em><\/li>\n<\/ol>\n\n\n\n<p class=\"wp-block-paragraph\">\ud83c\udf10\/\ud83c\uddfa\ud83c\uddf8<strong> Globale\/US-M\u00e4rkte<\/strong> \u2195\ufe0f<br><em>Zyklische Aktien \u2197\ufe0f\/\u2195\ufe0f<br>Technologie-\/Wachstumsaktien \u2197\ufe0f\/\u2195\ufe0f\/\u2198\ufe0f (fr\u00fche Gewinne gefolgt von leichten Gewinnmitnahme; Big Tech (- Tesla) in Outperformance)<br>Finanzaktien \u2197\ufe0f\/\u27a1\ufe0f<br>Defensivaktien \u27a1\ufe0f<br>Energieaktien \u27a1\ufe0f\/\u2198\ufe0f<br>Rohstoff-Aktien \u27a1\ufe0f\/\u2198\ufe0f<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\ud83d\udcb1 <strong>Forex<\/strong><br><em>GBP, AUD \u2197\ufe0f\/\u27a1\ufe0f (leichte Erholung nach j\u00fcngsten Verlusten)<br>USD \u27a1\ufe0f\/\u2197\ufe0f (meist seitw\u00e4rts, bleibt aber gefragt)<br>JPY \u27a1\ufe0f\/\u2197\ufe0f<br>CAD \u27a1\ufe0f<br>EUR, CHF \u27a1\ufe0f\/\u2198\ufe0f<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u2692 <strong>Rohstoffm\u00e4rkte<\/strong> \u2195\ufe0f<br><em>\u00d6lpreise \u2197\ufe0f\/\u27a1\ufe0f (leichte Erholung nach j\u00fcngsten starken Verlusten; bleibt seitw\u00e4rts)<br>Erdgaspreise \u2198\ufe0f\/\u2195\ufe0f<br>Metallpreise \u27a1\ufe0f<br>Gold \u2197\ufe0f\/\u27a1\ufe0f\/\u2198\ufe0f (fr\u00fche leichte Erholungsgewinne; Gold bleibt aufgrund hoher Renditen unter Druck)<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u26a1\ufe0f<strong>Kryptos <\/strong><em>\u2198\ufe0f\/\u27a1\ufe0f (meist seitw\u00e4rts &#8211; Bereich $42.0K &#8211; $43.5K \/ festgefahren)<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>(*\u2197\ufe0f bullisch, \u2198\ufe0f b\u00e4risch, \u27a1\ufe0f seitw\u00e4rts \/ stabil, \u2195\ufe0f gemischt \/ volatil)<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dein <strong>Robert<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die globalen Anleihem\u00e4rkte haben sich beruhigt nach dem gr\u00f6\u00dften zweit\u00e4gigen Ausverkauf seit Monaten, ausgel\u00f6st durch die sehr starken die NFP-Daten&#8230;<\/p>\n","protected":false},"author":663,"featured_media":33089,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","pmpro_default_level":"0","_daextam_enable_autolinks":"1","footnotes":""},"categories":[117],"tags":[],"class_list":["post-33091","post","type-post","status-publish","format-standard","has-post-thumbnail","category-taegliche-aktualisierungen","pmpro-has-access"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>M\u00e4rkte bewegen sich seitw\u00e4rts; Trader bewerten die Zinsaussichten - SmartTrader<\/title>\n<meta name=\"description\" content=\"M\u00e4rkte bewegen sich seitw\u00e4rts; Trader bewerten die Zinsaussichten. Die globalen Anleihem\u00e4rkte haben sich beruhigt nach dem gr\u00f6\u00dften...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/maerkte-bewegen-sich-seitwaerts-trader-bewerten-die-zinsaussichten\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"M\u00e4rkte bewegen sich seitw\u00e4rts; Trader bewerten die Zinsaussichten - SmartTrader\" \/>\n<meta property=\"og:description\" content=\"M\u00e4rkte bewegen sich seitw\u00e4rts; Trader bewerten die Zinsaussichten. Die globalen Anleihem\u00e4rkte haben sich beruhigt nach dem gr\u00f6\u00dften...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/maerkte-bewegen-sich-seitwaerts-trader-bewerten-die-zinsaussichten\/\" \/>\n<meta property=\"og:site_name\" content=\"SmartTrader\" \/>\n<meta property=\"article:published_time\" content=\"2024-02-06T14:10:50+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-02-06T14:17:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/smarttrader.community\/wp-content\/uploads\/2024\/02\/06.02.2024_TITLE_Artboard-1-copy-9.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1081\" \/>\n\t<meta property=\"og:image:height\" content=\"721\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Robert Lindner\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Robert Lindner\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taegliche-aktualisierungen\\\/maerkte-bewegen-sich-seitwaerts-trader-bewerten-die-zinsaussichten\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taegliche-aktualisierungen\\\/maerkte-bewegen-sich-seitwaerts-trader-bewerten-die-zinsaussichten\\\/\"},\"author\":{\"name\":\"Robert Lindner\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/#\\\/schema\\\/person\\\/4f791355f3f400fd2dd91d9c57c4c067\"},\"headline\":\"M\u00e4rkte bewegen sich seitw\u00e4rts; Trader bewerten die Zinsaussichten\",\"datePublished\":\"2024-02-06T14:10:50+00:00\",\"dateModified\":\"2024-02-06T14:17:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taegliche-aktualisierungen\\\/maerkte-bewegen-sich-seitwaerts-trader-bewerten-die-zinsaussichten\\\/\"},\"wordCount\":553,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taegliche-aktualisierungen\\\/maerkte-bewegen-sich-seitwaerts-trader-bewerten-die-zinsaussichten\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/06.02.2024_TITLE_Artboard-1-copy-9.webp\",\"articleSection\":[\"T\u00e4gliche Aktualisierungen\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/smarttrader.community\\\/de\\\/taegliche-aktualisierungen\\\/maerkte-bewegen-sich-seitwaerts-trader-bewerten-die-zinsaussichten\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taegliche-aktualisierungen\\\/maerkte-bewegen-sich-seitwaerts-trader-bewerten-die-zinsaussichten\\\/\",\"url\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taegliche-aktualisierungen\\\/maerkte-bewegen-sich-seitwaerts-trader-bewerten-die-zinsaussichten\\\/\",\"name\":\"M\u00e4rkte bewegen sich seitw\u00e4rts; Trader bewerten die Zinsaussichten - SmartTrader\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taegliche-aktualisierungen\\\/maerkte-bewegen-sich-seitwaerts-trader-bewerten-die-zinsaussichten\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taegliche-aktualisierungen\\\/maerkte-bewegen-sich-seitwaerts-trader-bewerten-die-zinsaussichten\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/06.02.2024_TITLE_Artboard-1-copy-9.webp\",\"datePublished\":\"2024-02-06T14:10:50+00:00\",\"dateModified\":\"2024-02-06T14:17:13+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/#\\\/schema\\\/person\\\/4f791355f3f400fd2dd91d9c57c4c067\"},\"description\":\"M\u00e4rkte bewegen sich seitw\u00e4rts; Trader bewerten die Zinsaussichten. Die globalen Anleihem\u00e4rkte haben sich beruhigt nach dem gr\u00f6\u00dften...\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taegliche-aktualisierungen\\\/maerkte-bewegen-sich-seitwaerts-trader-bewerten-die-zinsaussichten\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/smarttrader.community\\\/de\\\/taegliche-aktualisierungen\\\/maerkte-bewegen-sich-seitwaerts-trader-bewerten-die-zinsaussichten\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taegliche-aktualisierungen\\\/maerkte-bewegen-sich-seitwaerts-trader-bewerten-die-zinsaussichten\\\/#primaryimage\",\"url\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/06.02.2024_TITLE_Artboard-1-copy-9.webp\",\"contentUrl\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/06.02.2024_TITLE_Artboard-1-copy-9.webp\",\"width\":1081,\"height\":721},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taegliche-aktualisierungen\\\/maerkte-bewegen-sich-seitwaerts-trader-bewerten-die-zinsaussichten\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"M\u00e4rkte bewegen sich seitw\u00e4rts; Trader bewerten die Zinsaussichten\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/\",\"name\":\"SmartTrader\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/#\\\/schema\\\/person\\\/4f791355f3f400fd2dd91d9c57c4c067\",\"name\":\"Robert Lindner\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/robert-lindner_avatar_1-96x96.png\",\"url\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/robert-lindner_avatar_1-96x96.png\",\"contentUrl\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/robert-lindner_avatar_1-96x96.png\",\"caption\":\"Robert Lindner\"},\"sameAs\":[\"https:\\\/\\\/wwww.smarttrader.community\\\/\"],\"url\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/author\\\/robert_smarttrader\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"M\u00e4rkte bewegen sich seitw\u00e4rts; Trader bewerten die Zinsaussichten - SmartTrader","description":"M\u00e4rkte bewegen sich seitw\u00e4rts; Trader bewerten die Zinsaussichten. Die globalen Anleihem\u00e4rkte haben sich beruhigt nach dem gr\u00f6\u00dften...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/maerkte-bewegen-sich-seitwaerts-trader-bewerten-die-zinsaussichten\/","og_locale":"de_DE","og_type":"article","og_title":"M\u00e4rkte bewegen sich seitw\u00e4rts; Trader bewerten die Zinsaussichten - SmartTrader","og_description":"M\u00e4rkte bewegen sich seitw\u00e4rts; Trader bewerten die Zinsaussichten. Die globalen Anleihem\u00e4rkte haben sich beruhigt nach dem gr\u00f6\u00dften...","og_url":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/maerkte-bewegen-sich-seitwaerts-trader-bewerten-die-zinsaussichten\/","og_site_name":"SmartTrader","article_published_time":"2024-02-06T14:10:50+00:00","article_modified_time":"2024-02-06T14:17:13+00:00","og_image":[{"width":1081,"height":721,"url":"https:\/\/smarttrader.community\/wp-content\/uploads\/2024\/02\/06.02.2024_TITLE_Artboard-1-copy-9.webp","type":"image\/webp"}],"author":"Robert Lindner","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Robert Lindner","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/maerkte-bewegen-sich-seitwaerts-trader-bewerten-die-zinsaussichten\/#article","isPartOf":{"@id":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/maerkte-bewegen-sich-seitwaerts-trader-bewerten-die-zinsaussichten\/"},"author":{"name":"Robert Lindner","@id":"https:\/\/smarttrader.community\/de\/#\/schema\/person\/4f791355f3f400fd2dd91d9c57c4c067"},"headline":"M\u00e4rkte bewegen sich seitw\u00e4rts; Trader bewerten die Zinsaussichten","datePublished":"2024-02-06T14:10:50+00:00","dateModified":"2024-02-06T14:17:13+00:00","mainEntityOfPage":{"@id":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/maerkte-bewegen-sich-seitwaerts-trader-bewerten-die-zinsaussichten\/"},"wordCount":553,"commentCount":0,"image":{"@id":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/maerkte-bewegen-sich-seitwaerts-trader-bewerten-die-zinsaussichten\/#primaryimage"},"thumbnailUrl":"https:\/\/smarttrader.community\/wp-content\/uploads\/2024\/02\/06.02.2024_TITLE_Artboard-1-copy-9.webp","articleSection":["T\u00e4gliche Aktualisierungen"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/maerkte-bewegen-sich-seitwaerts-trader-bewerten-die-zinsaussichten\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/maerkte-bewegen-sich-seitwaerts-trader-bewerten-die-zinsaussichten\/","url":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/maerkte-bewegen-sich-seitwaerts-trader-bewerten-die-zinsaussichten\/","name":"M\u00e4rkte bewegen sich seitw\u00e4rts; Trader bewerten die Zinsaussichten - SmartTrader","isPartOf":{"@id":"https:\/\/smarttrader.community\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/maerkte-bewegen-sich-seitwaerts-trader-bewerten-die-zinsaussichten\/#primaryimage"},"image":{"@id":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/maerkte-bewegen-sich-seitwaerts-trader-bewerten-die-zinsaussichten\/#primaryimage"},"thumbnailUrl":"https:\/\/smarttrader.community\/wp-content\/uploads\/2024\/02\/06.02.2024_TITLE_Artboard-1-copy-9.webp","datePublished":"2024-02-06T14:10:50+00:00","dateModified":"2024-02-06T14:17:13+00:00","author":{"@id":"https:\/\/smarttrader.community\/de\/#\/schema\/person\/4f791355f3f400fd2dd91d9c57c4c067"},"description":"M\u00e4rkte bewegen sich seitw\u00e4rts; Trader bewerten die Zinsaussichten. Die globalen Anleihem\u00e4rkte haben sich beruhigt nach dem gr\u00f6\u00dften...","breadcrumb":{"@id":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/maerkte-bewegen-sich-seitwaerts-trader-bewerten-die-zinsaussichten\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/maerkte-bewegen-sich-seitwaerts-trader-bewerten-die-zinsaussichten\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/maerkte-bewegen-sich-seitwaerts-trader-bewerten-die-zinsaussichten\/#primaryimage","url":"https:\/\/smarttrader.community\/wp-content\/uploads\/2024\/02\/06.02.2024_TITLE_Artboard-1-copy-9.webp","contentUrl":"https:\/\/smarttrader.community\/wp-content\/uploads\/2024\/02\/06.02.2024_TITLE_Artboard-1-copy-9.webp","width":1081,"height":721},{"@type":"BreadcrumbList","@id":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/maerkte-bewegen-sich-seitwaerts-trader-bewerten-die-zinsaussichten\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/smarttrader.community\/de\/"},{"@type":"ListItem","position":2,"name":"M\u00e4rkte bewegen sich seitw\u00e4rts; Trader bewerten die Zinsaussichten"}]},{"@type":"WebSite","@id":"https:\/\/smarttrader.community\/de\/#website","url":"https:\/\/smarttrader.community\/de\/","name":"SmartTrader","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/smarttrader.community\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/smarttrader.community\/de\/#\/schema\/person\/4f791355f3f400fd2dd91d9c57c4c067","name":"Robert Lindner","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/05\/robert-lindner_avatar_1-96x96.png","url":"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/05\/robert-lindner_avatar_1-96x96.png","contentUrl":"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/05\/robert-lindner_avatar_1-96x96.png","caption":"Robert Lindner"},"sameAs":["https:\/\/wwww.smarttrader.community\/"],"url":"https:\/\/smarttrader.community\/de\/author\/robert_smarttrader\/"}]}},"_links":{"self":[{"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/posts\/33091","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/users\/663"}],"replies":[{"embeddable":true,"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/comments?post=33091"}],"version-history":[{"count":0,"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/posts\/33091\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/media\/33089"}],"wp:attachment":[{"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/media?parent=33091"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/categories?post=33091"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/tags?post=33091"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}