{"id":34555,"date":"2024-02-28T13:22:08","date_gmt":"2024-02-28T13:22:08","guid":{"rendered":"https:\/\/smarttrader.community\/?p=34555"},"modified":"2024-02-28T13:32:47","modified_gmt":"2024-02-28T13:32:47","slug":"anleger-besorgt-dass-daten-zinssenkungserwartungen-weiter-reduzieren","status":"publish","type":"post","link":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/anleger-besorgt-dass-daten-zinssenkungserwartungen-weiter-reduzieren\/","title":{"rendered":"Anleger besorgt, dass Daten Zinssenkungserwartungen weiter reduzieren"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Wir sehen, dass die <strong>Anleger vorsichtiger werden,<\/strong> da sie sich auf eine <strong>Reihe von Wirtschaftsdaten vorbereiten<\/strong>, die die Erwartung verst\u00e4rken k\u00f6nnten, dass die <strong>US-Wirtschaft stark genug ist und keine Zinssenkungen n\u00f6tig hat.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Wir sehen, dass die <strong>US-Futures im vorb\u00f6rslichen Handel leichte Verluste hinnehmen mussten<\/strong> und auch der europ\u00e4ische <strong>Stoxx 600 gab ebenfalls fr\u00fchere Gewinne wieder ab.<\/strong> <strong>Reckitt Benckiser<\/strong> brach um 12% ein und verzeichnete damit den st\u00e4rksten Einbruch an einem Tag seit 2008, nachdem das Konsumg\u00fcterunternehmen einen Umsatzr\u00fcckgang gemeldet hatte. <strong>ASM International <\/strong>fiel um 3,5%, nachdem der niederl\u00e4ndische Chipausr\u00fcster eine entt\u00e4uschende Umsatzprognose abgegeben hatte.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Das Hauptaugenmerk wird nun auf den <strong>kommenden Daten liegen &#8211; mit der Ver\u00f6ffentlichung des US-BIP <\/strong>um 14:30 MEZ und <strong>Inflationszahlen <\/strong>aus USA und Europa am Donnerstag bzw. Freitag. Au\u00dferdem werden weitere Stimmen von Zentralbanksprechern zu h\u00f6ren sein, die das Bild, dass die <strong>Fed derzeit keine Notwendigkeit f\u00fcr Zinssenkungen <\/strong>sieht, noch verst\u00e4rken d\u00fcrften. Die Swap-M\u00e4rkte haben die Zinssenkungserwartungen bereits auf <strong>nur noch etwa 75 Basispunkte f\u00fcr Zinssenkungen <\/strong>der Fed im Jahr 2024 reduziert.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Wir gehen davon aus, dass die <strong>Renditen trotz der weiter reduzierten Zinssenkungserwartungen auf einem hohen Niveau bleiben, aber <\/strong>(vor\u00fcbergehend) leicht nachgeben. Die weiter reduzierten Zinssenkungserwartungen belasten zwar die Marktstimmung, sind aber das Ergebnis einer <strong>starken US-Wirtschaft<\/strong>, eines <strong>angespannten Arbeitsmarktes<\/strong> und eines deutlichen <strong>Lohnwachstums<\/strong>, das die Inflation weiter anheizt.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Wir sehen, dass der <strong>USD heute wieder zugelegt hat <\/strong>&#8211; wie wir es schon fr\u00fcher erwartet hatten. Ich erwarte mehr <strong>fundamentalen R\u00fcckenwind f\u00fcr den USD von den US-BIP-Daten<\/strong> (heute) und &#8211; noch wichtiger &#8211; von den <strong>morgigen US-PCE-Daten.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Trotz <strong>einiger Gewinnmitnahmen sehen wir die M\u00e4rkte in einer Seitw\u00e4rtsbewegung<\/strong> und die Anleger bleiben insgesamt optimistisch. Mit Kryptow\u00e4hrungen verbundene Aktien wie Coinbase stiegen stark an. Wir sehen Bitcoin (und andere wichtige Kryptow\u00e4hrungen) auf dem Weg zum gr\u00f6\u00dften monatlichen Anstieg seit Oktober 2021. <strong>Bitcoin kletterte heute auf \u00fcber $59.000<\/strong> und legte in diesem Monat um fast 40 % zu.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">In <strong>Asien kam es an den Aktienm\u00e4rkten zu Verk\u00e4ufen <\/strong>&#8211; auch in <strong>China\/Hongkong<\/strong>. Wir sehen erneut die Sorge, dass die Konjunkturma\u00dfnahmen aus Peking nicht ausreichen, um die schwache Entwicklung der chinesischen M\u00e4rkte zu stoppen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die <strong>\u00d6lpreise fielen nach einem zweit\u00e4gigen Anstieg<\/strong>, als Anzeichen f\u00fcr h\u00f6here US-Lagerbest\u00e4nde auftraten. <strong>L\u00e4ngere Produktionsk\u00fcrzungen der OPEC+ k\u00f6nnten die \u00d6lpreise st\u00fctzen,<\/strong> zeigen aber letztlich, dass auch die OPEC \u00fcber die Nachfrageaussichten besorgt ist. Rohstoffe, insbesondere solche, die an die chinesische Wirtschaft gebunden sind, wie <strong>Eisenerz<\/strong>, verzeichneten erneut Verluste.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Wir erwarten <strong>positive US-Wirtschaftsdaten, <\/strong>die sich aber unterschiedlich auf die Aktien auswirken werden. Letztendlich werden jedoch das Bild eines sehr <strong>gesunden Wirtschaftswachstums in den USA<\/strong> und Anzeichen f\u00fcr eine R\u00fcckkehr des Wachstums in vielen anderen Volkswirtschaften die Marktstimmung positiv halten.<br><\/p>\n\n\n\n<h3 class=\"wp-block-heading\">\ud83d\udc41 ROBS MARKT\u00dcBERBLICK:<\/h3>\n\n\n\n<ol class=\"wp-block-list\" start=\"28\">\n<li><em>Februar 2024<\/em><\/li>\n<\/ol>\n\n\n\n<p class=\"wp-block-paragraph\">\ud83c\udf10\/\ud83c\uddfa\ud83c\uddf8 <strong>Globale M\u00e4rkte<\/strong> <em>\u2198\ufe0f\/\u2197\ufe0f\/\u2198\ufe0f (Ich erwarte heute gemischte Bewegungen, aber die Investoren werden im zweiten Teil des US-Handels wegen einer erneut hei\u00dfen Inflationsprognose f\u00fcr morgen besorgter sein)<br>Zyklische Aktien \u2198\ufe0f\/\u27a1\ufe0f\/\u2198\ufe0f<br>Technologie-\/Wachstumsaktien \u2198\ufe0f\/\u27a1\ufe0f\/\u2198\ufe0f<br>Finanzaktien \u2198\ufe0f\/\u27a1\ufe0f (mit einigen Gegenwinden; aber insgesamt bullisch)<br>Defensivaktien \u2197\ufe0f\/\u27a1\ufe0f<br>Energieaktien \u2198\ufe0f\/\u27a1\ufe0f<br>Rohstoff-Aktien \u2198\ufe0f<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\ud83d\udcb1 <strong>Forex<\/strong><br><em>USD \u2197\ufe0f (zus\u00e4tzlicher Schub durch US-BIP-Daten heute \/ PCE-Daten morgen)<br>JPY \u2197\ufe0f\/\u27a1\ufe0f<br>CHF \u27a1\ufe0f<br>EUR \u27a1\ufe0f\/\u2198\ufe0f\/\u27a1\ufe0f<br>AUD \u2198\ufe0f\/\u27a1\ufe0f (Gegenwind, da die Inflation nicht weiter beschleunigt hat, aber Zinserh\u00f6hungen bleiben auf dem Tisch)<br>GBP \u2198\ufe0f\/\u27a1\ufe0f<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u2692 <strong>Rohstoffm\u00e4rkte <\/strong><em>\u2198\ufe0f\/\u2195\ufe0f<br>\u00d6lpreise \u2198\ufe0f\/\u27a1\ufe0f<br>Erdgaspreise \u2197\ufe0f\/\u2195\ufe0f<br>Metallpreise \u2198\ufe0f (bleiben schwach)<br>Gold \u2195\ufe0f (k\u00f6nnte unter Druck geraten, wenn der USD weiter steigt &#8211; $2.030 bleibt entscheidend &#8211; Gold bleibt insgesamt bullisch)<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u26a1\ufe0f<strong>Kryptos<\/strong> <em>\u2197\ufe0f (Bitcoin sieht einen weiteren Tag starker K\u00e4ufe &#8211; wir erwarten mehr Widerstand nahe $60K und wahrscheinlich eine kurzlebige Gewinnmitnahmewelle)<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>(*\u2197\ufe0f bullisch, \u2198\ufe0f b\u00e4risch, \u27a1\ufe0f seitw\u00e4rts \/ stabil, \u2195\ufe0f gemischt \/ volatil)<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dein <strong>Robert<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Wir sehen, dass die Anleger vorsichtiger werden, da sie sich auf eine Reihe von Wirtschaftsdaten vorbereiten, die die Erwartung verst\u00e4rken&#8230;<\/p>\n","protected":false},"author":663,"featured_media":34553,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","pmpro_default_level":"0","_daextam_enable_autolinks":"1","footnotes":""},"categories":[117],"tags":[],"class_list":["post-34555","post","type-post","status-publish","format-standard","has-post-thumbnail","category-taegliche-aktualisierungen","pmpro-has-access"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Anleger besorgt, dass Daten Zinssenkungserwartungen weiter reduzieren - SmartTrader<\/title>\n<meta name=\"description\" content=\"Anleger besorgt, dass Daten Zinssenkungserwartungen weiter reduzieren. Wir sehen, dass die Anleger vorsichtiger werden, da sie sich auf...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/anleger-besorgt-dass-daten-zinssenkungserwartungen-weiter-reduzieren\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Anleger besorgt, dass Daten Zinssenkungserwartungen weiter reduzieren - SmartTrader\" \/>\n<meta property=\"og:description\" content=\"Anleger besorgt, dass Daten Zinssenkungserwartungen weiter reduzieren. Wir sehen, dass die Anleger vorsichtiger werden, da sie sich auf...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/anleger-besorgt-dass-daten-zinssenkungserwartungen-weiter-reduzieren\/\" \/>\n<meta property=\"og:site_name\" content=\"SmartTrader\" \/>\n<meta property=\"article:published_time\" content=\"2024-02-28T13:22:08+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-02-28T13:32:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/smarttrader.community\/wp-content\/uploads\/2024\/02\/28.02.2024_TITLE_Artboard-1-copy-9.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1081\" \/>\n\t<meta property=\"og:image:height\" content=\"721\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Robert Lindner\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Robert Lindner\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taegliche-aktualisierungen\\\/anleger-besorgt-dass-daten-zinssenkungserwartungen-weiter-reduzieren\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taegliche-aktualisierungen\\\/anleger-besorgt-dass-daten-zinssenkungserwartungen-weiter-reduzieren\\\/\"},\"author\":{\"name\":\"Robert Lindner\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/#\\\/schema\\\/person\\\/4f791355f3f400fd2dd91d9c57c4c067\"},\"headline\":\"Anleger besorgt, dass Daten Zinssenkungserwartungen weiter reduzieren\",\"datePublished\":\"2024-02-28T13:22:08+00:00\",\"dateModified\":\"2024-02-28T13:32:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taegliche-aktualisierungen\\\/anleger-besorgt-dass-daten-zinssenkungserwartungen-weiter-reduzieren\\\/\"},\"wordCount\":605,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taegliche-aktualisierungen\\\/anleger-besorgt-dass-daten-zinssenkungserwartungen-weiter-reduzieren\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/28.02.2024_TITLE_Artboard-1-copy-9.webp\",\"articleSection\":[\"T\u00e4gliche Aktualisierungen\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/smarttrader.community\\\/de\\\/taegliche-aktualisierungen\\\/anleger-besorgt-dass-daten-zinssenkungserwartungen-weiter-reduzieren\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taegliche-aktualisierungen\\\/anleger-besorgt-dass-daten-zinssenkungserwartungen-weiter-reduzieren\\\/\",\"url\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taegliche-aktualisierungen\\\/anleger-besorgt-dass-daten-zinssenkungserwartungen-weiter-reduzieren\\\/\",\"name\":\"Anleger besorgt, dass Daten Zinssenkungserwartungen weiter reduzieren - SmartTrader\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taegliche-aktualisierungen\\\/anleger-besorgt-dass-daten-zinssenkungserwartungen-weiter-reduzieren\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taegliche-aktualisierungen\\\/anleger-besorgt-dass-daten-zinssenkungserwartungen-weiter-reduzieren\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/28.02.2024_TITLE_Artboard-1-copy-9.webp\",\"datePublished\":\"2024-02-28T13:22:08+00:00\",\"dateModified\":\"2024-02-28T13:32:47+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/#\\\/schema\\\/person\\\/4f791355f3f400fd2dd91d9c57c4c067\"},\"description\":\"Anleger besorgt, dass Daten Zinssenkungserwartungen weiter reduzieren. Wir sehen, dass die Anleger vorsichtiger werden, da sie sich auf...\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taegliche-aktualisierungen\\\/anleger-besorgt-dass-daten-zinssenkungserwartungen-weiter-reduzieren\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/smarttrader.community\\\/de\\\/taegliche-aktualisierungen\\\/anleger-besorgt-dass-daten-zinssenkungserwartungen-weiter-reduzieren\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taegliche-aktualisierungen\\\/anleger-besorgt-dass-daten-zinssenkungserwartungen-weiter-reduzieren\\\/#primaryimage\",\"url\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/28.02.2024_TITLE_Artboard-1-copy-9.webp\",\"contentUrl\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/28.02.2024_TITLE_Artboard-1-copy-9.webp\",\"width\":1081,\"height\":721},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taegliche-aktualisierungen\\\/anleger-besorgt-dass-daten-zinssenkungserwartungen-weiter-reduzieren\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Anleger besorgt, dass Daten Zinssenkungserwartungen weiter reduzieren\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/\",\"name\":\"SmartTrader\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/#\\\/schema\\\/person\\\/4f791355f3f400fd2dd91d9c57c4c067\",\"name\":\"Robert Lindner\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/robert-lindner_avatar_1-96x96.png\",\"url\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/robert-lindner_avatar_1-96x96.png\",\"contentUrl\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/robert-lindner_avatar_1-96x96.png\",\"caption\":\"Robert Lindner\"},\"sameAs\":[\"https:\\\/\\\/wwww.smarttrader.community\\\/\"],\"url\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/author\\\/robert_smarttrader\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Anleger besorgt, dass Daten Zinssenkungserwartungen weiter reduzieren - SmartTrader","description":"Anleger besorgt, dass Daten Zinssenkungserwartungen weiter reduzieren. Wir sehen, dass die Anleger vorsichtiger werden, da sie sich auf...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/anleger-besorgt-dass-daten-zinssenkungserwartungen-weiter-reduzieren\/","og_locale":"de_DE","og_type":"article","og_title":"Anleger besorgt, dass Daten Zinssenkungserwartungen weiter reduzieren - SmartTrader","og_description":"Anleger besorgt, dass Daten Zinssenkungserwartungen weiter reduzieren. Wir sehen, dass die Anleger vorsichtiger werden, da sie sich auf...","og_url":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/anleger-besorgt-dass-daten-zinssenkungserwartungen-weiter-reduzieren\/","og_site_name":"SmartTrader","article_published_time":"2024-02-28T13:22:08+00:00","article_modified_time":"2024-02-28T13:32:47+00:00","og_image":[{"width":1081,"height":721,"url":"https:\/\/smarttrader.community\/wp-content\/uploads\/2024\/02\/28.02.2024_TITLE_Artboard-1-copy-9.webp","type":"image\/webp"}],"author":"Robert Lindner","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Robert Lindner","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/anleger-besorgt-dass-daten-zinssenkungserwartungen-weiter-reduzieren\/#article","isPartOf":{"@id":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/anleger-besorgt-dass-daten-zinssenkungserwartungen-weiter-reduzieren\/"},"author":{"name":"Robert Lindner","@id":"https:\/\/smarttrader.community\/de\/#\/schema\/person\/4f791355f3f400fd2dd91d9c57c4c067"},"headline":"Anleger besorgt, dass Daten Zinssenkungserwartungen weiter reduzieren","datePublished":"2024-02-28T13:22:08+00:00","dateModified":"2024-02-28T13:32:47+00:00","mainEntityOfPage":{"@id":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/anleger-besorgt-dass-daten-zinssenkungserwartungen-weiter-reduzieren\/"},"wordCount":605,"commentCount":0,"image":{"@id":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/anleger-besorgt-dass-daten-zinssenkungserwartungen-weiter-reduzieren\/#primaryimage"},"thumbnailUrl":"https:\/\/smarttrader.community\/wp-content\/uploads\/2024\/02\/28.02.2024_TITLE_Artboard-1-copy-9.webp","articleSection":["T\u00e4gliche Aktualisierungen"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/anleger-besorgt-dass-daten-zinssenkungserwartungen-weiter-reduzieren\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/anleger-besorgt-dass-daten-zinssenkungserwartungen-weiter-reduzieren\/","url":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/anleger-besorgt-dass-daten-zinssenkungserwartungen-weiter-reduzieren\/","name":"Anleger besorgt, dass Daten Zinssenkungserwartungen weiter reduzieren - SmartTrader","isPartOf":{"@id":"https:\/\/smarttrader.community\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/anleger-besorgt-dass-daten-zinssenkungserwartungen-weiter-reduzieren\/#primaryimage"},"image":{"@id":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/anleger-besorgt-dass-daten-zinssenkungserwartungen-weiter-reduzieren\/#primaryimage"},"thumbnailUrl":"https:\/\/smarttrader.community\/wp-content\/uploads\/2024\/02\/28.02.2024_TITLE_Artboard-1-copy-9.webp","datePublished":"2024-02-28T13:22:08+00:00","dateModified":"2024-02-28T13:32:47+00:00","author":{"@id":"https:\/\/smarttrader.community\/de\/#\/schema\/person\/4f791355f3f400fd2dd91d9c57c4c067"},"description":"Anleger besorgt, dass Daten Zinssenkungserwartungen weiter reduzieren. Wir sehen, dass die Anleger vorsichtiger werden, da sie sich auf...","breadcrumb":{"@id":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/anleger-besorgt-dass-daten-zinssenkungserwartungen-weiter-reduzieren\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/anleger-besorgt-dass-daten-zinssenkungserwartungen-weiter-reduzieren\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/anleger-besorgt-dass-daten-zinssenkungserwartungen-weiter-reduzieren\/#primaryimage","url":"https:\/\/smarttrader.community\/wp-content\/uploads\/2024\/02\/28.02.2024_TITLE_Artboard-1-copy-9.webp","contentUrl":"https:\/\/smarttrader.community\/wp-content\/uploads\/2024\/02\/28.02.2024_TITLE_Artboard-1-copy-9.webp","width":1081,"height":721},{"@type":"BreadcrumbList","@id":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/anleger-besorgt-dass-daten-zinssenkungserwartungen-weiter-reduzieren\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/smarttrader.community\/de\/"},{"@type":"ListItem","position":2,"name":"Anleger besorgt, dass Daten Zinssenkungserwartungen weiter reduzieren"}]},{"@type":"WebSite","@id":"https:\/\/smarttrader.community\/de\/#website","url":"https:\/\/smarttrader.community\/de\/","name":"SmartTrader","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/smarttrader.community\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/smarttrader.community\/de\/#\/schema\/person\/4f791355f3f400fd2dd91d9c57c4c067","name":"Robert Lindner","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/05\/robert-lindner_avatar_1-96x96.png","url":"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/05\/robert-lindner_avatar_1-96x96.png","contentUrl":"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/05\/robert-lindner_avatar_1-96x96.png","caption":"Robert Lindner"},"sameAs":["https:\/\/wwww.smarttrader.community\/"],"url":"https:\/\/smarttrader.community\/de\/author\/robert_smarttrader\/"}]}},"_links":{"self":[{"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/posts\/34555","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/users\/663"}],"replies":[{"embeddable":true,"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/comments?post=34555"}],"version-history":[{"count":0,"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/posts\/34555\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/media\/34553"}],"wp:attachment":[{"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/media?parent=34555"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/categories?post=34555"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/tags?post=34555"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}