{"id":34949,"date":"2024-03-04T10:53:31","date_gmt":"2024-03-04T10:53:31","guid":{"rendered":"https:\/\/smarttrader.community\/?p=34949"},"modified":"2024-03-04T10:58:06","modified_gmt":"2024-03-04T10:58:06","slug":"tech-rallye-fuehrt-globale-maerkte-weiter-an-ruhiger-start-in-eine-ereignisreiche-woche","status":"publish","type":"post","link":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/tech-rallye-fuehrt-globale-maerkte-weiter-an-ruhiger-start-in-eine-ereignisreiche-woche\/","title":{"rendered":"Tech-Rallye f\u00fchrt globale M\u00e4rkte weiter an; Ruhiger Start in eine ereignisreiche Woche"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">\ud83d\udcc6 Montag, 4. M\u00e4rz<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u25ba Die <strong>europ\u00e4ischen Aktienfutures starteten solide in die Woche<\/strong>, angef\u00fchrt von einem <strong>Anstieg der Technologieaktien<\/strong>. Dieser Optimismus am Markt steht vor dem Hintergrund wichtiger bevorstehender Ereignisse, darunter die Aussage des Vorsitzenden der Federal Reserve Jerome Powell vor dem Kongress und der Beginn des Nationalen Volkskongresses in China. Die M\u00e4rkte warten auch auf die Ergebnisse der EZB-Sitzung. Die <strong>europ\u00e4ischen M\u00e4rkte liegen derzeit 0,3 % im Plus<\/strong> (Stoxx 600), da die H\u00e4ndler auf weitere Hinweise warten. Die Anleiherenditen passen sich in Erwartung der politischen Entscheidungen leicht an.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u25ba In den <strong>USA zeigte sich der Aktienmarkt am Freitag robust<\/strong> und der S&P 500 erreichte sein 15. Allzeithoch in diesem Jahr. Der <strong>Nasdaq 100 verzeichnete starke Zuw\u00e4chse und stieg um fast 1,5 %<\/strong>. Diese positive Dynamik spiegelt das wachsende Vertrauen der Anleger in die Aussichten des Technologiesektors wider. In dieser Woche stehen die Anh\u00f6rung von Jerome Powell vor dem Kongress und eine Reihe von Wirtschaftsdaten (NFP-Daten, Arbeitslosenzahlen, etc.) im Mittelpunkt. Dazu geh\u00f6ren die <strong>US-Arbeitsmarktdaten<\/strong>, die zusammen mit Powells \u00c4u\u00dferungen die Markterwartungen hinsichtlich der k\u00fcnftigen Zinsentscheidungen der Federal Reserve ma\u00dfgeblich beeinflussen k\u00f6nnten.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/smarttrader.community\/membership-join\">Subscribe<\/a> to see more<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\ud83d\udcc6 Montag, 4. M\u00e4rz \u25ba Die europ\u00e4ischen Aktienfutures starteten solide in die Woche, angef\u00fchrt von einem Anstieg der Technologieaktien. Dieser&#8230;<\/p>\n","protected":false},"author":1,"featured_media":16483,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","pmpro_default_level":"0","_daextam_enable_autolinks":"1","footnotes":""},"categories":[172],"tags":[],"class_list":["post-34949","post","type-post","status-publish","format-standard","has-post-thumbnail","category-taglicher-marktuberblick","pmpro-has-access"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Tech-Rallye f\u00fchrt globale M\u00e4rkte weiter an; Ruhiger Start in eine ereignisreiche Woche - SmartTrader<\/title>\n<meta name=\"description\" content=\"Tech-Rallye f\u00fchrt globale M\u00e4rkte weiter an; Ruhiger Start in eine ereignisreiche Woche. Die europ\u00e4ischen Aktienfutures starteten solide in...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/tech-rallye-fuehrt-globale-maerkte-weiter-an-ruhiger-start-in-eine-ereignisreiche-woche\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tech-Rallye f\u00fchrt globale M\u00e4rkte weiter an; Ruhiger Start in eine ereignisreiche Woche - SmartTrader\" \/>\n<meta property=\"og:description\" content=\"Tech-Rallye f\u00fchrt globale M\u00e4rkte weiter an; Ruhiger Start in eine ereignisreiche Woche. Die europ\u00e4ischen Aktienfutures starteten solide in...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/tech-rallye-fuehrt-globale-maerkte-weiter-an-ruhiger-start-in-eine-ereignisreiche-woche\/\" \/>\n<meta property=\"og:site_name\" content=\"SmartTrader\" \/>\n<meta property=\"article:published_time\" content=\"2024-03-04T10:53:31+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-04T10:58:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/06\/lp-pics-list-1.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"621\" \/>\n\t<meta property=\"og:image:height\" content=\"435\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"SmartTrader Analyst Team\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"SmartTrader Analyst Team\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taglicher-marktuberblick\\\/tech-rallye-fuehrt-globale-maerkte-weiter-an-ruhiger-start-in-eine-ereignisreiche-woche\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taglicher-marktuberblick\\\/tech-rallye-fuehrt-globale-maerkte-weiter-an-ruhiger-start-in-eine-ereignisreiche-woche\\\/\"},\"author\":{\"name\":\"SmartTrader Analyst Team\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/#\\\/schema\\\/person\\\/bfe0c456aafbdc04b9707983e59c4e05\"},\"headline\":\"Tech-Rallye f\u00fchrt globale M\u00e4rkte weiter an; Ruhiger Start in eine ereignisreiche Woche\",\"datePublished\":\"2024-03-04T10:53:31+00:00\",\"dateModified\":\"2024-03-04T10:58:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taglicher-marktuberblick\\\/tech-rallye-fuehrt-globale-maerkte-weiter-an-ruhiger-start-in-eine-ereignisreiche-woche\\\/\"},\"wordCount\":449,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taglicher-marktuberblick\\\/tech-rallye-fuehrt-globale-maerkte-weiter-an-ruhiger-start-in-eine-ereignisreiche-woche\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/lp-pics-list-1.webp\",\"articleSection\":[\"T\u00e4glicher Markt\u00fcberblick\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/smarttrader.community\\\/de\\\/taglicher-marktuberblick\\\/tech-rallye-fuehrt-globale-maerkte-weiter-an-ruhiger-start-in-eine-ereignisreiche-woche\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taglicher-marktuberblick\\\/tech-rallye-fuehrt-globale-maerkte-weiter-an-ruhiger-start-in-eine-ereignisreiche-woche\\\/\",\"url\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taglicher-marktuberblick\\\/tech-rallye-fuehrt-globale-maerkte-weiter-an-ruhiger-start-in-eine-ereignisreiche-woche\\\/\",\"name\":\"Tech-Rallye f\u00fchrt globale M\u00e4rkte weiter an; Ruhiger Start in eine ereignisreiche Woche - SmartTrader\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taglicher-marktuberblick\\\/tech-rallye-fuehrt-globale-maerkte-weiter-an-ruhiger-start-in-eine-ereignisreiche-woche\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taglicher-marktuberblick\\\/tech-rallye-fuehrt-globale-maerkte-weiter-an-ruhiger-start-in-eine-ereignisreiche-woche\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/lp-pics-list-1.webp\",\"datePublished\":\"2024-03-04T10:53:31+00:00\",\"dateModified\":\"2024-03-04T10:58:06+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/#\\\/schema\\\/person\\\/bfe0c456aafbdc04b9707983e59c4e05\"},\"description\":\"Tech-Rallye f\u00fchrt globale M\u00e4rkte weiter an; Ruhiger Start in eine ereignisreiche Woche. Die europ\u00e4ischen Aktienfutures starteten solide in...\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taglicher-marktuberblick\\\/tech-rallye-fuehrt-globale-maerkte-weiter-an-ruhiger-start-in-eine-ereignisreiche-woche\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/smarttrader.community\\\/de\\\/taglicher-marktuberblick\\\/tech-rallye-fuehrt-globale-maerkte-weiter-an-ruhiger-start-in-eine-ereignisreiche-woche\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taglicher-marktuberblick\\\/tech-rallye-fuehrt-globale-maerkte-weiter-an-ruhiger-start-in-eine-ereignisreiche-woche\\\/#primaryimage\",\"url\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/lp-pics-list-1.webp\",\"contentUrl\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/lp-pics-list-1.webp\",\"width\":621,\"height\":435},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taglicher-marktuberblick\\\/tech-rallye-fuehrt-globale-maerkte-weiter-an-ruhiger-start-in-eine-ereignisreiche-woche\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tech-Rallye f\u00fchrt globale M\u00e4rkte weiter an; Ruhiger Start in eine ereignisreiche Woche\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/\",\"name\":\"SmartTrader\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/#\\\/schema\\\/person\\\/bfe0c456aafbdc04b9707983e59c4e05\",\"name\":\"SmartTrader Analyst Team\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/admin_avatar_3-96x96.png\",\"url\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/admin_avatar_3-96x96.png\",\"contentUrl\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/admin_avatar_3-96x96.png\",\"caption\":\"SmartTrader Analyst Team\"},\"sameAs\":[\"https:\\\/\\\/smarttrader.community\"],\"url\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tech-Rallye f\u00fchrt globale M\u00e4rkte weiter an; Ruhiger Start in eine ereignisreiche Woche - SmartTrader","description":"Tech-Rallye f\u00fchrt globale M\u00e4rkte weiter an; Ruhiger Start in eine ereignisreiche Woche. Die europ\u00e4ischen Aktienfutures starteten solide in...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/tech-rallye-fuehrt-globale-maerkte-weiter-an-ruhiger-start-in-eine-ereignisreiche-woche\/","og_locale":"de_DE","og_type":"article","og_title":"Tech-Rallye f\u00fchrt globale M\u00e4rkte weiter an; Ruhiger Start in eine ereignisreiche Woche - SmartTrader","og_description":"Tech-Rallye f\u00fchrt globale M\u00e4rkte weiter an; Ruhiger Start in eine ereignisreiche Woche. Die europ\u00e4ischen Aktienfutures starteten solide in...","og_url":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/tech-rallye-fuehrt-globale-maerkte-weiter-an-ruhiger-start-in-eine-ereignisreiche-woche\/","og_site_name":"SmartTrader","article_published_time":"2024-03-04T10:53:31+00:00","article_modified_time":"2024-03-04T10:58:06+00:00","og_image":[{"width":621,"height":435,"url":"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/06\/lp-pics-list-1.webp","type":"image\/webp"}],"author":"SmartTrader Analyst Team","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"SmartTrader Analyst Team","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/tech-rallye-fuehrt-globale-maerkte-weiter-an-ruhiger-start-in-eine-ereignisreiche-woche\/#article","isPartOf":{"@id":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/tech-rallye-fuehrt-globale-maerkte-weiter-an-ruhiger-start-in-eine-ereignisreiche-woche\/"},"author":{"name":"SmartTrader Analyst Team","@id":"https:\/\/smarttrader.community\/de\/#\/schema\/person\/bfe0c456aafbdc04b9707983e59c4e05"},"headline":"Tech-Rallye f\u00fchrt globale M\u00e4rkte weiter an; Ruhiger Start in eine ereignisreiche Woche","datePublished":"2024-03-04T10:53:31+00:00","dateModified":"2024-03-04T10:58:06+00:00","mainEntityOfPage":{"@id":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/tech-rallye-fuehrt-globale-maerkte-weiter-an-ruhiger-start-in-eine-ereignisreiche-woche\/"},"wordCount":449,"commentCount":0,"image":{"@id":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/tech-rallye-fuehrt-globale-maerkte-weiter-an-ruhiger-start-in-eine-ereignisreiche-woche\/#primaryimage"},"thumbnailUrl":"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/06\/lp-pics-list-1.webp","articleSection":["T\u00e4glicher Markt\u00fcberblick"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/tech-rallye-fuehrt-globale-maerkte-weiter-an-ruhiger-start-in-eine-ereignisreiche-woche\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/tech-rallye-fuehrt-globale-maerkte-weiter-an-ruhiger-start-in-eine-ereignisreiche-woche\/","url":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/tech-rallye-fuehrt-globale-maerkte-weiter-an-ruhiger-start-in-eine-ereignisreiche-woche\/","name":"Tech-Rallye f\u00fchrt globale M\u00e4rkte weiter an; Ruhiger Start in eine ereignisreiche Woche - SmartTrader","isPartOf":{"@id":"https:\/\/smarttrader.community\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/tech-rallye-fuehrt-globale-maerkte-weiter-an-ruhiger-start-in-eine-ereignisreiche-woche\/#primaryimage"},"image":{"@id":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/tech-rallye-fuehrt-globale-maerkte-weiter-an-ruhiger-start-in-eine-ereignisreiche-woche\/#primaryimage"},"thumbnailUrl":"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/06\/lp-pics-list-1.webp","datePublished":"2024-03-04T10:53:31+00:00","dateModified":"2024-03-04T10:58:06+00:00","author":{"@id":"https:\/\/smarttrader.community\/de\/#\/schema\/person\/bfe0c456aafbdc04b9707983e59c4e05"},"description":"Tech-Rallye f\u00fchrt globale M\u00e4rkte weiter an; Ruhiger Start in eine ereignisreiche Woche. Die europ\u00e4ischen Aktienfutures starteten solide in...","breadcrumb":{"@id":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/tech-rallye-fuehrt-globale-maerkte-weiter-an-ruhiger-start-in-eine-ereignisreiche-woche\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/tech-rallye-fuehrt-globale-maerkte-weiter-an-ruhiger-start-in-eine-ereignisreiche-woche\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/tech-rallye-fuehrt-globale-maerkte-weiter-an-ruhiger-start-in-eine-ereignisreiche-woche\/#primaryimage","url":"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/06\/lp-pics-list-1.webp","contentUrl":"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/06\/lp-pics-list-1.webp","width":621,"height":435},{"@type":"BreadcrumbList","@id":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/tech-rallye-fuehrt-globale-maerkte-weiter-an-ruhiger-start-in-eine-ereignisreiche-woche\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/smarttrader.community\/de\/"},{"@type":"ListItem","position":2,"name":"Tech-Rallye f\u00fchrt globale M\u00e4rkte weiter an; Ruhiger Start in eine ereignisreiche Woche"}]},{"@type":"WebSite","@id":"https:\/\/smarttrader.community\/de\/#website","url":"https:\/\/smarttrader.community\/de\/","name":"SmartTrader","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/smarttrader.community\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/smarttrader.community\/de\/#\/schema\/person\/bfe0c456aafbdc04b9707983e59c4e05","name":"SmartTrader Analyst Team","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/03\/admin_avatar_3-96x96.png","url":"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/03\/admin_avatar_3-96x96.png","contentUrl":"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/03\/admin_avatar_3-96x96.png","caption":"SmartTrader Analyst Team"},"sameAs":["https:\/\/smarttrader.community"],"url":"https:\/\/smarttrader.community\/de\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/posts\/34949","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/comments?post=34949"}],"version-history":[{"count":0,"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/posts\/34949\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/media\/16483"}],"wp:attachment":[{"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/media?parent=34949"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/categories?post=34949"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/tags?post=34949"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}