{"id":36615,"date":"2024-04-04T13:23:13","date_gmt":"2024-04-04T13:23:13","guid":{"rendered":"https:\/\/smarttrader.community\/?p=36615"},"modified":"2024-04-04T13:34:44","modified_gmt":"2024-04-04T13:34:44","slug":"aktien-erholen-sich-weiter-powell-bestaetigt-fed-weiter-auf-zinssenkungspfad","status":"publish","type":"post","link":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/aktien-erholen-sich-weiter-powell-bestaetigt-fed-weiter-auf-zinssenkungspfad\/","title":{"rendered":"Aktien erholen sich weiter; Powell best\u00e4tigt: Fed weiter auf Zinssenkungspfad"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Die Aktien erholen sich weiter von ihrem Einbruch am Dienstag, nachdem starke US-Wirtschaftsdaten die Erwartungen, dass die Fed die Zinsen im laufenden Quartal und insgesamt dreimal senken wird, zuerst weiter reduziert haben. J\u00fcngste Daten deuten auch darauf hin, dass der Arbeitsmarkt weiterhin angespannt ist und die Unternehmen weiterhin viele offene Stellen haben und es schwer haben, diese zu besetzen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die vor wenigen Minuten gemeldeten Erstantr\u00e4ge auf Arbeitslosenunterst\u00fctzung in den USA zeigen jetzt aber wieder ein eher gemischtes Bild des US-Arbeitsmarktes, da die Erstantr\u00e4ge auf Arbeitslosenunterst\u00fctzung in den USA in der letzten Woche auf den h\u00f6chsten Stand seit Januar gestiegen sind, was im Einklang mit dem j\u00fcngsten Anstieg der Zahl der Stellenstreichungen steht. Die Erstantr\u00e4ge auf Arbeitslosenunterst\u00fctzung stiegen um 9.000 auf 221.000 und lagen damit auch \u00fcber den Erwartungen von 214.000. Die fortlaufenden Antr\u00e4ge auf Arbeitslosenunterst\u00fctzung sind jedoch gegen\u00fcber Februar leicht gesunken. Das Hauptaugenmerk wird auf dem morgigen NFP-Bericht liegen, w\u00e4hrend die heutigen Bewegungen ged\u00e4mpft bleiben, da sich die H\u00e4ndler auf den Arbeitsmarktbericht am Freitag vorbereiten.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nach mehreren Warnungen von Investmentbanken, dass die Bewertungen an der Wall Street sehr hoch sind, sind die Anleger nerv\u00f6ser geworden, dass die M\u00e4rkte unter Druck kommen k\u00f6nnten &#8211; vor allem wenn Zinsen l\u00e4nger hoch bleiben. Powell milderte diese Bedenken etwas ab, nachdem er sagte, dass die j\u00fcngsten Inflationszahlen &#8211; obwohl sie h\u00f6her als erwartet waren &#8211; das Gesamtbild nicht &#8222;wesentlich ver\u00e4ndert&#8220; haben.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Wir sehen die Renditen nach den Daten zu den Erstantr\u00e4gen auf Arbeitslosenunterst\u00fctzung niedriger und die M\u00e4rkte wie erwartet weiter steigen. Die Risikostimmung hat sich verbessert und auch die M\u00e4rkte in Japan und Europa haben zugelegt. Der starke USD gab einen Teil der j\u00fcngsten kr\u00e4ftigen Gewinne wieder ab und die Sorge, dass sich der Einbruch der US-Staatsanleihen (der die Renditen auf den H\u00f6chststand von 2024 ansteigen lie\u00df) noch verst\u00e4rken k\u00f6nnte, hat sich deutlich verringert.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Der NFP-Bericht war in letzter Zeit unzuverl\u00e4ssig, da die Daten des Vormonats in der Regel (nach unten) angepasst wurden. Es ist daher schwer abzusch\u00e4tzen, wie die M\u00e4rkte reagieren und wie verl\u00e4sslich die NFP-Daten sind. Ich erwarte eine gemischte, anfangs leicht negative Reaktion, aber die M\u00e4rkte werden n\u00e4chste Woche zu einer insgesamt positiven Marktstimmung zur\u00fcckkehren. Wir sehen bereits, dass einige Investoren ihre Bedenken, dass h\u00f6here Zinsen f\u00fcr l\u00e4ngere Zeit eine deutliche Verlangsamung der US-Wirtschaft verursachen werden, verringern. Au\u00dferdem sehe ich weiterhin ausreichend gute Bedingungen f\u00fcr die US-Wirtschaft und starke Anzeichen daf\u00fcr, dass das Wachstum und damit die positive Gesamtdynamik intakt bleiben &#8211; die US-Wirtschaft braucht noch keine Zinssenkungen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die sich aufhellende Stimmung belastet Gold ein wenig, aber die Aussichten bleiben bullisch. Der \u00d6lpreis hat sich nach den j\u00fcngsten kr\u00e4ftigen Zuw\u00e4chsen stabilisiert &#8211; ein Zeichen daf\u00fcr, dass die Rohstoffh\u00e4ndler mit einer steigenden Nachfrage rechnen, wenn sich die Weltwirtschaft (insbesondere Chinas Wirtschaft) verbessert.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">\ud83d\udc41 ROBS MARKT\u00dcBERBLICK:<\/h3>\n\n\n\n<ol class=\"wp-block-list\" start=\"4\">\n<li><em>April 2024<\/em><\/li>\n<\/ol>\n\n\n\n<p class=\"wp-block-paragraph\">\ud83c\udf10\/\ud83c\uddfa\ud83c\uddf8 <strong>Globale M\u00e4rkte<\/strong> <em>\u2197\ufe0f\/\u27a1\ufe0f (mehr Vorsicht in der zweiten H\u00e4lfte des US-Handels)<br>Zyklische \/ Luxus-Aktien \u2197\ufe0f\/\u27a1\ufe0f<br>Technologie-\/Wachstumsaktien \u2197\ufe0f<br>Finanzaktien \u2197\ufe0f\/\u27a1\ufe0f<br>Defensivaktien \u27a1\ufe0f<br>Energieaktien \u27a1\ufe0f<br>Rohstoff-Aktien \u2197\ufe0f\/\u27a1\ufe0f<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\ud83d\udcb1 <strong>Forex<\/strong><br><em>AUD \u2197\ufe0f (profitiert von verbessertem Risikosentiment; bullische Rohstoffpreise)<br>CAD \u2197\ufe0f\/\u27a1\ufe0f (profitiert von verbessertem Risikosentiment; bullische Rohstoffpreise)<br>EUR \u2197\ufe0f\/\u27a1\ufe0f (profitiert von weiterhin optimistischen M\u00e4rkten \u00fcber Fed-Zinssenkungen)<br>GBP \u27a1\ufe0f\/\u2198\ufe0f<br>USD \u2198\ufe0f\/\u27a1\ufe0f (USD stabilisiert sich \/ neigt in der zweiten H\u00e4lfte des US-Handels nach oben)<br>CHF, JPY \u2198\ufe0f<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u2692 <strong>Rohstoffm\u00e4rkte <\/strong><em>\u27a1\ufe0f<br>\u00d6lpreise \u27a1\ufe0f (verweilen derzeit bei $85 (WTI); $89 (Brent))<br>Erdgaspreise \u27a1\ufe0f\/\u2198\ufe0f (in Seitw\u00e4rtsbewegung mit einigen Risiken kurzfristiger Gewinnmitnahmen)<br>Metallpreise \u2198\ufe0f\/\u2195\ufe0f (einige Gewinnmitnahmen, aber insgesamt bullisch bei verbessertem Risikosentiment)<br>Gold \u2198\ufe0f\/\u2195\ufe0f\/\u2197\ufe0f (bleibt bullisch; leichte Gegenwinde durch tempor\u00e4r geringere Nachfrage nach sicheren H\u00e4fen)<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u26a1\ufe0f<strong>Kryptos <\/strong><em>\u2195\ufe0f\/\u2197\ufe0f (Anzeichen einer kurzfristigen Erholung von scharfen Verlusten)<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>(*\u2197\ufe0f bullisch, \u2198\ufe0f b\u00e4risch, \u27a1\ufe0f seitw\u00e4rts \/ stabil, \u2195\ufe0f gemischt \/ volatil)<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dein <strong>Robert<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die Aktien erholen sich weiter von ihrem Einbruch am Dienstag, nachdem starke US-Wirtschaftsdaten die Erwartungen, dass die Fed die Zinsen&#8230;<\/p>\n","protected":false},"author":663,"featured_media":36613,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","pmpro_default_level":"","_daextam_enable_autolinks":"1","footnotes":""},"categories":[117],"tags":[],"class_list":["post-36615","post","type-post","status-publish","format-standard","has-post-thumbnail","category-taegliche-aktualisierungen","pmpro-has-access"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Aktien erholen sich weiter; Powell best\u00e4tigt: Fed weiter auf Zinssenkungspfad - SmartTrader<\/title>\n<meta name=\"description\" content=\"Aktien erholen sich weiter; Powell best\u00e4tigt: Fed weiter auf Zinssenkungspfad. Die Aktien erholen sich weiter von ihrem Einbruch am Dienstag...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/aktien-erholen-sich-weiter-powell-bestaetigt-fed-weiter-auf-zinssenkungspfad\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Aktien erholen sich weiter; Powell best\u00e4tigt: Fed weiter auf Zinssenkungspfad - SmartTrader\" \/>\n<meta property=\"og:description\" content=\"Aktien erholen sich weiter; Powell best\u00e4tigt: Fed weiter auf Zinssenkungspfad. Die Aktien erholen sich weiter von ihrem Einbruch am Dienstag...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/aktien-erholen-sich-weiter-powell-bestaetigt-fed-weiter-auf-zinssenkungspfad\/\" \/>\n<meta property=\"og:site_name\" content=\"SmartTrader\" \/>\n<meta property=\"article:published_time\" content=\"2024-04-04T13:23:13+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-04T13:34:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/smarttrader.community\/wp-content\/uploads\/2024\/04\/04.04.2024_TITLE_Artboard-1-copy-9.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1081\" \/>\n\t<meta property=\"og:image:height\" content=\"721\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Robert Lindner\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Robert Lindner\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taegliche-aktualisierungen\\\/aktien-erholen-sich-weiter-powell-bestaetigt-fed-weiter-auf-zinssenkungspfad\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taegliche-aktualisierungen\\\/aktien-erholen-sich-weiter-powell-bestaetigt-fed-weiter-auf-zinssenkungspfad\\\/\"},\"author\":{\"name\":\"Robert Lindner\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/#\\\/schema\\\/person\\\/4f791355f3f400fd2dd91d9c57c4c067\"},\"headline\":\"Aktien erholen sich weiter; Powell best\u00e4tigt: Fed weiter auf Zinssenkungspfad\",\"datePublished\":\"2024-04-04T13:23:13+00:00\",\"dateModified\":\"2024-04-04T13:34:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taegliche-aktualisierungen\\\/aktien-erholen-sich-weiter-powell-bestaetigt-fed-weiter-auf-zinssenkungspfad\\\/\"},\"wordCount\":629,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taegliche-aktualisierungen\\\/aktien-erholen-sich-weiter-powell-bestaetigt-fed-weiter-auf-zinssenkungspfad\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/04.04.2024_TITLE_Artboard-1-copy-9.webp\",\"articleSection\":[\"T\u00e4gliche Aktualisierungen\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/smarttrader.community\\\/de\\\/taegliche-aktualisierungen\\\/aktien-erholen-sich-weiter-powell-bestaetigt-fed-weiter-auf-zinssenkungspfad\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taegliche-aktualisierungen\\\/aktien-erholen-sich-weiter-powell-bestaetigt-fed-weiter-auf-zinssenkungspfad\\\/\",\"url\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taegliche-aktualisierungen\\\/aktien-erholen-sich-weiter-powell-bestaetigt-fed-weiter-auf-zinssenkungspfad\\\/\",\"name\":\"Aktien erholen sich weiter; Powell best\u00e4tigt: Fed weiter auf Zinssenkungspfad - SmartTrader\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taegliche-aktualisierungen\\\/aktien-erholen-sich-weiter-powell-bestaetigt-fed-weiter-auf-zinssenkungspfad\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taegliche-aktualisierungen\\\/aktien-erholen-sich-weiter-powell-bestaetigt-fed-weiter-auf-zinssenkungspfad\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/04.04.2024_TITLE_Artboard-1-copy-9.webp\",\"datePublished\":\"2024-04-04T13:23:13+00:00\",\"dateModified\":\"2024-04-04T13:34:44+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/#\\\/schema\\\/person\\\/4f791355f3f400fd2dd91d9c57c4c067\"},\"description\":\"Aktien erholen sich weiter; Powell best\u00e4tigt: Fed weiter auf Zinssenkungspfad. Die Aktien erholen sich weiter von ihrem Einbruch am Dienstag...\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taegliche-aktualisierungen\\\/aktien-erholen-sich-weiter-powell-bestaetigt-fed-weiter-auf-zinssenkungspfad\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/smarttrader.community\\\/de\\\/taegliche-aktualisierungen\\\/aktien-erholen-sich-weiter-powell-bestaetigt-fed-weiter-auf-zinssenkungspfad\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taegliche-aktualisierungen\\\/aktien-erholen-sich-weiter-powell-bestaetigt-fed-weiter-auf-zinssenkungspfad\\\/#primaryimage\",\"url\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/04.04.2024_TITLE_Artboard-1-copy-9.webp\",\"contentUrl\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/04.04.2024_TITLE_Artboard-1-copy-9.webp\",\"width\":1081,\"height\":721},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taegliche-aktualisierungen\\\/aktien-erholen-sich-weiter-powell-bestaetigt-fed-weiter-auf-zinssenkungspfad\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Aktien erholen sich weiter; Powell best\u00e4tigt: Fed weiter auf Zinssenkungspfad\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/\",\"name\":\"SmartTrader\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/#\\\/schema\\\/person\\\/4f791355f3f400fd2dd91d9c57c4c067\",\"name\":\"Robert Lindner\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/robert-lindner_avatar_1-96x96.png\",\"url\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/robert-lindner_avatar_1-96x96.png\",\"contentUrl\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/robert-lindner_avatar_1-96x96.png\",\"caption\":\"Robert Lindner\"},\"sameAs\":[\"https:\\\/\\\/wwww.smarttrader.community\\\/\"],\"url\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/author\\\/robert_smarttrader\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Aktien erholen sich weiter; Powell best\u00e4tigt: Fed weiter auf Zinssenkungspfad - SmartTrader","description":"Aktien erholen sich weiter; Powell best\u00e4tigt: Fed weiter auf Zinssenkungspfad. Die Aktien erholen sich weiter von ihrem Einbruch am Dienstag...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/aktien-erholen-sich-weiter-powell-bestaetigt-fed-weiter-auf-zinssenkungspfad\/","og_locale":"de_DE","og_type":"article","og_title":"Aktien erholen sich weiter; Powell best\u00e4tigt: Fed weiter auf Zinssenkungspfad - SmartTrader","og_description":"Aktien erholen sich weiter; Powell best\u00e4tigt: Fed weiter auf Zinssenkungspfad. Die Aktien erholen sich weiter von ihrem Einbruch am Dienstag...","og_url":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/aktien-erholen-sich-weiter-powell-bestaetigt-fed-weiter-auf-zinssenkungspfad\/","og_site_name":"SmartTrader","article_published_time":"2024-04-04T13:23:13+00:00","article_modified_time":"2024-04-04T13:34:44+00:00","og_image":[{"width":1081,"height":721,"url":"https:\/\/smarttrader.community\/wp-content\/uploads\/2024\/04\/04.04.2024_TITLE_Artboard-1-copy-9.webp","type":"image\/webp"}],"author":"Robert Lindner","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Robert Lindner","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/aktien-erholen-sich-weiter-powell-bestaetigt-fed-weiter-auf-zinssenkungspfad\/#article","isPartOf":{"@id":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/aktien-erholen-sich-weiter-powell-bestaetigt-fed-weiter-auf-zinssenkungspfad\/"},"author":{"name":"Robert Lindner","@id":"https:\/\/smarttrader.community\/de\/#\/schema\/person\/4f791355f3f400fd2dd91d9c57c4c067"},"headline":"Aktien erholen sich weiter; Powell best\u00e4tigt: Fed weiter auf Zinssenkungspfad","datePublished":"2024-04-04T13:23:13+00:00","dateModified":"2024-04-04T13:34:44+00:00","mainEntityOfPage":{"@id":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/aktien-erholen-sich-weiter-powell-bestaetigt-fed-weiter-auf-zinssenkungspfad\/"},"wordCount":629,"commentCount":0,"image":{"@id":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/aktien-erholen-sich-weiter-powell-bestaetigt-fed-weiter-auf-zinssenkungspfad\/#primaryimage"},"thumbnailUrl":"https:\/\/smarttrader.community\/wp-content\/uploads\/2024\/04\/04.04.2024_TITLE_Artboard-1-copy-9.webp","articleSection":["T\u00e4gliche Aktualisierungen"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/aktien-erholen-sich-weiter-powell-bestaetigt-fed-weiter-auf-zinssenkungspfad\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/aktien-erholen-sich-weiter-powell-bestaetigt-fed-weiter-auf-zinssenkungspfad\/","url":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/aktien-erholen-sich-weiter-powell-bestaetigt-fed-weiter-auf-zinssenkungspfad\/","name":"Aktien erholen sich weiter; Powell best\u00e4tigt: Fed weiter auf Zinssenkungspfad - SmartTrader","isPartOf":{"@id":"https:\/\/smarttrader.community\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/aktien-erholen-sich-weiter-powell-bestaetigt-fed-weiter-auf-zinssenkungspfad\/#primaryimage"},"image":{"@id":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/aktien-erholen-sich-weiter-powell-bestaetigt-fed-weiter-auf-zinssenkungspfad\/#primaryimage"},"thumbnailUrl":"https:\/\/smarttrader.community\/wp-content\/uploads\/2024\/04\/04.04.2024_TITLE_Artboard-1-copy-9.webp","datePublished":"2024-04-04T13:23:13+00:00","dateModified":"2024-04-04T13:34:44+00:00","author":{"@id":"https:\/\/smarttrader.community\/de\/#\/schema\/person\/4f791355f3f400fd2dd91d9c57c4c067"},"description":"Aktien erholen sich weiter; Powell best\u00e4tigt: Fed weiter auf Zinssenkungspfad. Die Aktien erholen sich weiter von ihrem Einbruch am Dienstag...","breadcrumb":{"@id":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/aktien-erholen-sich-weiter-powell-bestaetigt-fed-weiter-auf-zinssenkungspfad\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/aktien-erholen-sich-weiter-powell-bestaetigt-fed-weiter-auf-zinssenkungspfad\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/aktien-erholen-sich-weiter-powell-bestaetigt-fed-weiter-auf-zinssenkungspfad\/#primaryimage","url":"https:\/\/smarttrader.community\/wp-content\/uploads\/2024\/04\/04.04.2024_TITLE_Artboard-1-copy-9.webp","contentUrl":"https:\/\/smarttrader.community\/wp-content\/uploads\/2024\/04\/04.04.2024_TITLE_Artboard-1-copy-9.webp","width":1081,"height":721},{"@type":"BreadcrumbList","@id":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/aktien-erholen-sich-weiter-powell-bestaetigt-fed-weiter-auf-zinssenkungspfad\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/smarttrader.community\/de\/"},{"@type":"ListItem","position":2,"name":"Aktien erholen sich weiter; Powell best\u00e4tigt: Fed weiter auf Zinssenkungspfad"}]},{"@type":"WebSite","@id":"https:\/\/smarttrader.community\/de\/#website","url":"https:\/\/smarttrader.community\/de\/","name":"SmartTrader","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/smarttrader.community\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/smarttrader.community\/de\/#\/schema\/person\/4f791355f3f400fd2dd91d9c57c4c067","name":"Robert Lindner","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/05\/robert-lindner_avatar_1-96x96.png","url":"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/05\/robert-lindner_avatar_1-96x96.png","contentUrl":"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/05\/robert-lindner_avatar_1-96x96.png","caption":"Robert Lindner"},"sameAs":["https:\/\/wwww.smarttrader.community\/"],"url":"https:\/\/smarttrader.community\/de\/author\/robert_smarttrader\/"}]}},"_links":{"self":[{"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/posts\/36615","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/users\/663"}],"replies":[{"embeddable":true,"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/comments?post=36615"}],"version-history":[{"count":0,"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/posts\/36615\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/media\/36613"}],"wp:attachment":[{"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/media?parent=36615"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/categories?post=36615"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/tags?post=36615"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}