{"id":36854,"date":"2024-04-19T13:22:41","date_gmt":"2024-04-19T13:22:41","guid":{"rendered":"https:\/\/smarttrader.community\/?p=36854"},"modified":"2024-04-19T13:26:28","modified_gmt":"2024-04-19T13:26:28","slug":"aktienmaerkte-erholten-sich-da-sorge-um-israel-iran-konflikts-wieder-abkuehlte","status":"publish","type":"post","link":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/aktienmaerkte-erholten-sich-da-sorge-um-israel-iran-konflikts-wieder-abkuehlte\/","title":{"rendered":"Aktienm\u00e4rkte erholten sich da Sorge um Israel-Iran-Konflikts wieder abk\u00fchlte"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Wir halten uns heute kurz, da wir die <strong>Situation zwischen Israel und dem Iran weiter beobachten m\u00fcssen<\/strong>. Ich spreche auch mit meinen Kontakten in den USA und in Tel Aviv, um Informationen zu erhalten, bevor sie in den Medien erscheinen &#8211; schwierig; falls m\u00f6glich.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Wir sehen, dass die <strong>Wall Street ihre fr\u00fchen Verluste wieder wettgemacht hat<\/strong>. Auch <strong>\u00d6l <\/strong>und <strong>Gold<\/strong>, die zun\u00e4chst in die H\u00f6he geschnellt waren, <strong>fielen <\/strong>&#8211; sogar unter das Niveau vor dem angeblichen israelischen Angriff auf den Iran &#8211; was wir als einen <strong>\u00dcberverkauf <\/strong>des Marktes ansehen, nachdem die zun\u00e4chst gestiegen Sorgen vor einer weiteren Eskalation im Nahen Osten wieder verkauft wurden. Die iranischen <strong>Medien spielten die Auswirkungen der israelischen Angriffe herunter<\/strong> &#8211; beide Seiten versuchen offensichtlich eine <strong>weitere Eskalation zu vermeiden<\/strong>, um den Konflikt nicht zu einem Krieg ausarten zu lassen, und auch regionale M\u00e4chte sowie westliche Staaten versuchen, eine <strong>weitere Eskalation zu verhindern.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Auch die <strong>Renditen von Staatsanleihen machten einen Gro\u00dfteil der anf\u00e4nglichen Bewegung wieder wett<\/strong>, die die 10-j\u00e4hrige Rendite um 14 Basispunkte nach unten trieb, nachdem Israel weniger als eine Woche nach den Raketen- und Drohnenangriffen Teherans einen Vergeltungsangriff auf den Iran gestartet hatte. Ein iranischer Milit\u00e4rbeamter erkl\u00e4rte, <strong>Teheran sehe sich nicht gezwungen, auf die Explosionen zu reagieren<\/strong>, die laut US-Beamten durch israelische Angriffe verursacht wurden. Auch der <strong>USD <\/strong>gab einige seiner fr\u00fcheren Gewinne wieder ab, obwohl die Bewegungen relativ moderat waren.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die Angriffe k\u00f6nnen aber auch <strong>nicht ignoriert<\/strong> werden. Aus einem <strong>Schattenkrieg ist zumindest teilweise ein hei\u00dfer Konflikt geworden<\/strong>, bei dem sich nun beide Seiten direkt gegenseitig angreifen. Ich erwarte daher, dass <strong>die Besorgnis im Laufe des Tages und vor dem Wochenende wieder zunehmen wird<\/strong> und <strong>Gold <\/strong>wahrscheinlich auch wieder in den Bereich zwischen $2.390 &#8211; $2.400 hineinschauen wird.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">F\u00fcr Gegenwind an der <strong>Wall Street sorgten in den letzten Tagen vor allem die starken US-Wirtschaftsdaten<\/strong> und die hawkischen \u00c4u\u00dferungen von Fed-Vertretern &#8211; beides hat die Erwartungen des <strong>Marktes an Zinssenkungen in diesem Jahr reduziert<\/strong>. Der Chef der Minneapolis Fed, Neel Kashkari, sagte, dass die Fed die Zinsen im Laufe des Jahres beibehalten k\u00f6nnte.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">W\u00e4hrend sich die Aktienkurse erholten, werden sich die <strong>Anleger nicht trauen, k\u00fchne Wetten abzuschlie\u00dfen<\/strong> &#8211; auch wenn das starke Wachstum von <strong>Netflix <\/strong>im ersten Quartal einen positiven Grundton f\u00fcr die anstehenden Berichte \u00fcber die Gewinne der gro\u00dfen US-Tech-Unternehmen vorgibt &#8211; auch wenn <strong>Netflix selbst aufgrund einer eher entt\u00e4uschenden Prognose f\u00fcr das zweite Quartal niedriger notiert<\/strong>. Angesichts des sehr starken ersten Quartals von Netflix ist es jedoch wahrscheinlich, dass der Streaming-Riese einen Teil der vorb\u00f6rslichen Verluste wieder aufholen wird.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Auch die <strong>\u00d6lpreise fielen auf einen mehrw\u00f6chigen Tiefststand.<\/strong> Es ist schwer vorstellbar, dass die Anleger \u00fcber das Wochenende SHORT-Positionen in \u00d6l oder Gold halten wollen, da nicht auszuschlie\u00dfen ist, dass die geopolitischen Risiken nicht wieder steigen k\u00f6nnen.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Wir halten uns heute kurz, da wir die Situation zwischen Israel und dem Iran weiter beobachten m\u00fcssen. Ich spreche auch&#8230;<\/p>\n","protected":false},"author":663,"featured_media":36852,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","pmpro_default_level":"","_daextam_enable_autolinks":"1","footnotes":""},"categories":[117],"tags":[],"class_list":["post-36854","post","type-post","status-publish","format-standard","has-post-thumbnail","category-taegliche-aktualisierungen","pmpro-has-access"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Aktienm\u00e4rkte erholten sich da Sorge um Israel-Iran-Konflikts wieder abk\u00fchlte - SmartTrader<\/title>\n<meta name=\"description\" content=\"Aktienm\u00e4rkte erholten sich da Sorge um Israel-Iran-Konflikts wieder abk\u00fchlte. Wir halten uns heute kurz, da wir die Situation...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/aktienmaerkte-erholten-sich-da-sorge-um-israel-iran-konflikts-wieder-abkuehlte\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Aktienm\u00e4rkte erholten sich da Sorge um Israel-Iran-Konflikts wieder abk\u00fchlte - SmartTrader\" \/>\n<meta property=\"og:description\" content=\"Aktienm\u00e4rkte erholten sich da Sorge um Israel-Iran-Konflikts wieder abk\u00fchlte. Wir halten uns heute kurz, da wir die Situation...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/aktienmaerkte-erholten-sich-da-sorge-um-israel-iran-konflikts-wieder-abkuehlte\/\" \/>\n<meta property=\"og:site_name\" content=\"SmartTrader\" \/>\n<meta property=\"article:published_time\" content=\"2024-04-19T13:22:41+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-19T13:26:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/smarttrader.community\/wp-content\/uploads\/2024\/04\/19.04.2024_TITLE_Artboard-1-copy-9.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1081\" \/>\n\t<meta property=\"og:image:height\" content=\"721\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Robert Lindner\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Robert Lindner\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taegliche-aktualisierungen\\\/aktienmaerkte-erholten-sich-da-sorge-um-israel-iran-konflikts-wieder-abkuehlte\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taegliche-aktualisierungen\\\/aktienmaerkte-erholten-sich-da-sorge-um-israel-iran-konflikts-wieder-abkuehlte\\\/\"},\"author\":{\"name\":\"Robert Lindner\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/#\\\/schema\\\/person\\\/4f791355f3f400fd2dd91d9c57c4c067\"},\"headline\":\"Aktienm\u00e4rkte erholten sich da Sorge um Israel-Iran-Konflikts wieder abk\u00fchlte\",\"datePublished\":\"2024-04-19T13:22:41+00:00\",\"dateModified\":\"2024-04-19T13:26:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taegliche-aktualisierungen\\\/aktienmaerkte-erholten-sich-da-sorge-um-israel-iran-konflikts-wieder-abkuehlte\\\/\"},\"wordCount\":492,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taegliche-aktualisierungen\\\/aktienmaerkte-erholten-sich-da-sorge-um-israel-iran-konflikts-wieder-abkuehlte\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/19.04.2024_TITLE_Artboard-1-copy-9.webp\",\"articleSection\":[\"T\u00e4gliche Aktualisierungen\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/smarttrader.community\\\/de\\\/taegliche-aktualisierungen\\\/aktienmaerkte-erholten-sich-da-sorge-um-israel-iran-konflikts-wieder-abkuehlte\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taegliche-aktualisierungen\\\/aktienmaerkte-erholten-sich-da-sorge-um-israel-iran-konflikts-wieder-abkuehlte\\\/\",\"url\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taegliche-aktualisierungen\\\/aktienmaerkte-erholten-sich-da-sorge-um-israel-iran-konflikts-wieder-abkuehlte\\\/\",\"name\":\"Aktienm\u00e4rkte erholten sich da Sorge um Israel-Iran-Konflikts wieder abk\u00fchlte - SmartTrader\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taegliche-aktualisierungen\\\/aktienmaerkte-erholten-sich-da-sorge-um-israel-iran-konflikts-wieder-abkuehlte\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taegliche-aktualisierungen\\\/aktienmaerkte-erholten-sich-da-sorge-um-israel-iran-konflikts-wieder-abkuehlte\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/19.04.2024_TITLE_Artboard-1-copy-9.webp\",\"datePublished\":\"2024-04-19T13:22:41+00:00\",\"dateModified\":\"2024-04-19T13:26:28+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/#\\\/schema\\\/person\\\/4f791355f3f400fd2dd91d9c57c4c067\"},\"description\":\"Aktienm\u00e4rkte erholten sich da Sorge um Israel-Iran-Konflikts wieder abk\u00fchlte. Wir halten uns heute kurz, da wir die Situation...\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taegliche-aktualisierungen\\\/aktienmaerkte-erholten-sich-da-sorge-um-israel-iran-konflikts-wieder-abkuehlte\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/smarttrader.community\\\/de\\\/taegliche-aktualisierungen\\\/aktienmaerkte-erholten-sich-da-sorge-um-israel-iran-konflikts-wieder-abkuehlte\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taegliche-aktualisierungen\\\/aktienmaerkte-erholten-sich-da-sorge-um-israel-iran-konflikts-wieder-abkuehlte\\\/#primaryimage\",\"url\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/19.04.2024_TITLE_Artboard-1-copy-9.webp\",\"contentUrl\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/19.04.2024_TITLE_Artboard-1-copy-9.webp\",\"width\":1081,\"height\":721},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taegliche-aktualisierungen\\\/aktienmaerkte-erholten-sich-da-sorge-um-israel-iran-konflikts-wieder-abkuehlte\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Aktienm\u00e4rkte erholten sich da Sorge um Israel-Iran-Konflikts wieder abk\u00fchlte\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/\",\"name\":\"SmartTrader\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/#\\\/schema\\\/person\\\/4f791355f3f400fd2dd91d9c57c4c067\",\"name\":\"Robert Lindner\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/robert-lindner_avatar_1-96x96.png\",\"url\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/robert-lindner_avatar_1-96x96.png\",\"contentUrl\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/robert-lindner_avatar_1-96x96.png\",\"caption\":\"Robert Lindner\"},\"sameAs\":[\"https:\\\/\\\/wwww.smarttrader.community\\\/\"],\"url\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/author\\\/robert_smarttrader\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Aktienm\u00e4rkte erholten sich da Sorge um Israel-Iran-Konflikts wieder abk\u00fchlte - SmartTrader","description":"Aktienm\u00e4rkte erholten sich da Sorge um Israel-Iran-Konflikts wieder abk\u00fchlte. Wir halten uns heute kurz, da wir die Situation...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/aktienmaerkte-erholten-sich-da-sorge-um-israel-iran-konflikts-wieder-abkuehlte\/","og_locale":"de_DE","og_type":"article","og_title":"Aktienm\u00e4rkte erholten sich da Sorge um Israel-Iran-Konflikts wieder abk\u00fchlte - SmartTrader","og_description":"Aktienm\u00e4rkte erholten sich da Sorge um Israel-Iran-Konflikts wieder abk\u00fchlte. Wir halten uns heute kurz, da wir die Situation...","og_url":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/aktienmaerkte-erholten-sich-da-sorge-um-israel-iran-konflikts-wieder-abkuehlte\/","og_site_name":"SmartTrader","article_published_time":"2024-04-19T13:22:41+00:00","article_modified_time":"2024-04-19T13:26:28+00:00","og_image":[{"width":1081,"height":721,"url":"https:\/\/smarttrader.community\/wp-content\/uploads\/2024\/04\/19.04.2024_TITLE_Artboard-1-copy-9.webp","type":"image\/webp"}],"author":"Robert Lindner","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Robert Lindner","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/aktienmaerkte-erholten-sich-da-sorge-um-israel-iran-konflikts-wieder-abkuehlte\/#article","isPartOf":{"@id":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/aktienmaerkte-erholten-sich-da-sorge-um-israel-iran-konflikts-wieder-abkuehlte\/"},"author":{"name":"Robert Lindner","@id":"https:\/\/smarttrader.community\/de\/#\/schema\/person\/4f791355f3f400fd2dd91d9c57c4c067"},"headline":"Aktienm\u00e4rkte erholten sich da Sorge um Israel-Iran-Konflikts wieder abk\u00fchlte","datePublished":"2024-04-19T13:22:41+00:00","dateModified":"2024-04-19T13:26:28+00:00","mainEntityOfPage":{"@id":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/aktienmaerkte-erholten-sich-da-sorge-um-israel-iran-konflikts-wieder-abkuehlte\/"},"wordCount":492,"commentCount":0,"image":{"@id":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/aktienmaerkte-erholten-sich-da-sorge-um-israel-iran-konflikts-wieder-abkuehlte\/#primaryimage"},"thumbnailUrl":"https:\/\/smarttrader.community\/wp-content\/uploads\/2024\/04\/19.04.2024_TITLE_Artboard-1-copy-9.webp","articleSection":["T\u00e4gliche Aktualisierungen"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/aktienmaerkte-erholten-sich-da-sorge-um-israel-iran-konflikts-wieder-abkuehlte\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/aktienmaerkte-erholten-sich-da-sorge-um-israel-iran-konflikts-wieder-abkuehlte\/","url":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/aktienmaerkte-erholten-sich-da-sorge-um-israel-iran-konflikts-wieder-abkuehlte\/","name":"Aktienm\u00e4rkte erholten sich da Sorge um Israel-Iran-Konflikts wieder abk\u00fchlte - SmartTrader","isPartOf":{"@id":"https:\/\/smarttrader.community\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/aktienmaerkte-erholten-sich-da-sorge-um-israel-iran-konflikts-wieder-abkuehlte\/#primaryimage"},"image":{"@id":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/aktienmaerkte-erholten-sich-da-sorge-um-israel-iran-konflikts-wieder-abkuehlte\/#primaryimage"},"thumbnailUrl":"https:\/\/smarttrader.community\/wp-content\/uploads\/2024\/04\/19.04.2024_TITLE_Artboard-1-copy-9.webp","datePublished":"2024-04-19T13:22:41+00:00","dateModified":"2024-04-19T13:26:28+00:00","author":{"@id":"https:\/\/smarttrader.community\/de\/#\/schema\/person\/4f791355f3f400fd2dd91d9c57c4c067"},"description":"Aktienm\u00e4rkte erholten sich da Sorge um Israel-Iran-Konflikts wieder abk\u00fchlte. Wir halten uns heute kurz, da wir die Situation...","breadcrumb":{"@id":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/aktienmaerkte-erholten-sich-da-sorge-um-israel-iran-konflikts-wieder-abkuehlte\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/aktienmaerkte-erholten-sich-da-sorge-um-israel-iran-konflikts-wieder-abkuehlte\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/aktienmaerkte-erholten-sich-da-sorge-um-israel-iran-konflikts-wieder-abkuehlte\/#primaryimage","url":"https:\/\/smarttrader.community\/wp-content\/uploads\/2024\/04\/19.04.2024_TITLE_Artboard-1-copy-9.webp","contentUrl":"https:\/\/smarttrader.community\/wp-content\/uploads\/2024\/04\/19.04.2024_TITLE_Artboard-1-copy-9.webp","width":1081,"height":721},{"@type":"BreadcrumbList","@id":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/aktienmaerkte-erholten-sich-da-sorge-um-israel-iran-konflikts-wieder-abkuehlte\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/smarttrader.community\/de\/"},{"@type":"ListItem","position":2,"name":"Aktienm\u00e4rkte erholten sich da Sorge um Israel-Iran-Konflikts wieder abk\u00fchlte"}]},{"@type":"WebSite","@id":"https:\/\/smarttrader.community\/de\/#website","url":"https:\/\/smarttrader.community\/de\/","name":"SmartTrader","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/smarttrader.community\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/smarttrader.community\/de\/#\/schema\/person\/4f791355f3f400fd2dd91d9c57c4c067","name":"Robert Lindner","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/05\/robert-lindner_avatar_1-96x96.png","url":"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/05\/robert-lindner_avatar_1-96x96.png","contentUrl":"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/05\/robert-lindner_avatar_1-96x96.png","caption":"Robert Lindner"},"sameAs":["https:\/\/wwww.smarttrader.community\/"],"url":"https:\/\/smarttrader.community\/de\/author\/robert_smarttrader\/"}]}},"_links":{"self":[{"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/posts\/36854","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/users\/663"}],"replies":[{"embeddable":true,"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/comments?post=36854"}],"version-history":[{"count":0,"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/posts\/36854\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/media\/36852"}],"wp:attachment":[{"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/media?parent=36854"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/categories?post=36854"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/tags?post=36854"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}