{"id":36863,"date":"2024-04-22T09:41:43","date_gmt":"2024-04-22T09:41:43","guid":{"rendered":"https:\/\/smarttrader.community\/?p=36863"},"modified":"2024-04-22T09:46:58","modified_gmt":"2024-04-22T09:46:58","slug":"aktien-versuchen-nach-ausverkauf-wieder-in-schwung-zu-kommen-earnings-diese-woche-im-fokus","status":"publish","type":"post","link":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/aktien-versuchen-nach-ausverkauf-wieder-in-schwung-zu-kommen-earnings-diese-woche-im-fokus\/","title":{"rendered":"Aktien versuchen, nach Ausverkauf wieder in Schwung zu kommen; Earnings diese Woche im Fokus"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">\ud83d\udcc6 Montag, 22. April<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u25ba <strong>Europ\u00e4ische Aktien und US-Futures stiegen<\/strong>, als die Anleger ihren Fokus von den Spannungen im Nahen Osten auf die <strong>anstehenden Unternehmensgewinne und Wirtschaftsdaten richteten<\/strong>. Der <strong>Stoxx Europe 600 Index legte um 0,25% zu <\/strong>und versuchte, nach den Verlusten der letzten Woche wieder an Fahrt zu gewinnen. Der britische <strong>FTSE 100 kletterte um 1,1%<\/strong>, w\u00e4hrend der franz\u00f6sische <strong>CAC 40 um 0,1%<\/strong> und der deutsche <strong>DAX um 0,3% zulegten. Prosus NV <\/strong>in Europa verzeichnete einen deutlichen Kursanstieg, nachdem <strong>Tencent Holdings<\/strong> durch die erfolgreiche Markteinf\u00fchrung eines gro\u00dfen Handyspiels eine Kursrallye hinlegte.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u25ba In den <strong>USA deuteten die Futures auf eine positive Er\u00f6ffnung der Wall Street hin<\/strong>, nachdem der Markt in der vergangenen Woche so stark eingebrochen war wie seit M\u00e4rz 2023 nicht mehr. Die <strong>Stimmung am Markt hat sich verbessert<\/strong>, da die geopolitischen Risiken nachgelassen haben, wie von unserem Chefanalysten Robert Lindner vorhergesagt, und die Anleger ihre Aufmerksamkeit auf <strong>fundamentale Wirtschaftsindikatoren und Unternehmensgewinne<\/strong> richten k\u00f6nnen. Besonders im Fokus stehen in dieser Woche die hochkar\u00e4tigen Ergebnisberichte von Tech-Giganten wie Microsoft, Meta und Alphabet. Der deutsche Softwareriese SAP wird heute seinen Bericht vorlegen. Es wird erwartet, dass diese E<strong>rgebnisse den S&P 500 stark beeinflussen werden<\/strong>, da die Anleger hoffen, dass die starken Gewinne den j\u00fcngsten Wachstumskurs trotz der Sorgen \u00fcber steigende Anleiherenditen aufrechterhalten k\u00f6nnen. Au\u00dferdem werden in dieser Woche Wirtschaftsindikatoren wie das <strong>US-BIP<\/strong> und die <strong>PCE-Preisdaten<\/strong>, das <strong>bevorzugte Inflationsma\u00df der Fed<\/strong>, ver\u00f6ffentlicht, die genau beobachtet werden, um weitere Hinweise auf die geldpolitische Ausrichtung zu erhalten.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/smarttrader.community\/membership-join\">Subscribe<\/a> to see more<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\ud83d\udcc6 Montag, 22. April \u25ba Europ\u00e4ische Aktien und US-Futures stiegen, als die Anleger ihren Fokus von den Spannungen im Nahen&#8230;<\/p>\n","protected":false},"author":1,"featured_media":27728,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","pmpro_default_level":"","_daextam_enable_autolinks":"1","footnotes":""},"categories":[172],"tags":[],"class_list":["post-36863","post","type-post","status-publish","format-standard","has-post-thumbnail","category-taglicher-marktuberblick","pmpro-has-access"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Aktien versuchen, nach Ausverkauf wieder in Schwung zu kommen; Earnings diese Woche im Fokus - SmartTrader<\/title>\n<meta name=\"description\" content=\"Aktien versuchen, nach Ausverkauf wieder in Schwung zu kommen; Earnings diese Woche im Fokus. \u25ba Europ\u00e4ische Aktien und US-Futures stiegen...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/aktien-versuchen-nach-ausverkauf-wieder-in-schwung-zu-kommen-earnings-diese-woche-im-fokus\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Aktien versuchen, nach Ausverkauf wieder in Schwung zu kommen; Earnings diese Woche im Fokus - SmartTrader\" \/>\n<meta property=\"og:description\" content=\"Aktien versuchen, nach Ausverkauf wieder in Schwung zu kommen; Earnings diese Woche im Fokus. \u25ba Europ\u00e4ische Aktien und US-Futures stiegen...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/aktien-versuchen-nach-ausverkauf-wieder-in-schwung-zu-kommen-earnings-diese-woche-im-fokus\/\" \/>\n<meta property=\"og:site_name\" content=\"SmartTrader\" \/>\n<meta property=\"article:published_time\" content=\"2024-04-22T09:41:43+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-22T09:46:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/11\/images-59.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"SmartTrader Analyst Team\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"SmartTrader Analyst Team\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taglicher-marktuberblick\\\/aktien-versuchen-nach-ausverkauf-wieder-in-schwung-zu-kommen-earnings-diese-woche-im-fokus\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taglicher-marktuberblick\\\/aktien-versuchen-nach-ausverkauf-wieder-in-schwung-zu-kommen-earnings-diese-woche-im-fokus\\\/\"},\"author\":{\"name\":\"SmartTrader Analyst Team\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/#\\\/schema\\\/person\\\/bfe0c456aafbdc04b9707983e59c4e05\"},\"headline\":\"Aktien versuchen, nach Ausverkauf wieder in Schwung zu kommen; Earnings diese Woche im Fokus\",\"datePublished\":\"2024-04-22T09:41:43+00:00\",\"dateModified\":\"2024-04-22T09:46:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taglicher-marktuberblick\\\/aktien-versuchen-nach-ausverkauf-wieder-in-schwung-zu-kommen-earnings-diese-woche-im-fokus\\\/\"},\"wordCount\":518,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taglicher-marktuberblick\\\/aktien-versuchen-nach-ausverkauf-wieder-in-schwung-zu-kommen-earnings-diese-woche-im-fokus\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/images-59.jpg\",\"articleSection\":[\"T\u00e4glicher Markt\u00fcberblick\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/smarttrader.community\\\/de\\\/taglicher-marktuberblick\\\/aktien-versuchen-nach-ausverkauf-wieder-in-schwung-zu-kommen-earnings-diese-woche-im-fokus\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taglicher-marktuberblick\\\/aktien-versuchen-nach-ausverkauf-wieder-in-schwung-zu-kommen-earnings-diese-woche-im-fokus\\\/\",\"url\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taglicher-marktuberblick\\\/aktien-versuchen-nach-ausverkauf-wieder-in-schwung-zu-kommen-earnings-diese-woche-im-fokus\\\/\",\"name\":\"Aktien versuchen, nach Ausverkauf wieder in Schwung zu kommen; Earnings diese Woche im Fokus - SmartTrader\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taglicher-marktuberblick\\\/aktien-versuchen-nach-ausverkauf-wieder-in-schwung-zu-kommen-earnings-diese-woche-im-fokus\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taglicher-marktuberblick\\\/aktien-versuchen-nach-ausverkauf-wieder-in-schwung-zu-kommen-earnings-diese-woche-im-fokus\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/images-59.jpg\",\"datePublished\":\"2024-04-22T09:41:43+00:00\",\"dateModified\":\"2024-04-22T09:46:58+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/#\\\/schema\\\/person\\\/bfe0c456aafbdc04b9707983e59c4e05\"},\"description\":\"Aktien versuchen, nach Ausverkauf wieder in Schwung zu kommen; Earnings diese Woche im Fokus. \u25ba Europ\u00e4ische Aktien und US-Futures stiegen...\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taglicher-marktuberblick\\\/aktien-versuchen-nach-ausverkauf-wieder-in-schwung-zu-kommen-earnings-diese-woche-im-fokus\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/smarttrader.community\\\/de\\\/taglicher-marktuberblick\\\/aktien-versuchen-nach-ausverkauf-wieder-in-schwung-zu-kommen-earnings-diese-woche-im-fokus\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taglicher-marktuberblick\\\/aktien-versuchen-nach-ausverkauf-wieder-in-schwung-zu-kommen-earnings-diese-woche-im-fokus\\\/#primaryimage\",\"url\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/images-59.jpg\",\"contentUrl\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/images-59.jpg\",\"width\":800,\"height\":500},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taglicher-marktuberblick\\\/aktien-versuchen-nach-ausverkauf-wieder-in-schwung-zu-kommen-earnings-diese-woche-im-fokus\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Aktien versuchen, nach Ausverkauf wieder in Schwung zu kommen; Earnings diese Woche im Fokus\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/\",\"name\":\"SmartTrader\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/#\\\/schema\\\/person\\\/bfe0c456aafbdc04b9707983e59c4e05\",\"name\":\"SmartTrader Analyst Team\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/admin_avatar_3-96x96.png\",\"url\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/admin_avatar_3-96x96.png\",\"contentUrl\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/admin_avatar_3-96x96.png\",\"caption\":\"SmartTrader Analyst Team\"},\"sameAs\":[\"https:\\\/\\\/smarttrader.community\"],\"url\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Aktien versuchen, nach Ausverkauf wieder in Schwung zu kommen; Earnings diese Woche im Fokus - SmartTrader","description":"Aktien versuchen, nach Ausverkauf wieder in Schwung zu kommen; Earnings diese Woche im Fokus. \u25ba Europ\u00e4ische Aktien und US-Futures stiegen...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/aktien-versuchen-nach-ausverkauf-wieder-in-schwung-zu-kommen-earnings-diese-woche-im-fokus\/","og_locale":"de_DE","og_type":"article","og_title":"Aktien versuchen, nach Ausverkauf wieder in Schwung zu kommen; Earnings diese Woche im Fokus - SmartTrader","og_description":"Aktien versuchen, nach Ausverkauf wieder in Schwung zu kommen; Earnings diese Woche im Fokus. \u25ba Europ\u00e4ische Aktien und US-Futures stiegen...","og_url":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/aktien-versuchen-nach-ausverkauf-wieder-in-schwung-zu-kommen-earnings-diese-woche-im-fokus\/","og_site_name":"SmartTrader","article_published_time":"2024-04-22T09:41:43+00:00","article_modified_time":"2024-04-22T09:46:58+00:00","og_image":[{"width":800,"height":500,"url":"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/11\/images-59.jpg","type":"image\/jpeg"}],"author":"SmartTrader Analyst Team","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"SmartTrader Analyst Team","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/aktien-versuchen-nach-ausverkauf-wieder-in-schwung-zu-kommen-earnings-diese-woche-im-fokus\/#article","isPartOf":{"@id":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/aktien-versuchen-nach-ausverkauf-wieder-in-schwung-zu-kommen-earnings-diese-woche-im-fokus\/"},"author":{"name":"SmartTrader Analyst Team","@id":"https:\/\/smarttrader.community\/de\/#\/schema\/person\/bfe0c456aafbdc04b9707983e59c4e05"},"headline":"Aktien versuchen, nach Ausverkauf wieder in Schwung zu kommen; Earnings diese Woche im Fokus","datePublished":"2024-04-22T09:41:43+00:00","dateModified":"2024-04-22T09:46:58+00:00","mainEntityOfPage":{"@id":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/aktien-versuchen-nach-ausverkauf-wieder-in-schwung-zu-kommen-earnings-diese-woche-im-fokus\/"},"wordCount":518,"commentCount":0,"image":{"@id":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/aktien-versuchen-nach-ausverkauf-wieder-in-schwung-zu-kommen-earnings-diese-woche-im-fokus\/#primaryimage"},"thumbnailUrl":"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/11\/images-59.jpg","articleSection":["T\u00e4glicher Markt\u00fcberblick"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/aktien-versuchen-nach-ausverkauf-wieder-in-schwung-zu-kommen-earnings-diese-woche-im-fokus\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/aktien-versuchen-nach-ausverkauf-wieder-in-schwung-zu-kommen-earnings-diese-woche-im-fokus\/","url":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/aktien-versuchen-nach-ausverkauf-wieder-in-schwung-zu-kommen-earnings-diese-woche-im-fokus\/","name":"Aktien versuchen, nach Ausverkauf wieder in Schwung zu kommen; Earnings diese Woche im Fokus - SmartTrader","isPartOf":{"@id":"https:\/\/smarttrader.community\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/aktien-versuchen-nach-ausverkauf-wieder-in-schwung-zu-kommen-earnings-diese-woche-im-fokus\/#primaryimage"},"image":{"@id":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/aktien-versuchen-nach-ausverkauf-wieder-in-schwung-zu-kommen-earnings-diese-woche-im-fokus\/#primaryimage"},"thumbnailUrl":"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/11\/images-59.jpg","datePublished":"2024-04-22T09:41:43+00:00","dateModified":"2024-04-22T09:46:58+00:00","author":{"@id":"https:\/\/smarttrader.community\/de\/#\/schema\/person\/bfe0c456aafbdc04b9707983e59c4e05"},"description":"Aktien versuchen, nach Ausverkauf wieder in Schwung zu kommen; Earnings diese Woche im Fokus. \u25ba Europ\u00e4ische Aktien und US-Futures stiegen...","breadcrumb":{"@id":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/aktien-versuchen-nach-ausverkauf-wieder-in-schwung-zu-kommen-earnings-diese-woche-im-fokus\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/aktien-versuchen-nach-ausverkauf-wieder-in-schwung-zu-kommen-earnings-diese-woche-im-fokus\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/aktien-versuchen-nach-ausverkauf-wieder-in-schwung-zu-kommen-earnings-diese-woche-im-fokus\/#primaryimage","url":"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/11\/images-59.jpg","contentUrl":"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/11\/images-59.jpg","width":800,"height":500},{"@type":"BreadcrumbList","@id":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/aktien-versuchen-nach-ausverkauf-wieder-in-schwung-zu-kommen-earnings-diese-woche-im-fokus\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/smarttrader.community\/de\/"},{"@type":"ListItem","position":2,"name":"Aktien versuchen, nach Ausverkauf wieder in Schwung zu kommen; Earnings diese Woche im Fokus"}]},{"@type":"WebSite","@id":"https:\/\/smarttrader.community\/de\/#website","url":"https:\/\/smarttrader.community\/de\/","name":"SmartTrader","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/smarttrader.community\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/smarttrader.community\/de\/#\/schema\/person\/bfe0c456aafbdc04b9707983e59c4e05","name":"SmartTrader Analyst Team","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/03\/admin_avatar_3-96x96.png","url":"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/03\/admin_avatar_3-96x96.png","contentUrl":"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/03\/admin_avatar_3-96x96.png","caption":"SmartTrader Analyst Team"},"sameAs":["https:\/\/smarttrader.community"],"url":"https:\/\/smarttrader.community\/de\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/posts\/36863","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/comments?post=36863"}],"version-history":[{"count":0,"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/posts\/36863\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/media\/27728"}],"wp:attachment":[{"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/media?parent=36863"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/categories?post=36863"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/tags?post=36863"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}