{"id":37407,"date":"2024-05-09T09:20:56","date_gmt":"2024-05-09T09:20:56","guid":{"rendered":"https:\/\/smarttrader.community\/?p=37407"},"modified":"2024-05-09T09:26:38","modified_gmt":"2024-05-09T09:26:38","slug":"globale-aktien-leicht-im-minus-vor-boe-zinsentscheidung-us-arbeitsmarktdaten-stimmungsdaten","status":"publish","type":"post","link":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/globale-aktien-leicht-im-minus-vor-boe-zinsentscheidung-us-arbeitsmarktdaten-stimmungsdaten\/","title":{"rendered":"Globale Aktien leicht im Minus vor BOE-Zinsentscheidung &amp; US-Arbeitsmarktdaten \/ Stimmungsdaten"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">\ud83d\udcc6 Donnerstag, 9. Mai<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u25ba Der <strong>Stoxx 600 in Europa gab nach vier aufeinanderfolgenden Tagen mit Kursgewinnen leicht nach<\/strong>, da die Investoren auf die <strong>Zinsentscheidung der Bank of England <\/strong>warten. Es wird erwartet, dass die <strong>BOE die Zinss\u00e4tze beibeh\u00e4lt,<\/strong> aber die H\u00e4ndler werden die Abstimmung auf m\u00f6gliche dovishe Signale hin \u00fcberpr\u00fcfen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u25ba Die <strong>US-Aktienfutures deuten zur Er\u00f6ffnung an der Wall Street auf R\u00fcckg\u00e4nge hin, der S&P 500 verliert 0,2%.<\/strong> Die Investoren verdauen gemischte Gewinnmeldungen, vor allem von <strong>Airbnb <\/strong>und den in den USA notierten Aktien von <strong>Arm Holdings<\/strong>, die beide einen schw\u00e4cher als erwarteten Ausblick gaben. Auch Intel musste Einbu\u00dfen hinnehmen, da die USA Lizenzen f\u00fcr den Verkauf von Chips an Huawei Technologies widerrufen haben. Die Pr\u00e4sidentin der Fed Bank of Boston, Susan <strong>Collins<\/strong>, signalisierte, dass die <strong>Zinss\u00e4tze m\u00f6glicherweise l\u00e4nger als bisher angenommen hoch bleiben m\u00fcssen<\/strong>, um die <strong>Inflation zu kontrollieren<\/strong>. Die <strong>w\u00f6chentlichen Erstantr\u00e4ge auf Arbeitslosenunterst\u00fctzung <\/strong>und der <strong>Verbraucherstimmungsindex der University of Michigan<\/strong> werden im Laufe des Tages ver\u00f6ffentlicht, w\u00e4hrend die Inflationsdaten n\u00e4chste Woche erwartet werden.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/smarttrader.community\/membership-join\">Subscribe<\/a> to see more<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\ud83d\udcc6 Donnerstag, 9. Mai \u25ba Der Stoxx 600 in Europa gab nach vier aufeinanderfolgenden Tagen mit Kursgewinnen leicht nach, da&#8230;<\/p>\n","protected":false},"author":1,"featured_media":21020,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","pmpro_default_level":"","_daextam_enable_autolinks":"1","footnotes":""},"categories":[172],"tags":[],"class_list":["post-37407","post","type-post","status-publish","format-standard","has-post-thumbnail","category-taglicher-marktuberblick","pmpro-has-access"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Globale Aktien leicht im Minus vor BOE-Zinsentscheidung &amp; US-Arbeitsmarktdaten \/ Stimmungsdaten - SmartTrader<\/title>\n<meta name=\"description\" content=\"Globale Aktien leicht im Minus vor BOE-Zinsentscheidung &amp; US-Arbeitsmarktdaten \/ Stimmungsdaten. \u25ba Der Stoxx 600 in Europa gab nach vier...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/globale-aktien-leicht-im-minus-vor-boe-zinsentscheidung-us-arbeitsmarktdaten-stimmungsdaten\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Globale Aktien leicht im Minus vor BOE-Zinsentscheidung &amp; US-Arbeitsmarktdaten \/ Stimmungsdaten - SmartTrader\" \/>\n<meta property=\"og:description\" content=\"Globale Aktien leicht im Minus vor BOE-Zinsentscheidung &amp; US-Arbeitsmarktdaten \/ Stimmungsdaten. \u25ba Der Stoxx 600 in Europa gab nach vier...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/globale-aktien-leicht-im-minus-vor-boe-zinsentscheidung-us-arbeitsmarktdaten-stimmungsdaten\/\" \/>\n<meta property=\"og:site_name\" content=\"SmartTrader\" \/>\n<meta property=\"article:published_time\" content=\"2024-05-09T09:20:56+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-05-09T09:26:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/08\/images-9.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"SmartTrader Analyst Team\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"SmartTrader Analyst Team\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taglicher-marktuberblick\\\/globale-aktien-leicht-im-minus-vor-boe-zinsentscheidung-us-arbeitsmarktdaten-stimmungsdaten\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taglicher-marktuberblick\\\/globale-aktien-leicht-im-minus-vor-boe-zinsentscheidung-us-arbeitsmarktdaten-stimmungsdaten\\\/\"},\"author\":{\"name\":\"SmartTrader Analyst Team\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/#\\\/schema\\\/person\\\/bfe0c456aafbdc04b9707983e59c4e05\"},\"headline\":\"Globale Aktien leicht im Minus vor BOE-Zinsentscheidung &amp; US-Arbeitsmarktdaten \\\/ Stimmungsdaten\",\"datePublished\":\"2024-05-09T09:20:56+00:00\",\"dateModified\":\"2024-05-09T09:26:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taglicher-marktuberblick\\\/globale-aktien-leicht-im-minus-vor-boe-zinsentscheidung-us-arbeitsmarktdaten-stimmungsdaten\\\/\"},\"wordCount\":473,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taglicher-marktuberblick\\\/globale-aktien-leicht-im-minus-vor-boe-zinsentscheidung-us-arbeitsmarktdaten-stimmungsdaten\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/images-9.jpg\",\"articleSection\":[\"T\u00e4glicher Markt\u00fcberblick\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/smarttrader.community\\\/de\\\/taglicher-marktuberblick\\\/globale-aktien-leicht-im-minus-vor-boe-zinsentscheidung-us-arbeitsmarktdaten-stimmungsdaten\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taglicher-marktuberblick\\\/globale-aktien-leicht-im-minus-vor-boe-zinsentscheidung-us-arbeitsmarktdaten-stimmungsdaten\\\/\",\"url\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taglicher-marktuberblick\\\/globale-aktien-leicht-im-minus-vor-boe-zinsentscheidung-us-arbeitsmarktdaten-stimmungsdaten\\\/\",\"name\":\"Globale Aktien leicht im Minus vor BOE-Zinsentscheidung &amp; US-Arbeitsmarktdaten \\\/ Stimmungsdaten - SmartTrader\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taglicher-marktuberblick\\\/globale-aktien-leicht-im-minus-vor-boe-zinsentscheidung-us-arbeitsmarktdaten-stimmungsdaten\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taglicher-marktuberblick\\\/globale-aktien-leicht-im-minus-vor-boe-zinsentscheidung-us-arbeitsmarktdaten-stimmungsdaten\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/images-9.jpg\",\"datePublished\":\"2024-05-09T09:20:56+00:00\",\"dateModified\":\"2024-05-09T09:26:38+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/#\\\/schema\\\/person\\\/bfe0c456aafbdc04b9707983e59c4e05\"},\"description\":\"Globale Aktien leicht im Minus vor BOE-Zinsentscheidung & US-Arbeitsmarktdaten \\\/ Stimmungsdaten. \u25ba Der Stoxx 600 in Europa gab nach vier...\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taglicher-marktuberblick\\\/globale-aktien-leicht-im-minus-vor-boe-zinsentscheidung-us-arbeitsmarktdaten-stimmungsdaten\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/smarttrader.community\\\/de\\\/taglicher-marktuberblick\\\/globale-aktien-leicht-im-minus-vor-boe-zinsentscheidung-us-arbeitsmarktdaten-stimmungsdaten\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taglicher-marktuberblick\\\/globale-aktien-leicht-im-minus-vor-boe-zinsentscheidung-us-arbeitsmarktdaten-stimmungsdaten\\\/#primaryimage\",\"url\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/images-9.jpg\",\"contentUrl\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/images-9.jpg\",\"width\":800,\"height\":500},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taglicher-marktuberblick\\\/globale-aktien-leicht-im-minus-vor-boe-zinsentscheidung-us-arbeitsmarktdaten-stimmungsdaten\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Globale Aktien leicht im Minus vor BOE-Zinsentscheidung &amp; US-Arbeitsmarktdaten \\\/ Stimmungsdaten\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/\",\"name\":\"SmartTrader\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/#\\\/schema\\\/person\\\/bfe0c456aafbdc04b9707983e59c4e05\",\"name\":\"SmartTrader Analyst Team\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/admin_avatar_3-96x96.png\",\"url\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/admin_avatar_3-96x96.png\",\"contentUrl\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/admin_avatar_3-96x96.png\",\"caption\":\"SmartTrader Analyst Team\"},\"sameAs\":[\"https:\\\/\\\/smarttrader.community\"],\"url\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Globale Aktien leicht im Minus vor BOE-Zinsentscheidung &amp; US-Arbeitsmarktdaten \/ Stimmungsdaten - SmartTrader","description":"Globale Aktien leicht im Minus vor BOE-Zinsentscheidung & US-Arbeitsmarktdaten \/ Stimmungsdaten. \u25ba Der Stoxx 600 in Europa gab nach vier...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/globale-aktien-leicht-im-minus-vor-boe-zinsentscheidung-us-arbeitsmarktdaten-stimmungsdaten\/","og_locale":"de_DE","og_type":"article","og_title":"Globale Aktien leicht im Minus vor BOE-Zinsentscheidung &amp; US-Arbeitsmarktdaten \/ Stimmungsdaten - SmartTrader","og_description":"Globale Aktien leicht im Minus vor BOE-Zinsentscheidung & US-Arbeitsmarktdaten \/ Stimmungsdaten. \u25ba Der Stoxx 600 in Europa gab nach vier...","og_url":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/globale-aktien-leicht-im-minus-vor-boe-zinsentscheidung-us-arbeitsmarktdaten-stimmungsdaten\/","og_site_name":"SmartTrader","article_published_time":"2024-05-09T09:20:56+00:00","article_modified_time":"2024-05-09T09:26:38+00:00","og_image":[{"width":800,"height":500,"url":"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/08\/images-9.jpg","type":"image\/jpeg"}],"author":"SmartTrader Analyst Team","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"SmartTrader Analyst Team","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/globale-aktien-leicht-im-minus-vor-boe-zinsentscheidung-us-arbeitsmarktdaten-stimmungsdaten\/#article","isPartOf":{"@id":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/globale-aktien-leicht-im-minus-vor-boe-zinsentscheidung-us-arbeitsmarktdaten-stimmungsdaten\/"},"author":{"name":"SmartTrader Analyst Team","@id":"https:\/\/smarttrader.community\/de\/#\/schema\/person\/bfe0c456aafbdc04b9707983e59c4e05"},"headline":"Globale Aktien leicht im Minus vor BOE-Zinsentscheidung &amp; US-Arbeitsmarktdaten \/ Stimmungsdaten","datePublished":"2024-05-09T09:20:56+00:00","dateModified":"2024-05-09T09:26:38+00:00","mainEntityOfPage":{"@id":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/globale-aktien-leicht-im-minus-vor-boe-zinsentscheidung-us-arbeitsmarktdaten-stimmungsdaten\/"},"wordCount":473,"commentCount":0,"image":{"@id":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/globale-aktien-leicht-im-minus-vor-boe-zinsentscheidung-us-arbeitsmarktdaten-stimmungsdaten\/#primaryimage"},"thumbnailUrl":"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/08\/images-9.jpg","articleSection":["T\u00e4glicher Markt\u00fcberblick"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/globale-aktien-leicht-im-minus-vor-boe-zinsentscheidung-us-arbeitsmarktdaten-stimmungsdaten\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/globale-aktien-leicht-im-minus-vor-boe-zinsentscheidung-us-arbeitsmarktdaten-stimmungsdaten\/","url":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/globale-aktien-leicht-im-minus-vor-boe-zinsentscheidung-us-arbeitsmarktdaten-stimmungsdaten\/","name":"Globale Aktien leicht im Minus vor BOE-Zinsentscheidung &amp; US-Arbeitsmarktdaten \/ Stimmungsdaten - SmartTrader","isPartOf":{"@id":"https:\/\/smarttrader.community\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/globale-aktien-leicht-im-minus-vor-boe-zinsentscheidung-us-arbeitsmarktdaten-stimmungsdaten\/#primaryimage"},"image":{"@id":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/globale-aktien-leicht-im-minus-vor-boe-zinsentscheidung-us-arbeitsmarktdaten-stimmungsdaten\/#primaryimage"},"thumbnailUrl":"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/08\/images-9.jpg","datePublished":"2024-05-09T09:20:56+00:00","dateModified":"2024-05-09T09:26:38+00:00","author":{"@id":"https:\/\/smarttrader.community\/de\/#\/schema\/person\/bfe0c456aafbdc04b9707983e59c4e05"},"description":"Globale Aktien leicht im Minus vor BOE-Zinsentscheidung & US-Arbeitsmarktdaten \/ Stimmungsdaten. \u25ba Der Stoxx 600 in Europa gab nach vier...","breadcrumb":{"@id":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/globale-aktien-leicht-im-minus-vor-boe-zinsentscheidung-us-arbeitsmarktdaten-stimmungsdaten\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/globale-aktien-leicht-im-minus-vor-boe-zinsentscheidung-us-arbeitsmarktdaten-stimmungsdaten\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/globale-aktien-leicht-im-minus-vor-boe-zinsentscheidung-us-arbeitsmarktdaten-stimmungsdaten\/#primaryimage","url":"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/08\/images-9.jpg","contentUrl":"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/08\/images-9.jpg","width":800,"height":500},{"@type":"BreadcrumbList","@id":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/globale-aktien-leicht-im-minus-vor-boe-zinsentscheidung-us-arbeitsmarktdaten-stimmungsdaten\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/smarttrader.community\/de\/"},{"@type":"ListItem","position":2,"name":"Globale Aktien leicht im Minus vor BOE-Zinsentscheidung &amp; US-Arbeitsmarktdaten \/ Stimmungsdaten"}]},{"@type":"WebSite","@id":"https:\/\/smarttrader.community\/de\/#website","url":"https:\/\/smarttrader.community\/de\/","name":"SmartTrader","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/smarttrader.community\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/smarttrader.community\/de\/#\/schema\/person\/bfe0c456aafbdc04b9707983e59c4e05","name":"SmartTrader Analyst Team","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/03\/admin_avatar_3-96x96.png","url":"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/03\/admin_avatar_3-96x96.png","contentUrl":"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/03\/admin_avatar_3-96x96.png","caption":"SmartTrader Analyst Team"},"sameAs":["https:\/\/smarttrader.community"],"url":"https:\/\/smarttrader.community\/de\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/posts\/37407","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/comments?post=37407"}],"version-history":[{"count":0,"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/posts\/37407\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/media\/21020"}],"wp:attachment":[{"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/media?parent=37407"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/categories?post=37407"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/tags?post=37407"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}