{"id":37508,"date":"2024-05-10T09:31:25","date_gmt":"2024-05-10T09:31:25","guid":{"rendered":"https:\/\/smarttrader.community\/?p=37508"},"modified":"2024-05-10T09:36:30","modified_gmt":"2024-05-10T09:36:30","slug":"aktienrallye-geht-weiter-da-us-daten-fuer-zinssenkungen-sprechen-uk-gdp-daten-zeigen-ende-milder-rezession","status":"publish","type":"post","link":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/aktienrallye-geht-weiter-da-us-daten-fuer-zinssenkungen-sprechen-uk-gdp-daten-zeigen-ende-milder-rezession\/","title":{"rendered":"Aktienrallye geht weiter, da US-Daten f\u00fcr Zinssenkungen sprechen; UK-GDP-Daten zeigen Ende milder Rezession"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">\ud83d\udcc6 Freitag, 10. Mai<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u25ba Die<strong> europ\u00e4ischen M\u00e4rkte erholten sich<\/strong>, der <strong>Stoxx 600 stieg um 0,6% <\/strong>und erreicht damit den h\u00f6chsten Wochengewinn seit \u00fcber drei Monaten. Das <strong>britische Bruttoinlandsprodukt <\/strong>(BIP) wuchs im ersten Quartal 2024 um <strong>0,6% gegen\u00fcber dem Vorquartal u<\/strong>nd \u00fcbertraf damit die Erwartungen. Das monatliche BIP stieg von 0,2% im Februar auf 0,4% im M\u00e4rz, was auf Zuw\u00e4chse im Dienstleistungs- und Produktionssektor zur\u00fcckzuf\u00fchren ist. Der GBP legte zu, nachdem die Daten zeigten, dass die britische Wirtschaft eine leichte Rezession hinter sich gelassen hatte.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u25ba Im vorb\u00f6rslichen US-Handel wird der <strong>S&P 500-Future um 0,25 % h\u00f6her gehandelt <\/strong>(Nasdaq 100 0,3 %), nachdem der Index nur noch 1 % von seinem Allzeithoch entfernt war. <strong>Staatsanleihen und der USD blieben stabil,<\/strong> da die H\u00e4ndler mit <strong>m\u00f6glichen Zinssenkungen der Federal Reserve <\/strong>rechneten<strong>. <\/strong>H\u00f6her als erwartet ausgefallene <strong>US-Arbeitslosenantr\u00e4ge sprachen f\u00fcr eine Zinssenkung.<\/strong> Die Investoren beobachten aufmerksam die Kommentare der Fed-Sprecher Michelle <strong>Bowman <\/strong>und Neel <strong>Kashkari <\/strong>vor den wichtigen <strong>US-VPI-Daten <\/strong>in der n\u00e4chsten Woche.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/smarttrader.community\/membership-join\">Subscribe<\/a> to see more<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\ud83d\udcc6 Freitag, 10. Mai \u25ba Die europ\u00e4ischen M\u00e4rkte erholten sich, der Stoxx 600 stieg um 0,6% und erreicht damit den&#8230;<\/p>\n","protected":false},"author":1,"featured_media":27728,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","pmpro_default_level":"","_daextam_enable_autolinks":"1","footnotes":""},"categories":[172],"tags":[],"class_list":["post-37508","post","type-post","status-publish","format-standard","has-post-thumbnail","category-taglicher-marktuberblick","pmpro-has-access"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Aktienrallye geht weiter, da US-Daten f\u00fcr Zinssenkungen sprechen; UK-GDP-Daten zeigen Ende milder Rezession - SmartTrader<\/title>\n<meta name=\"description\" content=\"Aktienrallye geht weiter, da US-Daten f\u00fcr Zinssenkungen sprechen; UK-GDP-Daten zeigen Ende milder Rezession...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/aktienrallye-geht-weiter-da-us-daten-fuer-zinssenkungen-sprechen-uk-gdp-daten-zeigen-ende-milder-rezession\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Aktienrallye geht weiter, da US-Daten f\u00fcr Zinssenkungen sprechen; UK-GDP-Daten zeigen Ende milder Rezession - SmartTrader\" \/>\n<meta property=\"og:description\" content=\"Aktienrallye geht weiter, da US-Daten f\u00fcr Zinssenkungen sprechen; UK-GDP-Daten zeigen Ende milder Rezession...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/aktienrallye-geht-weiter-da-us-daten-fuer-zinssenkungen-sprechen-uk-gdp-daten-zeigen-ende-milder-rezession\/\" \/>\n<meta property=\"og:site_name\" content=\"SmartTrader\" \/>\n<meta property=\"article:published_time\" content=\"2024-05-10T09:31:25+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-05-10T09:36:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/11\/images-59.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"SmartTrader Analyst Team\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"SmartTrader Analyst Team\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taglicher-marktuberblick\\\/aktienrallye-geht-weiter-da-us-daten-fuer-zinssenkungen-sprechen-uk-gdp-daten-zeigen-ende-milder-rezession\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taglicher-marktuberblick\\\/aktienrallye-geht-weiter-da-us-daten-fuer-zinssenkungen-sprechen-uk-gdp-daten-zeigen-ende-milder-rezession\\\/\"},\"author\":{\"name\":\"SmartTrader Analyst Team\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/#\\\/schema\\\/person\\\/bfe0c456aafbdc04b9707983e59c4e05\"},\"headline\":\"Aktienrallye geht weiter, da US-Daten f\u00fcr Zinssenkungen sprechen; UK-GDP-Daten zeigen Ende milder Rezession\",\"datePublished\":\"2024-05-10T09:31:25+00:00\",\"dateModified\":\"2024-05-10T09:36:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taglicher-marktuberblick\\\/aktienrallye-geht-weiter-da-us-daten-fuer-zinssenkungen-sprechen-uk-gdp-daten-zeigen-ende-milder-rezession\\\/\"},\"wordCount\":387,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taglicher-marktuberblick\\\/aktienrallye-geht-weiter-da-us-daten-fuer-zinssenkungen-sprechen-uk-gdp-daten-zeigen-ende-milder-rezession\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/images-59.jpg\",\"articleSection\":[\"T\u00e4glicher Markt\u00fcberblick\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/smarttrader.community\\\/de\\\/taglicher-marktuberblick\\\/aktienrallye-geht-weiter-da-us-daten-fuer-zinssenkungen-sprechen-uk-gdp-daten-zeigen-ende-milder-rezession\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taglicher-marktuberblick\\\/aktienrallye-geht-weiter-da-us-daten-fuer-zinssenkungen-sprechen-uk-gdp-daten-zeigen-ende-milder-rezession\\\/\",\"url\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taglicher-marktuberblick\\\/aktienrallye-geht-weiter-da-us-daten-fuer-zinssenkungen-sprechen-uk-gdp-daten-zeigen-ende-milder-rezession\\\/\",\"name\":\"Aktienrallye geht weiter, da US-Daten f\u00fcr Zinssenkungen sprechen; UK-GDP-Daten zeigen Ende milder Rezession - SmartTrader\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taglicher-marktuberblick\\\/aktienrallye-geht-weiter-da-us-daten-fuer-zinssenkungen-sprechen-uk-gdp-daten-zeigen-ende-milder-rezession\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taglicher-marktuberblick\\\/aktienrallye-geht-weiter-da-us-daten-fuer-zinssenkungen-sprechen-uk-gdp-daten-zeigen-ende-milder-rezession\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/images-59.jpg\",\"datePublished\":\"2024-05-10T09:31:25+00:00\",\"dateModified\":\"2024-05-10T09:36:30+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/#\\\/schema\\\/person\\\/bfe0c456aafbdc04b9707983e59c4e05\"},\"description\":\"Aktienrallye geht weiter, da US-Daten f\u00fcr Zinssenkungen sprechen; UK-GDP-Daten zeigen Ende milder Rezession...\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taglicher-marktuberblick\\\/aktienrallye-geht-weiter-da-us-daten-fuer-zinssenkungen-sprechen-uk-gdp-daten-zeigen-ende-milder-rezession\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/smarttrader.community\\\/de\\\/taglicher-marktuberblick\\\/aktienrallye-geht-weiter-da-us-daten-fuer-zinssenkungen-sprechen-uk-gdp-daten-zeigen-ende-milder-rezession\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taglicher-marktuberblick\\\/aktienrallye-geht-weiter-da-us-daten-fuer-zinssenkungen-sprechen-uk-gdp-daten-zeigen-ende-milder-rezession\\\/#primaryimage\",\"url\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/images-59.jpg\",\"contentUrl\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/images-59.jpg\",\"width\":800,\"height\":500},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taglicher-marktuberblick\\\/aktienrallye-geht-weiter-da-us-daten-fuer-zinssenkungen-sprechen-uk-gdp-daten-zeigen-ende-milder-rezession\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Aktienrallye geht weiter, da US-Daten f\u00fcr Zinssenkungen sprechen; UK-GDP-Daten zeigen Ende milder Rezession\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/\",\"name\":\"SmartTrader\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/#\\\/schema\\\/person\\\/bfe0c456aafbdc04b9707983e59c4e05\",\"name\":\"SmartTrader Analyst Team\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/admin_avatar_3-96x96.png\",\"url\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/admin_avatar_3-96x96.png\",\"contentUrl\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/admin_avatar_3-96x96.png\",\"caption\":\"SmartTrader Analyst Team\"},\"sameAs\":[\"https:\\\/\\\/smarttrader.community\"],\"url\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Aktienrallye geht weiter, da US-Daten f\u00fcr Zinssenkungen sprechen; UK-GDP-Daten zeigen Ende milder Rezession - SmartTrader","description":"Aktienrallye geht weiter, da US-Daten f\u00fcr Zinssenkungen sprechen; UK-GDP-Daten zeigen Ende milder Rezession...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/aktienrallye-geht-weiter-da-us-daten-fuer-zinssenkungen-sprechen-uk-gdp-daten-zeigen-ende-milder-rezession\/","og_locale":"de_DE","og_type":"article","og_title":"Aktienrallye geht weiter, da US-Daten f\u00fcr Zinssenkungen sprechen; UK-GDP-Daten zeigen Ende milder Rezession - SmartTrader","og_description":"Aktienrallye geht weiter, da US-Daten f\u00fcr Zinssenkungen sprechen; UK-GDP-Daten zeigen Ende milder Rezession...","og_url":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/aktienrallye-geht-weiter-da-us-daten-fuer-zinssenkungen-sprechen-uk-gdp-daten-zeigen-ende-milder-rezession\/","og_site_name":"SmartTrader","article_published_time":"2024-05-10T09:31:25+00:00","article_modified_time":"2024-05-10T09:36:30+00:00","og_image":[{"width":800,"height":500,"url":"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/11\/images-59.jpg","type":"image\/jpeg"}],"author":"SmartTrader Analyst Team","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"SmartTrader Analyst Team","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/aktienrallye-geht-weiter-da-us-daten-fuer-zinssenkungen-sprechen-uk-gdp-daten-zeigen-ende-milder-rezession\/#article","isPartOf":{"@id":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/aktienrallye-geht-weiter-da-us-daten-fuer-zinssenkungen-sprechen-uk-gdp-daten-zeigen-ende-milder-rezession\/"},"author":{"name":"SmartTrader Analyst Team","@id":"https:\/\/smarttrader.community\/de\/#\/schema\/person\/bfe0c456aafbdc04b9707983e59c4e05"},"headline":"Aktienrallye geht weiter, da US-Daten f\u00fcr Zinssenkungen sprechen; UK-GDP-Daten zeigen Ende milder Rezession","datePublished":"2024-05-10T09:31:25+00:00","dateModified":"2024-05-10T09:36:30+00:00","mainEntityOfPage":{"@id":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/aktienrallye-geht-weiter-da-us-daten-fuer-zinssenkungen-sprechen-uk-gdp-daten-zeigen-ende-milder-rezession\/"},"wordCount":387,"commentCount":0,"image":{"@id":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/aktienrallye-geht-weiter-da-us-daten-fuer-zinssenkungen-sprechen-uk-gdp-daten-zeigen-ende-milder-rezession\/#primaryimage"},"thumbnailUrl":"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/11\/images-59.jpg","articleSection":["T\u00e4glicher Markt\u00fcberblick"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/aktienrallye-geht-weiter-da-us-daten-fuer-zinssenkungen-sprechen-uk-gdp-daten-zeigen-ende-milder-rezession\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/aktienrallye-geht-weiter-da-us-daten-fuer-zinssenkungen-sprechen-uk-gdp-daten-zeigen-ende-milder-rezession\/","url":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/aktienrallye-geht-weiter-da-us-daten-fuer-zinssenkungen-sprechen-uk-gdp-daten-zeigen-ende-milder-rezession\/","name":"Aktienrallye geht weiter, da US-Daten f\u00fcr Zinssenkungen sprechen; UK-GDP-Daten zeigen Ende milder Rezession - SmartTrader","isPartOf":{"@id":"https:\/\/smarttrader.community\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/aktienrallye-geht-weiter-da-us-daten-fuer-zinssenkungen-sprechen-uk-gdp-daten-zeigen-ende-milder-rezession\/#primaryimage"},"image":{"@id":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/aktienrallye-geht-weiter-da-us-daten-fuer-zinssenkungen-sprechen-uk-gdp-daten-zeigen-ende-milder-rezession\/#primaryimage"},"thumbnailUrl":"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/11\/images-59.jpg","datePublished":"2024-05-10T09:31:25+00:00","dateModified":"2024-05-10T09:36:30+00:00","author":{"@id":"https:\/\/smarttrader.community\/de\/#\/schema\/person\/bfe0c456aafbdc04b9707983e59c4e05"},"description":"Aktienrallye geht weiter, da US-Daten f\u00fcr Zinssenkungen sprechen; UK-GDP-Daten zeigen Ende milder Rezession...","breadcrumb":{"@id":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/aktienrallye-geht-weiter-da-us-daten-fuer-zinssenkungen-sprechen-uk-gdp-daten-zeigen-ende-milder-rezession\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/aktienrallye-geht-weiter-da-us-daten-fuer-zinssenkungen-sprechen-uk-gdp-daten-zeigen-ende-milder-rezession\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/aktienrallye-geht-weiter-da-us-daten-fuer-zinssenkungen-sprechen-uk-gdp-daten-zeigen-ende-milder-rezession\/#primaryimage","url":"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/11\/images-59.jpg","contentUrl":"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/11\/images-59.jpg","width":800,"height":500},{"@type":"BreadcrumbList","@id":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/aktienrallye-geht-weiter-da-us-daten-fuer-zinssenkungen-sprechen-uk-gdp-daten-zeigen-ende-milder-rezession\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/smarttrader.community\/de\/"},{"@type":"ListItem","position":2,"name":"Aktienrallye geht weiter, da US-Daten f\u00fcr Zinssenkungen sprechen; UK-GDP-Daten zeigen Ende milder Rezession"}]},{"@type":"WebSite","@id":"https:\/\/smarttrader.community\/de\/#website","url":"https:\/\/smarttrader.community\/de\/","name":"SmartTrader","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/smarttrader.community\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/smarttrader.community\/de\/#\/schema\/person\/bfe0c456aafbdc04b9707983e59c4e05","name":"SmartTrader Analyst Team","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/03\/admin_avatar_3-96x96.png","url":"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/03\/admin_avatar_3-96x96.png","contentUrl":"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/03\/admin_avatar_3-96x96.png","caption":"SmartTrader Analyst Team"},"sameAs":["https:\/\/smarttrader.community"],"url":"https:\/\/smarttrader.community\/de\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/posts\/37508","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/comments?post=37508"}],"version-history":[{"count":0,"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/posts\/37508\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/media\/27728"}],"wp:attachment":[{"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/media?parent=37508"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/categories?post=37508"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/tags?post=37508"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}