{"id":39195,"date":"2024-05-29T12:59:29","date_gmt":"2024-05-29T12:59:29","guid":{"rendered":"https:\/\/smarttrader.community\/?p=39195"},"modified":"2024-05-30T12:29:02","modified_gmt":"2024-05-30T12:29:02","slug":"zunehmende-inflationssorgen-belasten-aktien-anleihen-risikobereitschaft","status":"publish","type":"post","link":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/zunehmende-inflationssorgen-belasten-aktien-anleihen-risikobereitschaft\/","title":{"rendered":"Zunehmende Inflationssorgen belasten Aktien, Anleihen &amp; Risikobereitschaft"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Die <strong>Inflation steigt <\/strong>wieder. Ist das so? <strong>Hartn\u00e4ckige Inflationsdaten<\/strong>, sei es aus dem Vereinigten K\u00f6nigreich letzte Woche oder heute aus <strong>Australien<\/strong>, wo die VPI-Daten im April statt der erwarteten Abk\u00fchlung gestiegen sind, oder aus Deutschland (soeben gemeldet), wo die Inflation jetzt wieder bei <strong>2,4 % im Jahresvergleich<\/strong> liegt (von 2,2 % im April; vorl\u00e4ufige Daten).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die wachsende Besorgnis, dass das <strong>Inflationsproblem von l\u00e4ngerer Dauer ist<\/strong> und dazu f\u00fchren wird, dass die <strong>Zentralbanken die Zinsen l\u00e4nger hoch halten werden<\/strong>, dr\u00fcckt auf die Stimmung an den M\u00e4rkten. Aktien und Anleihen ziehen sich zur\u00fcck. Die entt\u00e4uschende Nachfrage nach der gestrigen Auktion von US-Schatzpapieren und die allgemein <strong>hawkischen \u00c4u\u00dferungen der Fed-Beamten<\/strong> treiben die Renditen weiter in die H\u00f6he. Heute findet eine weitere Auktion von US-Schatzpapieren statt (f\u00fcr 7-j\u00e4hrige Staatsanleihen).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die Futures an der Wall Street deuten auf einen <strong>R\u00fcckgang von 0,5 % bis 0,6 % zur Er\u00f6ffnung hin<\/strong>, und auch der europ\u00e4ische <strong>Stoxx 600 liegt bei -0,5 %<\/strong>. Nach dem gestrigen <strong>starken Anstieg der Renditen<\/strong>, der die deutschen Anleiherenditen auf ein Sechsmonatshoch brachte, gibt es kaum Anzeichen daf\u00fcr, dass die Zins\u00e4ngste vor den <strong>US-PCE-Daten<\/strong> &#8211; dem wichtigsten und von der Fed bevorzugten Inflationswert dieser Woche &#8211; nachlassen werden. Auch der asiatische Handel war heute \u00fcberwiegend negativ.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Positiv zu vermerken ist, dass sich die <strong>Inflation im Vereinigten K\u00f6nigreich immer noch abk\u00fchlt<\/strong> (Daten aus der Vorwoche) und die deutsche Inflation, obwohl sie hei\u00dfer war, ziemlich genau den Erwartungen entsprach. Die M\u00e4rkte rechnen weiterhin mit einer <strong>ersten Zinssenkung der EZB im Juni.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Das Risiko, dass <strong>h\u00f6here Renditen den teuren Aktienmarkt unter Druck setzen, scheint vorerst bestehen zu bleiben<\/strong>. Die Inflation steigt jedoch auch aufgrund einer globalen Wirtschaft, die gr\u00f6\u00dftenteils widerstandsf\u00e4hig oder sogar im Wachstum begriffen ist (US-Wirtschaft). Die anhaltend <strong>starke Performance der US-Mega-Caps<\/strong>, die sehr soliden Unternehmensgewinne und der Enthusiasmus der KI halten die M\u00e4rkte aufrecht &#8211; auch wenn wir davon ausgehen, dass der Druck weiter anh\u00e4lt, da die Renditen aufgrund der zunehmenden Inflationssorgen wahrscheinlich erh\u00f6ht bleiben.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Der <strong>Nasdaq Composite erreichte gestern ein neues ATH<\/strong>, unterst\u00fctzt von den Mega-Caps, insbesondere <strong>Nvidia<\/strong>. Allerdings hat die Bedeutung der <strong>Mega-Cap-Aktien<\/strong>, wie z.B. der Magnificent Seven, nach den sehr starken Gewinnen von Nvidia nach dem Gewinnbericht nun ein Rekordhoch erreicht.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Wir sehen auch eine <strong>anhaltende Nachfrage nach Energie<\/strong>, da <strong>WTI<\/strong> wieder <strong>\u00fcber $80\/Barrel <\/strong>gestiegen ist. Auch andere Rohstoffe, die f\u00fcr die Industrie wichtig sind, bleiben auf einem hohen Preisniveau &#8211; was <strong>nicht f\u00fcr eine Disinflation <\/strong>spricht, aber ein Zeichen daf\u00fcr ist, dass der Markt insgesamt optimistisch bleibt. <strong>Gold machte eine Kehrtwende<\/strong>, gerade als viele H\u00e4ndler nach den starken Verlusten der letzten Woche eine starke Erholung des gelben Edelmetalls erwarteten. Wir haben den zunehmenden <strong>fundamentalen Gegenwind sofort verstanden<\/strong> und uns in der N\u00e4he der gestrigen H\u00f6chstst\u00e4nde SHORT positioniert. Da die Renditen wieder steigen, bleibt <strong>Gold aus fundamentaler Sicht unter Druck<\/strong>. Ich rechne auch damit, dass der <strong>USD in Richtung der PCE-Daten anziehen wird<\/strong>, w\u00e4hrend die Renditen allerdings nicht nur in den USA, sondern aktuell weltweit steigen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\ud83d\udc41 ROB'S MARKT\u00dcBERSICHT:<\/strong><\/p>\n\n\n\n<ol class=\"wp-block-list\" start=\"29\">\n<li>Mai 2024<\/li>\n<\/ol>\n\n\n\n<p class=\"wp-block-paragraph\">\ud83c\udf10\/\ud83c\uddfa\ud83c\uddf8 <strong>Globale M\u00e4rkte<\/strong> <em>\u2198\ufe0f\/\u27a1\ufe0f<br>Zyklische \/ Luxus-Aktien \u2198\ufe0f\/\u27a1\ufe0f<br>Tech-\/Wachstumsaktien \u2198\ufe0f (geben einige der j\u00fcngsten starken Gewinne zur\u00fcck)<br>Finanzaktien \u2198\ufe0f\/\u27a1\ufe0f<br>Defensive Aktien \u27a1\ufe0f<br>Energie-Aktien \u2197\ufe0f\/\u27a1\ufe0f<br>Rohstoff-Aktien \u27a1\ufe0f\/\u2198\ufe0f<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\ud83d\udcb1 <strong>Forex<\/strong><br><em>USD \u2197\ufe0f (bleibt im Erholungsmodus mit verschlechtertem Risikosentiment)<br>EUR, CHF \u2197\ufe0f\/\u27a1\ufe0f<br>AUD \u2197\ufe0f\/\u27a1\ufe0f\/\u2198\ufe0f (anf\u00e4ngliche Gewinne nach hoher AU-Inflation verloren, Gegenwind durch verschlechtertes Risikomanagement & st\u00e4rkeren USD)<br>JPY \u27a1\ufe0f (unterst\u00fctzt durch Nachfrage nach sicheren H\u00e4fen, bleibt leicht b\u00e4risch)<br>CAD \u27a1\ufe0f (Unterst\u00fctzung durch h\u00f6here Energiepreise, Gegenwind durch st\u00e4rkeren USD)<br>GBP \u27a1\ufe0f\/\u2198\ufe0f<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u2692 <strong>Rohstoffm\u00e4rkte <\/strong><em>\u2197\ufe0f\/\u27a1\ufe0f<br>\u00d6lpreise \u2197\ufe0f\/\u2195\ufe0f (wahrscheinlich bald auf Widerstand treffen &#8211; m\u00f6glicherweise Gewinnmitnahmen)<br>Erdgaspreise \u2198\ufe0f\/\u2195\ufe0f<br>Metallpreise \u2198\ufe0f\/\u27a1\ufe0f<br>Gold \u2198\ufe0f (Gegenwind durch steigende Renditen \/ st\u00e4rkeren USD)<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u26a1\ufe0f<strong>Kryptos <\/strong><em>\u2198\ufe0f\/\u2195\ufe0f (Gegenwind durch steigende Renditen \/ st\u00e4rkeren USD &#8211; BTC m\u00f6glicherweise erneuter Test bei $67K)<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>(*\u2197\ufe0f bullisch, \u2198\ufe0f b\u00e4risch, \u27a1\ufe0f seitw\u00e4rts \/ stabil, \u2195\ufe0f gemischt \/ volatil)<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dein <strong>Robert<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die Inflation steigt wieder. Ist das so? Hartn\u00e4ckige Inflationsdaten, sei es aus dem Vereinigten K\u00f6nigreich letzte Woche oder heute aus&#8230;<\/p>\n","protected":false},"author":663,"featured_media":39191,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","pmpro_default_level":"","_daextam_enable_autolinks":"1","footnotes":""},"categories":[117],"tags":[],"class_list":["post-39195","post","type-post","status-publish","format-standard","has-post-thumbnail","category-taegliche-aktualisierungen","pmpro-has-access"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Zunehmende Inflationssorgen belasten Aktien, Anleihen &amp; Risikobereitschaft - SmartTrader<\/title>\n<meta name=\"description\" content=\"Zunehmende Inflationssorgen belasten Aktien, Anleihen &amp; Risikobereitschaft. Die Inflation steigt wieder. Ist das so? Hartn\u00e4ckige...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/zunehmende-inflationssorgen-belasten-aktien-anleihen-risikobereitschaft\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Zunehmende Inflationssorgen belasten Aktien, Anleihen &amp; Risikobereitschaft - SmartTrader\" \/>\n<meta property=\"og:description\" content=\"Zunehmende Inflationssorgen belasten Aktien, Anleihen &amp; Risikobereitschaft. Die Inflation steigt wieder. Ist das so? Hartn\u00e4ckige...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/zunehmende-inflationssorgen-belasten-aktien-anleihen-risikobereitschaft\/\" \/>\n<meta property=\"og:site_name\" content=\"SmartTrader\" \/>\n<meta property=\"article:published_time\" content=\"2024-05-29T12:59:29+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-05-30T12:29:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/smarttrader.community\/wp-content\/uploads\/2024\/05\/Web-BlogTemplate-Final_2-1-3.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Robert Lindner\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Robert Lindner\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taegliche-aktualisierungen\\\/zunehmende-inflationssorgen-belasten-aktien-anleihen-risikobereitschaft\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taegliche-aktualisierungen\\\/zunehmende-inflationssorgen-belasten-aktien-anleihen-risikobereitschaft\\\/\"},\"author\":{\"name\":\"Robert Lindner\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/#\\\/schema\\\/person\\\/4f791355f3f400fd2dd91d9c57c4c067\"},\"headline\":\"Zunehmende Inflationssorgen belasten Aktien, Anleihen &amp; Risikobereitschaft\",\"datePublished\":\"2024-05-29T12:59:29+00:00\",\"dateModified\":\"2024-05-30T12:29:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taegliche-aktualisierungen\\\/zunehmende-inflationssorgen-belasten-aktien-anleihen-risikobereitschaft\\\/\"},\"wordCount\":647,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taegliche-aktualisierungen\\\/zunehmende-inflationssorgen-belasten-aktien-anleihen-risikobereitschaft\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/Web-BlogTemplate-Final_2-1-3.webp\",\"articleSection\":[\"T\u00e4gliche Aktualisierungen\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/smarttrader.community\\\/de\\\/taegliche-aktualisierungen\\\/zunehmende-inflationssorgen-belasten-aktien-anleihen-risikobereitschaft\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taegliche-aktualisierungen\\\/zunehmende-inflationssorgen-belasten-aktien-anleihen-risikobereitschaft\\\/\",\"url\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taegliche-aktualisierungen\\\/zunehmende-inflationssorgen-belasten-aktien-anleihen-risikobereitschaft\\\/\",\"name\":\"Zunehmende Inflationssorgen belasten Aktien, Anleihen &amp; Risikobereitschaft - SmartTrader\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taegliche-aktualisierungen\\\/zunehmende-inflationssorgen-belasten-aktien-anleihen-risikobereitschaft\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taegliche-aktualisierungen\\\/zunehmende-inflationssorgen-belasten-aktien-anleihen-risikobereitschaft\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/Web-BlogTemplate-Final_2-1-3.webp\",\"datePublished\":\"2024-05-29T12:59:29+00:00\",\"dateModified\":\"2024-05-30T12:29:02+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/#\\\/schema\\\/person\\\/4f791355f3f400fd2dd91d9c57c4c067\"},\"description\":\"Zunehmende Inflationssorgen belasten Aktien, Anleihen & Risikobereitschaft. Die Inflation steigt wieder. Ist das so? Hartn\u00e4ckige...\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taegliche-aktualisierungen\\\/zunehmende-inflationssorgen-belasten-aktien-anleihen-risikobereitschaft\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/smarttrader.community\\\/de\\\/taegliche-aktualisierungen\\\/zunehmende-inflationssorgen-belasten-aktien-anleihen-risikobereitschaft\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taegliche-aktualisierungen\\\/zunehmende-inflationssorgen-belasten-aktien-anleihen-risikobereitschaft\\\/#primaryimage\",\"url\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/Web-BlogTemplate-Final_2-1-3.webp\",\"contentUrl\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/Web-BlogTemplate-Final_2-1-3.webp\",\"width\":1080,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taegliche-aktualisierungen\\\/zunehmende-inflationssorgen-belasten-aktien-anleihen-risikobereitschaft\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Zunehmende Inflationssorgen belasten Aktien, Anleihen &amp; Risikobereitschaft\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/\",\"name\":\"SmartTrader\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/#\\\/schema\\\/person\\\/4f791355f3f400fd2dd91d9c57c4c067\",\"name\":\"Robert Lindner\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/robert-lindner_avatar_1-96x96.png\",\"url\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/robert-lindner_avatar_1-96x96.png\",\"contentUrl\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/robert-lindner_avatar_1-96x96.png\",\"caption\":\"Robert Lindner\"},\"sameAs\":[\"https:\\\/\\\/wwww.smarttrader.community\\\/\"],\"url\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/author\\\/robert_smarttrader\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Zunehmende Inflationssorgen belasten Aktien, Anleihen &amp; Risikobereitschaft - SmartTrader","description":"Zunehmende Inflationssorgen belasten Aktien, Anleihen & Risikobereitschaft. Die Inflation steigt wieder. Ist das so? Hartn\u00e4ckige...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/zunehmende-inflationssorgen-belasten-aktien-anleihen-risikobereitschaft\/","og_locale":"de_DE","og_type":"article","og_title":"Zunehmende Inflationssorgen belasten Aktien, Anleihen &amp; Risikobereitschaft - SmartTrader","og_description":"Zunehmende Inflationssorgen belasten Aktien, Anleihen & Risikobereitschaft. Die Inflation steigt wieder. Ist das so? Hartn\u00e4ckige...","og_url":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/zunehmende-inflationssorgen-belasten-aktien-anleihen-risikobereitschaft\/","og_site_name":"SmartTrader","article_published_time":"2024-05-29T12:59:29+00:00","article_modified_time":"2024-05-30T12:29:02+00:00","og_image":[{"width":1080,"height":720,"url":"https:\/\/smarttrader.community\/wp-content\/uploads\/2024\/05\/Web-BlogTemplate-Final_2-1-3.webp","type":"image\/webp"}],"author":"Robert Lindner","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Robert Lindner","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/zunehmende-inflationssorgen-belasten-aktien-anleihen-risikobereitschaft\/#article","isPartOf":{"@id":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/zunehmende-inflationssorgen-belasten-aktien-anleihen-risikobereitschaft\/"},"author":{"name":"Robert Lindner","@id":"https:\/\/smarttrader.community\/de\/#\/schema\/person\/4f791355f3f400fd2dd91d9c57c4c067"},"headline":"Zunehmende Inflationssorgen belasten Aktien, Anleihen &amp; Risikobereitschaft","datePublished":"2024-05-29T12:59:29+00:00","dateModified":"2024-05-30T12:29:02+00:00","mainEntityOfPage":{"@id":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/zunehmende-inflationssorgen-belasten-aktien-anleihen-risikobereitschaft\/"},"wordCount":647,"commentCount":0,"image":{"@id":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/zunehmende-inflationssorgen-belasten-aktien-anleihen-risikobereitschaft\/#primaryimage"},"thumbnailUrl":"https:\/\/smarttrader.community\/wp-content\/uploads\/2024\/05\/Web-BlogTemplate-Final_2-1-3.webp","articleSection":["T\u00e4gliche Aktualisierungen"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/zunehmende-inflationssorgen-belasten-aktien-anleihen-risikobereitschaft\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/zunehmende-inflationssorgen-belasten-aktien-anleihen-risikobereitschaft\/","url":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/zunehmende-inflationssorgen-belasten-aktien-anleihen-risikobereitschaft\/","name":"Zunehmende Inflationssorgen belasten Aktien, Anleihen &amp; Risikobereitschaft - SmartTrader","isPartOf":{"@id":"https:\/\/smarttrader.community\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/zunehmende-inflationssorgen-belasten-aktien-anleihen-risikobereitschaft\/#primaryimage"},"image":{"@id":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/zunehmende-inflationssorgen-belasten-aktien-anleihen-risikobereitschaft\/#primaryimage"},"thumbnailUrl":"https:\/\/smarttrader.community\/wp-content\/uploads\/2024\/05\/Web-BlogTemplate-Final_2-1-3.webp","datePublished":"2024-05-29T12:59:29+00:00","dateModified":"2024-05-30T12:29:02+00:00","author":{"@id":"https:\/\/smarttrader.community\/de\/#\/schema\/person\/4f791355f3f400fd2dd91d9c57c4c067"},"description":"Zunehmende Inflationssorgen belasten Aktien, Anleihen & Risikobereitschaft. Die Inflation steigt wieder. Ist das so? Hartn\u00e4ckige...","breadcrumb":{"@id":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/zunehmende-inflationssorgen-belasten-aktien-anleihen-risikobereitschaft\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/zunehmende-inflationssorgen-belasten-aktien-anleihen-risikobereitschaft\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/zunehmende-inflationssorgen-belasten-aktien-anleihen-risikobereitschaft\/#primaryimage","url":"https:\/\/smarttrader.community\/wp-content\/uploads\/2024\/05\/Web-BlogTemplate-Final_2-1-3.webp","contentUrl":"https:\/\/smarttrader.community\/wp-content\/uploads\/2024\/05\/Web-BlogTemplate-Final_2-1-3.webp","width":1080,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/smarttrader.community\/de\/taegliche-aktualisierungen\/zunehmende-inflationssorgen-belasten-aktien-anleihen-risikobereitschaft\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/smarttrader.community\/de\/"},{"@type":"ListItem","position":2,"name":"Zunehmende Inflationssorgen belasten Aktien, Anleihen &amp; Risikobereitschaft"}]},{"@type":"WebSite","@id":"https:\/\/smarttrader.community\/de\/#website","url":"https:\/\/smarttrader.community\/de\/","name":"SmartTrader","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/smarttrader.community\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/smarttrader.community\/de\/#\/schema\/person\/4f791355f3f400fd2dd91d9c57c4c067","name":"Robert Lindner","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/05\/robert-lindner_avatar_1-96x96.png","url":"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/05\/robert-lindner_avatar_1-96x96.png","contentUrl":"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/05\/robert-lindner_avatar_1-96x96.png","caption":"Robert Lindner"},"sameAs":["https:\/\/wwww.smarttrader.community\/"],"url":"https:\/\/smarttrader.community\/de\/author\/robert_smarttrader\/"}]}},"_links":{"self":[{"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/posts\/39195","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/users\/663"}],"replies":[{"embeddable":true,"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/comments?post=39195"}],"version-history":[{"count":0,"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/posts\/39195\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/media\/39191"}],"wp:attachment":[{"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/media?parent=39195"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/categories?post=39195"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/tags?post=39195"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}