{"id":42891,"date":"2024-08-29T10:25:05","date_gmt":"2024-08-29T10:25:05","guid":{"rendered":"https:\/\/smarttrader.community\/?p=42891"},"modified":"2024-08-29T10:28:02","modified_gmt":"2024-08-29T10:28:02","slug":"europaeische-aktien-hoeher-us-aktien-stabilisieren-sich-trotz-nvidia-gefuehrtem-technologieeinbruch","status":"publish","type":"post","link":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/europaeische-aktien-hoeher-us-aktien-stabilisieren-sich-trotz-nvidia-gefuehrtem-technologieeinbruch\/","title":{"rendered":"Europ\u00e4ische Aktien h\u00f6her, US-Aktien stabilisieren sich trotz Nvidia-gef\u00fchrtem Technologieeinbruch"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><em>\ud83d\udcc6 Donnerstag, 29. August<\/em><br><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u25ba Die <strong>europ\u00e4ischen Aktien-Futures stiegen<\/strong>, obwohl die globale KI-Rallye aufgrund der <strong>unbeeindruckenden<\/strong><em> (aus Sicher vieler Investoren)<\/em> <strong>Umsatzaussichten<\/strong> von <strong>Nvidia<\/strong> und vorsichtige Anzeichen einer Verlangsamung. Die Euro<strong> Stoxx 600-Kontrakte stiegen um 0,6 %.<\/strong> Die Inflationsrate<strong> Spaniens ging im August auf 2,2 % zur\u00fcck<\/strong>, nachdem sie im Juli noch bei <strong>2,8 % gelegen hatte,<\/strong> was an der Inflationsfront f\u00fcr etwas Entspannung sorgte. Die europ\u00e4ischen M\u00e4rkte warten auf die Ver\u00f6ffentlichung der deutschen Inflationsdaten im Laufe des Tages.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u25ba Die <strong>US-M\u00e4rkte haben sich im fr\u00fchen vorb\u00f6rslichen Handel stabilisiert <\/strong>und erholt, obwohl die Prognose von <strong>Nvidia<\/strong> entt\u00e4uschend ausfiel und die Aktien des Unternehmens im erweiterten Handel um \u00fcber 7 % fielen (derzeit im vorb\u00f6rslichen Handel nur um \u00fcber 3 % gefallen). Obwohl sich der Umsatz im zweiten Quartal des Gesch\u00e4ftsjahres auf <strong>$30 Milliarden verdoppelte<\/strong> und ein <strong>Aktienr\u00fcckkauf in H\u00f6he von $50 Milliarden<\/strong>eingeleitet wurde, blieb die Prognose von <strong>Nvidia<\/strong> hinter den wohl <strong>\u00fcberzogenen Erwartungen des Marktes<\/strong> zur\u00fcck, was zu einem <strong>R\u00fcckgang von 7 % im nachb\u00f6rslichen Handel f\u00fchrte<\/strong>. Die <strong>Nasdaq-100-Futures fielen um bis zu 1,4 %,<\/strong> was die Schw\u00e4che des Technologiesektors insgesamt widerspiegelt und unsere SHORT-Position tief ins Geld dr\u00fcckte. Der <strong>Nasdaq 100 ist jetzt nur noch um 0,4 % niedriger<\/strong>, da sich die Investoren auf die anstehenden <strong>US-Wirtschaftsdaten konzentrieren,<\/strong> darunter die <strong>BIP-Sch\u00e4tzungen f\u00fcr das 2. Quartal <\/strong>und die <strong>Arbeitslosenantr\u00e4ge<\/strong>, um die n\u00e4chsten Schritte der Federal Reserve abzusch\u00e4tzen. Hinzkommt, dass der Bericht von Nvidia im Nachhinein scheinbar doch positiver gesehen wird &#8211; mit immer noch sehr beeindruckendem <strong>Umsatzwachstum von Nvidia<\/strong> &#8211; wenn auch mit Anzeichen, dass das massive explosionsartige Wachstum sich etwas abschw\u00e4cht in der Wachstumsrate. Das von der Fed bevorzugte <strong>Inflationsma\u00df<\/strong>, der <strong>PCE-Preisindex<\/strong>, wird am Freitag ver\u00f6ffentlicht.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u25ba Die a<strong>siatischen M\u00e4rkte gaben gr\u00f6\u00dftenteils nach<\/strong>, wobei die Chiphersteller <strong>TSMC<\/strong> und <strong>SK Hynix die R\u00fcckg\u00e4nge anf\u00fchrten<\/strong>, was den weltweiten Abschwung des Technologiesektors widerspiegelt. Der <strong>Nikkei 225 Index in Japan schloss unver\u00e4ndert <\/strong>und <strong>beendete damit eine zweit\u00e4gige Rally<\/strong>, w\u00e4hrend der<strong> Shanghai Composite um 0,5 % auf den niedrigsten Stand seit fast sieben Monaten fiel. <\/strong>Der <strong>Hang Seng Index in Hongkong stieg um 0,52 %.<\/strong> Die Stimmung wurde durch die Herabstufung der <strong>Wachstumsprognose f\u00fcr China durch UBS<\/strong> weiter geschw\u00e4cht, die einen st\u00e4rker als erwarteten Einbruch des Immobilienmarktes anf\u00fchrte. Der australische<strong> S&P\/ASX 200 Index ging ebenfalls zur\u00fcck<\/strong>, was auf schw\u00e4cher als erwartete Investitionsdaten zur\u00fcckzuf\u00fchren ist.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/smarttrader.community\/membership-join\">Subscribe<\/a> to see more<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\ud83d\udcc6 Donnerstag, 29. August \u25ba Die europ\u00e4ischen Aktien-Futures stiegen, obwohl die globale KI-Rallye aufgrund der unbeeindruckenden (aus Sicher vieler Investoren)&#8230;<\/p>\n","protected":false},"author":2118,"featured_media":22369,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","pmpro_default_level":"","_daextam_enable_autolinks":"1","footnotes":""},"categories":[172],"tags":[],"class_list":["post-42891","post","type-post","status-publish","format-standard","has-post-thumbnail","category-taglicher-marktuberblick","pmpro-has-access"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Europ\u00e4ische Aktien h\u00f6her, US-Aktien stabilisieren sich trotz Nvidia-gef\u00fchrtem Technologieeinbruch - SmartTrader<\/title>\n<meta name=\"description\" content=\"Die europ\u00e4ischen Aktien-Futures stiegen, obwohl die globale KI-Rallye aufgrund der unbeeindruckenden (aus Sicher vieler Investoren)...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/europaeische-aktien-hoeher-us-aktien-stabilisieren-sich-trotz-nvidia-gefuehrtem-technologieeinbruch\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Europ\u00e4ische Aktien h\u00f6her, US-Aktien stabilisieren sich trotz Nvidia-gef\u00fchrtem Technologieeinbruch - SmartTrader\" \/>\n<meta property=\"og:description\" content=\"Die europ\u00e4ischen Aktien-Futures stiegen, obwohl die globale KI-Rallye aufgrund der unbeeindruckenden (aus Sicher vieler Investoren)...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/europaeische-aktien-hoeher-us-aktien-stabilisieren-sich-trotz-nvidia-gefuehrtem-technologieeinbruch\/\" \/>\n<meta property=\"og:site_name\" content=\"SmartTrader\" \/>\n<meta property=\"article:published_time\" content=\"2024-08-29T10:25:05+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-08-29T10:28:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/09\/images-4.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"SMARTTRADER ANALYST TEAM\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"SMARTTRADER ANALYST TEAM\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"4\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taglicher-marktuberblick\\\/europaeische-aktien-hoeher-us-aktien-stabilisieren-sich-trotz-nvidia-gefuehrtem-technologieeinbruch\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taglicher-marktuberblick\\\/europaeische-aktien-hoeher-us-aktien-stabilisieren-sich-trotz-nvidia-gefuehrtem-technologieeinbruch\\\/\"},\"author\":{\"name\":\"SMARTTRADER ANALYST TEAM\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/#\\\/schema\\\/person\\\/d4b47123df7b8ecdf5061cb0bcecdfef\"},\"headline\":\"Europ\u00e4ische Aktien h\u00f6her, US-Aktien stabilisieren sich trotz Nvidia-gef\u00fchrtem Technologieeinbruch\",\"datePublished\":\"2024-08-29T10:25:05+00:00\",\"dateModified\":\"2024-08-29T10:28:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taglicher-marktuberblick\\\/europaeische-aktien-hoeher-us-aktien-stabilisieren-sich-trotz-nvidia-gefuehrtem-technologieeinbruch\\\/\"},\"wordCount\":652,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taglicher-marktuberblick\\\/europaeische-aktien-hoeher-us-aktien-stabilisieren-sich-trotz-nvidia-gefuehrtem-technologieeinbruch\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/images-4.png\",\"articleSection\":[\"T\u00e4glicher Markt\u00fcberblick\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/smarttrader.community\\\/de\\\/taglicher-marktuberblick\\\/europaeische-aktien-hoeher-us-aktien-stabilisieren-sich-trotz-nvidia-gefuehrtem-technologieeinbruch\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taglicher-marktuberblick\\\/europaeische-aktien-hoeher-us-aktien-stabilisieren-sich-trotz-nvidia-gefuehrtem-technologieeinbruch\\\/\",\"url\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taglicher-marktuberblick\\\/europaeische-aktien-hoeher-us-aktien-stabilisieren-sich-trotz-nvidia-gefuehrtem-technologieeinbruch\\\/\",\"name\":\"Europ\u00e4ische Aktien h\u00f6her, US-Aktien stabilisieren sich trotz Nvidia-gef\u00fchrtem Technologieeinbruch - SmartTrader\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taglicher-marktuberblick\\\/europaeische-aktien-hoeher-us-aktien-stabilisieren-sich-trotz-nvidia-gefuehrtem-technologieeinbruch\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taglicher-marktuberblick\\\/europaeische-aktien-hoeher-us-aktien-stabilisieren-sich-trotz-nvidia-gefuehrtem-technologieeinbruch\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/images-4.png\",\"datePublished\":\"2024-08-29T10:25:05+00:00\",\"dateModified\":\"2024-08-29T10:28:02+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/#\\\/schema\\\/person\\\/d4b47123df7b8ecdf5061cb0bcecdfef\"},\"description\":\"Die europ\u00e4ischen Aktien-Futures stiegen, obwohl die globale KI-Rallye aufgrund der unbeeindruckenden (aus Sicher vieler Investoren)...\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taglicher-marktuberblick\\\/europaeische-aktien-hoeher-us-aktien-stabilisieren-sich-trotz-nvidia-gefuehrtem-technologieeinbruch\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/smarttrader.community\\\/de\\\/taglicher-marktuberblick\\\/europaeische-aktien-hoeher-us-aktien-stabilisieren-sich-trotz-nvidia-gefuehrtem-technologieeinbruch\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taglicher-marktuberblick\\\/europaeische-aktien-hoeher-us-aktien-stabilisieren-sich-trotz-nvidia-gefuehrtem-technologieeinbruch\\\/#primaryimage\",\"url\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/images-4.png\",\"contentUrl\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/images-4.png\",\"width\":800,\"height\":500},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taglicher-marktuberblick\\\/europaeische-aktien-hoeher-us-aktien-stabilisieren-sich-trotz-nvidia-gefuehrtem-technologieeinbruch\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Europ\u00e4ische Aktien h\u00f6her, US-Aktien stabilisieren sich trotz Nvidia-gef\u00fchrtem Technologieeinbruch\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/\",\"name\":\"SmartTrader\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/#\\\/schema\\\/person\\\/d4b47123df7b8ecdf5061cb0bcecdfef\",\"name\":\"SMARTTRADER ANALYST TEAM\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/cropped-favicon-site-96x96.png\",\"url\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/cropped-favicon-site-96x96.png\",\"contentUrl\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/cropped-favicon-site-96x96.png\",\"caption\":\"SMARTTRADER ANALYST TEAM\"},\"url\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/author\\\/kateryna-admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Europ\u00e4ische Aktien h\u00f6her, US-Aktien stabilisieren sich trotz Nvidia-gef\u00fchrtem Technologieeinbruch - SmartTrader","description":"Die europ\u00e4ischen Aktien-Futures stiegen, obwohl die globale KI-Rallye aufgrund der unbeeindruckenden (aus Sicher vieler Investoren)...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/europaeische-aktien-hoeher-us-aktien-stabilisieren-sich-trotz-nvidia-gefuehrtem-technologieeinbruch\/","og_locale":"de_DE","og_type":"article","og_title":"Europ\u00e4ische Aktien h\u00f6her, US-Aktien stabilisieren sich trotz Nvidia-gef\u00fchrtem Technologieeinbruch - SmartTrader","og_description":"Die europ\u00e4ischen Aktien-Futures stiegen, obwohl die globale KI-Rallye aufgrund der unbeeindruckenden (aus Sicher vieler Investoren)...","og_url":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/europaeische-aktien-hoeher-us-aktien-stabilisieren-sich-trotz-nvidia-gefuehrtem-technologieeinbruch\/","og_site_name":"SmartTrader","article_published_time":"2024-08-29T10:25:05+00:00","article_modified_time":"2024-08-29T10:28:02+00:00","og_image":[{"width":800,"height":500,"url":"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/09\/images-4.png","type":"image\/png"}],"author":"SMARTTRADER ANALYST TEAM","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"SMARTTRADER ANALYST TEAM","Gesch\u00e4tzte Lesezeit":"4\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/europaeische-aktien-hoeher-us-aktien-stabilisieren-sich-trotz-nvidia-gefuehrtem-technologieeinbruch\/#article","isPartOf":{"@id":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/europaeische-aktien-hoeher-us-aktien-stabilisieren-sich-trotz-nvidia-gefuehrtem-technologieeinbruch\/"},"author":{"name":"SMARTTRADER ANALYST TEAM","@id":"https:\/\/smarttrader.community\/de\/#\/schema\/person\/d4b47123df7b8ecdf5061cb0bcecdfef"},"headline":"Europ\u00e4ische Aktien h\u00f6her, US-Aktien stabilisieren sich trotz Nvidia-gef\u00fchrtem Technologieeinbruch","datePublished":"2024-08-29T10:25:05+00:00","dateModified":"2024-08-29T10:28:02+00:00","mainEntityOfPage":{"@id":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/europaeische-aktien-hoeher-us-aktien-stabilisieren-sich-trotz-nvidia-gefuehrtem-technologieeinbruch\/"},"wordCount":652,"commentCount":0,"image":{"@id":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/europaeische-aktien-hoeher-us-aktien-stabilisieren-sich-trotz-nvidia-gefuehrtem-technologieeinbruch\/#primaryimage"},"thumbnailUrl":"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/09\/images-4.png","articleSection":["T\u00e4glicher Markt\u00fcberblick"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/europaeische-aktien-hoeher-us-aktien-stabilisieren-sich-trotz-nvidia-gefuehrtem-technologieeinbruch\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/europaeische-aktien-hoeher-us-aktien-stabilisieren-sich-trotz-nvidia-gefuehrtem-technologieeinbruch\/","url":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/europaeische-aktien-hoeher-us-aktien-stabilisieren-sich-trotz-nvidia-gefuehrtem-technologieeinbruch\/","name":"Europ\u00e4ische Aktien h\u00f6her, US-Aktien stabilisieren sich trotz Nvidia-gef\u00fchrtem Technologieeinbruch - SmartTrader","isPartOf":{"@id":"https:\/\/smarttrader.community\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/europaeische-aktien-hoeher-us-aktien-stabilisieren-sich-trotz-nvidia-gefuehrtem-technologieeinbruch\/#primaryimage"},"image":{"@id":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/europaeische-aktien-hoeher-us-aktien-stabilisieren-sich-trotz-nvidia-gefuehrtem-technologieeinbruch\/#primaryimage"},"thumbnailUrl":"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/09\/images-4.png","datePublished":"2024-08-29T10:25:05+00:00","dateModified":"2024-08-29T10:28:02+00:00","author":{"@id":"https:\/\/smarttrader.community\/de\/#\/schema\/person\/d4b47123df7b8ecdf5061cb0bcecdfef"},"description":"Die europ\u00e4ischen Aktien-Futures stiegen, obwohl die globale KI-Rallye aufgrund der unbeeindruckenden (aus Sicher vieler Investoren)...","breadcrumb":{"@id":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/europaeische-aktien-hoeher-us-aktien-stabilisieren-sich-trotz-nvidia-gefuehrtem-technologieeinbruch\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/europaeische-aktien-hoeher-us-aktien-stabilisieren-sich-trotz-nvidia-gefuehrtem-technologieeinbruch\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/europaeische-aktien-hoeher-us-aktien-stabilisieren-sich-trotz-nvidia-gefuehrtem-technologieeinbruch\/#primaryimage","url":"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/09\/images-4.png","contentUrl":"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/09\/images-4.png","width":800,"height":500},{"@type":"BreadcrumbList","@id":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/europaeische-aktien-hoeher-us-aktien-stabilisieren-sich-trotz-nvidia-gefuehrtem-technologieeinbruch\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/smarttrader.community\/de\/"},{"@type":"ListItem","position":2,"name":"Europ\u00e4ische Aktien h\u00f6her, US-Aktien stabilisieren sich trotz Nvidia-gef\u00fchrtem Technologieeinbruch"}]},{"@type":"WebSite","@id":"https:\/\/smarttrader.community\/de\/#website","url":"https:\/\/smarttrader.community\/de\/","name":"SmartTrader","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/smarttrader.community\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/smarttrader.community\/de\/#\/schema\/person\/d4b47123df7b8ecdf5061cb0bcecdfef","name":"SMARTTRADER ANALYST TEAM","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/03\/cropped-favicon-site-96x96.png","url":"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/03\/cropped-favicon-site-96x96.png","contentUrl":"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/03\/cropped-favicon-site-96x96.png","caption":"SMARTTRADER ANALYST TEAM"},"url":"https:\/\/smarttrader.community\/de\/author\/kateryna-admin\/"}]}},"_links":{"self":[{"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/posts\/42891","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/users\/2118"}],"replies":[{"embeddable":true,"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/comments?post=42891"}],"version-history":[{"count":0,"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/posts\/42891\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/media\/22369"}],"wp:attachment":[{"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/media?parent=42891"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/categories?post=42891"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/tags?post=42891"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}