{"id":49286,"date":"2025-02-06T12:40:07","date_gmt":"2025-02-06T12:40:07","guid":{"rendered":"https:\/\/smarttrader.community\/?p=49286"},"modified":"2025-02-06T12:43:17","modified_gmt":"2025-02-06T12:43:17","slug":"gemischte-globale-aktien-nach-gewinnberichten-anleger-warten-auf-boe-entscheidung-amazon-earnings","status":"publish","type":"post","link":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/gemischte-globale-aktien-nach-gewinnberichten-anleger-warten-auf-boe-entscheidung-amazon-earnings\/","title":{"rendered":"Gemischte globale Aktien nach Gewinnberichten; Anleger warten auf BOE-Entscheidung &amp; Amazon-Earnings"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><em>\ud83d\udcc6 Donnerstag, 6. Februar \u00a0<\/em><br><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u25ba Die <strong>europ\u00e4ischen M\u00e4rkte kletterten am Donnerstag <\/strong>nach oben, da die Anleger die <strong>positiven Unternehmensgewinne<\/strong> der europ\u00e4ischen Unternehmen verdauten und auf die <strong>Zinsentscheidung der Bank of England <\/strong>warteten. Der<strong> Stoxx 600 stieg um 0,65%<\/strong> und verzeichnete damit den dritten Anstieg in Folge, angetrieben durch die St\u00e4rke der Finanz- und Gesundheitswerte. Der deutsche <strong>DAX legte um 0,6 % zu<\/strong>, gest\u00fctzt durch einen <strong>\u00fcberraschenden Anstieg der Auftragseing\u00e4nge in der Industrie<\/strong>, w\u00e4hrend der franz\u00f6sische <strong>CAC 40 um 0,6 % stieg,<\/strong> obwohl die Anleger angesichts <strong>gemischter Industriedaten<\/strong> vorsichtig blieben. Der britische<strong> FTSE 100 \u00fcbertraf mit einem Plus von 1,1 % <\/strong>die Erwartungen an eine<strong> Zinssenkung der BOE<\/strong>, die den<strong> GBP belasteten.<\/strong> <strong>AstraZeneca<\/strong> kletterte um 4,5% nach einem Umsatzanstieg von 23,9% im Jahresvergleich und einem positiven Ausblick f\u00fcr 2025.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u25ba Die <strong>US-Aktienfutures notieren nach den Gewinnen vom Mittwoch wenig ver\u00e4ndert.<\/strong> Der anf\u00e4ngliche Gewinnoptimismus erhielt nach entt\u00e4uschenden Ergebnissen von <strong>Qualcomm<\/strong>, <strong>Ford<\/strong> und Skyworks Solutions etwas Gegenwind. Die<strong> S&P 500-Futures liegen immer noch 0,2%<\/strong> im Plus, w\u00e4hrend die <strong>Nasdaq 100-Futures leicht im Minus liegen (-0,15%), <\/strong>aber durch die <strong>sinkenden Treasury-Renditen <\/strong>in der N\u00e4he der <strong>Einmonatstiefs<\/strong> weiterhin unterst\u00fctzt werden. Der Fokus liegt nun auf den Ergebnissen von <strong>Amazon<\/strong> f\u00fcr das vierte Quartal, die nach der Schlussglocke ver\u00f6ffentlicht werden, da die Anleger nach den <strong>eher entt\u00e4uschenden Ergebnissen von Microsoft und Alphabet<\/strong> auf eine Wachstumsprognose f\u00fcr den Cloud-Markt warten. <strong>Eli Lilly <\/strong>meldete Ergebnisse, die den Erwartungen entsprachen, und wird wenig ver\u00e4ndert gehandelt (- 0,3%). An der Wirtschaftsfront beobachten die H\u00e4ndler die w\u00f6chentlichen <strong>Erstantr\u00e4ge auf Arbeitslosenunterst\u00fctzung <\/strong>und den Bericht \u00fcber die Besch\u00e4ftigtenzahlen au\u00dferhalb der Landwirtschaft vom Freitag, die die Zinsaussichten der Federal Reserve beeinflussen k\u00f6nnten.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u25ba Die <strong>asiatischen M\u00e4rkte folgten den Kursgewinnen <\/strong>an der Wall Street und den nachlassenden Handelsspannungen zwischen den USA und China. Der japanische <strong>Nikkei 225 stieg um 0,63%<\/strong> und \u00fcberschritt die Marke von <strong>39.000<\/strong> Punkten. Der chinesische <strong>Shanghai Composite stieg um 1,27%<\/strong>, angef\u00fchrt von KI- und Tech-Aktien, da die Fortschritte von DeepSeek f\u00fcr Optimismus sorgten. Der Offshore-<strong>CNY stabilisierte sich bei 7,28\/USD<\/strong>, da Peking wegen der neuen US-Z\u00f6lle <strong>um eine Intervention der WTO bat. <\/strong>Der<strong> Hang Seng in Hongkong legte um 1,43%<\/strong> zu und erholte sich damit von fr\u00fcheren Verlusten.<\/p>\n\n\n\n<div class=\"wp-block-group is-vertical is-layout-flex wp-container-core-group-is-layout-4fc3f8e1 wp-block-group-is-layout-flex\">\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/smarttrader.community\/membership-join\">Subscribe<\/a> to see more<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00a0\u00a0\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00a0 \u00a0<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>\ud83d\udcc6 Donnerstag, 6. Februar \u00a0 \u25ba Die europ\u00e4ischen M\u00e4rkte kletterten am Donnerstag nach oben, da die Anleger die positiven Unternehmensgewinne&#8230;<\/p>\n","protected":false},"author":2118,"featured_media":49284,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","pmpro_default_level":"","_daextam_enable_autolinks":"1","footnotes":""},"categories":[172],"tags":[],"class_list":["post-49286","post","type-post","status-publish","format-standard","has-post-thumbnail","category-taglicher-marktuberblick","pmpro-has-access"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Gemischte globale Aktien nach Gewinnberichten; Anleger warten auf BOE-Entscheidung &amp; Amazon-Earnings - SmartTrader<\/title>\n<meta name=\"description\" content=\"Die europ\u00e4ischen M\u00e4rkte kletterten am Donnerstag nach oben, da die Anleger die positiven Unternehmensgewinne der europ\u00e4ischen Unternehmen...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/gemischte-globale-aktien-nach-gewinnberichten-anleger-warten-auf-boe-entscheidung-amazon-earnings\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gemischte globale Aktien nach Gewinnberichten; Anleger warten auf BOE-Entscheidung &amp; Amazon-Earnings - SmartTrader\" \/>\n<meta property=\"og:description\" content=\"Die europ\u00e4ischen M\u00e4rkte kletterten am Donnerstag nach oben, da die Anleger die positiven Unternehmensgewinne der europ\u00e4ischen Unternehmen...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/gemischte-globale-aktien-nach-gewinnberichten-anleger-warten-auf-boe-entscheidung-amazon-earnings\/\" \/>\n<meta property=\"og:site_name\" content=\"SmartTrader\" \/>\n<meta property=\"article:published_time\" content=\"2025-02-06T12:40:07+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-02-06T12:43:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/smarttrader.community\/wp-content\/uploads\/2025\/02\/Amazon.png\" \/>\n\t<meta property=\"og:image:width\" content=\"683\" \/>\n\t<meta property=\"og:image:height\" content=\"455\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"SMARTTRADER ANALYST TEAM\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"SMARTTRADER ANALYST TEAM\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"4\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taglicher-marktuberblick\\\/gemischte-globale-aktien-nach-gewinnberichten-anleger-warten-auf-boe-entscheidung-amazon-earnings\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taglicher-marktuberblick\\\/gemischte-globale-aktien-nach-gewinnberichten-anleger-warten-auf-boe-entscheidung-amazon-earnings\\\/\"},\"author\":{\"name\":\"SMARTTRADER ANALYST TEAM\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/#\\\/schema\\\/person\\\/d4b47123df7b8ecdf5061cb0bcecdfef\"},\"headline\":\"Gemischte globale Aktien nach Gewinnberichten; Anleger warten auf BOE-Entscheidung &amp; Amazon-Earnings\",\"datePublished\":\"2025-02-06T12:40:07+00:00\",\"dateModified\":\"2025-02-06T12:43:17+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taglicher-marktuberblick\\\/gemischte-globale-aktien-nach-gewinnberichten-anleger-warten-auf-boe-entscheidung-amazon-earnings\\\/\"},\"wordCount\":736,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taglicher-marktuberblick\\\/gemischte-globale-aktien-nach-gewinnberichten-anleger-warten-auf-boe-entscheidung-amazon-earnings\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/Amazon.png\",\"articleSection\":[\"T\u00e4glicher Markt\u00fcberblick\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/smarttrader.community\\\/de\\\/taglicher-marktuberblick\\\/gemischte-globale-aktien-nach-gewinnberichten-anleger-warten-auf-boe-entscheidung-amazon-earnings\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taglicher-marktuberblick\\\/gemischte-globale-aktien-nach-gewinnberichten-anleger-warten-auf-boe-entscheidung-amazon-earnings\\\/\",\"url\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taglicher-marktuberblick\\\/gemischte-globale-aktien-nach-gewinnberichten-anleger-warten-auf-boe-entscheidung-amazon-earnings\\\/\",\"name\":\"Gemischte globale Aktien nach Gewinnberichten; Anleger warten auf BOE-Entscheidung &amp; Amazon-Earnings - SmartTrader\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taglicher-marktuberblick\\\/gemischte-globale-aktien-nach-gewinnberichten-anleger-warten-auf-boe-entscheidung-amazon-earnings\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taglicher-marktuberblick\\\/gemischte-globale-aktien-nach-gewinnberichten-anleger-warten-auf-boe-entscheidung-amazon-earnings\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/Amazon.png\",\"datePublished\":\"2025-02-06T12:40:07+00:00\",\"dateModified\":\"2025-02-06T12:43:17+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/#\\\/schema\\\/person\\\/d4b47123df7b8ecdf5061cb0bcecdfef\"},\"description\":\"Die europ\u00e4ischen M\u00e4rkte kletterten am Donnerstag nach oben, da die Anleger die positiven Unternehmensgewinne der europ\u00e4ischen Unternehmen...\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taglicher-marktuberblick\\\/gemischte-globale-aktien-nach-gewinnberichten-anleger-warten-auf-boe-entscheidung-amazon-earnings\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/smarttrader.community\\\/de\\\/taglicher-marktuberblick\\\/gemischte-globale-aktien-nach-gewinnberichten-anleger-warten-auf-boe-entscheidung-amazon-earnings\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taglicher-marktuberblick\\\/gemischte-globale-aktien-nach-gewinnberichten-anleger-warten-auf-boe-entscheidung-amazon-earnings\\\/#primaryimage\",\"url\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/Amazon.png\",\"contentUrl\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/Amazon.png\",\"width\":683,\"height\":455},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taglicher-marktuberblick\\\/gemischte-globale-aktien-nach-gewinnberichten-anleger-warten-auf-boe-entscheidung-amazon-earnings\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gemischte globale Aktien nach Gewinnberichten; Anleger warten auf BOE-Entscheidung &amp; Amazon-Earnings\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/\",\"name\":\"SmartTrader\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/#\\\/schema\\\/person\\\/d4b47123df7b8ecdf5061cb0bcecdfef\",\"name\":\"SMARTTRADER ANALYST TEAM\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/cropped-favicon-site-96x96.png\",\"url\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/cropped-favicon-site-96x96.png\",\"contentUrl\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/cropped-favicon-site-96x96.png\",\"caption\":\"SMARTTRADER ANALYST TEAM\"},\"url\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/author\\\/kateryna-admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gemischte globale Aktien nach Gewinnberichten; Anleger warten auf BOE-Entscheidung &amp; Amazon-Earnings - SmartTrader","description":"Die europ\u00e4ischen M\u00e4rkte kletterten am Donnerstag nach oben, da die Anleger die positiven Unternehmensgewinne der europ\u00e4ischen Unternehmen...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/gemischte-globale-aktien-nach-gewinnberichten-anleger-warten-auf-boe-entscheidung-amazon-earnings\/","og_locale":"de_DE","og_type":"article","og_title":"Gemischte globale Aktien nach Gewinnberichten; Anleger warten auf BOE-Entscheidung &amp; Amazon-Earnings - SmartTrader","og_description":"Die europ\u00e4ischen M\u00e4rkte kletterten am Donnerstag nach oben, da die Anleger die positiven Unternehmensgewinne der europ\u00e4ischen Unternehmen...","og_url":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/gemischte-globale-aktien-nach-gewinnberichten-anleger-warten-auf-boe-entscheidung-amazon-earnings\/","og_site_name":"SmartTrader","article_published_time":"2025-02-06T12:40:07+00:00","article_modified_time":"2025-02-06T12:43:17+00:00","og_image":[{"width":683,"height":455,"url":"https:\/\/smarttrader.community\/wp-content\/uploads\/2025\/02\/Amazon.png","type":"image\/png"}],"author":"SMARTTRADER ANALYST TEAM","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"SMARTTRADER ANALYST TEAM","Gesch\u00e4tzte Lesezeit":"4\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/gemischte-globale-aktien-nach-gewinnberichten-anleger-warten-auf-boe-entscheidung-amazon-earnings\/#article","isPartOf":{"@id":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/gemischte-globale-aktien-nach-gewinnberichten-anleger-warten-auf-boe-entscheidung-amazon-earnings\/"},"author":{"name":"SMARTTRADER ANALYST TEAM","@id":"https:\/\/smarttrader.community\/de\/#\/schema\/person\/d4b47123df7b8ecdf5061cb0bcecdfef"},"headline":"Gemischte globale Aktien nach Gewinnberichten; Anleger warten auf BOE-Entscheidung &amp; Amazon-Earnings","datePublished":"2025-02-06T12:40:07+00:00","dateModified":"2025-02-06T12:43:17+00:00","mainEntityOfPage":{"@id":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/gemischte-globale-aktien-nach-gewinnberichten-anleger-warten-auf-boe-entscheidung-amazon-earnings\/"},"wordCount":736,"commentCount":0,"image":{"@id":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/gemischte-globale-aktien-nach-gewinnberichten-anleger-warten-auf-boe-entscheidung-amazon-earnings\/#primaryimage"},"thumbnailUrl":"https:\/\/smarttrader.community\/wp-content\/uploads\/2025\/02\/Amazon.png","articleSection":["T\u00e4glicher Markt\u00fcberblick"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/gemischte-globale-aktien-nach-gewinnberichten-anleger-warten-auf-boe-entscheidung-amazon-earnings\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/gemischte-globale-aktien-nach-gewinnberichten-anleger-warten-auf-boe-entscheidung-amazon-earnings\/","url":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/gemischte-globale-aktien-nach-gewinnberichten-anleger-warten-auf-boe-entscheidung-amazon-earnings\/","name":"Gemischte globale Aktien nach Gewinnberichten; Anleger warten auf BOE-Entscheidung &amp; Amazon-Earnings - SmartTrader","isPartOf":{"@id":"https:\/\/smarttrader.community\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/gemischte-globale-aktien-nach-gewinnberichten-anleger-warten-auf-boe-entscheidung-amazon-earnings\/#primaryimage"},"image":{"@id":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/gemischte-globale-aktien-nach-gewinnberichten-anleger-warten-auf-boe-entscheidung-amazon-earnings\/#primaryimage"},"thumbnailUrl":"https:\/\/smarttrader.community\/wp-content\/uploads\/2025\/02\/Amazon.png","datePublished":"2025-02-06T12:40:07+00:00","dateModified":"2025-02-06T12:43:17+00:00","author":{"@id":"https:\/\/smarttrader.community\/de\/#\/schema\/person\/d4b47123df7b8ecdf5061cb0bcecdfef"},"description":"Die europ\u00e4ischen M\u00e4rkte kletterten am Donnerstag nach oben, da die Anleger die positiven Unternehmensgewinne der europ\u00e4ischen Unternehmen...","breadcrumb":{"@id":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/gemischte-globale-aktien-nach-gewinnberichten-anleger-warten-auf-boe-entscheidung-amazon-earnings\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/gemischte-globale-aktien-nach-gewinnberichten-anleger-warten-auf-boe-entscheidung-amazon-earnings\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/gemischte-globale-aktien-nach-gewinnberichten-anleger-warten-auf-boe-entscheidung-amazon-earnings\/#primaryimage","url":"https:\/\/smarttrader.community\/wp-content\/uploads\/2025\/02\/Amazon.png","contentUrl":"https:\/\/smarttrader.community\/wp-content\/uploads\/2025\/02\/Amazon.png","width":683,"height":455},{"@type":"BreadcrumbList","@id":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/gemischte-globale-aktien-nach-gewinnberichten-anleger-warten-auf-boe-entscheidung-amazon-earnings\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/smarttrader.community\/de\/"},{"@type":"ListItem","position":2,"name":"Gemischte globale Aktien nach Gewinnberichten; Anleger warten auf BOE-Entscheidung &amp; Amazon-Earnings"}]},{"@type":"WebSite","@id":"https:\/\/smarttrader.community\/de\/#website","url":"https:\/\/smarttrader.community\/de\/","name":"SmartTrader","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/smarttrader.community\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/smarttrader.community\/de\/#\/schema\/person\/d4b47123df7b8ecdf5061cb0bcecdfef","name":"SMARTTRADER ANALYST TEAM","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/03\/cropped-favicon-site-96x96.png","url":"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/03\/cropped-favicon-site-96x96.png","contentUrl":"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/03\/cropped-favicon-site-96x96.png","caption":"SMARTTRADER ANALYST TEAM"},"url":"https:\/\/smarttrader.community\/de\/author\/kateryna-admin\/"}]}},"_links":{"self":[{"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/posts\/49286","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/users\/2118"}],"replies":[{"embeddable":true,"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/comments?post=49286"}],"version-history":[{"count":1,"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/posts\/49286\/revisions"}],"predecessor-version":[{"id":49287,"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/posts\/49286\/revisions\/49287"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/media\/49284"}],"wp:attachment":[{"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/media?parent=49286"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/categories?post=49286"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/tags?post=49286"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}