{"id":49890,"date":"2025-03-07T11:20:41","date_gmt":"2025-03-07T11:20:41","guid":{"rendered":"https:\/\/smarttrader.community\/?p=49890"},"modified":"2025-03-07T11:23:31","modified_gmt":"2025-03-07T11:23:31","slug":"maerkte-geben-aufgrund-von-instabilitaet-durch-handelskrieg-nfp-bericht-fed-im-fokus","status":"publish","type":"post","link":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/maerkte-geben-aufgrund-von-instabilitaet-durch-handelskrieg-nfp-bericht-fed-im-fokus\/","title":{"rendered":"M\u00e4rkte geben aufgrund von Instabilit\u00e4t durch Handelskrieg &amp; starker Unsicherheit nach; NFP-Bericht &amp; Fed im Fokus\u00a0"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><em>\ud83d\udcc6 Freitag, 7. M\u00e4rz \u00a0<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>\u25ba <strong>Europ\u00e4ische M\u00e4rkte geben nach<\/strong>, nachdem die <strong>Wall Street <\/strong><em>\u2013 die die schlechteste Woche seit September erlebte \u2013<\/em> gestern weitere Verluste verzeichnete, da die <strong>Unsicherheit \u00fcber Trumps wechselnde Handelspolitik <\/strong>die <strong>Risikobereitschaft<\/strong> d\u00e4mpfte. Der <strong>Stoxx 600 rutschte um 0,7 % <\/strong>ab, w\u00e4hrend der <strong>deutsche DAX um mehr als 1,7 % fiel <\/strong>und damit die Gewinne aus seiner j\u00fcngsten Rally, die durch historische Pl\u00e4ne f\u00fcr <strong>Verteidigungsausgaben<\/strong> angeheizt wurde, wieder aufgab (<strong>CAC 40 -0.9 %<\/strong>). <strong>Luxusaktien f\u00fchrten die Verluste an,<\/strong> nachdem <strong>China Vergeltungsz\u00f6lle auf US-amerikanische <\/strong>und auch auf <strong>europ\u00e4ische (!) Waren <\/strong>verh\u00e4ngt hatte, was Bedenken hinsichtlich der Exportnachfrage aufkommen lie\u00df. Unterdessen senkte die <strong>EZB die Zinss\u00e4tze um 25 Basispunkte auf 2,50 %<\/strong>, signalisierte jedoch eine vorsichtige Haltung gegen\u00fcber weiteren Senkungen und verwies auf anhaltende Inflationsrisiken. Dadurch blieben die <strong>Renditen deutscher Bundesanleihen unter Druck<\/strong> (-5 Basispunkte auf 2,83 %). Die <strong>Wirtschaftsdaten blieben schwach,<\/strong> wobei das Handelsdefizit Frankreichs bei -\u20ac5,6 Mrd. verharrte und die Industrieproduktion Spaniens im Jahresvergleich um 1 % schrumpfte, was die<strong> schwache Verbrauchernachfrage<\/strong> und die Probleme im verarbeitenden Gewerbe verdeutlicht.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u25ba Die <strong>US-M\u00e4rkte blieben unruhig<\/strong>, wobei die S&P-500-Futures vor dem Bericht \u00fcber die Besch\u00e4ftigtenzahlen au\u00dferhalb der Landwirtschaft im Februar, einem wichtigen Gradmesser f\u00fcr die <strong>St\u00e4rke des Arbeitsmarktes <\/strong>und m\u00f6gliche Kurs\u00e4nderungen der Fed, schwankten. Die <strong>Anleger blieben nerv\u00f6s,<\/strong> da Trumps inkonsistente Handelspolitik f\u00fcr weitere Unsicherheit sorgte \u2013 <strong>Z\u00f6lle in H\u00f6he von 25 %<\/strong> auf <strong>Mexiko<\/strong> und <strong>Kanada<\/strong> wurden verh\u00e4ngt und dann schnell ausgesetzt, w\u00e4hrend umfassendere gegenseitige Z\u00f6lle weiterhin in der Schwebe bleiben. Dies dr\u00fcckte die <strong>Renditen von US-Staatsanleihen auf 4,26 %<\/strong>, was die Bef\u00fcrchtung widerspiegelt, dass die Instabilit\u00e4t des Handels das Wirtschaftswachstum behindern k\u00f6nnte. Die Technologieaktien waren sehr volatil, wobei <strong>Broadcom im vorb\u00f6rslichen Handel um 11 % zulegte<\/strong>, nachdem das Unternehmen starke Gewinne ($11,96 Mrd. Umsatz, +34 % im Jahresvergleich), eine <strong>optimistische Prognose<\/strong> und die Ank\u00fcndigung eines <strong>Aktiensplits im Verh\u00e4ltnis 10:1<\/strong> gemeldet hatte. <strong>Broadcom<\/strong> war eine der am st\u00e4rksten verkauften Aktien in New York \u2013 wir sind den umgekehrten Weg gegangen \u2013<em> Gl\u00fcckwunsch an die Community!<\/em> Der starke Gewinnbericht von <strong>Broadcom<\/strong> kurbelt den zuletzt <strong>unterdurchschnittlich abschneidenden US-Chipsektor<\/strong> an. Investoren warten auf die Rede des Fed-Vorsitzenden Jerome <strong>Powell<\/strong> heute Nachmittag, um Signale zu erhalten, wie die Fed mit Handelsst\u00f6rungen und allgemeiner wirtschaftlicher Unsicherheit umgehen k\u00f6nnte.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u25ba Die <strong>asiatischen M\u00e4rkte verzeichneten anhaltende Verluste<\/strong>, da die Angst vor einem Handelskrieg und schwache Wirtschaftsdaten die Stimmung belasteten. Der japanische <strong>Nikkei st\u00fcrzte um 2,26 % ab <\/strong>und n\u00e4herte sich einem <strong>F\u00fcnfmonatstief<\/strong>, w\u00e4hrend der <strong>Hang Seng in Hongkong um 0,57 % <\/strong>nachgab und damit eine dreit\u00e4gige Siegesserie beendete. Die Spekulationen \u00fcber eine<strong> Zinserh\u00f6hung der Bank of Japan<\/strong> nahmen zu und trieben den<strong> JPY auf 148\/USD<\/strong>, ein <strong>F\u00fcnfmonatshoch<\/strong>, w\u00e4hrend die Regierung sich darauf vorbereitete, das offizielle Ende der langfristigen Deflation zu verk\u00fcnden. Unterdessen stieg der Handels\u00fcberschuss Chinas auf $170,5 Milliarden und \u00fcbertraf damit die Erwartungen, aber die <strong>Exporte stiegen nur um 2,3 %<\/strong> (gegen\u00fcber erwarteten 5 %), w\u00e4hrend die <strong>Importe um 8,4 % einbrachen<\/strong>, was auf eine schw\u00e4chelnde Inlandsnachfrage hindeutet. Die Spannungen eskalierten, als <strong>China eine harte Haltung im Handel <\/strong>einnahm und die US-Zollma\u00dfnahmen f\u00fcr Fentanyl-bezogene Produkte ablehnte. In Australien st\u00fcrzte der<strong> ASX 200 um 1,81 % ab<\/strong> und erreichte ein Sechsmonatstief, was auf starke R\u00fcckg\u00e4nge bei Bank- und Rohstoffaktien zur\u00fcckzuf\u00fchren war. Der<strong> AUD schw\u00e4chte sich in Richtung 0,63 US-Dollar ab<\/strong>, was auf die sich verschlechternde Marktstimmung und die <strong>sinkende Nachfrage nach Industrierohstoffen<\/strong> zur\u00fcckzuf\u00fchren war.<\/p>\n\n\n\n<div class=\"wp-block-group is-vertical is-layout-flex wp-container-core-group-is-layout-4fc3f8e1 wp-block-group-is-layout-flex\">\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/smarttrader.community\/membership-join\">Subscribe<\/a> to see more<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;&nbsp;&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\ud83d\udcc6 Freitag, 7. M\u00e4rz \u00a0 \u25ba Europ\u00e4ische M\u00e4rkte geben nach, nachdem die Wall Street \u2013 die die schlechteste Woche seit&#8230;<\/p>\n","protected":false},"author":2118,"featured_media":49886,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","pmpro_default_level":"","_daextam_enable_autolinks":"1","footnotes":""},"categories":[172],"tags":[],"class_list":["post-49890","post","type-post","status-publish","format-standard","has-post-thumbnail","category-taglicher-marktuberblick","pmpro-has-access"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>M\u00e4rkte geben aufgrund von Instabilit\u00e4t durch Handelskrieg &amp; starker Unsicherheit nach; NFP-Bericht &amp; Fed im Fokus\u00a0 - SmartTrader<\/title>\n<meta name=\"description\" content=\"Europ\u00e4ische M\u00e4rkte geben nach, nachdem die Wall Street \u2013 die die schlechteste Woche seit September erlebte \u2013 gestern weitere Verluste...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/maerkte-geben-aufgrund-von-instabilitaet-durch-handelskrieg-nfp-bericht-fed-im-fokus\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"M\u00e4rkte geben aufgrund von Instabilit\u00e4t durch Handelskrieg &amp; starker Unsicherheit nach; NFP-Bericht &amp; Fed im Fokus\u00a0 - SmartTrader\" \/>\n<meta property=\"og:description\" content=\"Europ\u00e4ische M\u00e4rkte geben nach, nachdem die Wall Street \u2013 die die schlechteste Woche seit September erlebte \u2013 gestern weitere Verluste...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/maerkte-geben-aufgrund-von-instabilitaet-durch-handelskrieg-nfp-bericht-fed-im-fokus\/\" \/>\n<meta property=\"og:site_name\" content=\"SmartTrader\" \/>\n<meta property=\"article:published_time\" content=\"2025-03-07T11:20:41+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-07T11:23:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/smarttrader.community\/wp-content\/uploads\/2025\/03\/Markets-decline.png\" \/>\n\t<meta property=\"og:image:width\" content=\"735\" \/>\n\t<meta property=\"og:image:height\" content=\"490\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"SMARTTRADER ANALYST TEAM\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"SMARTTRADER ANALYST TEAM\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"5\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taglicher-marktuberblick\\\/maerkte-geben-aufgrund-von-instabilitaet-durch-handelskrieg-nfp-bericht-fed-im-fokus\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taglicher-marktuberblick\\\/maerkte-geben-aufgrund-von-instabilitaet-durch-handelskrieg-nfp-bericht-fed-im-fokus\\\/\"},\"author\":{\"name\":\"SMARTTRADER ANALYST TEAM\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/#\\\/schema\\\/person\\\/d4b47123df7b8ecdf5061cb0bcecdfef\"},\"headline\":\"M\u00e4rkte geben aufgrund von Instabilit\u00e4t durch Handelskrieg &amp; starker Unsicherheit nach; NFP-Bericht &amp; Fed im Fokus\u00a0\",\"datePublished\":\"2025-03-07T11:20:41+00:00\",\"dateModified\":\"2025-03-07T11:23:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taglicher-marktuberblick\\\/maerkte-geben-aufgrund-von-instabilitaet-durch-handelskrieg-nfp-bericht-fed-im-fokus\\\/\"},\"wordCount\":959,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taglicher-marktuberblick\\\/maerkte-geben-aufgrund-von-instabilitaet-durch-handelskrieg-nfp-bericht-fed-im-fokus\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/Markets-decline.png\",\"articleSection\":[\"T\u00e4glicher Markt\u00fcberblick\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/smarttrader.community\\\/de\\\/taglicher-marktuberblick\\\/maerkte-geben-aufgrund-von-instabilitaet-durch-handelskrieg-nfp-bericht-fed-im-fokus\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taglicher-marktuberblick\\\/maerkte-geben-aufgrund-von-instabilitaet-durch-handelskrieg-nfp-bericht-fed-im-fokus\\\/\",\"url\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taglicher-marktuberblick\\\/maerkte-geben-aufgrund-von-instabilitaet-durch-handelskrieg-nfp-bericht-fed-im-fokus\\\/\",\"name\":\"M\u00e4rkte geben aufgrund von Instabilit\u00e4t durch Handelskrieg &amp; starker Unsicherheit nach; NFP-Bericht &amp; Fed im Fokus\u00a0 - SmartTrader\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taglicher-marktuberblick\\\/maerkte-geben-aufgrund-von-instabilitaet-durch-handelskrieg-nfp-bericht-fed-im-fokus\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taglicher-marktuberblick\\\/maerkte-geben-aufgrund-von-instabilitaet-durch-handelskrieg-nfp-bericht-fed-im-fokus\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/Markets-decline.png\",\"datePublished\":\"2025-03-07T11:20:41+00:00\",\"dateModified\":\"2025-03-07T11:23:31+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/#\\\/schema\\\/person\\\/d4b47123df7b8ecdf5061cb0bcecdfef\"},\"description\":\"Europ\u00e4ische M\u00e4rkte geben nach, nachdem die Wall Street \u2013 die die schlechteste Woche seit September erlebte \u2013 gestern weitere Verluste...\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taglicher-marktuberblick\\\/maerkte-geben-aufgrund-von-instabilitaet-durch-handelskrieg-nfp-bericht-fed-im-fokus\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/smarttrader.community\\\/de\\\/taglicher-marktuberblick\\\/maerkte-geben-aufgrund-von-instabilitaet-durch-handelskrieg-nfp-bericht-fed-im-fokus\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taglicher-marktuberblick\\\/maerkte-geben-aufgrund-von-instabilitaet-durch-handelskrieg-nfp-bericht-fed-im-fokus\\\/#primaryimage\",\"url\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/Markets-decline.png\",\"contentUrl\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/Markets-decline.png\",\"width\":735,\"height\":490},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taglicher-marktuberblick\\\/maerkte-geben-aufgrund-von-instabilitaet-durch-handelskrieg-nfp-bericht-fed-im-fokus\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"M\u00e4rkte geben aufgrund von Instabilit\u00e4t durch Handelskrieg &amp; starker Unsicherheit nach; NFP-Bericht &amp; Fed im Fokus\u00a0\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/\",\"name\":\"SmartTrader\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/#\\\/schema\\\/person\\\/d4b47123df7b8ecdf5061cb0bcecdfef\",\"name\":\"SMARTTRADER ANALYST TEAM\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/cropped-favicon-site-96x96.png\",\"url\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/cropped-favicon-site-96x96.png\",\"contentUrl\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/cropped-favicon-site-96x96.png\",\"caption\":\"SMARTTRADER ANALYST TEAM\"},\"url\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/author\\\/kateryna-admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"M\u00e4rkte geben aufgrund von Instabilit\u00e4t durch Handelskrieg &amp; starker Unsicherheit nach; NFP-Bericht &amp; Fed im Fokus\u00a0 - SmartTrader","description":"Europ\u00e4ische M\u00e4rkte geben nach, nachdem die Wall Street \u2013 die die schlechteste Woche seit September erlebte \u2013 gestern weitere Verluste...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/maerkte-geben-aufgrund-von-instabilitaet-durch-handelskrieg-nfp-bericht-fed-im-fokus\/","og_locale":"de_DE","og_type":"article","og_title":"M\u00e4rkte geben aufgrund von Instabilit\u00e4t durch Handelskrieg &amp; starker Unsicherheit nach; NFP-Bericht &amp; Fed im Fokus\u00a0 - SmartTrader","og_description":"Europ\u00e4ische M\u00e4rkte geben nach, nachdem die Wall Street \u2013 die die schlechteste Woche seit September erlebte \u2013 gestern weitere Verluste...","og_url":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/maerkte-geben-aufgrund-von-instabilitaet-durch-handelskrieg-nfp-bericht-fed-im-fokus\/","og_site_name":"SmartTrader","article_published_time":"2025-03-07T11:20:41+00:00","article_modified_time":"2025-03-07T11:23:31+00:00","og_image":[{"width":735,"height":490,"url":"https:\/\/smarttrader.community\/wp-content\/uploads\/2025\/03\/Markets-decline.png","type":"image\/png"}],"author":"SMARTTRADER ANALYST TEAM","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"SMARTTRADER ANALYST TEAM","Gesch\u00e4tzte Lesezeit":"5\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/maerkte-geben-aufgrund-von-instabilitaet-durch-handelskrieg-nfp-bericht-fed-im-fokus\/#article","isPartOf":{"@id":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/maerkte-geben-aufgrund-von-instabilitaet-durch-handelskrieg-nfp-bericht-fed-im-fokus\/"},"author":{"name":"SMARTTRADER ANALYST TEAM","@id":"https:\/\/smarttrader.community\/de\/#\/schema\/person\/d4b47123df7b8ecdf5061cb0bcecdfef"},"headline":"M\u00e4rkte geben aufgrund von Instabilit\u00e4t durch Handelskrieg &amp; starker Unsicherheit nach; NFP-Bericht &amp; Fed im Fokus\u00a0","datePublished":"2025-03-07T11:20:41+00:00","dateModified":"2025-03-07T11:23:31+00:00","mainEntityOfPage":{"@id":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/maerkte-geben-aufgrund-von-instabilitaet-durch-handelskrieg-nfp-bericht-fed-im-fokus\/"},"wordCount":959,"commentCount":0,"image":{"@id":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/maerkte-geben-aufgrund-von-instabilitaet-durch-handelskrieg-nfp-bericht-fed-im-fokus\/#primaryimage"},"thumbnailUrl":"https:\/\/smarttrader.community\/wp-content\/uploads\/2025\/03\/Markets-decline.png","articleSection":["T\u00e4glicher Markt\u00fcberblick"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/maerkte-geben-aufgrund-von-instabilitaet-durch-handelskrieg-nfp-bericht-fed-im-fokus\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/maerkte-geben-aufgrund-von-instabilitaet-durch-handelskrieg-nfp-bericht-fed-im-fokus\/","url":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/maerkte-geben-aufgrund-von-instabilitaet-durch-handelskrieg-nfp-bericht-fed-im-fokus\/","name":"M\u00e4rkte geben aufgrund von Instabilit\u00e4t durch Handelskrieg &amp; starker Unsicherheit nach; NFP-Bericht &amp; Fed im Fokus\u00a0 - SmartTrader","isPartOf":{"@id":"https:\/\/smarttrader.community\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/maerkte-geben-aufgrund-von-instabilitaet-durch-handelskrieg-nfp-bericht-fed-im-fokus\/#primaryimage"},"image":{"@id":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/maerkte-geben-aufgrund-von-instabilitaet-durch-handelskrieg-nfp-bericht-fed-im-fokus\/#primaryimage"},"thumbnailUrl":"https:\/\/smarttrader.community\/wp-content\/uploads\/2025\/03\/Markets-decline.png","datePublished":"2025-03-07T11:20:41+00:00","dateModified":"2025-03-07T11:23:31+00:00","author":{"@id":"https:\/\/smarttrader.community\/de\/#\/schema\/person\/d4b47123df7b8ecdf5061cb0bcecdfef"},"description":"Europ\u00e4ische M\u00e4rkte geben nach, nachdem die Wall Street \u2013 die die schlechteste Woche seit September erlebte \u2013 gestern weitere Verluste...","breadcrumb":{"@id":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/maerkte-geben-aufgrund-von-instabilitaet-durch-handelskrieg-nfp-bericht-fed-im-fokus\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/maerkte-geben-aufgrund-von-instabilitaet-durch-handelskrieg-nfp-bericht-fed-im-fokus\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/maerkte-geben-aufgrund-von-instabilitaet-durch-handelskrieg-nfp-bericht-fed-im-fokus\/#primaryimage","url":"https:\/\/smarttrader.community\/wp-content\/uploads\/2025\/03\/Markets-decline.png","contentUrl":"https:\/\/smarttrader.community\/wp-content\/uploads\/2025\/03\/Markets-decline.png","width":735,"height":490},{"@type":"BreadcrumbList","@id":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/maerkte-geben-aufgrund-von-instabilitaet-durch-handelskrieg-nfp-bericht-fed-im-fokus\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/smarttrader.community\/de\/"},{"@type":"ListItem","position":2,"name":"M\u00e4rkte geben aufgrund von Instabilit\u00e4t durch Handelskrieg &amp; starker Unsicherheit nach; NFP-Bericht &amp; Fed im Fokus\u00a0"}]},{"@type":"WebSite","@id":"https:\/\/smarttrader.community\/de\/#website","url":"https:\/\/smarttrader.community\/de\/","name":"SmartTrader","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/smarttrader.community\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/smarttrader.community\/de\/#\/schema\/person\/d4b47123df7b8ecdf5061cb0bcecdfef","name":"SMARTTRADER ANALYST TEAM","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/03\/cropped-favicon-site-96x96.png","url":"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/03\/cropped-favicon-site-96x96.png","contentUrl":"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/03\/cropped-favicon-site-96x96.png","caption":"SMARTTRADER ANALYST TEAM"},"url":"https:\/\/smarttrader.community\/de\/author\/kateryna-admin\/"}]}},"_links":{"self":[{"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/posts\/49890","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/users\/2118"}],"replies":[{"embeddable":true,"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/comments?post=49890"}],"version-history":[{"count":1,"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/posts\/49890\/revisions"}],"predecessor-version":[{"id":49891,"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/posts\/49890\/revisions\/49891"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/media\/49886"}],"wp:attachment":[{"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/media?parent=49890"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/categories?post=49890"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/tags?post=49890"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}