{"id":50584,"date":"2025-04-18T11:25:39","date_gmt":"2025-04-18T11:25:39","guid":{"rendered":"https:\/\/smarttrader.community\/?p=50584"},"modified":"2025-04-18T11:28:38","modified_gmt":"2025-04-18T11:28:38","slug":"maerkte-stabil-waehrend-feiertagsschliessungen-handelsgespraeche-zwischen-den-usa-fed-signalisiert-verzoegerung-bei-zinssenkungen","status":"publish","type":"post","link":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/maerkte-stabil-waehrend-feiertagsschliessungen-handelsgespraeche-zwischen-den-usa-fed-signalisiert-verzoegerung-bei-zinssenkungen\/","title":{"rendered":"M\u00e4rkte stabil w\u00e4hrend Feiertagsschlie\u00dfungen; Handelsgespr\u00e4che zwischen den USA &amp; Japan st\u00fctzen Asien; Fed signalisiert Verz\u00f6gerung bei Zinssenkungen"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><em>\ud83d\udcc6 Freitag, 18. April \u00a0<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u25ba Die europ\u00e4ischen M\u00e4rkte blieben wegen des <strong>Karfreitags geschlossen<\/strong> und gaben den H\u00e4ndlern damit keine Richtung vor. Die<strong> Stimmung blieb jedoch vorsichtig<\/strong> <strong>positiv<\/strong>, da Pr\u00e4sident <strong>Trump<\/strong> m\u00f6gliche Fortschritte in den <strong>Handelsgespr\u00e4chen zwischen den USA und der EU <\/strong>andeutete, w\u00e4hrend die <strong>Spannungen mit China anhielten<\/strong>. Das Treffen zwischen der italienischen Ministerpr\u00e4sidenten Giorgia <strong>Meloni<\/strong> und Trump im Wei\u00dfen Haus verlief sehr harmonisch. Die europ\u00e4ischen Anleihem\u00e4rkte blieben nach den j\u00fcngsten Zinssenkungen der EZB fest, wobei sich die H\u00e4ndler darauf konzentrierten, ob die Handelskonflikte eine weitere Lockerung der Geldpolitik nach sich ziehen werden.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u25ba Die <strong>US-M\u00e4rkte schlossen am Donnerstag uneinheitlich<\/strong>, da die Anleger die Gewinne und die abwartenden Signale der Fed verdauten. Der<strong> S&P 500 verzeichnete einen leichten Wochenverlust<\/strong> und schloss am Donnerstag mit einer gewissen Entt\u00e4uschung, nachdem der Fed-Vorsitzende Jerome <strong>Powell sich gegen eine sofortige Zinssenkung ausgesprochen <\/strong>hatte, da die aktuellen Z\u00f6lle ein <strong>Inflationsrisiko<\/strong> darstellen. In der Zwischenzeit hat Pr\u00e4sident Trump die Spannungen wieder angeheizt, indem er Powell in den sozialen Medien kritisierte und behauptete, dass die Absetzung des Fed-Vorsitzenden<em> \u201enicht fr\u00fch genug kommen kann\u201c<\/em>. <em>\u201eWenn ich will, dass er geht, wird er sehr schnell gehen, glauben Sie mir\u201c, <\/em>sagte Trump im Oval Office, w\u00e4hrend er sich den Fragen von Reportern w\u00e4hrend eines Besuchs beim italienischen Ministerpr\u00e4sidenten Giorgia Meloni stellte. <em>\u201eIch bin nicht gl\u00fccklich mit ihm.\u201c (<\/em><em>siehe Video<\/em><em> \ud83d\udcfa)<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u25ba Die asiatischen <strong>Aktien legten bei leichtem Handel \u00fcberwiegend zu.<\/strong> Der japanische <strong>Nikkei 225 stieg um 0,72% <\/strong>und setzte damit seine Rallye fort, nachdem in den <strong>Handelsgespr\u00e4chen zwischen den USA und Japan<\/strong> \u201egro\u00dfe Fortschritte\u201c verk\u00fcndet worden waren. Optimismus befl\u00fcgelte die Technologiewerte, unterst\u00fctzt durch <strong>solide Gewinne von TSM<\/strong>. Der chinesische S<strong>hanghai Composite fiel um 0,12% <\/strong>und beendete damit eine achtt\u00e4gige Gewinnstr\u00e4hne, nachdem die USA mit neuen Z\u00f6llen auf chinesische Schiffe gedroht hatten. Der Offshore-<strong>CNY schw\u00e4chte sich auf etwa 7,30\/USD ab<\/strong>, da die Anleger angesichts einer m\u00f6glichen Eskalation vorsichtig wurden. Die M\u00e4rkte in <strong>Hongkong, Indien und Australien waren wegen des Osterfestes geschlossen.<\/strong><\/p>\n\n\n\n<div class=\"wp-block-group is-vertical is-layout-flex wp-container-core-group-is-layout-4fc3f8e1 wp-block-group-is-layout-flex\">\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/smarttrader.community\/membership-join\">Subscribe<\/a> to see more<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\ud83d\udcc6 Freitag, 18. April \u00a0 \u25ba Die europ\u00e4ischen M\u00e4rkte blieben wegen des Karfreitags geschlossen und gaben den H\u00e4ndlern damit keine&#8230;<\/p>\n","protected":false},"author":2118,"featured_media":50582,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","pmpro_default_level":"","_daextam_enable_autolinks":"1","footnotes":""},"categories":[172],"tags":[],"class_list":["post-50584","post","type-post","status-publish","format-standard","has-post-thumbnail","category-taglicher-marktuberblick","pmpro-has-access"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>M\u00e4rkte stabil w\u00e4hrend Feiertagsschlie\u00dfungen; Handelsgespr\u00e4che zwischen den USA &amp; Japan st\u00fctzen Asien; Fed signalisiert Verz\u00f6gerung bei Zinssenkungen - SmartTrader<\/title>\n<meta name=\"description\" content=\"Die europ\u00e4ischen M\u00e4rkte blieben wegen des Karfreitags geschlossen und gaben den H\u00e4ndlern damit keine Richtung vor. Die Stimmung blieb...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/maerkte-stabil-waehrend-feiertagsschliessungen-handelsgespraeche-zwischen-den-usa-fed-signalisiert-verzoegerung-bei-zinssenkungen\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"M\u00e4rkte stabil w\u00e4hrend Feiertagsschlie\u00dfungen; Handelsgespr\u00e4che zwischen den USA &amp; Japan st\u00fctzen Asien; Fed signalisiert Verz\u00f6gerung bei Zinssenkungen - SmartTrader\" \/>\n<meta property=\"og:description\" content=\"Die europ\u00e4ischen M\u00e4rkte blieben wegen des Karfreitags geschlossen und gaben den H\u00e4ndlern damit keine Richtung vor. Die Stimmung blieb...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/maerkte-stabil-waehrend-feiertagsschliessungen-handelsgespraeche-zwischen-den-usa-fed-signalisiert-verzoegerung-bei-zinssenkungen\/\" \/>\n<meta property=\"og:site_name\" content=\"SmartTrader\" \/>\n<meta property=\"article:published_time\" content=\"2025-04-18T11:25:39+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-18T11:28:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/smarttrader.community\/wp-content\/uploads\/2025\/04\/Stock-markets.png\" \/>\n\t<meta property=\"og:image:width\" content=\"683\" \/>\n\t<meta property=\"og:image:height\" content=\"455\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"SMARTTRADER ANALYST TEAM\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"SMARTTRADER ANALYST TEAM\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taglicher-marktuberblick\\\/maerkte-stabil-waehrend-feiertagsschliessungen-handelsgespraeche-zwischen-den-usa-fed-signalisiert-verzoegerung-bei-zinssenkungen\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taglicher-marktuberblick\\\/maerkte-stabil-waehrend-feiertagsschliessungen-handelsgespraeche-zwischen-den-usa-fed-signalisiert-verzoegerung-bei-zinssenkungen\\\/\"},\"author\":{\"name\":\"SMARTTRADER ANALYST TEAM\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/#\\\/schema\\\/person\\\/d4b47123df7b8ecdf5061cb0bcecdfef\"},\"headline\":\"M\u00e4rkte stabil w\u00e4hrend Feiertagsschlie\u00dfungen; Handelsgespr\u00e4che zwischen den USA &amp; Japan st\u00fctzen Asien; Fed signalisiert Verz\u00f6gerung bei Zinssenkungen\",\"datePublished\":\"2025-04-18T11:25:39+00:00\",\"dateModified\":\"2025-04-18T11:28:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taglicher-marktuberblick\\\/maerkte-stabil-waehrend-feiertagsschliessungen-handelsgespraeche-zwischen-den-usa-fed-signalisiert-verzoegerung-bei-zinssenkungen\\\/\"},\"wordCount\":547,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taglicher-marktuberblick\\\/maerkte-stabil-waehrend-feiertagsschliessungen-handelsgespraeche-zwischen-den-usa-fed-signalisiert-verzoegerung-bei-zinssenkungen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/Stock-markets.png\",\"articleSection\":[\"T\u00e4glicher Markt\u00fcberblick\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/smarttrader.community\\\/de\\\/taglicher-marktuberblick\\\/maerkte-stabil-waehrend-feiertagsschliessungen-handelsgespraeche-zwischen-den-usa-fed-signalisiert-verzoegerung-bei-zinssenkungen\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taglicher-marktuberblick\\\/maerkte-stabil-waehrend-feiertagsschliessungen-handelsgespraeche-zwischen-den-usa-fed-signalisiert-verzoegerung-bei-zinssenkungen\\\/\",\"url\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taglicher-marktuberblick\\\/maerkte-stabil-waehrend-feiertagsschliessungen-handelsgespraeche-zwischen-den-usa-fed-signalisiert-verzoegerung-bei-zinssenkungen\\\/\",\"name\":\"M\u00e4rkte stabil w\u00e4hrend Feiertagsschlie\u00dfungen; Handelsgespr\u00e4che zwischen den USA &amp; Japan st\u00fctzen Asien; Fed signalisiert Verz\u00f6gerung bei Zinssenkungen - SmartTrader\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taglicher-marktuberblick\\\/maerkte-stabil-waehrend-feiertagsschliessungen-handelsgespraeche-zwischen-den-usa-fed-signalisiert-verzoegerung-bei-zinssenkungen\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taglicher-marktuberblick\\\/maerkte-stabil-waehrend-feiertagsschliessungen-handelsgespraeche-zwischen-den-usa-fed-signalisiert-verzoegerung-bei-zinssenkungen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/Stock-markets.png\",\"datePublished\":\"2025-04-18T11:25:39+00:00\",\"dateModified\":\"2025-04-18T11:28:38+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/#\\\/schema\\\/person\\\/d4b47123df7b8ecdf5061cb0bcecdfef\"},\"description\":\"Die europ\u00e4ischen M\u00e4rkte blieben wegen des Karfreitags geschlossen und gaben den H\u00e4ndlern damit keine Richtung vor. Die Stimmung blieb...\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taglicher-marktuberblick\\\/maerkte-stabil-waehrend-feiertagsschliessungen-handelsgespraeche-zwischen-den-usa-fed-signalisiert-verzoegerung-bei-zinssenkungen\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/smarttrader.community\\\/de\\\/taglicher-marktuberblick\\\/maerkte-stabil-waehrend-feiertagsschliessungen-handelsgespraeche-zwischen-den-usa-fed-signalisiert-verzoegerung-bei-zinssenkungen\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taglicher-marktuberblick\\\/maerkte-stabil-waehrend-feiertagsschliessungen-handelsgespraeche-zwischen-den-usa-fed-signalisiert-verzoegerung-bei-zinssenkungen\\\/#primaryimage\",\"url\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/Stock-markets.png\",\"contentUrl\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/Stock-markets.png\",\"width\":683,\"height\":455},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taglicher-marktuberblick\\\/maerkte-stabil-waehrend-feiertagsschliessungen-handelsgespraeche-zwischen-den-usa-fed-signalisiert-verzoegerung-bei-zinssenkungen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"M\u00e4rkte stabil w\u00e4hrend Feiertagsschlie\u00dfungen; Handelsgespr\u00e4che zwischen den USA &amp; Japan st\u00fctzen Asien; Fed signalisiert Verz\u00f6gerung bei Zinssenkungen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/\",\"name\":\"SmartTrader\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/#\\\/schema\\\/person\\\/d4b47123df7b8ecdf5061cb0bcecdfef\",\"name\":\"SMARTTRADER ANALYST TEAM\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/cropped-favicon-site-96x96.png\",\"url\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/cropped-favicon-site-96x96.png\",\"contentUrl\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/cropped-favicon-site-96x96.png\",\"caption\":\"SMARTTRADER ANALYST TEAM\"},\"url\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/author\\\/kateryna-admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"M\u00e4rkte stabil w\u00e4hrend Feiertagsschlie\u00dfungen; Handelsgespr\u00e4che zwischen den USA &amp; Japan st\u00fctzen Asien; Fed signalisiert Verz\u00f6gerung bei Zinssenkungen - SmartTrader","description":"Die europ\u00e4ischen M\u00e4rkte blieben wegen des Karfreitags geschlossen und gaben den H\u00e4ndlern damit keine Richtung vor. Die Stimmung blieb...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/maerkte-stabil-waehrend-feiertagsschliessungen-handelsgespraeche-zwischen-den-usa-fed-signalisiert-verzoegerung-bei-zinssenkungen\/","og_locale":"de_DE","og_type":"article","og_title":"M\u00e4rkte stabil w\u00e4hrend Feiertagsschlie\u00dfungen; Handelsgespr\u00e4che zwischen den USA &amp; Japan st\u00fctzen Asien; Fed signalisiert Verz\u00f6gerung bei Zinssenkungen - SmartTrader","og_description":"Die europ\u00e4ischen M\u00e4rkte blieben wegen des Karfreitags geschlossen und gaben den H\u00e4ndlern damit keine Richtung vor. Die Stimmung blieb...","og_url":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/maerkte-stabil-waehrend-feiertagsschliessungen-handelsgespraeche-zwischen-den-usa-fed-signalisiert-verzoegerung-bei-zinssenkungen\/","og_site_name":"SmartTrader","article_published_time":"2025-04-18T11:25:39+00:00","article_modified_time":"2025-04-18T11:28:38+00:00","og_image":[{"width":683,"height":455,"url":"https:\/\/smarttrader.community\/wp-content\/uploads\/2025\/04\/Stock-markets.png","type":"image\/png"}],"author":"SMARTTRADER ANALYST TEAM","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"SMARTTRADER ANALYST TEAM","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/maerkte-stabil-waehrend-feiertagsschliessungen-handelsgespraeche-zwischen-den-usa-fed-signalisiert-verzoegerung-bei-zinssenkungen\/#article","isPartOf":{"@id":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/maerkte-stabil-waehrend-feiertagsschliessungen-handelsgespraeche-zwischen-den-usa-fed-signalisiert-verzoegerung-bei-zinssenkungen\/"},"author":{"name":"SMARTTRADER ANALYST TEAM","@id":"https:\/\/smarttrader.community\/de\/#\/schema\/person\/d4b47123df7b8ecdf5061cb0bcecdfef"},"headline":"M\u00e4rkte stabil w\u00e4hrend Feiertagsschlie\u00dfungen; Handelsgespr\u00e4che zwischen den USA &amp; Japan st\u00fctzen Asien; Fed signalisiert Verz\u00f6gerung bei Zinssenkungen","datePublished":"2025-04-18T11:25:39+00:00","dateModified":"2025-04-18T11:28:38+00:00","mainEntityOfPage":{"@id":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/maerkte-stabil-waehrend-feiertagsschliessungen-handelsgespraeche-zwischen-den-usa-fed-signalisiert-verzoegerung-bei-zinssenkungen\/"},"wordCount":547,"commentCount":0,"image":{"@id":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/maerkte-stabil-waehrend-feiertagsschliessungen-handelsgespraeche-zwischen-den-usa-fed-signalisiert-verzoegerung-bei-zinssenkungen\/#primaryimage"},"thumbnailUrl":"https:\/\/smarttrader.community\/wp-content\/uploads\/2025\/04\/Stock-markets.png","articleSection":["T\u00e4glicher Markt\u00fcberblick"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/maerkte-stabil-waehrend-feiertagsschliessungen-handelsgespraeche-zwischen-den-usa-fed-signalisiert-verzoegerung-bei-zinssenkungen\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/maerkte-stabil-waehrend-feiertagsschliessungen-handelsgespraeche-zwischen-den-usa-fed-signalisiert-verzoegerung-bei-zinssenkungen\/","url":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/maerkte-stabil-waehrend-feiertagsschliessungen-handelsgespraeche-zwischen-den-usa-fed-signalisiert-verzoegerung-bei-zinssenkungen\/","name":"M\u00e4rkte stabil w\u00e4hrend Feiertagsschlie\u00dfungen; Handelsgespr\u00e4che zwischen den USA &amp; Japan st\u00fctzen Asien; Fed signalisiert Verz\u00f6gerung bei Zinssenkungen - SmartTrader","isPartOf":{"@id":"https:\/\/smarttrader.community\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/maerkte-stabil-waehrend-feiertagsschliessungen-handelsgespraeche-zwischen-den-usa-fed-signalisiert-verzoegerung-bei-zinssenkungen\/#primaryimage"},"image":{"@id":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/maerkte-stabil-waehrend-feiertagsschliessungen-handelsgespraeche-zwischen-den-usa-fed-signalisiert-verzoegerung-bei-zinssenkungen\/#primaryimage"},"thumbnailUrl":"https:\/\/smarttrader.community\/wp-content\/uploads\/2025\/04\/Stock-markets.png","datePublished":"2025-04-18T11:25:39+00:00","dateModified":"2025-04-18T11:28:38+00:00","author":{"@id":"https:\/\/smarttrader.community\/de\/#\/schema\/person\/d4b47123df7b8ecdf5061cb0bcecdfef"},"description":"Die europ\u00e4ischen M\u00e4rkte blieben wegen des Karfreitags geschlossen und gaben den H\u00e4ndlern damit keine Richtung vor. Die Stimmung blieb...","breadcrumb":{"@id":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/maerkte-stabil-waehrend-feiertagsschliessungen-handelsgespraeche-zwischen-den-usa-fed-signalisiert-verzoegerung-bei-zinssenkungen\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/maerkte-stabil-waehrend-feiertagsschliessungen-handelsgespraeche-zwischen-den-usa-fed-signalisiert-verzoegerung-bei-zinssenkungen\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/maerkte-stabil-waehrend-feiertagsschliessungen-handelsgespraeche-zwischen-den-usa-fed-signalisiert-verzoegerung-bei-zinssenkungen\/#primaryimage","url":"https:\/\/smarttrader.community\/wp-content\/uploads\/2025\/04\/Stock-markets.png","contentUrl":"https:\/\/smarttrader.community\/wp-content\/uploads\/2025\/04\/Stock-markets.png","width":683,"height":455},{"@type":"BreadcrumbList","@id":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/maerkte-stabil-waehrend-feiertagsschliessungen-handelsgespraeche-zwischen-den-usa-fed-signalisiert-verzoegerung-bei-zinssenkungen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/smarttrader.community\/de\/"},{"@type":"ListItem","position":2,"name":"M\u00e4rkte stabil w\u00e4hrend Feiertagsschlie\u00dfungen; Handelsgespr\u00e4che zwischen den USA &amp; Japan st\u00fctzen Asien; Fed signalisiert Verz\u00f6gerung bei Zinssenkungen"}]},{"@type":"WebSite","@id":"https:\/\/smarttrader.community\/de\/#website","url":"https:\/\/smarttrader.community\/de\/","name":"SmartTrader","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/smarttrader.community\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/smarttrader.community\/de\/#\/schema\/person\/d4b47123df7b8ecdf5061cb0bcecdfef","name":"SMARTTRADER ANALYST TEAM","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/03\/cropped-favicon-site-96x96.png","url":"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/03\/cropped-favicon-site-96x96.png","contentUrl":"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/03\/cropped-favicon-site-96x96.png","caption":"SMARTTRADER ANALYST TEAM"},"url":"https:\/\/smarttrader.community\/de\/author\/kateryna-admin\/"}]}},"_links":{"self":[{"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/posts\/50584","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/users\/2118"}],"replies":[{"embeddable":true,"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/comments?post=50584"}],"version-history":[{"count":1,"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/posts\/50584\/revisions"}],"predecessor-version":[{"id":50585,"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/posts\/50584\/revisions\/50585"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/media\/50582"}],"wp:attachment":[{"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/media?parent=50584"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/categories?post=50584"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/tags?post=50584"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}