{"id":50686,"date":"2025-04-28T10:50:13","date_gmt":"2025-04-28T10:50:13","guid":{"rendered":"https:\/\/smarttrader.community\/?p=50686"},"modified":"2025-04-28T11:03:21","modified_gmt":"2025-04-28T11:03:21","slug":"globale-aktien-vor-wichtiger-gewinnwoche-gemischt-gold-rutscht-ab-oel-stagniert-bitcoin-konsolidiert","status":"publish","type":"post","link":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/globale-aktien-vor-wichtiger-gewinnwoche-gemischt-gold-rutscht-ab-oel-stagniert-bitcoin-konsolidiert\/","title":{"rendered":"Globale Aktien vor wichtiger Gewinnwoche gemischt; Gold rutscht ab, \u00d6l stagniert, Bitcoin konsolidiert \u00a0"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><em>\ud83d\udcc6 Montag, 28. April<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u25ba Die <strong>europ\u00e4ischen M\u00e4rkte legten zu<\/strong>, da sich die Investoren vor einer Woche mit wichtigen Unternehmenszahlen und Wirtschaftsdaten positionierten. Der <strong>Stoxx 600 stieg um 0,5 %<\/strong>, da sich die Investoren auf die im Laufe dieser Woche erwarteten Unternehmensergebnisse von <strong>BP<\/strong>, <strong>Deutsche Bank<\/strong>, <strong>HSBC<\/strong>, Deutsche B\u00f6rse und <strong>Shell<\/strong> konzentrierten. Der deutsche<strong> DAX (+ 0,55%)<\/strong>, der franz\u00f6sische <strong>CAC 40 (+ 0,65%) <\/strong>und der Londoner <strong>FTSE 100 (+ 0,35%)<\/strong> sind alle gestiegen. Der Aufschwung ist schon weit fortgeschritten, der DAX zum Beispiel liegt schon wieder auf dem Niveau vor Trumps Befreiungstag (2. April). Die \u00dcbernahme der Verm\u00f6gensverwaltungssparte von Assicurazioni Generali durch Mediobanca im Wert von 6,3 Mrd. \u20ac und die robuste Entwicklung der Banken in der Eurozone st\u00fctzten den Optimismus. Die <strong>spanische Arbeitslosenquote stieg im ersten Quartal auf 11,36%<\/strong>, w\u00e4hrend die schwedischen Erzeugerpreise und die norwegische Arbeitslosigkeit Anzeichen von Schw\u00e4che zeigten. Die allgemeine Stimmung blieb angesichts der anhaltenden Besorgnis \u00fcber die US-Handelspolitik zur\u00fcckhaltend.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u25ba Die <strong>US-M\u00e4rkte zeigten zu Beginn Schw\u00e4che<\/strong>, nachdem sie vier Tage in Folge zugelegt hatten. Die <strong>S&P 500-Futures sanken um 0,2 %<\/strong>, nachdem sie in der vergangenen Woche so stark gestiegen waren wie seit Januar nicht mehr. Die Investoren waren vor den wichtigen Unternehmenszahlen von <strong>Microsoft<\/strong>, <strong>Amazon<\/strong>, <strong>Meta<\/strong> und <strong>Apple<\/strong> zur\u00fcckhaltend. Die <strong>Verwirrung \u00fcber die Zollverhandlunge<\/strong>n zwischen den USA und China hielt an, nachdem Pr\u00e4sident Trump und Finanzminister Scott Bessent widerspr\u00fcchliche Signale gaben (und auch die chinesische Seite keine Fortschritte in den Gespr\u00e4chen best\u00e4tigte). Der Markt konzentrierte sich auch auf die anstehenden <strong>BIP- und Arbeitsmarktdaten. <\/strong>Die Renditen 10-j\u00e4hriger Staatsanleihen notieren unver\u00e4ndert bei 4,26%, w\u00e4hrend der<strong> USD leicht im Plus<\/strong> liegt (DXY +0,1%). US-Finanzminister Scott Bessent erkl\u00e4rte, dass die US-Regierung an bilateralen <strong>Handelsabkommen mit 17 wichtigen Partnern<\/strong>, darunter <strong>nicht China<\/strong>, arbeitet.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u25ba Die <strong>asiatischen M\u00e4rkte handelten \u00fcberwiegend h\u00f6her<\/strong>, aber mit einem vorsichtigen Ton. Der japanische<strong> Nikkei 225 stieg um 0,35%<\/strong>, angetrieben von Tech-Aktien und Optimismus \u00fcber das Binnenwachstum. Der<strong> JPY schw\u00e4chte sich in Richtung 144\/USD ab<\/strong>. Der chinesische <strong>Shanghai Composite schloss mit einem Minus von 0,2 %<\/strong>, belastet durch die <strong>anhaltenden Sorgen um den Handel zwischen den USA und China<\/strong>, obwohl Peking einige wichtige US-Waren (z. B. Halbleiter) von den Vergeltungsz\u00f6llen ausgenommen hat. Der Hang Seng in <strong>Hongkong notierte unver\u00e4ndert, <\/strong>da die H\u00e4ndler ihre Gewinne mitnahmen. Der indische Sensex stieg um \u00fcber 1%, w\u00e4hrend der australische <strong>ASX 200 um 0,36% <\/strong>zulegte.<\/p>\n\n\n\n<div class=\"wp-block-group is-vertical is-layout-flex wp-container-core-group-is-layout-4fc3f8e1 wp-block-group-is-layout-flex\">\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/smarttrader.community\/membership-join\">Subscribe<\/a> to see more<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\ud83d\udcc6 Montag, 28. April \u25ba Die europ\u00e4ischen M\u00e4rkte legten zu, da sich die Investoren vor einer Woche mit wichtigen Unternehmenszahlen&#8230;<\/p>\n","protected":false},"author":2118,"featured_media":50684,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","pmpro_default_level":"","_daextam_enable_autolinks":"1","footnotes":""},"categories":[172],"tags":[],"class_list":["post-50686","post","type-post","status-publish","format-standard","has-post-thumbnail","category-taglicher-marktuberblick","pmpro-has-access"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Globale Aktien vor wichtiger Gewinnwoche gemischt; Gold rutscht ab, \u00d6l stagniert, Bitcoin konsolidiert \u00a0 - SmartTrader<\/title>\n<meta name=\"description\" content=\"Die europ\u00e4ischen M\u00e4rkte legten zu, da sich die Investoren vor einer Woche mit wichtigen Unternehmenszahlen und Wirtschaftsdaten...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/globale-aktien-vor-wichtiger-gewinnwoche-gemischt-gold-rutscht-ab-oel-stagniert-bitcoin-konsolidiert\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Globale Aktien vor wichtiger Gewinnwoche gemischt; Gold rutscht ab, \u00d6l stagniert, Bitcoin konsolidiert \u00a0 - SmartTrader\" \/>\n<meta property=\"og:description\" content=\"Die europ\u00e4ischen M\u00e4rkte legten zu, da sich die Investoren vor einer Woche mit wichtigen Unternehmenszahlen und Wirtschaftsdaten...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/globale-aktien-vor-wichtiger-gewinnwoche-gemischt-gold-rutscht-ab-oel-stagniert-bitcoin-konsolidiert\/\" \/>\n<meta property=\"og:site_name\" content=\"SmartTrader\" \/>\n<meta property=\"article:published_time\" content=\"2025-04-28T10:50:13+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-28T11:03:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/smarttrader.community\/wp-content\/uploads\/2025\/04\/Mixed-markets.png\" \/>\n\t<meta property=\"og:image:width\" content=\"683\" \/>\n\t<meta property=\"og:image:height\" content=\"455\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"SMARTTRADER ANALYST TEAM\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"SMARTTRADER ANALYST TEAM\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taglicher-marktuberblick\\\/globale-aktien-vor-wichtiger-gewinnwoche-gemischt-gold-rutscht-ab-oel-stagniert-bitcoin-konsolidiert\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taglicher-marktuberblick\\\/globale-aktien-vor-wichtiger-gewinnwoche-gemischt-gold-rutscht-ab-oel-stagniert-bitcoin-konsolidiert\\\/\"},\"author\":{\"name\":\"SMARTTRADER ANALYST TEAM\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/#\\\/schema\\\/person\\\/d4b47123df7b8ecdf5061cb0bcecdfef\"},\"headline\":\"Globale Aktien vor wichtiger Gewinnwoche gemischt; Gold rutscht ab, \u00d6l stagniert, Bitcoin konsolidiert \u00a0\",\"datePublished\":\"2025-04-28T10:50:13+00:00\",\"dateModified\":\"2025-04-28T11:03:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taglicher-marktuberblick\\\/globale-aktien-vor-wichtiger-gewinnwoche-gemischt-gold-rutscht-ab-oel-stagniert-bitcoin-konsolidiert\\\/\"},\"wordCount\":626,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taglicher-marktuberblick\\\/globale-aktien-vor-wichtiger-gewinnwoche-gemischt-gold-rutscht-ab-oel-stagniert-bitcoin-konsolidiert\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/Mixed-markets.png\",\"articleSection\":[\"T\u00e4glicher Markt\u00fcberblick\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/smarttrader.community\\\/de\\\/taglicher-marktuberblick\\\/globale-aktien-vor-wichtiger-gewinnwoche-gemischt-gold-rutscht-ab-oel-stagniert-bitcoin-konsolidiert\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taglicher-marktuberblick\\\/globale-aktien-vor-wichtiger-gewinnwoche-gemischt-gold-rutscht-ab-oel-stagniert-bitcoin-konsolidiert\\\/\",\"url\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taglicher-marktuberblick\\\/globale-aktien-vor-wichtiger-gewinnwoche-gemischt-gold-rutscht-ab-oel-stagniert-bitcoin-konsolidiert\\\/\",\"name\":\"Globale Aktien vor wichtiger Gewinnwoche gemischt; Gold rutscht ab, \u00d6l stagniert, Bitcoin konsolidiert \u00a0 - SmartTrader\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taglicher-marktuberblick\\\/globale-aktien-vor-wichtiger-gewinnwoche-gemischt-gold-rutscht-ab-oel-stagniert-bitcoin-konsolidiert\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taglicher-marktuberblick\\\/globale-aktien-vor-wichtiger-gewinnwoche-gemischt-gold-rutscht-ab-oel-stagniert-bitcoin-konsolidiert\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/Mixed-markets.png\",\"datePublished\":\"2025-04-28T10:50:13+00:00\",\"dateModified\":\"2025-04-28T11:03:21+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/#\\\/schema\\\/person\\\/d4b47123df7b8ecdf5061cb0bcecdfef\"},\"description\":\"Die europ\u00e4ischen M\u00e4rkte legten zu, da sich die Investoren vor einer Woche mit wichtigen Unternehmenszahlen und Wirtschaftsdaten...\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taglicher-marktuberblick\\\/globale-aktien-vor-wichtiger-gewinnwoche-gemischt-gold-rutscht-ab-oel-stagniert-bitcoin-konsolidiert\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/smarttrader.community\\\/de\\\/taglicher-marktuberblick\\\/globale-aktien-vor-wichtiger-gewinnwoche-gemischt-gold-rutscht-ab-oel-stagniert-bitcoin-konsolidiert\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taglicher-marktuberblick\\\/globale-aktien-vor-wichtiger-gewinnwoche-gemischt-gold-rutscht-ab-oel-stagniert-bitcoin-konsolidiert\\\/#primaryimage\",\"url\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/Mixed-markets.png\",\"contentUrl\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/Mixed-markets.png\",\"width\":683,\"height\":455},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taglicher-marktuberblick\\\/globale-aktien-vor-wichtiger-gewinnwoche-gemischt-gold-rutscht-ab-oel-stagniert-bitcoin-konsolidiert\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Globale Aktien vor wichtiger Gewinnwoche gemischt; Gold rutscht ab, \u00d6l stagniert, Bitcoin konsolidiert \u00a0\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/\",\"name\":\"SmartTrader\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/#\\\/schema\\\/person\\\/d4b47123df7b8ecdf5061cb0bcecdfef\",\"name\":\"SMARTTRADER ANALYST TEAM\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/cropped-favicon-site-96x96.png\",\"url\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/cropped-favicon-site-96x96.png\",\"contentUrl\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/cropped-favicon-site-96x96.png\",\"caption\":\"SMARTTRADER ANALYST TEAM\"},\"url\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/author\\\/kateryna-admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Globale Aktien vor wichtiger Gewinnwoche gemischt; Gold rutscht ab, \u00d6l stagniert, Bitcoin konsolidiert \u00a0 - SmartTrader","description":"Die europ\u00e4ischen M\u00e4rkte legten zu, da sich die Investoren vor einer Woche mit wichtigen Unternehmenszahlen und Wirtschaftsdaten...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/globale-aktien-vor-wichtiger-gewinnwoche-gemischt-gold-rutscht-ab-oel-stagniert-bitcoin-konsolidiert\/","og_locale":"de_DE","og_type":"article","og_title":"Globale Aktien vor wichtiger Gewinnwoche gemischt; Gold rutscht ab, \u00d6l stagniert, Bitcoin konsolidiert \u00a0 - SmartTrader","og_description":"Die europ\u00e4ischen M\u00e4rkte legten zu, da sich die Investoren vor einer Woche mit wichtigen Unternehmenszahlen und Wirtschaftsdaten...","og_url":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/globale-aktien-vor-wichtiger-gewinnwoche-gemischt-gold-rutscht-ab-oel-stagniert-bitcoin-konsolidiert\/","og_site_name":"SmartTrader","article_published_time":"2025-04-28T10:50:13+00:00","article_modified_time":"2025-04-28T11:03:21+00:00","og_image":[{"width":683,"height":455,"url":"https:\/\/smarttrader.community\/wp-content\/uploads\/2025\/04\/Mixed-markets.png","type":"image\/png"}],"author":"SMARTTRADER ANALYST TEAM","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"SMARTTRADER ANALYST TEAM","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/globale-aktien-vor-wichtiger-gewinnwoche-gemischt-gold-rutscht-ab-oel-stagniert-bitcoin-konsolidiert\/#article","isPartOf":{"@id":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/globale-aktien-vor-wichtiger-gewinnwoche-gemischt-gold-rutscht-ab-oel-stagniert-bitcoin-konsolidiert\/"},"author":{"name":"SMARTTRADER ANALYST TEAM","@id":"https:\/\/smarttrader.community\/de\/#\/schema\/person\/d4b47123df7b8ecdf5061cb0bcecdfef"},"headline":"Globale Aktien vor wichtiger Gewinnwoche gemischt; Gold rutscht ab, \u00d6l stagniert, Bitcoin konsolidiert \u00a0","datePublished":"2025-04-28T10:50:13+00:00","dateModified":"2025-04-28T11:03:21+00:00","mainEntityOfPage":{"@id":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/globale-aktien-vor-wichtiger-gewinnwoche-gemischt-gold-rutscht-ab-oel-stagniert-bitcoin-konsolidiert\/"},"wordCount":626,"commentCount":0,"image":{"@id":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/globale-aktien-vor-wichtiger-gewinnwoche-gemischt-gold-rutscht-ab-oel-stagniert-bitcoin-konsolidiert\/#primaryimage"},"thumbnailUrl":"https:\/\/smarttrader.community\/wp-content\/uploads\/2025\/04\/Mixed-markets.png","articleSection":["T\u00e4glicher Markt\u00fcberblick"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/globale-aktien-vor-wichtiger-gewinnwoche-gemischt-gold-rutscht-ab-oel-stagniert-bitcoin-konsolidiert\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/globale-aktien-vor-wichtiger-gewinnwoche-gemischt-gold-rutscht-ab-oel-stagniert-bitcoin-konsolidiert\/","url":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/globale-aktien-vor-wichtiger-gewinnwoche-gemischt-gold-rutscht-ab-oel-stagniert-bitcoin-konsolidiert\/","name":"Globale Aktien vor wichtiger Gewinnwoche gemischt; Gold rutscht ab, \u00d6l stagniert, Bitcoin konsolidiert \u00a0 - SmartTrader","isPartOf":{"@id":"https:\/\/smarttrader.community\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/globale-aktien-vor-wichtiger-gewinnwoche-gemischt-gold-rutscht-ab-oel-stagniert-bitcoin-konsolidiert\/#primaryimage"},"image":{"@id":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/globale-aktien-vor-wichtiger-gewinnwoche-gemischt-gold-rutscht-ab-oel-stagniert-bitcoin-konsolidiert\/#primaryimage"},"thumbnailUrl":"https:\/\/smarttrader.community\/wp-content\/uploads\/2025\/04\/Mixed-markets.png","datePublished":"2025-04-28T10:50:13+00:00","dateModified":"2025-04-28T11:03:21+00:00","author":{"@id":"https:\/\/smarttrader.community\/de\/#\/schema\/person\/d4b47123df7b8ecdf5061cb0bcecdfef"},"description":"Die europ\u00e4ischen M\u00e4rkte legten zu, da sich die Investoren vor einer Woche mit wichtigen Unternehmenszahlen und Wirtschaftsdaten...","breadcrumb":{"@id":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/globale-aktien-vor-wichtiger-gewinnwoche-gemischt-gold-rutscht-ab-oel-stagniert-bitcoin-konsolidiert\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/globale-aktien-vor-wichtiger-gewinnwoche-gemischt-gold-rutscht-ab-oel-stagniert-bitcoin-konsolidiert\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/globale-aktien-vor-wichtiger-gewinnwoche-gemischt-gold-rutscht-ab-oel-stagniert-bitcoin-konsolidiert\/#primaryimage","url":"https:\/\/smarttrader.community\/wp-content\/uploads\/2025\/04\/Mixed-markets.png","contentUrl":"https:\/\/smarttrader.community\/wp-content\/uploads\/2025\/04\/Mixed-markets.png","width":683,"height":455},{"@type":"BreadcrumbList","@id":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/globale-aktien-vor-wichtiger-gewinnwoche-gemischt-gold-rutscht-ab-oel-stagniert-bitcoin-konsolidiert\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/smarttrader.community\/de\/"},{"@type":"ListItem","position":2,"name":"Globale Aktien vor wichtiger Gewinnwoche gemischt; Gold rutscht ab, \u00d6l stagniert, Bitcoin konsolidiert \u00a0"}]},{"@type":"WebSite","@id":"https:\/\/smarttrader.community\/de\/#website","url":"https:\/\/smarttrader.community\/de\/","name":"SmartTrader","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/smarttrader.community\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/smarttrader.community\/de\/#\/schema\/person\/d4b47123df7b8ecdf5061cb0bcecdfef","name":"SMARTTRADER ANALYST TEAM","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/03\/cropped-favicon-site-96x96.png","url":"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/03\/cropped-favicon-site-96x96.png","contentUrl":"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/03\/cropped-favicon-site-96x96.png","caption":"SMARTTRADER ANALYST TEAM"},"url":"https:\/\/smarttrader.community\/de\/author\/kateryna-admin\/"}]}},"_links":{"self":[{"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/posts\/50686","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/users\/2118"}],"replies":[{"embeddable":true,"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/comments?post=50686"}],"version-history":[{"count":1,"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/posts\/50686\/revisions"}],"predecessor-version":[{"id":50687,"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/posts\/50686\/revisions\/50687"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/media\/50684"}],"wp:attachment":[{"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/media?parent=50686"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/categories?post=50686"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/tags?post=50686"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}