{"id":50736,"date":"2025-04-30T14:30:00","date_gmt":"2025-04-30T14:30:00","guid":{"rendered":"https:\/\/smarttrader.community\/?p=50736"},"modified":"2025-04-30T20:44:01","modified_gmt":"2025-04-30T20:44:01","slug":"aktienrallye-kommt-vor-big-tech-earnings-wichtigen-wirtschaftsdaten-us-bip-pce-ins-stocken","status":"publish","type":"post","link":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/aktienrallye-kommt-vor-big-tech-earnings-wichtigen-wirtschaftsdaten-us-bip-pce-ins-stocken\/","title":{"rendered":"Aktienrallye kommt vor Big-Tech-Earnings &amp; wichtigen Wirtschaftsdaten (US-BIP &amp; PCE) ins Stocken"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><em>\ud83d\udcc6 Mittwoch, 30. April \u00a0<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u25ba Die <strong>europ\u00e4ischen Aktien legten zu<\/strong> trotz eher gemischter Earnings, da die Investoren mit einer Vielzahl von Gewinnmeldungen konfrontiert waren und wichtige Konjunkturdaten aus den USA erwarteten. Der <strong>Stoxx 600 stieg um 0,4 %<\/strong>, der deutsche<strong> DAX um 0,6 %<\/strong> und der franz\u00f6sische <strong>CAC leicht um 0,5 %<\/strong>. <strong>UBS<\/strong> legte um 0,2% zu, nachdem sie mit einem Umsatz von 12,56 Mrd. $ die Sch\u00e4tzungen \u00fcbertroffen hatte, w\u00e4hrend <strong>Barclays<\/strong> trotz starker Q1-Zahlen und eines angehobenen Ausblicks f\u00fcr das GJ25 um 1,5% nachgab. <strong>Mercedes-Benz<\/strong> (-2,1%) meldete einen Umsatz von \u20ac33,2 Mrd. (-7,4% im Jahresvergleich) und ein GAAP-EPS von \u20ac1,74 und warnte, dass die anhaltende <strong>Zollunsicherheit<\/strong> die GJ-Prognose erheblich beeintr\u00e4chtigen k\u00f6nnte. <strong>Volkswagen<\/strong> (-0,5%) wies ebenfalls auf <strong>Abw\u00e4rtsrisiken f\u00fcr Gewinn und Cashflow<\/strong> hin, da sein<strong> Gewinn im ersten Quartal um 40% sank.<\/strong> Trotz dieser Warnungen hielten sich die <strong>europ\u00e4ischen Autoaktien relativ stabil, <\/strong>nachdem Pr\u00e4sident Trump eine Durchf\u00fchrungsverordnung unterzeichnet hatte, die die <strong>Erhebung von Z\u00f6llen auf ausl\u00e4ndische Fahrzeuge und Teile lockerte.<\/strong> Das <strong>deutsche BIP schrumpfte im Jahresvergleich um 0,2 %<\/strong>, w\u00e4hrend <strong>Frankreich<\/strong> dank einer unerwartet starken Nachfrage der privaten Haushalte <strong>um 0,8 % zulegte. <\/strong>Die<strong> Wirtschaftsdaten der Eurozone sind insgesamt eher besser als erwartet,<\/strong> wobei die deutschen Daten noch hinterherhinken. Die <strong>BIP-Wachstumsrate der Eurozone wurde mit +1,2%<\/strong> gegen\u00fcber dem Vorjahr gemeldet (gegen\u00fcber 1,0% erwartet).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u25ba Die <strong>US-Futures gaben nach einer sechst\u00e4gigen Rallye (vorerst) leicht nach,<\/strong> wobei die Kontrakte des <strong>S&P 500<\/strong> und des<strong> Nasdaq 100 ins Minus<\/strong> rutschten. Der R\u00fcckzug erfolgte im Vorfeld der wichtigen<strong> US-BIP- und PCE-Inflationsdaten<\/strong>, die als entscheidend f\u00fcr die Zinssenkungserwartungen gelten. Die <strong>Rendite 10-j\u00e4hriger Staatsanleihen stabilisierte sich <\/strong>bei 4,165%. Die Stimmung bei den Unternehmensergebnissen schlug um, nachdem <strong>Snap (- 13.5%)<\/strong> im nachb\u00f6rslichen Handel einbrach und sich weigerte, eine Prognose f\u00fcr die Zukunft abzugeben, weil der makro\u00f6konomische Gegenwind zu gro\u00df war. <strong>Super Micro Computer <\/strong>sank um mehr als <strong>16,5 %,<\/strong> nachdem das Unternehmen seine vorl\u00e4ufigen Ziele verfehlt hatte, und<strong> Starbucks (- 7 %) <\/strong>meldete einen Umsatzr\u00fcckgang, der etwas st\u00e4rker ausfiel als erwartet. <strong>General Motors <\/strong>und <strong>JetBlue<\/strong> zogen ihre Prognosen f\u00fcr das Gesamtjahr zur\u00fcck, w\u00e4hrend <strong>UPS<\/strong> ank\u00fcndigte, in diesem Jahr 20.000 Stellen abzubauen (alles am Vortag). Analysten gehen davon aus, dass die \u201eMagnificent Seven\u201c in diesem Jahr ein durchschnittliches Gewinnwachstum von 15 % verzeichnen werden, wobei <strong>Microsoft<\/strong> und <strong>Meta<\/strong> im Laufe des heutigen Tages und <strong>Apple<\/strong> und <strong>Amazon<\/strong> im Laufe der Woche Bericht erstatten werden.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u25ba Die<strong> asiatischen M\u00e4rkte schlossen trotz schwacher Konjunkturdaten, <\/strong>insbesondere aus <strong>China<\/strong>, <strong>\u00fcberwiegend h\u00f6her. <\/strong>Der offizielle <strong>PMI des verarbeitenden Gewerbes fiel auf 49,0 <\/strong>und verzeichnete damit den st\u00e4rksten R\u00fcckgang seit Dezember 2023, w\u00e4hrend der PMI des Dienstleistungssektors ebenfalls hinter den Erwartungen zur\u00fcckblieb. De<strong>r Shanghai Composite sank um 0,23%<\/strong>, w\u00e4hrend<strong> Shenzhen um 0,51% stieg. Schwache Fabrikdate<\/strong>n und ged\u00e4mpfte Verbraucherausgaben dr\u00fcckten auf die Stimmung, und der<strong> Offshore-CNY gab einen zweiten Tag lang nach<\/strong>, da die Handelsspannungen anhielten. Der japanische<strong> Nikkei legte bei der Wiederer\u00f6ffnung der M\u00e4rkte um 0,57% zu,<\/strong> unterst\u00fctzt durch den <strong>Handelsdialog zwischen den USA und Japan.<\/strong> Der australische <strong>ASX stieg <\/strong>zum f\u00fcnften Mal in Folge und schloss mit einem Plus von 0,34%, nachdem die Inflation im ersten Quartal bei 2,4% verharrte.<\/p>\n\n\n\n<div class=\"wp-block-group is-vertical is-layout-flex wp-container-core-group-is-layout-4fc3f8e1 wp-block-group-is-layout-flex\">\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/smarttrader.community\/membership-join\">Subscribe<\/a> to see more<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;&nbsp; &nbsp;<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>\ud83d\udcc6 Mittwoch, 30. April \u00a0 \u25ba Die europ\u00e4ischen Aktien legten zu trotz eher gemischter Earnings, da die Investoren mit einer&#8230;<\/p>\n","protected":false},"author":2118,"featured_media":50734,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","pmpro_default_level":"","_daextam_enable_autolinks":"1","footnotes":""},"categories":[172],"tags":[],"class_list":["post-50736","post","type-post","status-publish","format-standard","has-post-thumbnail","category-taglicher-marktuberblick","pmpro-has-access"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Aktienrallye kommt vor Big-Tech-Earnings &amp; wichtigen Wirtschaftsdaten (US-BIP &amp; PCE) ins Stocken - SmartTrader<\/title>\n<meta name=\"description\" content=\"Die europ\u00e4ischen Aktien legten zu trotz eher gemischter Earnings, da die Investoren mit einer Vielzahl von Gewinnmeldungen konfrontiert...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/aktienrallye-kommt-vor-big-tech-earnings-wichtigen-wirtschaftsdaten-us-bip-pce-ins-stocken\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Aktienrallye kommt vor Big-Tech-Earnings &amp; wichtigen Wirtschaftsdaten (US-BIP &amp; PCE) ins Stocken - SmartTrader\" \/>\n<meta property=\"og:description\" content=\"Die europ\u00e4ischen Aktien legten zu trotz eher gemischter Earnings, da die Investoren mit einer Vielzahl von Gewinnmeldungen konfrontiert...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/aktienrallye-kommt-vor-big-tech-earnings-wichtigen-wirtschaftsdaten-us-bip-pce-ins-stocken\/\" \/>\n<meta property=\"og:site_name\" content=\"SmartTrader\" \/>\n<meta property=\"article:published_time\" content=\"2025-04-30T14:30:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-30T20:44:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/smarttrader.community\/wp-content\/uploads\/2025\/04\/GDP.png\" \/>\n\t<meta property=\"og:image:width\" content=\"683\" \/>\n\t<meta property=\"og:image:height\" content=\"455\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"SMARTTRADER ANALYST TEAM\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"SMARTTRADER ANALYST TEAM\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"5\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taglicher-marktuberblick\\\/aktienrallye-kommt-vor-big-tech-earnings-wichtigen-wirtschaftsdaten-us-bip-pce-ins-stocken\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taglicher-marktuberblick\\\/aktienrallye-kommt-vor-big-tech-earnings-wichtigen-wirtschaftsdaten-us-bip-pce-ins-stocken\\\/\"},\"author\":{\"name\":\"SMARTTRADER ANALYST TEAM\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/#\\\/schema\\\/person\\\/d4b47123df7b8ecdf5061cb0bcecdfef\"},\"headline\":\"Aktienrallye kommt vor Big-Tech-Earnings &amp; wichtigen Wirtschaftsdaten (US-BIP &amp; PCE) ins Stocken\",\"datePublished\":\"2025-04-30T14:30:00+00:00\",\"dateModified\":\"2025-04-30T20:44:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taglicher-marktuberblick\\\/aktienrallye-kommt-vor-big-tech-earnings-wichtigen-wirtschaftsdaten-us-bip-pce-ins-stocken\\\/\"},\"wordCount\":910,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taglicher-marktuberblick\\\/aktienrallye-kommt-vor-big-tech-earnings-wichtigen-wirtschaftsdaten-us-bip-pce-ins-stocken\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/GDP.png\",\"articleSection\":[\"T\u00e4glicher Markt\u00fcberblick\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/smarttrader.community\\\/de\\\/taglicher-marktuberblick\\\/aktienrallye-kommt-vor-big-tech-earnings-wichtigen-wirtschaftsdaten-us-bip-pce-ins-stocken\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taglicher-marktuberblick\\\/aktienrallye-kommt-vor-big-tech-earnings-wichtigen-wirtschaftsdaten-us-bip-pce-ins-stocken\\\/\",\"url\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taglicher-marktuberblick\\\/aktienrallye-kommt-vor-big-tech-earnings-wichtigen-wirtschaftsdaten-us-bip-pce-ins-stocken\\\/\",\"name\":\"Aktienrallye kommt vor Big-Tech-Earnings &amp; wichtigen Wirtschaftsdaten (US-BIP &amp; PCE) ins Stocken - SmartTrader\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taglicher-marktuberblick\\\/aktienrallye-kommt-vor-big-tech-earnings-wichtigen-wirtschaftsdaten-us-bip-pce-ins-stocken\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taglicher-marktuberblick\\\/aktienrallye-kommt-vor-big-tech-earnings-wichtigen-wirtschaftsdaten-us-bip-pce-ins-stocken\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/GDP.png\",\"datePublished\":\"2025-04-30T14:30:00+00:00\",\"dateModified\":\"2025-04-30T20:44:01+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/#\\\/schema\\\/person\\\/d4b47123df7b8ecdf5061cb0bcecdfef\"},\"description\":\"Die europ\u00e4ischen Aktien legten zu trotz eher gemischter Earnings, da die Investoren mit einer Vielzahl von Gewinnmeldungen konfrontiert...\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taglicher-marktuberblick\\\/aktienrallye-kommt-vor-big-tech-earnings-wichtigen-wirtschaftsdaten-us-bip-pce-ins-stocken\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/smarttrader.community\\\/de\\\/taglicher-marktuberblick\\\/aktienrallye-kommt-vor-big-tech-earnings-wichtigen-wirtschaftsdaten-us-bip-pce-ins-stocken\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taglicher-marktuberblick\\\/aktienrallye-kommt-vor-big-tech-earnings-wichtigen-wirtschaftsdaten-us-bip-pce-ins-stocken\\\/#primaryimage\",\"url\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/GDP.png\",\"contentUrl\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/GDP.png\",\"width\":683,\"height\":455},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taglicher-marktuberblick\\\/aktienrallye-kommt-vor-big-tech-earnings-wichtigen-wirtschaftsdaten-us-bip-pce-ins-stocken\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Aktienrallye kommt vor Big-Tech-Earnings &amp; wichtigen Wirtschaftsdaten (US-BIP &amp; PCE) ins Stocken\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/\",\"name\":\"SmartTrader\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/#\\\/schema\\\/person\\\/d4b47123df7b8ecdf5061cb0bcecdfef\",\"name\":\"SMARTTRADER ANALYST TEAM\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/cropped-favicon-site-96x96.png\",\"url\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/cropped-favicon-site-96x96.png\",\"contentUrl\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/cropped-favicon-site-96x96.png\",\"caption\":\"SMARTTRADER ANALYST TEAM\"},\"url\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/author\\\/kateryna-admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Aktienrallye kommt vor Big-Tech-Earnings &amp; wichtigen Wirtschaftsdaten (US-BIP &amp; PCE) ins Stocken - SmartTrader","description":"Die europ\u00e4ischen Aktien legten zu trotz eher gemischter Earnings, da die Investoren mit einer Vielzahl von Gewinnmeldungen konfrontiert...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/aktienrallye-kommt-vor-big-tech-earnings-wichtigen-wirtschaftsdaten-us-bip-pce-ins-stocken\/","og_locale":"de_DE","og_type":"article","og_title":"Aktienrallye kommt vor Big-Tech-Earnings &amp; wichtigen Wirtschaftsdaten (US-BIP &amp; PCE) ins Stocken - SmartTrader","og_description":"Die europ\u00e4ischen Aktien legten zu trotz eher gemischter Earnings, da die Investoren mit einer Vielzahl von Gewinnmeldungen konfrontiert...","og_url":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/aktienrallye-kommt-vor-big-tech-earnings-wichtigen-wirtschaftsdaten-us-bip-pce-ins-stocken\/","og_site_name":"SmartTrader","article_published_time":"2025-04-30T14:30:00+00:00","article_modified_time":"2025-04-30T20:44:01+00:00","og_image":[{"width":683,"height":455,"url":"https:\/\/smarttrader.community\/wp-content\/uploads\/2025\/04\/GDP.png","type":"image\/png"}],"author":"SMARTTRADER ANALYST TEAM","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"SMARTTRADER ANALYST TEAM","Gesch\u00e4tzte Lesezeit":"5\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/aktienrallye-kommt-vor-big-tech-earnings-wichtigen-wirtschaftsdaten-us-bip-pce-ins-stocken\/#article","isPartOf":{"@id":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/aktienrallye-kommt-vor-big-tech-earnings-wichtigen-wirtschaftsdaten-us-bip-pce-ins-stocken\/"},"author":{"name":"SMARTTRADER ANALYST TEAM","@id":"https:\/\/smarttrader.community\/de\/#\/schema\/person\/d4b47123df7b8ecdf5061cb0bcecdfef"},"headline":"Aktienrallye kommt vor Big-Tech-Earnings &amp; wichtigen Wirtschaftsdaten (US-BIP &amp; PCE) ins Stocken","datePublished":"2025-04-30T14:30:00+00:00","dateModified":"2025-04-30T20:44:01+00:00","mainEntityOfPage":{"@id":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/aktienrallye-kommt-vor-big-tech-earnings-wichtigen-wirtschaftsdaten-us-bip-pce-ins-stocken\/"},"wordCount":910,"commentCount":0,"image":{"@id":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/aktienrallye-kommt-vor-big-tech-earnings-wichtigen-wirtschaftsdaten-us-bip-pce-ins-stocken\/#primaryimage"},"thumbnailUrl":"https:\/\/smarttrader.community\/wp-content\/uploads\/2025\/04\/GDP.png","articleSection":["T\u00e4glicher Markt\u00fcberblick"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/aktienrallye-kommt-vor-big-tech-earnings-wichtigen-wirtschaftsdaten-us-bip-pce-ins-stocken\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/aktienrallye-kommt-vor-big-tech-earnings-wichtigen-wirtschaftsdaten-us-bip-pce-ins-stocken\/","url":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/aktienrallye-kommt-vor-big-tech-earnings-wichtigen-wirtschaftsdaten-us-bip-pce-ins-stocken\/","name":"Aktienrallye kommt vor Big-Tech-Earnings &amp; wichtigen Wirtschaftsdaten (US-BIP &amp; PCE) ins Stocken - SmartTrader","isPartOf":{"@id":"https:\/\/smarttrader.community\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/aktienrallye-kommt-vor-big-tech-earnings-wichtigen-wirtschaftsdaten-us-bip-pce-ins-stocken\/#primaryimage"},"image":{"@id":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/aktienrallye-kommt-vor-big-tech-earnings-wichtigen-wirtschaftsdaten-us-bip-pce-ins-stocken\/#primaryimage"},"thumbnailUrl":"https:\/\/smarttrader.community\/wp-content\/uploads\/2025\/04\/GDP.png","datePublished":"2025-04-30T14:30:00+00:00","dateModified":"2025-04-30T20:44:01+00:00","author":{"@id":"https:\/\/smarttrader.community\/de\/#\/schema\/person\/d4b47123df7b8ecdf5061cb0bcecdfef"},"description":"Die europ\u00e4ischen Aktien legten zu trotz eher gemischter Earnings, da die Investoren mit einer Vielzahl von Gewinnmeldungen konfrontiert...","breadcrumb":{"@id":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/aktienrallye-kommt-vor-big-tech-earnings-wichtigen-wirtschaftsdaten-us-bip-pce-ins-stocken\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/aktienrallye-kommt-vor-big-tech-earnings-wichtigen-wirtschaftsdaten-us-bip-pce-ins-stocken\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/aktienrallye-kommt-vor-big-tech-earnings-wichtigen-wirtschaftsdaten-us-bip-pce-ins-stocken\/#primaryimage","url":"https:\/\/smarttrader.community\/wp-content\/uploads\/2025\/04\/GDP.png","contentUrl":"https:\/\/smarttrader.community\/wp-content\/uploads\/2025\/04\/GDP.png","width":683,"height":455},{"@type":"BreadcrumbList","@id":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/aktienrallye-kommt-vor-big-tech-earnings-wichtigen-wirtschaftsdaten-us-bip-pce-ins-stocken\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/smarttrader.community\/de\/"},{"@type":"ListItem","position":2,"name":"Aktienrallye kommt vor Big-Tech-Earnings &amp; wichtigen Wirtschaftsdaten (US-BIP &amp; PCE) ins Stocken"}]},{"@type":"WebSite","@id":"https:\/\/smarttrader.community\/de\/#website","url":"https:\/\/smarttrader.community\/de\/","name":"SmartTrader","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/smarttrader.community\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/smarttrader.community\/de\/#\/schema\/person\/d4b47123df7b8ecdf5061cb0bcecdfef","name":"SMARTTRADER ANALYST TEAM","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/03\/cropped-favicon-site-96x96.png","url":"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/03\/cropped-favicon-site-96x96.png","contentUrl":"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/03\/cropped-favicon-site-96x96.png","caption":"SMARTTRADER ANALYST TEAM"},"url":"https:\/\/smarttrader.community\/de\/author\/kateryna-admin\/"}]}},"_links":{"self":[{"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/posts\/50736","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/users\/2118"}],"replies":[{"embeddable":true,"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/comments?post=50736"}],"version-history":[{"count":1,"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/posts\/50736\/revisions"}],"predecessor-version":[{"id":50737,"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/posts\/50736\/revisions\/50737"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/media\/50734"}],"wp:attachment":[{"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/media?parent=50736"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/categories?post=50736"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/tags?post=50736"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}