{"id":51706,"date":"2025-07-25T12:51:01","date_gmt":"2025-07-25T12:51:01","guid":{"rendered":"https:\/\/smarttrader.community\/?p=51706"},"modified":"2025-07-25T13:01:45","modified_gmt":"2025-07-25T13:01:45","slug":"gemischte-earnings-belasten-maerkte-usd-erholung-trifft-rohstoffe-typische-freitagsvorsicht-nach-starker-woche","status":"publish","type":"post","link":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/gemischte-earnings-belasten-maerkte-usd-erholung-trifft-rohstoffe-typische-freitagsvorsicht-nach-starker-woche\/","title":{"rendered":"Gemischte Earnings belasten M\u00e4rkte; USD-Erholung trifft Rohstoffe; Typische Freitagsvorsicht nach starker Woche"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><em>\ud83d\uddd3 Freitag, 25. Juli<\/em><\/p>\n\n\n\n<div class=\"wp-block-group is-vertical is-layout-flex wp-container-core-group-is-layout-4fc3f8e1 wp-block-group-is-layout-flex\">\n<p class=\"wp-block-paragraph\">\u25ba<strong> Europa gibt nach Gewinnausf\u00e4llen leicht nach; Hoffnungen auf Handelsabkommen halten an<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Der <strong>Stoxx 600 gab um 0,45 %<\/strong> nach, belastet durch die Gewinnschw\u00e4che des deutschen DAX (-0,70 %) und eine allgemeine Schw\u00e4che in der Region. Der CAC notiert unver\u00e4ndert, w\u00e4hrend der britische Leitindex FTSE 100 mit -0,4 % zu Buche steht. Puma brach nach einer Gewinnwarnung um -18 % ein, w\u00e4hrend Volkswagen nach den erwarteten und besser als bef\u00fcrchteten Ergebnissen mit +1,7 % zulegte. Die LVMH-Aktie (+ 3,3 %) erholte sich nach der Ver\u00f6ffentlichung der weniger schlecht als bef\u00fcrchteten Ergebnisse und st\u00fctzte den CAC_40. Die Anleger beobachten weiterhin die Fortschritte bei den<strong> Handelsverhandlungen zwischen den USA und der EU<\/strong>, wobei die Zollvereinbarungen wahrscheinlich 15 % als Basiswert festlegen werden. Die deutschen 10-Jahres-Renditen stiegen um +4 Basispunkte auf 2,74 %, w\u00e4hrend der <strong>EUR\/USD<\/strong> aufgrund der Dollarst\u00e4rke auf 1,172 (-0,35 %) nachgab. Der GBP\/USD gab sogar um 0,55 % nach.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-group is-vertical is-layout-flex wp-container-core-group-is-layout-4fc3f8e1 wp-block-group-is-layout-flex\">\n<p class=\"wp-block-paragraph\"><strong>\u25ba Wall Street gibt nach Intel-Einbruch von H\u00f6chstst\u00e4nden nach; Fed & Handelsgespr\u00e4che im Fokus<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die<strong> US-Futures blieben stabil,<\/strong> nachdem der S&P 500 und der Nasdaq am Donnerstag auf neuen Rekordst\u00e4nden geschlossen hatten. Die Stimmung am Freitag wurde jedoch durch <strong>Intel<\/strong> (-8,2 %) getr\u00fcbt, nachdem das Unternehmen entt\u00e4uschende Ergebnisse f\u00fcr das zweite Quartal und Pl\u00e4ne zum Stellenabbau bekannt gegeben hatte.<strong> N\u00e4chste Woche erreicht die Berichtssaison ihren H\u00f6hepunkt, <\/strong>dann legen 38 % der S&P-500-Unternehmen ihre Zahlen vor. Auf makro\u00f6konomischer Ebene steht die Fed-Sitzung am 30. Juli bevor, wobei der Markt nach den j\u00fcngsten starken Daten nun einen hawkischeren Powell einpreist. Der<strong> USD-Index stieg um +0,45 %<\/strong> und die Renditen 10-j\u00e4hriger US-Staatsanleihen stiegen um +2 Basispunkte auf 4,42 %. Der Optimismus im Handel h\u00e4lt nach den Abkommen mit Japan und Indonesien an, und die Hoffnungen auf Durchbr\u00fcche zwischen den USA und der EU sowie zwischen den USA und China bleiben hoch.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-group is-vertical is-layout-flex wp-container-core-group-is-layout-4fc3f8e1 wp-block-group-is-layout-flex\">\n<p class=\"wp-block-paragraph\"><strong>\u25ba Asien uneinheitlich; Japan gibt nach starker Woche nach, Indien verl\u00e4ngert Verluste<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nach der j\u00fcngsten St\u00e4rke kam es an den <strong>asiatischen M\u00e4rkten zu leichten Gewinnmitnahmen.<\/strong> Der japanische Nikkei fiel um -0,88 %, wobei die Exporteure durch den Sprung des USD\/JPY auf 147,85 (+ 0,6 %) unter Druck gerieten. Die schwachen Prognosen von Puma belasteten auch die regionalen Bekleidungsaktien. Der indische Nifty fiel um -0,9 % und verzeichnete angesichts von Spekulationen \u00fcber ein Handelsabkommen und Vorsicht vor den Signalen der US-Notenbank weitere Verluste. Der s\u00fcdkoreanische Kospi stieg um +0,18 %, w\u00e4hrend der chinesische Shanghai-Index trotz anhaltender Ruhe an den Devisenm\u00e4rkten um -0,33 % nachgab. Die Marktstimmung bleibt hinsichtlich der Handelsvereinbarungen zwischen den USA und Asien konstruktiv, wobei Indien \u201epr\u00e4ferenzielle\u201d Zollbedingungen von den USA erwartet.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/smarttrader.community\/membership-join\">Subscribe<\/a> to see more<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\ud83d\uddd3 Freitag, 25. Juli \u25ba Europa gibt nach Gewinnausf\u00e4llen leicht nach; Hoffnungen auf Handelsabkommen halten an Der Stoxx 600 gab&#8230;<\/p>\n","protected":false},"author":2118,"featured_media":49397,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","pmpro_default_level":"","_daextam_enable_autolinks":"1","footnotes":""},"categories":[172],"tags":[],"class_list":["post-51706","post","type-post","status-publish","format-standard","has-post-thumbnail","category-taglicher-marktuberblick","pmpro-has-access"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Gemischte Earnings belasten M\u00e4rkte; USD-Erholung trifft Rohstoffe; Typische Freitagsvorsicht nach starker Woche - SmartTrader<\/title>\n<meta name=\"description\" content=\"Europa gibt nach Gewinnausf\u00e4llen leicht nach; Hoffnungen auf Handelsabkommen halten anDer Stoxx 600 gab um 0,45 % nach, belastet durch die...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/gemischte-earnings-belasten-maerkte-usd-erholung-trifft-rohstoffe-typische-freitagsvorsicht-nach-starker-woche\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gemischte Earnings belasten M\u00e4rkte; USD-Erholung trifft Rohstoffe; Typische Freitagsvorsicht nach starker Woche - SmartTrader\" \/>\n<meta property=\"og:description\" content=\"Europa gibt nach Gewinnausf\u00e4llen leicht nach; Hoffnungen auf Handelsabkommen halten anDer Stoxx 600 gab um 0,45 % nach, belastet durch die...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/gemischte-earnings-belasten-maerkte-usd-erholung-trifft-rohstoffe-typische-freitagsvorsicht-nach-starker-woche\/\" \/>\n<meta property=\"og:site_name\" content=\"SmartTrader\" \/>\n<meta property=\"article:published_time\" content=\"2025-07-25T12:51:01+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-25T13:01:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/smarttrader.community\/wp-content\/uploads\/2025\/02\/Inflation_data_us.png\" \/>\n\t<meta property=\"og:image:width\" content=\"683\" \/>\n\t<meta property=\"og:image:height\" content=\"455\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"SMARTTRADER ANALYST TEAM\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"SMARTTRADER ANALYST TEAM\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"4\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taglicher-marktuberblick\\\/gemischte-earnings-belasten-maerkte-usd-erholung-trifft-rohstoffe-typische-freitagsvorsicht-nach-starker-woche\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taglicher-marktuberblick\\\/gemischte-earnings-belasten-maerkte-usd-erholung-trifft-rohstoffe-typische-freitagsvorsicht-nach-starker-woche\\\/\"},\"author\":{\"name\":\"SMARTTRADER ANALYST TEAM\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/#\\\/schema\\\/person\\\/d4b47123df7b8ecdf5061cb0bcecdfef\"},\"headline\":\"Gemischte Earnings belasten M\u00e4rkte; USD-Erholung trifft Rohstoffe; Typische Freitagsvorsicht nach starker Woche\",\"datePublished\":\"2025-07-25T12:51:01+00:00\",\"dateModified\":\"2025-07-25T13:01:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taglicher-marktuberblick\\\/gemischte-earnings-belasten-maerkte-usd-erholung-trifft-rohstoffe-typische-freitagsvorsicht-nach-starker-woche\\\/\"},\"wordCount\":817,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taglicher-marktuberblick\\\/gemischte-earnings-belasten-maerkte-usd-erholung-trifft-rohstoffe-typische-freitagsvorsicht-nach-starker-woche\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/Inflation_data_us.png\",\"articleSection\":[\"T\u00e4glicher Markt\u00fcberblick\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/smarttrader.community\\\/de\\\/taglicher-marktuberblick\\\/gemischte-earnings-belasten-maerkte-usd-erholung-trifft-rohstoffe-typische-freitagsvorsicht-nach-starker-woche\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taglicher-marktuberblick\\\/gemischte-earnings-belasten-maerkte-usd-erholung-trifft-rohstoffe-typische-freitagsvorsicht-nach-starker-woche\\\/\",\"url\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taglicher-marktuberblick\\\/gemischte-earnings-belasten-maerkte-usd-erholung-trifft-rohstoffe-typische-freitagsvorsicht-nach-starker-woche\\\/\",\"name\":\"Gemischte Earnings belasten M\u00e4rkte; USD-Erholung trifft Rohstoffe; Typische Freitagsvorsicht nach starker Woche - SmartTrader\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taglicher-marktuberblick\\\/gemischte-earnings-belasten-maerkte-usd-erholung-trifft-rohstoffe-typische-freitagsvorsicht-nach-starker-woche\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taglicher-marktuberblick\\\/gemischte-earnings-belasten-maerkte-usd-erholung-trifft-rohstoffe-typische-freitagsvorsicht-nach-starker-woche\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/Inflation_data_us.png\",\"datePublished\":\"2025-07-25T12:51:01+00:00\",\"dateModified\":\"2025-07-25T13:01:45+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/#\\\/schema\\\/person\\\/d4b47123df7b8ecdf5061cb0bcecdfef\"},\"description\":\"Europa gibt nach Gewinnausf\u00e4llen leicht nach; Hoffnungen auf Handelsabkommen halten anDer Stoxx 600 gab um 0,45 % nach, belastet durch die...\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taglicher-marktuberblick\\\/gemischte-earnings-belasten-maerkte-usd-erholung-trifft-rohstoffe-typische-freitagsvorsicht-nach-starker-woche\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/smarttrader.community\\\/de\\\/taglicher-marktuberblick\\\/gemischte-earnings-belasten-maerkte-usd-erholung-trifft-rohstoffe-typische-freitagsvorsicht-nach-starker-woche\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taglicher-marktuberblick\\\/gemischte-earnings-belasten-maerkte-usd-erholung-trifft-rohstoffe-typische-freitagsvorsicht-nach-starker-woche\\\/#primaryimage\",\"url\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/Inflation_data_us.png\",\"contentUrl\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/Inflation_data_us.png\",\"width\":683,\"height\":455},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taglicher-marktuberblick\\\/gemischte-earnings-belasten-maerkte-usd-erholung-trifft-rohstoffe-typische-freitagsvorsicht-nach-starker-woche\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gemischte Earnings belasten M\u00e4rkte; USD-Erholung trifft Rohstoffe; Typische Freitagsvorsicht nach starker Woche\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/\",\"name\":\"SmartTrader\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/#\\\/schema\\\/person\\\/d4b47123df7b8ecdf5061cb0bcecdfef\",\"name\":\"SMARTTRADER ANALYST TEAM\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/cropped-favicon-site-96x96.png\",\"url\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/cropped-favicon-site-96x96.png\",\"contentUrl\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/cropped-favicon-site-96x96.png\",\"caption\":\"SMARTTRADER ANALYST TEAM\"},\"url\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/author\\\/kateryna-admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gemischte Earnings belasten M\u00e4rkte; USD-Erholung trifft Rohstoffe; Typische Freitagsvorsicht nach starker Woche - SmartTrader","description":"Europa gibt nach Gewinnausf\u00e4llen leicht nach; Hoffnungen auf Handelsabkommen halten anDer Stoxx 600 gab um 0,45 % nach, belastet durch die...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/gemischte-earnings-belasten-maerkte-usd-erholung-trifft-rohstoffe-typische-freitagsvorsicht-nach-starker-woche\/","og_locale":"de_DE","og_type":"article","og_title":"Gemischte Earnings belasten M\u00e4rkte; USD-Erholung trifft Rohstoffe; Typische Freitagsvorsicht nach starker Woche - SmartTrader","og_description":"Europa gibt nach Gewinnausf\u00e4llen leicht nach; Hoffnungen auf Handelsabkommen halten anDer Stoxx 600 gab um 0,45 % nach, belastet durch die...","og_url":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/gemischte-earnings-belasten-maerkte-usd-erholung-trifft-rohstoffe-typische-freitagsvorsicht-nach-starker-woche\/","og_site_name":"SmartTrader","article_published_time":"2025-07-25T12:51:01+00:00","article_modified_time":"2025-07-25T13:01:45+00:00","og_image":[{"width":683,"height":455,"url":"https:\/\/smarttrader.community\/wp-content\/uploads\/2025\/02\/Inflation_data_us.png","type":"image\/png"}],"author":"SMARTTRADER ANALYST TEAM","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"SMARTTRADER ANALYST TEAM","Gesch\u00e4tzte Lesezeit":"4\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/gemischte-earnings-belasten-maerkte-usd-erholung-trifft-rohstoffe-typische-freitagsvorsicht-nach-starker-woche\/#article","isPartOf":{"@id":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/gemischte-earnings-belasten-maerkte-usd-erholung-trifft-rohstoffe-typische-freitagsvorsicht-nach-starker-woche\/"},"author":{"name":"SMARTTRADER ANALYST TEAM","@id":"https:\/\/smarttrader.community\/de\/#\/schema\/person\/d4b47123df7b8ecdf5061cb0bcecdfef"},"headline":"Gemischte Earnings belasten M\u00e4rkte; USD-Erholung trifft Rohstoffe; Typische Freitagsvorsicht nach starker Woche","datePublished":"2025-07-25T12:51:01+00:00","dateModified":"2025-07-25T13:01:45+00:00","mainEntityOfPage":{"@id":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/gemischte-earnings-belasten-maerkte-usd-erholung-trifft-rohstoffe-typische-freitagsvorsicht-nach-starker-woche\/"},"wordCount":817,"commentCount":0,"image":{"@id":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/gemischte-earnings-belasten-maerkte-usd-erholung-trifft-rohstoffe-typische-freitagsvorsicht-nach-starker-woche\/#primaryimage"},"thumbnailUrl":"https:\/\/smarttrader.community\/wp-content\/uploads\/2025\/02\/Inflation_data_us.png","articleSection":["T\u00e4glicher Markt\u00fcberblick"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/gemischte-earnings-belasten-maerkte-usd-erholung-trifft-rohstoffe-typische-freitagsvorsicht-nach-starker-woche\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/gemischte-earnings-belasten-maerkte-usd-erholung-trifft-rohstoffe-typische-freitagsvorsicht-nach-starker-woche\/","url":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/gemischte-earnings-belasten-maerkte-usd-erholung-trifft-rohstoffe-typische-freitagsvorsicht-nach-starker-woche\/","name":"Gemischte Earnings belasten M\u00e4rkte; USD-Erholung trifft Rohstoffe; Typische Freitagsvorsicht nach starker Woche - SmartTrader","isPartOf":{"@id":"https:\/\/smarttrader.community\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/gemischte-earnings-belasten-maerkte-usd-erholung-trifft-rohstoffe-typische-freitagsvorsicht-nach-starker-woche\/#primaryimage"},"image":{"@id":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/gemischte-earnings-belasten-maerkte-usd-erholung-trifft-rohstoffe-typische-freitagsvorsicht-nach-starker-woche\/#primaryimage"},"thumbnailUrl":"https:\/\/smarttrader.community\/wp-content\/uploads\/2025\/02\/Inflation_data_us.png","datePublished":"2025-07-25T12:51:01+00:00","dateModified":"2025-07-25T13:01:45+00:00","author":{"@id":"https:\/\/smarttrader.community\/de\/#\/schema\/person\/d4b47123df7b8ecdf5061cb0bcecdfef"},"description":"Europa gibt nach Gewinnausf\u00e4llen leicht nach; Hoffnungen auf Handelsabkommen halten anDer Stoxx 600 gab um 0,45 % nach, belastet durch die...","breadcrumb":{"@id":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/gemischte-earnings-belasten-maerkte-usd-erholung-trifft-rohstoffe-typische-freitagsvorsicht-nach-starker-woche\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/gemischte-earnings-belasten-maerkte-usd-erholung-trifft-rohstoffe-typische-freitagsvorsicht-nach-starker-woche\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/gemischte-earnings-belasten-maerkte-usd-erholung-trifft-rohstoffe-typische-freitagsvorsicht-nach-starker-woche\/#primaryimage","url":"https:\/\/smarttrader.community\/wp-content\/uploads\/2025\/02\/Inflation_data_us.png","contentUrl":"https:\/\/smarttrader.community\/wp-content\/uploads\/2025\/02\/Inflation_data_us.png","width":683,"height":455},{"@type":"BreadcrumbList","@id":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/gemischte-earnings-belasten-maerkte-usd-erholung-trifft-rohstoffe-typische-freitagsvorsicht-nach-starker-woche\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/smarttrader.community\/de\/"},{"@type":"ListItem","position":2,"name":"Gemischte Earnings belasten M\u00e4rkte; USD-Erholung trifft Rohstoffe; Typische Freitagsvorsicht nach starker Woche"}]},{"@type":"WebSite","@id":"https:\/\/smarttrader.community\/de\/#website","url":"https:\/\/smarttrader.community\/de\/","name":"SmartTrader","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/smarttrader.community\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/smarttrader.community\/de\/#\/schema\/person\/d4b47123df7b8ecdf5061cb0bcecdfef","name":"SMARTTRADER ANALYST TEAM","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/03\/cropped-favicon-site-96x96.png","url":"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/03\/cropped-favicon-site-96x96.png","contentUrl":"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/03\/cropped-favicon-site-96x96.png","caption":"SMARTTRADER ANALYST TEAM"},"url":"https:\/\/smarttrader.community\/de\/author\/kateryna-admin\/"}]}},"_links":{"self":[{"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/posts\/51706","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/users\/2118"}],"replies":[{"embeddable":true,"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/comments?post=51706"}],"version-history":[{"count":1,"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/posts\/51706\/revisions"}],"predecessor-version":[{"id":51707,"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/posts\/51706\/revisions\/51707"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/media\/49397"}],"wp:attachment":[{"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/media?parent=51706"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/categories?post=51706"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/tags?post=51706"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}