{"id":51794,"date":"2025-08-04T11:53:27","date_gmt":"2025-08-04T11:53:27","guid":{"rendered":"https:\/\/smarttrader.community\/?p=51794"},"modified":"2025-08-04T12:10:14","modified_gmt":"2025-08-04T12:10:14","slug":"maerkte-in-erholung-nach-schockierenden-nfp-revisionen-hoffnung-auf-fed-zinssenkungen-schweizer-aktien-schwach-asien-gemischt","status":"publish","type":"post","link":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/maerkte-in-erholung-nach-schockierenden-nfp-revisionen-hoffnung-auf-fed-zinssenkungen-schweizer-aktien-schwach-asien-gemischt\/","title":{"rendered":"M\u00e4rkte in Erholung nach schockierenden NFP-Revisionen; Hoffnung auf Fed-Zinssenkungen; Schweizer Aktien schwach, Asien gemischt"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><em>\ud83d\uddd3 Montag, 4. August<\/em><\/p>\n\n\n\n<div class=\"wp-block-group is-vertical is-layout-flex wp-container-core-group-is-layout-4fc3f8e1 wp-block-group-is-layout-flex\">\n<p class=\"wp-block-paragraph\"><strong>\u25ba Europa er\u00f6ffnet mit Fed-Optimismus h\u00f6her; Schweizer Aktien hinken wegen Zollsorgen hinterher<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die europ\u00e4ischen Aktienm\u00e4rkte erholen sich, da die H\u00e4ndler die Zollsorgen hinter sich lie\u00dfen und sich auf die wachsende Aussicht auf Zinssenkungen der Fed konzentrierten. Der<strong> Stoxx 600 stieg um 0,60%<\/strong>, der italienische FTSE MIB um 1,70%, der DAX um 1,05%, der CAC um 0,75% und der FTSE 100 um 0,3%. Im Gegensatz dazu wurde der Schweizer SMI -0,7% deutlich niedriger gehandelt, da die Anleger Trumps 39%ige Z\u00f6lle und den erneuten Druck auf die Arzneimittelhersteller einpreisten. Die Renditen f\u00fcr 10-j\u00e4hrige Bundesanleihen sanken auf 2,67%, w\u00e4hrend EUR\/USD leicht auf 1,156 fiel, was auf die <strong>Underperformance der Eurozone<\/strong> gegen\u00fcber einem stabileren Wall Street bzw. USD zur\u00fcckzuf\u00fchren ist.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-group is-vertical is-layout-flex wp-container-core-group-is-layout-4fc3f8e1 wp-block-group-is-layout-flex\">\n<p class=\"wp-block-paragraph\">\u25ba<strong> US-Futures erholen sich, da Zinssenkungswetten trotz politischer Unsicherheiten zunehmen<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die Futures an der Wall Street stiegen nach starken Verlusten, da die schlechten Arbeitsmarktdaten zumindest die Hoffnung auf eine baldige Zinssenkung durch die Fed befl\u00fcgelten. Der S&P 500 (+0,65%), der Nasdaq 100 (+0,75%) und der Dow (+0,65%) machten einige der starken Verluste vom Freitag wieder wett. Fed-Swaps preisen jetzt eine Lockerung um 57 Basispunkte bis zum Jahresende ein, wobei einige H\u00e4ndler sogar eine m\u00f6gliche Zinssenkung um 50 Basispunkte im September ins Auge fassen. Die Renditen von Staatsanleihen stiegen nach dem Einbruch am Freitag leicht an und die 10-Jahres-Rendite lag bei 4,24 %. Unterdessen k\u00fcndigte Trump neue Ernennungen f\u00fcr die Fed an, was den weiteren Weg der Zentralbank noch interessanter macht. Technologie- und zyklische Werte f\u00fchrten die vorb\u00f6rslichen Kursgewinne an, obwohl die politische Unsicherheit und die Auswirkungen der Z\u00f6lle die Hauptrisiken bleiben.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-group is-vertical is-layout-flex wp-container-core-group-is-layout-4fc3f8e1 wp-block-group-is-layout-flex\">\n<p class=\"wp-block-paragraph\"><strong>\u25ba Asien uneinheitlich, w\u00e4hrend US-Daten Stimmung anheizen; Japan & Taiwan underperformen&nbsp;<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die M\u00e4rkte im asiatisch-pazifischen Raum wurden inmitten eines sich ver\u00e4ndernden globalen Narrativs <strong>uneinheitlich<\/strong> gehandelt. Hang Seng +0,92%, Kospi +0,91% und Shanghai +0,66% legten aufgrund der Hoffnung auf eine Zinssenkung in den USA und einer verbesserten Risikobereitschaft zu. Der Nikkei -1,25% fiel jedoch, da die Exporteure einbrachen, und Taiwan -0,24% gab neben einem schw\u00e4cheren NZX -0,36% leicht nach. Am Devisenmarkt stieg USD\/JPY auf 147,75, und USD\/CNY gab auf 7,175 nach. Die Renditen der japanischen Staatsanleihen sanken, da sich die japanischen Anleiheinvestoren auf eine schwache Auktion vorbereiten und die globalen W\u00e4hrungstrends angesichts der <strong>Handelsstreitigkeiten der Trump-\u00c4ra<\/strong>, einschlie\u00dflich der deutlich h\u00f6heren <strong>US-Z\u00f6lle<\/strong>, neu bewerten.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/smarttrader.community\/membership-join\">Subscribe<\/a> to see more<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\ud83d\uddd3 Montag, 4. August \u25ba Europa er\u00f6ffnet mit Fed-Optimismus h\u00f6her; Schweizer Aktien hinken wegen Zollsorgen hinterher Die europ\u00e4ischen Aktienm\u00e4rkte erholen&#8230;<\/p>\n","protected":false},"author":2118,"featured_media":50987,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","pmpro_default_level":"","_daextam_enable_autolinks":"1","footnotes":""},"categories":[172],"tags":[],"class_list":["post-51794","post","type-post","status-publish","format-standard","has-post-thumbnail","category-taglicher-marktuberblick","pmpro-has-access"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>M\u00e4rkte in Erholung nach schockierenden NFP-Revisionen; Hoffnung auf Fed-Zinssenkungen; Schweizer Aktien schwach, Asien gemischt - SmartTrader<\/title>\n<meta name=\"description\" content=\"Europa er\u00f6ffnet mit Fed-Optimismus h\u00f6her; Schweizer Aktien hinken wegen Zollsorgen hinterherDie europ\u00e4ischen Aktienm\u00e4rkte erholen sich, da...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/maerkte-in-erholung-nach-schockierenden-nfp-revisionen-hoffnung-auf-fed-zinssenkungen-schweizer-aktien-schwach-asien-gemischt\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"M\u00e4rkte in Erholung nach schockierenden NFP-Revisionen; Hoffnung auf Fed-Zinssenkungen; Schweizer Aktien schwach, Asien gemischt - SmartTrader\" \/>\n<meta property=\"og:description\" content=\"Europa er\u00f6ffnet mit Fed-Optimismus h\u00f6her; Schweizer Aktien hinken wegen Zollsorgen hinterherDie europ\u00e4ischen Aktienm\u00e4rkte erholen sich, da...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/maerkte-in-erholung-nach-schockierenden-nfp-revisionen-hoffnung-auf-fed-zinssenkungen-schweizer-aktien-schwach-asien-gemischt\/\" \/>\n<meta property=\"og:site_name\" content=\"SmartTrader\" \/>\n<meta property=\"article:published_time\" content=\"2025-08-04T11:53:27+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-04T12:10:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/smarttrader.community\/wp-content\/uploads\/2025\/05\/Fed.png\" \/>\n\t<meta property=\"og:image:width\" content=\"683\" \/>\n\t<meta property=\"og:image:height\" content=\"455\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"SMARTTRADER ANALYST TEAM\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"SMARTTRADER ANALYST TEAM\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"4\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taglicher-marktuberblick\\\/maerkte-in-erholung-nach-schockierenden-nfp-revisionen-hoffnung-auf-fed-zinssenkungen-schweizer-aktien-schwach-asien-gemischt\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taglicher-marktuberblick\\\/maerkte-in-erholung-nach-schockierenden-nfp-revisionen-hoffnung-auf-fed-zinssenkungen-schweizer-aktien-schwach-asien-gemischt\\\/\"},\"author\":{\"name\":\"SMARTTRADER ANALYST TEAM\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/#\\\/schema\\\/person\\\/d4b47123df7b8ecdf5061cb0bcecdfef\"},\"headline\":\"M\u00e4rkte in Erholung nach schockierenden NFP-Revisionen; Hoffnung auf Fed-Zinssenkungen; Schweizer Aktien schwach, Asien gemischt\",\"datePublished\":\"2025-08-04T11:53:27+00:00\",\"dateModified\":\"2025-08-04T12:10:14+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taglicher-marktuberblick\\\/maerkte-in-erholung-nach-schockierenden-nfp-revisionen-hoffnung-auf-fed-zinssenkungen-schweizer-aktien-schwach-asien-gemischt\\\/\"},\"wordCount\":631,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taglicher-marktuberblick\\\/maerkte-in-erholung-nach-schockierenden-nfp-revisionen-hoffnung-auf-fed-zinssenkungen-schweizer-aktien-schwach-asien-gemischt\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/Fed.png\",\"articleSection\":[\"T\u00e4glicher Markt\u00fcberblick\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/smarttrader.community\\\/de\\\/taglicher-marktuberblick\\\/maerkte-in-erholung-nach-schockierenden-nfp-revisionen-hoffnung-auf-fed-zinssenkungen-schweizer-aktien-schwach-asien-gemischt\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taglicher-marktuberblick\\\/maerkte-in-erholung-nach-schockierenden-nfp-revisionen-hoffnung-auf-fed-zinssenkungen-schweizer-aktien-schwach-asien-gemischt\\\/\",\"url\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taglicher-marktuberblick\\\/maerkte-in-erholung-nach-schockierenden-nfp-revisionen-hoffnung-auf-fed-zinssenkungen-schweizer-aktien-schwach-asien-gemischt\\\/\",\"name\":\"M\u00e4rkte in Erholung nach schockierenden NFP-Revisionen; Hoffnung auf Fed-Zinssenkungen; Schweizer Aktien schwach, Asien gemischt - SmartTrader\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taglicher-marktuberblick\\\/maerkte-in-erholung-nach-schockierenden-nfp-revisionen-hoffnung-auf-fed-zinssenkungen-schweizer-aktien-schwach-asien-gemischt\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taglicher-marktuberblick\\\/maerkte-in-erholung-nach-schockierenden-nfp-revisionen-hoffnung-auf-fed-zinssenkungen-schweizer-aktien-schwach-asien-gemischt\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/Fed.png\",\"datePublished\":\"2025-08-04T11:53:27+00:00\",\"dateModified\":\"2025-08-04T12:10:14+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/#\\\/schema\\\/person\\\/d4b47123df7b8ecdf5061cb0bcecdfef\"},\"description\":\"Europa er\u00f6ffnet mit Fed-Optimismus h\u00f6her; Schweizer Aktien hinken wegen Zollsorgen hinterherDie europ\u00e4ischen Aktienm\u00e4rkte erholen sich, da...\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taglicher-marktuberblick\\\/maerkte-in-erholung-nach-schockierenden-nfp-revisionen-hoffnung-auf-fed-zinssenkungen-schweizer-aktien-schwach-asien-gemischt\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/smarttrader.community\\\/de\\\/taglicher-marktuberblick\\\/maerkte-in-erholung-nach-schockierenden-nfp-revisionen-hoffnung-auf-fed-zinssenkungen-schweizer-aktien-schwach-asien-gemischt\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taglicher-marktuberblick\\\/maerkte-in-erholung-nach-schockierenden-nfp-revisionen-hoffnung-auf-fed-zinssenkungen-schweizer-aktien-schwach-asien-gemischt\\\/#primaryimage\",\"url\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/Fed.png\",\"contentUrl\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/Fed.png\",\"width\":683,\"height\":455},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/taglicher-marktuberblick\\\/maerkte-in-erholung-nach-schockierenden-nfp-revisionen-hoffnung-auf-fed-zinssenkungen-schweizer-aktien-schwach-asien-gemischt\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"M\u00e4rkte in Erholung nach schockierenden NFP-Revisionen; Hoffnung auf Fed-Zinssenkungen; Schweizer Aktien schwach, Asien gemischt\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/\",\"name\":\"SmartTrader\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/#\\\/schema\\\/person\\\/d4b47123df7b8ecdf5061cb0bcecdfef\",\"name\":\"SMARTTRADER ANALYST TEAM\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/cropped-favicon-site-96x96.png\",\"url\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/cropped-favicon-site-96x96.png\",\"contentUrl\":\"https:\\\/\\\/smarttrader.community\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/cropped-favicon-site-96x96.png\",\"caption\":\"SMARTTRADER ANALYST TEAM\"},\"url\":\"https:\\\/\\\/smarttrader.community\\\/de\\\/author\\\/kateryna-admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"M\u00e4rkte in Erholung nach schockierenden NFP-Revisionen; Hoffnung auf Fed-Zinssenkungen; Schweizer Aktien schwach, Asien gemischt - SmartTrader","description":"Europa er\u00f6ffnet mit Fed-Optimismus h\u00f6her; Schweizer Aktien hinken wegen Zollsorgen hinterherDie europ\u00e4ischen Aktienm\u00e4rkte erholen sich, da...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/maerkte-in-erholung-nach-schockierenden-nfp-revisionen-hoffnung-auf-fed-zinssenkungen-schweizer-aktien-schwach-asien-gemischt\/","og_locale":"de_DE","og_type":"article","og_title":"M\u00e4rkte in Erholung nach schockierenden NFP-Revisionen; Hoffnung auf Fed-Zinssenkungen; Schweizer Aktien schwach, Asien gemischt - SmartTrader","og_description":"Europa er\u00f6ffnet mit Fed-Optimismus h\u00f6her; Schweizer Aktien hinken wegen Zollsorgen hinterherDie europ\u00e4ischen Aktienm\u00e4rkte erholen sich, da...","og_url":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/maerkte-in-erholung-nach-schockierenden-nfp-revisionen-hoffnung-auf-fed-zinssenkungen-schweizer-aktien-schwach-asien-gemischt\/","og_site_name":"SmartTrader","article_published_time":"2025-08-04T11:53:27+00:00","article_modified_time":"2025-08-04T12:10:14+00:00","og_image":[{"width":683,"height":455,"url":"https:\/\/smarttrader.community\/wp-content\/uploads\/2025\/05\/Fed.png","type":"image\/png"}],"author":"SMARTTRADER ANALYST TEAM","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"SMARTTRADER ANALYST TEAM","Gesch\u00e4tzte Lesezeit":"4\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/maerkte-in-erholung-nach-schockierenden-nfp-revisionen-hoffnung-auf-fed-zinssenkungen-schweizer-aktien-schwach-asien-gemischt\/#article","isPartOf":{"@id":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/maerkte-in-erholung-nach-schockierenden-nfp-revisionen-hoffnung-auf-fed-zinssenkungen-schweizer-aktien-schwach-asien-gemischt\/"},"author":{"name":"SMARTTRADER ANALYST TEAM","@id":"https:\/\/smarttrader.community\/de\/#\/schema\/person\/d4b47123df7b8ecdf5061cb0bcecdfef"},"headline":"M\u00e4rkte in Erholung nach schockierenden NFP-Revisionen; Hoffnung auf Fed-Zinssenkungen; Schweizer Aktien schwach, Asien gemischt","datePublished":"2025-08-04T11:53:27+00:00","dateModified":"2025-08-04T12:10:14+00:00","mainEntityOfPage":{"@id":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/maerkte-in-erholung-nach-schockierenden-nfp-revisionen-hoffnung-auf-fed-zinssenkungen-schweizer-aktien-schwach-asien-gemischt\/"},"wordCount":631,"commentCount":0,"image":{"@id":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/maerkte-in-erholung-nach-schockierenden-nfp-revisionen-hoffnung-auf-fed-zinssenkungen-schweizer-aktien-schwach-asien-gemischt\/#primaryimage"},"thumbnailUrl":"https:\/\/smarttrader.community\/wp-content\/uploads\/2025\/05\/Fed.png","articleSection":["T\u00e4glicher Markt\u00fcberblick"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/maerkte-in-erholung-nach-schockierenden-nfp-revisionen-hoffnung-auf-fed-zinssenkungen-schweizer-aktien-schwach-asien-gemischt\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/maerkte-in-erholung-nach-schockierenden-nfp-revisionen-hoffnung-auf-fed-zinssenkungen-schweizer-aktien-schwach-asien-gemischt\/","url":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/maerkte-in-erholung-nach-schockierenden-nfp-revisionen-hoffnung-auf-fed-zinssenkungen-schweizer-aktien-schwach-asien-gemischt\/","name":"M\u00e4rkte in Erholung nach schockierenden NFP-Revisionen; Hoffnung auf Fed-Zinssenkungen; Schweizer Aktien schwach, Asien gemischt - SmartTrader","isPartOf":{"@id":"https:\/\/smarttrader.community\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/maerkte-in-erholung-nach-schockierenden-nfp-revisionen-hoffnung-auf-fed-zinssenkungen-schweizer-aktien-schwach-asien-gemischt\/#primaryimage"},"image":{"@id":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/maerkte-in-erholung-nach-schockierenden-nfp-revisionen-hoffnung-auf-fed-zinssenkungen-schweizer-aktien-schwach-asien-gemischt\/#primaryimage"},"thumbnailUrl":"https:\/\/smarttrader.community\/wp-content\/uploads\/2025\/05\/Fed.png","datePublished":"2025-08-04T11:53:27+00:00","dateModified":"2025-08-04T12:10:14+00:00","author":{"@id":"https:\/\/smarttrader.community\/de\/#\/schema\/person\/d4b47123df7b8ecdf5061cb0bcecdfef"},"description":"Europa er\u00f6ffnet mit Fed-Optimismus h\u00f6her; Schweizer Aktien hinken wegen Zollsorgen hinterherDie europ\u00e4ischen Aktienm\u00e4rkte erholen sich, da...","breadcrumb":{"@id":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/maerkte-in-erholung-nach-schockierenden-nfp-revisionen-hoffnung-auf-fed-zinssenkungen-schweizer-aktien-schwach-asien-gemischt\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/maerkte-in-erholung-nach-schockierenden-nfp-revisionen-hoffnung-auf-fed-zinssenkungen-schweizer-aktien-schwach-asien-gemischt\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/maerkte-in-erholung-nach-schockierenden-nfp-revisionen-hoffnung-auf-fed-zinssenkungen-schweizer-aktien-schwach-asien-gemischt\/#primaryimage","url":"https:\/\/smarttrader.community\/wp-content\/uploads\/2025\/05\/Fed.png","contentUrl":"https:\/\/smarttrader.community\/wp-content\/uploads\/2025\/05\/Fed.png","width":683,"height":455},{"@type":"BreadcrumbList","@id":"https:\/\/smarttrader.community\/de\/taglicher-marktuberblick\/maerkte-in-erholung-nach-schockierenden-nfp-revisionen-hoffnung-auf-fed-zinssenkungen-schweizer-aktien-schwach-asien-gemischt\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/smarttrader.community\/de\/"},{"@type":"ListItem","position":2,"name":"M\u00e4rkte in Erholung nach schockierenden NFP-Revisionen; Hoffnung auf Fed-Zinssenkungen; Schweizer Aktien schwach, Asien gemischt"}]},{"@type":"WebSite","@id":"https:\/\/smarttrader.community\/de\/#website","url":"https:\/\/smarttrader.community\/de\/","name":"SmartTrader","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/smarttrader.community\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/smarttrader.community\/de\/#\/schema\/person\/d4b47123df7b8ecdf5061cb0bcecdfef","name":"SMARTTRADER ANALYST TEAM","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/03\/cropped-favicon-site-96x96.png","url":"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/03\/cropped-favicon-site-96x96.png","contentUrl":"https:\/\/smarttrader.community\/wp-content\/uploads\/2023\/03\/cropped-favicon-site-96x96.png","caption":"SMARTTRADER ANALYST TEAM"},"url":"https:\/\/smarttrader.community\/de\/author\/kateryna-admin\/"}]}},"_links":{"self":[{"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/posts\/51794","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/users\/2118"}],"replies":[{"embeddable":true,"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/comments?post=51794"}],"version-history":[{"count":1,"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/posts\/51794\/revisions"}],"predecessor-version":[{"id":51795,"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/posts\/51794\/revisions\/51795"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/media\/50987"}],"wp:attachment":[{"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/media?parent=51794"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/categories?post=51794"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/smarttrader.community\/de\/wp-json\/wp\/v2\/tags?post=51794"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}